{"id":1460698,"date":"2025-04-01T09:03:51","date_gmt":"2025-04-01T16:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/"},"modified":"2025-04-01T09:03:51","modified_gmt":"2025-04-01T16:03:51","slug":"washington-23-estados-demandan-trump-salud-publica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","title":{"rendered":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica"},"content":{"rendered":"<p>Fiscales generales dem\u00f3cratas de 23 estados y de la ciudad de Washington presentaron <a href=\"https:\/\/ag.ny.gov\/press-release\/2025\/attorney-general-james-sues-trump-administration-slashing-vital-health-funding\">una demanda<\/a> contra el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s) y contra su secretario, Robert F. Kennedy Jr., por la repentina reducci\u00f3n de US$ 12.000 millones en fondos de salud p\u00fablica por parte del departamento que alegan que fue ilegal y perjudicial.<\/p>\n<p>En la demanda, presentada este martes, los fiscales generales solicitan una orden de restricci\u00f3n temporal y una medida cautelar para detener de inmediato los recortes de los fondos por parte de la administraci\u00f3n que \u2014seg\u00fan afirman\u2014 provocar\u00e1n la interrupci\u00f3n de servicios clave de salud p\u00fablica y la p\u00e9rdida de empleos de miles de trabajadores de la salud.<\/p>\n<p>La semana pasada, los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC) recortaron aproximadamente US$ 11.400 millones en fondos asignados a los departamentos de salud estatales y comunitarios durante la respuesta a la pandemia de covid-19. Los CDC esperan comenzar a recuperar este dinero en aproximadamente 30 d\u00edas, seg\u00fan el HHS. Se cancelaron US$ mil millones adicionales de la Administraci\u00f3n de Servicios de Abuso de Sustancias y Salud Mental, seg\u00fan los fiscales generales.<\/p>\n<p>El HHS declar\u00f3 este martes que no har\u00eda comentarios sobre los litigios en curso.<\/p>\n<p>\u201cLa pandemia de covid-19 ha terminado, y el HHS ya no malgastar\u00e1 miles de millones de d\u00f3lares de los contribuyentes para responder a una pandemia inexistente que los estadounidenses superaron hace a\u00f1os. El HHS priorizar\u00e1 el financiamiento de proyectos que cumplan con el mandato del presidente Trump de abordar nuestra epidemia de enfermedades cr\u00f3nicas y hacer que Estados Unidos vuelva a ser saludable\u201d, declar\u00f3 la agencia la semana pasada.<\/p>\n<p>La coalici\u00f3n de fiscales generales argumenta que, si bien es cierto que esos fondos eliminados fueron asignados durante la pandemia de covid-19, nunca se destinaron \u00fanicamente a la respuesta al covid-19. M\u00e1s bien gran parte de los fondos se asignaron para apoyar el sistema de salud p\u00fablica a largo plazo, as\u00ed como para la preparaci\u00f3n ante pandemias y ciertos servicios de salud conductual, incluyendo el tratamiento de adicciones y la prevenci\u00f3n del suicidio.<\/p>\n<p>\u201cRecortar estos fondos ahora revertir\u00e1 nuestro progreso en la crisis de opioides, sumir\u00e1 en el caos nuestros sistemas de salud mental y dejar\u00e1 a los hospitales con dificultades para atender a los pacientes\u201d, declar\u00f3 en un comunicado de prensa la fiscal general de Nueva York, Letitia James, cuyo estado podr\u00eda perder m\u00e1s de US$ 400 millones en fondos de salud p\u00fablica.<\/p>\n<p>Los fondos estaban siendo utilizados para dar respuestas sanitarias m\u00e1s s\u00f3lidas en el futuro, incluyendo los brotes de sarampi\u00f3n y gripe aviar H5N1 que hay actualmente, declar\u00f3 el Dr. Joseph Kanter, director ejecutivo de la Asociaci\u00f3n de Funcionarios de Salud Estatales y Territoriales, cuando se anunciaron los recortes la semana pasada.<\/p>\n<p>\u201cEstos fondos fueron asignados por el Congreso y fueron asignados a los departamentos de salud con planes de trabajo, presupuestos y plazos aprobados por las agencias federales\u201d, declar\u00f3 Kanter en un comunicado. Su organizaci\u00f3n no est\u00e1 involucrada en la nueva demanda.<\/p>\n<p>\u201cCon el apoyo del Congreso y del poder ejecutivo, estos fondos se estaban utilizando para modernizar los sistemas de datos, reforzar la capacidad de los laboratorios, mejorar la notificaci\u00f3n electr\u00f3nica de casos de brotes de enfermedades infecciosas urgentes, mejorar las pruebas de detecci\u00f3n del H5N1 y el sarampi\u00f3n, y reforzar la preparaci\u00f3n biom\u00e9dica contra el terrorismo, por nombrar solo algunos ejemplos\u201d, declar\u00f3. \u201cNos preocupa que la abrupta interrupci\u00f3n de estas actividades perjudique la capacidad de los estados y territorios para responder a las amenazas actuales y futuras\u201d.<\/p>\n<p>La nueva demanda alega que el gobierno est\u00e1 socavando el poder constitucional del Congreso, ya que los fondos estaban vinculados a asignaciones espec\u00edficas del \u00f3rgano legislativo. Argumenta que la administraci\u00f3n carece de la autoridad legal para rescindir los fondos ya asignados.<\/p>\n<p>Esta es la \u00faltima de una ola de litigios contra la administraci\u00f3n el Gobierno Trump. Se han presentado m\u00e1s de 100 demandas contra las medidas ejecutivas de la administraci\u00f3n en los primeros meses de su segunda presidencia.<\/p>\n<p>Si bien la \u00faltima demanda solicita una orden de restricci\u00f3n temporal como primer paso, la coalici\u00f3n de fiscales generales podr\u00eda trabajar para lograr una orden judicial permanente sobre estos recortes a la salud p\u00fablica, afirm\u00f3 Daniel Karon, abogado con sede en Cleveland que no participa en la demanda, pero que ha estado siguiendo los casos contra la administraci\u00f3n.<\/p>\n<p>\u201cLa preocupaci\u00f3n es, por supuesto, si el gobierno federal pierde, \u00bfla administraci\u00f3n honrar\u00e1, respetar\u00e1 e implementar\u00e1 el fallo del tribunal?\u201d, pregunt\u00f3 Karon, profesor de derecho del consumidor en la Facultad de Derecho de la Universidad de Michigan y en la Facultad de Derecho Moritz de la Universidad Estatal de Ohio.<\/p>\n<p>\u201cCuando se habla de una crisis constitucional, se refieren a esto\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fiscales generales dem\u00f3cratas de 23 estados y de la ciudad de Washington presentaron una demanda contra el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s) y contra su secretario, Robert F. Kennedy Jr., por la repentina reducci\u00f3n de US$ 12.000 millones en fondos de salud p\u00fablica por parte del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460698","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias\" \/>\n<meta property=\"og:description\" content=\"Fiscales generales dem\u00f3cratas de 23 estados y de la ciudad de Washington presentaron una demanda contra el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s) y contra su secretario, Robert F. Kennedy Jr., por la repentina reducci\u00f3n de US$ 12.000 millones en fondos de salud p\u00fablica por parte del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T16:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica\",\"datePublished\":\"2025-04-01T16:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\"},\"wordCount\":877,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\",\"name\":\"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-01T16:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias","og_description":"Fiscales generales dem\u00f3cratas de 23 estados y de la ciudad de Washington presentaron una demanda contra el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s) y contra su secretario, Robert F. Kennedy Jr., por la repentina reducci\u00f3n de US$ 12.000 millones en fondos de salud p\u00fablica por parte del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-01T16:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/"},"author":{"name":"","@id":""},"headline":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica","datePublished":"2025-04-01T16:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/"},"wordCount":877,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","name":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-01T16:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica","url":"http:\/\/noticiasya.com\/boston\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-01T16:03:51Z","datePublished":"2025-04-01T16:03:51Z","dateModified":"2025-04-01T16:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\\u00fablica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/04\\\/01\\\/washington-23-estados-demandan-trump-salud-publica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/04\\\/01\\\/washington-23-estados-demandan-trump-salud-publica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-01T16:03:51Z\",\"datePublished\":\"2025-04-01T16:03:51Z\",\"dateModified\":\"2025-04-01T16:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465612,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/18\/demanda-condicionar-fondos-cooperacion-materia-migratoria-trax\/","url_meta":{"origin":1460698,"position":0},"title":"Demandan al Gobierno de Trump por condicionar fondos para v\u00edctimas de cr\u00edmenes a cambio de cooperaci\u00f3n en materia migratoria","author":"","date":"agosto 18, 2025","format":false,"excerpt":"Veinte estados y Washington demandaron al Gobierno de Trump este lunes, alegando que retiene indebidamente cientos de millones de d\u00f3lares destinados a ayudar a las v\u00edctimas de cr\u00edmenes con el fin de obligar a los estados a cooperar con los esfuerzos federales de control migratorio.Los estados, todos con fiscales generales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469827,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","url_meta":{"origin":1460698,"position":1},"title":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas","author":"","date":"enero 6, 2026","format":false,"excerpt":"El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460484,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/27\/recortes-subvenciones-departamento-salud-cdc-trax\/","url_meta":{"origin":1460698,"position":2},"title":"La administraci\u00f3n Trump retira miles de millones en fondos de la era covid-19 para departamentos de salud estatales y locales","author":"","date":"marzo 27, 2025","format":false,"excerpt":"Los departamentos de salud p\u00fablica estatales y locales se preparan para que los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. retiren unos US$ 11.400 millones en subvenciones que se asignaron a los departamentos de salud estatales y comunitarios durante la respuesta a la pandemia de covid-19.\u201cLa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469953,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/10\/juez-detiene-recorte-fondos-trump-estados-democratas-trax\/","url_meta":{"origin":1460698,"position":3},"title":"Juez detiene recorte de fondos sociales y cuidado infantil que orden\u00f3 Trump contra cinco estados liderados por dem\u00f3cratas","author":"","date":"enero 10, 2026","format":false,"excerpt":"Un juez federal suspendi\u00f3 temporalmente este viernes la congelaci\u00f3n de US$ 10.000 millones en fondos de asistencia social y cuidado infantil por parte de la administraci\u00f3n Trump en cinco estados liderados por dem\u00f3cratas a ra\u00edz de una amplia investigaci\u00f3n sobre un presunto fraude en la financiaci\u00f3n federal en Minnesota.El juez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469566,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/25\/pediatras-demanda-trump-subvenciones-trax\/","url_meta":{"origin":1460698,"position":4},"title":"Pediatras demandan al Gobierno de Trump para detener un recorte de casi US$ 12 millones en subvenciones federales","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"Un importante grupo de pediatr\u00eda solicit\u00f3 a un juez federal que impida que la administraci\u00f3n Trump cancelar casi US$ 12 millones en subvenciones federales.La Academia Estadounidense de Pediatr\u00eda (AAP, por sus siglas en ingl\u00e9s) argumenta que el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470407,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/22\/administracion-trump-estados-democratas-revision-financiacion-trax\/","url_meta":{"origin":1460698,"position":5},"title":"La administraci\u00f3n Trump somete a 14 estados dem\u00f3cratas a una revisi\u00f3n radical de la financiaci\u00f3n federal","author":"","date":"enero 22, 2026","format":false,"excerpt":"La administraci\u00f3n Trump ha ordenado una revisi\u00f3n de los fondos federales enviados a m\u00e1s de una docena de estados liderados por dem\u00f3cratas, seg\u00fan m\u00faltiples fuentes familiarizadas con el asunto.La amplia escala de la revisi\u00f3n se describe en una solicitud de datos presupuestarios que se envi\u00f3 el martes a todos los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1460698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1460698"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1460698\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1460698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1460698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1460698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}