{"id":1466956,"date":"2025-09-29T15:03:44","date_gmt":"2025-09-29T22:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/"},"modified":"2025-09-29T15:03:44","modified_gmt":"2025-09-29T22:03:44","slug":"protestas-ice-chicago-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2025\/09\/29\/protestas-ice-chicago-trax\/","title":{"rendered":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia"},"content":{"rendered":"<p>Tras enfrentamientos con las fuerzas del orden en un centro de detenci\u00f3n de ICE en un suburbio de Chicago durante el fin de semana, cuatro manifestantes enfrentar\u00e1n cargos federales, incluyendo uno que amenaz\u00f3 con matar a un agente, seg\u00fan las denuncias penales.<\/p>\n<p>Docenas de agentes federales en equipo t\u00e1ctico desplegaron municiones no letales mientras dispersaban a una multitud de manifestantes afuera del centro la tarde del s\u00e1bado. Durante semanas, manifestantes se han reunido en ese lugar, a unos 16 kil\u00f3metros al oeste de Chicago, para protestar contra el aumento de operativos de ICE y t\u00e1cticas agresivas.<\/p>\n<p>En los \u00faltimos d\u00edas, agentes apostados en ese centro, tanto en tierra como desde el techo, han utilizado balas de pimienta, balas de goma y gas lacrim\u00f3geno para dispersar a los manifestantes.<\/p>\n<p>Tres personas enfrentan cargos por agredir a agentes federales, seg\u00fan las denuncias presentadas el domingo en la corte federal del Distrito Norte de Illinois. Una persona enfrenta cargos por resistirse al arresto.<\/p>\n<p>En uno de los casos, un agente de Investigaciones de Seguridad Nacional alega que el manifestante Paul Ivery admiti\u00f3 haber amenazado con matar a un agente de la Patrulla Fronteriza, gritando frases como \u201cte voy a matar ahora mismo\u201d y \u201chaz algo\u201d, seg\u00fan la denuncia penal.<\/p>\n<p>Ivery luego se resisti\u00f3 al arresto cuando huy\u00f3 de la polic\u00eda y luego se subi\u00f3 a un autom\u00f3vil. La denuncia tambi\u00e9n acusa a Ivery de agredir a un agente federal al agarrar su casco.<\/p>\n<p>\u201cLas acciones de Ivery tambi\u00e9n hicieron que el casco de la V\u00edctima 1 se moviera y lo expusiera temporalmente al gas pimienta en la zona; le caus\u00f3 dolor en la barbilla debido a la correa del casco; y le tir\u00f3 bruscamente la barbilla hacia la clav\u00edcula\u201d, dice la denuncia.<\/p>\n<p>Otra denuncia presentada por un agente de la Oficina de Alcohol, Tabaco, Armas de Fuego y Explosivos (ATF, por sus siglas en ingl\u00e9s) acusa a Ray Collins y Jocelyne Robledo, una pareja de esposos, seg\u00fan la denuncia, de agredir a agentes federales. Se acusa a Robledo de \u201cprovocar un forcejeo con los agentes\u201d, cuando \u201cempuj\u00f3 a los agentes que intentaban ampliar el per\u00edmetro\u201d.<\/p>\n<p>A Collins se le acusa de arremeter contra los agentes durante el enfrentamiento. Seg\u00fan la denuncia, Collins caus\u00f3 una \u201clesi\u00f3n f\u00edsica en el pulgar de un agente especial de la ATF\u201d.<\/p>\n<p>Seg\u00fan la denuncia, tanto Collins como Robledo portaban pistolas semiautom\u00e1ticas de 9 mil\u00edmetros durante las protestas y tienen permisos legales para las armas. No enfrentan cargos relacionados con armas de fuego.<\/p>\n<p>El FBI acus\u00f3 a una cuarta persona, Hubert Mazur, de resistirse al arresto tras negarse a retroceder cuando los agentes se lo ordenaron.<\/p>\n<p>Seg\u00fan la base de datos de reclusos de la Oficina de Prisiones, Ivery y Mazur est\u00e1n bajo custodia federal. Robledo y Collins no parecen estar detenidos.<\/p>\n<p>Se desconoce hasta el momento si alguno de los manifestantes acusados cuenta con abogados.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras enfrentamientos con las fuerzas del orden en un centro de detenci\u00f3n de ICE en un suburbio de Chicago durante el fin de semana, cuatro manifestantes enfrentar\u00e1n cargos federales, incluyendo uno que amenaz\u00f3 con matar a un agente, seg\u00fan las denuncias penales. Docenas de agentes federales en equipo t\u00e1ctico desplegaron municiones no letales mientras dispersaban [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466956","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras enfrentamientos con las fuerzas del orden en un centro de detenci\u00f3n de ICE en un suburbio de Chicago durante el fin de semana, cuatro manifestantes enfrentar\u00e1n cargos federales, incluyendo uno que amenaz\u00f3 con matar a un agente, seg\u00fan las denuncias penales. Docenas de agentes federales en equipo t\u00e1ctico desplegaron municiones no letales mientras dispersaban [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T22:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia\",\"datePublished\":\"2025-09-29T22:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\"},\"wordCount\":537,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\",\"name\":\"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-29T22:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias","og_description":"Tras enfrentamientos con las fuerzas del orden en un centro de detenci\u00f3n de ICE en un suburbio de Chicago durante el fin de semana, cuatro manifestantes enfrentar\u00e1n cargos federales, incluyendo uno que amenaz\u00f3 con matar a un agente, seg\u00fan las denuncias penales. Docenas de agentes federales en equipo t\u00e1ctico desplegaron municiones no letales mientras dispersaban [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-29T22:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/"},"author":{"name":"","@id":""},"headline":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia","datePublished":"2025-09-29T22:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/"},"wordCount":537,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/","name":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-29T22:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/protestas-ice-chicago-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2025\/09\/29\/protestas-ice-chicago-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\u00f3 a un agente, seg\u00fan denuncia","url":"http:\/\/noticiasya.com\/boston\/2025\/09\/29\/protestas-ice-chicago-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2025\/09\/29\/protestas-ice-chicago-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-29T22:03:44Z","datePublished":"2025-09-29T22:03:44Z","dateModified":"2025-09-29T22:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuatro manifestantes en centro de ICE en Illinois enfrentan cargos federales; uno amenaz\\u00f3 a un agente, seg\\u00fan denuncia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/09\\\/29\\\/protestas-ice-chicago-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/09\\\/29\\\/protestas-ice-chicago-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-29T22:03:44Z\",\"datePublished\":\"2025-09-29T22:03:44Z\",\"dateModified\":\"2025-09-29T22:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468012,"url":"https:\/\/noticiasya.com\/boston\/2025\/11\/04\/manifestantes-ice-alcaldesa-broadview-caos-trax\/","url_meta":{"origin":1466956,"position":0},"title":"Manifestantes contra ICE se enfrentan a la alcaldesa de Broadview durante reuni\u00f3n del consejo municipal que termin\u00f3 en caos","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Una reuni\u00f3n del consejo municipal en Broadview, Illinois, se interrumpi\u00f3 este lunes por la noche despu\u00e9s de que los manifestantes se enfrentaran ruidosamente a la alcaldesa por su gesti\u00f3n de las manifestaciones que se han celebrado durante semanas en las instalaciones cercanas del ICE.\u201c\u00a1Deber\u00eda darle verg\u00fcenza, alcaldesa!\u201d, grit\u00f3 un manifestante,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469982,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/11\/protestas-contra-ice-muerte-mujer-minneapolis-trax\/","url_meta":{"origin":1466956,"position":1},"title":"Protestas contra ICE en todo Estados Unidos tras la muerte a tiros de una mujer en Minneapolis por parte de un agente","author":"","date":"enero 11, 2026","format":false,"excerpt":"La indignaci\u00f3n nacional por la muerte a tiros de una mujer de Minneapolis a manos de un agente de ICE se traslad\u00f3 el s\u00e1bado a las calles de ciudades en todo Estados Unidos, con manifestantes que exig\u00edan la salida de las autoridades federales de inmigraci\u00f3n de sus comunidades y justicia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469025,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/06\/agentes-federales-fuerza-manifestantes-pacificos-trax\/","url_meta":{"origin":1466956,"position":2},"title":"Videos muestran que agentes federales de EE.UU. detienen y usan la fuerza contra manifestantes pac\u00edficos","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Agentes federales desplegados durante el aumento de efectivos policiales del Gobierno de Trump en ciudades estadounidenses dispararon a dos cl\u00e9rigos cristianos en la cabeza con sustancias qu\u00edmicas o proyectiles.Uno meditaba con un cartel en la mano, y el otro ten\u00eda los brazos extendidos en se\u00f1al de oraci\u00f3n.El Gobierno afirma que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467089,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/03\/manifestacion-illinois-ice-noem-trax\/","url_meta":{"origin":1466956,"position":3},"title":"Manifestantes protestan ante las instalaciones de ICE en Illinois durante visita de Kristi Noem","author":"","date":"octubre 3, 2025","format":false,"excerpt":"Varias agencias del orden p\u00fablico se encuentran, aparentemente, en un enfrentamiento con decenas de manifestantes este viernes frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) cerca de Chicago, donde este viernes estuvo la secretaria de Seguridad Nacional, Kristi Noem.Al menos una persona ha sido arrestada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468351,"url":"https:\/\/noticiasya.com\/boston\/2025\/11\/14\/detienen-manifestantes-ice-chicago-trax\/","url_meta":{"origin":1466956,"position":4},"title":"Detienen a manifestantes frente a un edificio de ICE cerca de Chicago","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Una protesta mayormente pac\u00edfica frente al edificio del controvertido Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en un suburbio al oeste de Chicago se torn\u00f3 ca\u00f3tica este viernes, cuando la Polic\u00eda local detuvo a varias personas despu\u00e9s de que, presuntamente, derribaran las barreras frente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468829,"url":"https:\/\/noticiasya.com\/boston\/2025\/11\/29\/arrestan-manifestantes-agentes-manhattan-trax\/","url_meta":{"origin":1466956,"position":5},"title":"Arrestan a varios manifestantes que bloquearon a agentes federales en un garaje de Manhattan","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"M\u00e1s de una decena de manifestantes fueron arrestados en el sur de Manhattan este s\u00e1bado tras impedir que agentes federales realizaran actividades de inmigraci\u00f3n y control, seg\u00fan un funcionario de las fuerzas del orden.El grupo de manifestantes coreaba \u201cICE fuera de Nueva York\u201d en im\u00e1genes que los mostraban formando una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1466956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1466956"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1466956\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1466956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1466956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1466956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}