{"id":1470741,"date":"2026-02-01T20:03:51","date_gmt":"2026-02-02T04:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/"},"modified":"2026-02-01T20:03:51","modified_gmt":"2026-02-02T04:03:51","slug":"mapa-resultados-primera-vuelta-elecciones-costa-rica-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","title":{"rendered":"Mapa de resultados de las elecciones en Costa Rica"},"content":{"rendered":"<p>Los costarricenses acudieron a las urnas este domingo para elegir qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente del pa\u00eds. Se presentan un total de 20 candidatos, entre los que se destacan la oficialista Laura Fern\u00e1ndez, \u00c1lvaro Ramos y Claudia Dobles. Si ninguno de los postulantes logra obtener m\u00e1s del 40 % de los votos, los dos primeros se enfrentar\u00e1n a una segunda vuelta electoral.<\/p>\n<p>Si bien la seguridad es la preocupaci\u00f3n principal para los ciudadanos a la hora de elegir a un candidato, tambi\u00e9n hay otras inquietudes que han ido ganando fuerza, como el deterioro de la educaci\u00f3n p\u00fablica y la ausencia de un di\u00e1logo social que permita trazar un rumbo claro para el pa\u00eds.<\/p>\n<p><strong>Con el 61,5% de los votos contabilizados, estos son los resultados preliminares:<\/strong><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los costarricenses acudieron a las urnas este domingo para elegir qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente del pa\u00eds. Se presentan un total de 20 candidatos, entre los que se destacan la oficialista Laura Fern\u00e1ndez, \u00c1lvaro Ramos y Claudia Dobles. Si ninguno de los postulantes logra obtener m\u00e1s del 40 % de los votos, los dos primeros [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470741","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mapa de resultados de las elecciones en Costa Rica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa de resultados de las elecciones en Costa Rica - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los costarricenses acudieron a las urnas este domingo para elegir qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente del pa\u00eds. Se presentan un total de 20 candidatos, entre los que se destacan la oficialista Laura Fern\u00e1ndez, \u00c1lvaro Ramos y Claudia Dobles. Si ninguno de los postulantes logra obtener m\u00e1s del 40 % de los votos, los dos primeros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T04:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mapa de resultados de las elecciones en Costa Rica\",\"datePublished\":\"2026-02-02T04:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\"},\"wordCount\":158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\",\"name\":\"Mapa de resultados de las elecciones en Costa Rica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-02T04:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa de resultados de las elecciones en Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa de resultados de las elecciones en Costa Rica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa de resultados de las elecciones en Costa Rica - Noticias","og_description":"Los costarricenses acudieron a las urnas este domingo para elegir qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente del pa\u00eds. Se presentan un total de 20 candidatos, entre los que se destacan la oficialista Laura Fern\u00e1ndez, \u00c1lvaro Ramos y Claudia Dobles. Si ninguno de los postulantes logra obtener m\u00e1s del 40 % de los votos, los dos primeros [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-02T04:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/"},"author":{"name":"","@id":""},"headline":"Mapa de resultados de las elecciones en Costa Rica","datePublished":"2026-02-02T04:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/"},"wordCount":158,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","name":"Mapa de resultados de las elecciones en Costa Rica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-02T04:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mapa de resultados de las elecciones en Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mapa de resultados de las elecciones en Costa Rica","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/01\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-02T04:03:51Z","datePublished":"2026-02-02T04:03:51Z","dateModified":"2026-02-02T04:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mapa de resultados de las elecciones en Costa Rica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/01\\\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/01\\\/mapa-resultados-primera-vuelta-elecciones-costa-rica-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-02T04:03:51Z\",\"datePublished\":\"2026-02-02T04:03:51Z\",\"dateModified\":\"2026-02-02T04:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473084,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/12\/mapa-resultados-primera-vuelta-elecciones-peru-orix\/","url_meta":{"origin":1470741,"position":0},"title":"Mapa de resultados de la primera vuelta de las elecciones presidenciales en Per\u00fa 2026: d\u00f3nde gana cada candidato","author":"","date":"abril 12, 2026","format":false,"excerpt":"Los peruanos acudieron a las urnas este 12 de abril para elegir presidente en una jornada que marcar\u00e1 el rumbo pol\u00edtico y econ\u00f3mico del pa\u00eds en los pr\u00f3ximos a\u00f1os.En medio de un escenario de alta fragmentaci\u00f3n y descontento ciudadano, los votantes decidieron entre diversas propuestas que buscaban responder a desaf\u00edos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455486,"url":"https:\/\/noticiasya.com\/boston\/2024\/10\/31\/elecciones-uruguay-yamandu-orsi-alvaro-delgado-votos-decisivos-orix\/","url_meta":{"origin":1470741,"position":1},"title":"Elecciones en Uruguay: Yamand\u00fa Orsi y \u00c1lvaro Delgado van en busca de votos decisivos","author":"","date":"octubre 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Barajar y dar de nuevo. La carrera presidencial en Uruguay dej\u00f3 a nueve candidatos en el camino en la primera vuelta y solo quedan dos en la contienda hacia la Torre Ejecutiva: Yamand\u00fa Orsi, del centroizquierdista Frente Amplio, y \u00c1lvaro Delgado, del centroderechista Partido Nacional. Los uruguayos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462063,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/07\/como-vota-conclave-elegir-nuevo-papa-orix\/","url_meta":{"origin":1470741,"position":2},"title":"\u00bfC\u00f3mo vota el c\u00f3nclave para elegir al nuevo papa?","author":"","date":"mayo 7, 2025","format":false,"excerpt":"Con la muerte del papa Francisco se puso en marcha la tradici\u00f3n centenaria, solemne y secreta para elegir al nuevo l\u00edder de la Iglesia cat\u00f3lica que ahora comienza: el c\u00f3nclave. Este evento re\u00fane a un grupo de cardenales de todo el mundo, quienes se encierran en la Capilla Sixtina con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455610,"url":"https:\/\/noticiasya.com\/boston\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","url_meta":{"origin":1470741,"position":3},"title":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n","author":"","date":"noviembre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, fue la preferida de los puertorrique\u00f1os en una votaci\u00f3n simb\u00f3lica que tuvo lugar en la isla para la elecci\u00f3n presidencial de Estados Unidos, con 73,46% de los votos (709.902 personas) frente al 26,54% (256.505) del candidato presidencial republicano, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451601,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/05\/empate-2024-eleccion-contingente-elecciones-presidenciales-eeuu-trax\/","url_meta":{"origin":1470741,"position":4},"title":"AN\u00c1LISIS | \u00bfQu\u00e9 pasa si hay empate en 2024? Prep\u00e1rate para una &#171;elecci\u00f3n contingente&#187;","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- Con dos candidatos presidenciales luchando por tan s\u00f3lo 538 votos del Colegio Electoral, un escenario de empate es m\u00e1s que posible. De hecho, es sorprendente que hasta ahora s\u00f3lo haya habido un empate, en 1800, entre Thomas Jefferson y Aaron Burr.Ese empate fue el resultado de un fallo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451661,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/07\/actas-resultados-venezuela-oposicion-cne-comprobar-orix\/","url_meta":{"origin":1470741,"position":5},"title":"\u00bfPor qu\u00e9 los resultados de la oposici\u00f3n en Venezuela se pueden comprobar y los del CNE no?","author":"","date":"agosto 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un an\u00e1lisis de varios expertos a pedido de CNN de los resultados ofrecidos tanto por el Consejo Nacional Electoral (CNE) como por el opositor Comando Con Venezuela de las elecciones presidenciales de ese pa\u00eds concluye que los n\u00fameros que dan como ganador al presidente Nicol\u00e1s Maduro \u201cson\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1470741"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470741\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1470741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1470741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1470741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}