{"id":1470771,"date":"2026-02-02T15:03:51","date_gmt":"2026-02-02T23:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/"},"modified":"2026-02-02T15:03:51","modified_gmt":"2026-02-02T23:03:51","slug":"abogados-victimas-epstein-retirar-archivos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","title":{"rendered":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres"},"content":{"rendered":"<p>Abogados que representan a v\u00edctimas de Jeffrey Epstein est\u00e1n pidiendo a jueces que ordenen al Departamento de Justicia de EE.UU. retirar los millones de documentos relacionados con Epstein que ha publicado en l\u00ednea, al se\u00f1alar en una carta fechada el domingo que la falta de una adecuada censura de la informaci\u00f3n de las v\u00edctimas ha desencadenado una \u201cemergencia en desarrollo\u201d.<\/p>\n<p>La carta, escrita por los destacados abogados de v\u00edctimas de Epstein Brittany Henderson y Brad Edwards y dirigida a dos jueces federales en Nueva York que supervisan los casos de Epstein y de Ghislaine Maxwell, solicita una \u201cintervenci\u00f3n judicial inmediata\u201d para abordar el hecho de que la informaci\u00f3n de las v\u00edctimas se incluy\u00f3 en los millones de registros relacionados con Epstein que fueron divulgados.<\/p>\n<p>Henderson dijo a CNN que la carta fue enviada a los jueces. El documento a\u00fan no est\u00e1 disponible en el expediente judicial p\u00fablico.<\/p>\n<p>\u201cEn las \u00faltimas 48 horas, quien suscribe ha reportado por s\u00ed sola miles de fallas de censura en nombre de casi 100 sobrevivientes individuales cuyas vidas han quedado patas arriba por la m\u00e1s reciente divulgaci\u00f3n del Departamento de Justicia\u201d, escribieron Henderson y Edwards a los jueces Richard Berman y Paul Engelmayer.<\/p>\n<p>\u201cNo existe ning\u00fan grado imaginable de incompetencia institucional suficiente para explicar la magnitud, coherencia y persistencia de las fallas que ocurrieron \u2014en particular cuando la \u00fanica tarea ordenada por el tribunal y reiteradamente enfatizada por el Departamento de Justicia era simple: censurar los nombres conocidos de las v\u00edctimas antes de la publicaci\u00f3n\u201d, agregaron.<\/p>\n<p>Los abogados enumeran numerosos ejemplos de errores de censura que han encontrado, como el caso de una v\u00edctima menor de edad cuyo nombre presuntamente fue \u201crevelado 20 veces en un solo documento\u201d. Una vez que esos errores fueron reportados al Departamento de Justicia, la entidad solo corrigi\u00f3 tres, \u201cdejando 17 instancias a\u00fan sin censurar al momento de esta presentaci\u00f3n\u201d, escribieron los abogados.<\/p>\n<p>Otros ejemplos incluyen un correo electr\u00f3nico que presuntamente enumera a 32 v\u00edctimas menores de edad \u201ccon solo un nombre censurado y 31 visibles\u201d, as\u00ed como formularios \u201c302\u201d del FBI con nombres y apellidos completos de las v\u00edctimas sin censura.<\/p>\n<p>El Departamento de Justicia dijo en una respuesta presentada el lunes ante los jueces en ambos casos que ha retirado todos los documentos identificados por las v\u00edctimas o sus abogados.<\/p>\n<p>\u201cAl momento de redactar esta carta, todos los documentos cuya retirada fue solicitada por las v\u00edctimas o sus abogados hasta anoche han sido retirados para una censura adicional, y el Departamento contin\u00faa procesando cualquier nueva solicitud y realizando sus propias b\u00fasquedas para identificar otros documentos que puedan requerir mayor censura\u201d, dijo el Departamento de Justicia.<\/p>\n<p>CNN inform\u00f3 el viernes que varias sobrevivientes, incluidas v\u00edctimas an\u00f3nimas identificadas como \u201cJane Doe\u201d, estaban viendo sus nombres e informaci\u00f3n a lo largo de los archivos publicados.<\/p>\n<p>La carta del domingo tambi\u00e9n incluye testimonios de varias v\u00edctimas an\u00f3nimas \u201cJane Doe\u201d, quienes describieron haber recibido amenazas de muerte y acoso por parte de medios de comunicaci\u00f3n desde la publicaci\u00f3n de los archivos.<\/p>\n<p>Una Jane Doe es citada diciendo: \u201cla divulgaci\u00f3n de esta informaci\u00f3n no solo es profundamente angustiante y retraumatizante, sino que tambi\u00e9n me coloca a m\u00ed y a mi hijo ante un posible riesgo f\u00edsico\u201d.<\/p>\n<p>\u201cEl Departamento de Justicia no puede caracterizar de manera cre\u00edble esto como un error, negligencia o falla burocr\u00e1tica. La tarea era sencilla: tomar la lista de v\u00edctimas conocidas y censurar esos nombres en todos los lugares donde aparecieran\u201d, escribieron los abogados. \u201cCuando el Departamento de Justicia crey\u00f3 estar listo para publicar, solo necesitaba escribir el nombre de cada v\u00edctima en su propia funci\u00f3n de b\u00fasqueda. Cualquier resultado deb\u00eda haber sido censurado antes de la publicaci\u00f3n. De haberlo hecho, el da\u00f1o se habr\u00eda evitado\u201d.<\/p>\n<p>En una declaraci\u00f3n separada a CNN, Henderson dijo: \u201ccon cada segundo que pasa, se est\u00e1 causando un da\u00f1o adicional a estas mujeres. Est\u00e1n asustadas y devastadas, y ruegan que nuestro Gobierno las proteja de m\u00e1s da\u00f1o\u201d.<\/p>\n<p>Un portavoz del Departamento de Justicia dijo previamente a CNN que la entidad se toma la protecci\u00f3n de las v\u00edctimas \u201cmuy en serio\u201d y que ha censurado miles de nombres de v\u00edctimas en los registros publicados, con 500 revisores examinando los archivos \u201cprecisamente por esta raz\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abogados que representan a v\u00edctimas de Jeffrey Epstein est\u00e1n pidiendo a jueces que ordenen al Departamento de Justicia de EE.UU. retirar los millones de documentos relacionados con Epstein que ha publicado en l\u00ednea, al se\u00f1alar en una carta fechada el domingo que la falta de una adecuada censura de la informaci\u00f3n de las v\u00edctimas ha [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470771","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &quot;miles de fallas de censura&quot; de nombres - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &quot;miles de fallas de censura&quot; de nombres - Noticias\" \/>\n<meta property=\"og:description\" content=\"Abogados que representan a v\u00edctimas de Jeffrey Epstein est\u00e1n pidiendo a jueces que ordenen al Departamento de Justicia de EE.UU. retirar los millones de documentos relacionados con Epstein que ha publicado en l\u00ednea, al se\u00f1alar en una carta fechada el domingo que la falta de una adecuada censura de la informaci\u00f3n de las v\u00edctimas ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T23:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres\",\"datePublished\":\"2026-02-02T23:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\",\"name\":\"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por \\\"miles de fallas de censura\\\" de nombres - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-02T23:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por \"miles de fallas de censura\" de nombres - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por \"miles de fallas de censura\" de nombres - Noticias","og_description":"Abogados que representan a v\u00edctimas de Jeffrey Epstein est\u00e1n pidiendo a jueces que ordenen al Departamento de Justicia de EE.UU. retirar los millones de documentos relacionados con Epstein que ha publicado en l\u00ednea, al se\u00f1alar en una carta fechada el domingo que la falta de una adecuada censura de la informaci\u00f3n de las v\u00edctimas ha [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-02T23:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/"},"author":{"name":"","@id":""},"headline":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres","datePublished":"2026-02-02T23:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","name":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por \"miles de fallas de censura\" de nombres - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-02T23:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Abogados de v\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/02\/abogados-victimas-epstein-retirar-archivos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-02T23:03:51Z","datePublished":"2026-02-02T23:03:51Z","dateModified":"2026-02-02T23:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Abogados de v\\u00edctimas de Epstein piden a jueces retirar los archivos publicados por &#171;miles de fallas de censura&#187; de nombres\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/02\\\/abogados-victimas-epstein-retirar-archivos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/02\\\/abogados-victimas-epstein-retirar-archivos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-02T23:03:51Z\",\"datePublished\":\"2026-02-02T23:03:51Z\",\"dateModified\":\"2026-02-02T23:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472611,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/27\/sobrevivientes-epstein-demandan-doj-google-trax\/","url_meta":{"origin":1470771,"position":0},"title":"Sobrevivientes del caso Epstein demandan al Departamento de Justicia y a Google por la divulgaci\u00f3n de informaci\u00f3n privada","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Un grupo de sobrevivientes del caso de Jeffrey Epstein present\u00f3 el jueves una demanda colectiva contra el Departamento de Justicia y Google, a ra\u00edz de la divulgaci\u00f3n de informaci\u00f3n que identifica a las v\u00edctimas en archivos relacionados con el difunto delincuente sexual convicto.La demanda, presentada ante el tribunal federal del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470886,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/05\/archivos-epstein-departamento-justicia-datos-victimas-facilitadores-trax\/","url_meta":{"origin":1470771,"position":1},"title":"El Departamento de Justicia en la mira por revelar datos de v\u00edctimas y ocultar posibles facilitadores en archivos de Epstein","author":"","date":"febrero 5, 2026","format":false,"excerpt":"El Departamento de Justicia no ocult\u00f3 informaci\u00f3n que identificaba a muchas de las v\u00edctimas de Jeffrey Epstein y redact\u00f3 los detalles de individuos que podr\u00edan haber ayudado al delincuente sexual convicto, lo que provoc\u00f3 una protesta de los sobrevivientes que acusan al Departamento de Justicia de arruinar la publicaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470547,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/28\/departamento-justicia-archivos-epstein-publicacion-trax\/","url_meta":{"origin":1470771,"position":2},"title":"El Departamento de Justicia espera publicar pronto sus archivos de Epstein, dicen altos funcionarios","author":"","date":"enero 28, 2026","format":false,"excerpt":"Los principales l\u00edderes del Departamento de Justicia dijeron en una presentaci\u00f3n judicial el martes que esperan publicar los archivos del departamento relacionados con Jeffrey Epstein \u201cen el corto plazo\u201d.La secretaria de Justicia, Pam Bondi, el secretario de Justicia adjunto, Todd Blanche, y el fiscal federal para el Distrito Sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465157,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/05\/rechazan-legitimacion-maxwell-divulgar-jurado-investigador-trax\/","url_meta":{"origin":1470771,"position":3},"title":"V\u00edctimas rechazan &#171;legitimaci\u00f3n&#187; de Maxwell mientras juez eval\u00faa divulgar transcripciones del jurado investigador de Epstein","author":"","date":"agosto 5, 2025","format":false,"excerpt":"Numerosas v\u00edctimas de Jeffrey Epstein arremetieron contra la \u201clegitimaci\u00f3n p\u00fablica\u201d de su c\u00f3mplice Ghislaine Maxwell mientras instaban a un juez federal, que considera revelar las transcripciones del jurado investigador, a tomar en cuenta su privacidad al tomar su decisi\u00f3n.Los abogados Brad Edwards y Paul Cassell, quienes representan a numerosas v\u00edctimas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465260,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/08\/departamento-justicia-pruebas-jurado-investigador-epstein-trax\/","url_meta":{"origin":1470771,"position":4},"title":"Departamento de Justicia dice que quiere publicar las pruebas del jurado investigador de Epstein, adem\u00e1s de transcripciones","author":"","date":"agosto 8, 2025","format":false,"excerpt":"El Departamento de Justicia inform\u00f3 este viernes a dos jueces federales que desea publicar las pruebas del jurado investigador en los casos de Jeffrey Epstein y Ghislaine Maxwell, adem\u00e1s de las transcripciones, con la \u201crevisi\u00f3n apropiada de la informaci\u00f3n relacionada con las v\u00edctimas y otra informaci\u00f3n de identificaci\u00f3n personal\u201d.La presentaci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469333,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/17\/claves-publicacion-archivos-epstein-trax\/","url_meta":{"origin":1470771,"position":5},"title":"Claves para entender la pr\u00f3xima publicaci\u00f3n de los archivos de Epstein","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Una nueva ley federal exige que el Departamento de Justicia publique antes del viernes una enorme cantidad de documentos de investigaci\u00f3n relacionados con Jeffrey Epstein.La publicaci\u00f3n de los archivos de Epstein, que detallan las investigaciones sobre el multimillonario y delincuente sexual ca\u00eddo en desgracia, fallecido en 2019, ha atra\u00eddo una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1470771"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470771\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1470771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1470771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1470771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}