{"id":1470774,"date":"2026-02-02T16:03:43","date_gmt":"2026-02-03T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/"},"modified":"2026-02-02T16:03:43","modified_gmt":"2026-02-03T00:03:43","slug":"spacex-bloquea-starlink-rusia-drones-ucrania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","title":{"rendered":"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania"},"content":{"rendered":"<p>El ministro de Defensa de Ucrania, Mykhailo Fedorov, confirm\u00f3 el domingo que los esfuerzos conjuntos para bloquear el acceso no autorizado al sistema de internet satelital est\u00e1n produciendo \u201cresultados reales\u201d. Esta medida estrat\u00e9gica busca impedir que las fuerzas armadas de Rusia utilicen la red de SpaceX para guiar drones en sus ataques contra territorio ucraniano.<\/p>\n<p>Fedorov dijo que Ucrania trabaj\u00f3 con la empresa SpaceX de Elon Musk, que es propietaria de Starlink, para tomar medidas iniciales para contrarrestar los drones rusos.<\/p>\n<p>Dijo que el siguiente paso es \u201cimplementar un sistema que solo permitir\u00e1 operar terminales autorizados en el territorio de Ucrania\u201d.<\/p>\n<p>Fedorov continu\u00f3: \u201cEn los pr\u00f3ximos d\u00edas, compartiremos instrucciones para que los usuarios ucranianos registren sus terminales Starlink para su verificaci\u00f3n. Las terminales no verificadas ser\u00e1n desactivadas\u201d.<\/p>\n<p>Agreg\u00f3 que el proceso de registro ser\u00eda \u201csimple, r\u00e1pido y f\u00e1cil de usar\u201d.<\/p>\n<p>En respuesta a Fedorov, Musk dijo que \u201clas medidas que tomamos para detener el uso no autorizado de Starlink por parte de Rusia han funcionado\u201d.<\/p>\n<p>\u201cH\u00e1gannos saber si se requiere hacer m\u00e1s\u201d, escribi\u00f3 Musk en X.<\/p>\n<p>De manera similar, Fedorov se\u00f1al\u00f3 que los primeros pasos ya \u201cest\u00e1n entregando resultados reales\u201d.<\/p>\n<p>\u201cGracias por apoyarnos. Eres un verdadero campe\u00f3n de la libertad y un verdadero amigo del pueblo ucraniano\u201d, escribi\u00f3 Fedorov a Musk.<\/p>\n<p>Desde el comienzo de la guerra, <a href=\"https:\/\/www.cnn.com\/2024\/03\/25\/europe\/ukraine-starlink-drones-russia-intl-cmd\">Ucrania ha dependido del servicio de internet satelital de Musk<\/a>, que es utilizado por las fuerzas armadas para comunicarse y operar drones, por el Gobierno, as\u00ed como por muchos civiles, empresas e instituciones p\u00fablicas, incluidos hospitales y escuelas.<\/p>\n<p>Bajo las sanciones estadounidenses, Starlink no puede ser vendido ni utilizado en Rusia. Sin embargo, analistas y funcionarios ucranianos han advertido que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/29\/mundo\/rusia-drones-starlink-ucrania-trax\">Rusia ha encontrado cada vez m\u00e1s formas de aprovechar el sistema para su propio beneficio<\/a>, montando terminales en sus drones de ataque para golpear m\u00e1s profundamente en territorio ucraniano.<\/p>\n<p>Los drones equipados con Starlink tienen mayor alcance que los guiados por radio o cable y no pueden ser interferidos. La conexi\u00f3n ultrarr\u00e1pida tambi\u00e9n permite controlarlos en tiempo real desde dentro de Rusia, lo que los hace mucho m\u00e1s precisos.<\/p>\n<p>Ucrania ha recopilado evidencia de \u201ccientos\u201d de ataques por drones rusos equipados con terminales Starlink, seg\u00fan Serhii Beskrestnov, experto en tecnolog\u00eda militar y asesor del Ministerio de Defensa ucraniano.<\/p>\n<p>Beskrestnov tambi\u00e9n afirm\u00f3 que probablemente un mortal ataque a un tren civil en el este de Ucrania<a href=\"https:\/\/www.cnn.com\/2026\/01\/28\/world\/russia-strikes-civilian-train-ukraine-intl\"> fue realizado con un dron Shahed<\/a> equipado con un m\u00f3dem de radio mallada o posiblemente con un Starlink.<\/p>\n<p>La semana pasada, Musk llam\u00f3 al viceprimer ministro y ministro de Asuntos Exteriores de Polonia, Rados\u0142aw Sikorski, un \u201c<a href=\"https:\/\/x.com\/elonmusk\/status\/2016294735925633425\">imb\u00e9cil babeante<\/a>\u201d despu\u00e9s de que el l\u00edder polaco cuestionara por qu\u00e9 Musk no \u201cdetiene a los rusos para que no usen los Starlinks para atacar ciudades ucranianas\u201d.<\/p>\n<p>En marzo pasado, mientras las relaciones <a href=\"https:\/\/www.cnn.com\/2025\/03\/05\/politics\/us-pause-intelligence-support-ukraine\">entre EE.UU. y Ucrania se deterioraban <\/a>mientras el presidente Donald Trump presionaba a su hom\u00f3logo ucraniano Volodymyr Zelensky para negociar, Musk describi\u00f3 a Starlink como \u201c<a href=\"https:\/\/x.com\/elonmusk\/status\/1898612062533956047?lang=en\">la columna vertebral de las fuerzas armadas ucranian<\/a>as\u201d.<\/p>\n<p>\u201cLa l\u00ednea del frente entera colapsar\u00eda si lo apagara\u201d, dijo, antes de agregar que \u201csin importar cu\u00e1nto no est\u00e9 de acuerdo con la pol\u00edtica respecto a Ucrania, Starlink nunca apagar\u00e1 sus terminales\u201d.<\/p>\n<p>En 2024, <a href=\"https:\/\/www.cnn.com\/2024\/03\/25\/europe\/ukraine-starlink-drones-russia-intl-cmd\">Musk neg\u00f3 que se hubieran vendido sistemas Starlink a Rusia<\/a>, agregando que \u201chasta donde sabemos, ning\u00fan Starlink ha sido vendido directa o indirectamente a Rusia\u201d.<\/p>\n<p>En ese momento, la Inteligencia de Defensa de Ucrania afirm\u00f3 que hab\u00eda confirmado el uso de comunicaciones satelitales Starlink por parte de las fuerzas rusas en \u00e1reas ocupadas.<\/p>\n<p>\u201cSi SpaceX obtiene conocimiento de que una terminal Starlink est\u00e1 siendo utilizada por una parte sancionada o no autorizada, investigamos el caso y tomamos medidas para desactivar la terminal si se confirma\u201d, dijo SpaceX en un comunicado.<\/p>\n<p>Durante el fin de semana, Beskrestnov dijo que los esfuerzos para frenar el uso de Starlink por parte de Rusia hab\u00edan afectado temporalmente a algunos usuarios ucranianos.<\/p>\n<p>\u201cPido disculpas a quienes se han visto afectados temporalmente por las medidas tomadas, pero por la seguridad del pa\u00eds, estas son acciones muy importantes y necesarias en este momento\u201d, <a href=\"https:\/\/www.facebook.com\/Serhii.Flash\/posts\/pfbid029P3Drf52fL6Q2dSX54CvkyWMXN59ymJkuLd8pKzdTxHJTpGt258N3eNJBYC5oXqYl\">escribi\u00f3 en Facebook<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Defensa de Ucrania, Mykhailo Fedorov, confirm\u00f3 el domingo que los esfuerzos conjuntos para bloquear el acceso no autorizado al sistema de internet satelital est\u00e1n produciendo \u201cresultados reales\u201d. Esta medida estrat\u00e9gica busca impedir que las fuerzas armadas de Rusia utilicen la red de SpaceX para guiar drones en sus ataques contra territorio ucraniano. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470774","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SpaceX contrarresta el uso &quot;no autorizado&quot; de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SpaceX contrarresta el uso &quot;no autorizado&quot; de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ministro de Defensa de Ucrania, Mykhailo Fedorov, confirm\u00f3 el domingo que los esfuerzos conjuntos para bloquear el acceso no autorizado al sistema de internet satelital est\u00e1n produciendo \u201cresultados reales\u201d. Esta medida estrat\u00e9gica busca impedir que las fuerzas armadas de Rusia utilicen la red de SpaceX para guiar drones en sus ataques contra territorio ucraniano. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania\",\"datePublished\":\"2026-02-03T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\"},\"wordCount\":748,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\",\"name\":\"SpaceX contrarresta el uso \\\"no autorizado\\\" de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SpaceX contrarresta el uso \"no autorizado\" de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"SpaceX contrarresta el uso \"no autorizado\" de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias","og_description":"El ministro de Defensa de Ucrania, Mykhailo Fedorov, confirm\u00f3 el domingo que los esfuerzos conjuntos para bloquear el acceso no autorizado al sistema de internet satelital est\u00e1n produciendo \u201cresultados reales\u201d. Esta medida estrat\u00e9gica busca impedir que las fuerzas armadas de Rusia utilicen la red de SpaceX para guiar drones en sus ataques contra territorio ucraniano. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-03T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/"},"author":{"name":"","@id":""},"headline":"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania","datePublished":"2026-02-03T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/"},"wordCount":748,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","name":"SpaceX contrarresta el uso \"no autorizado\" de Starlink por parte de Rusia para guiar drones en Ucrania - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/02\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T00:03:43Z","datePublished":"2026-02-03T00:03:43Z","dateModified":"2026-02-03T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"SpaceX contrarresta el uso &#171;no autorizado&#187; de Starlink por parte de Rusia para guiar drones en Ucrania\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/02\\\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/02\\\/spacex-bloquea-starlink-rusia-drones-ucrania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T00:03:43Z\",\"datePublished\":\"2026-02-03T00:03:43Z\",\"dateModified\":\"2026-02-03T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470616,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/29\/rusia-drones-starlink-ucrania-trax\/","url_meta":{"origin":1470774,"position":0},"title":"Rusia est\u00e1 usando Starlink para que sus drones letales vuelen m\u00e1s lejos","author":"","date":"enero 29, 2026","format":false,"excerpt":"Rusia ha instalado los sistemas satelitales Starlink de Elon Musk en sus drones de ataque para golpear m\u00e1s profundamente en Ucrania, extendiendo su alcance potencial hasta bien dentro del territorio de la OTAN, seg\u00fan han dicho analistas y funcionarios ucranianos.Ucrania ha recopilado pruebas de \u201ccientos\u201d de ataques con drones rusos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447361,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/26\/ucrania-starlink-guerra-drones-rusia-uso-elon-musk-trax\/","url_meta":{"origin":1470774,"position":1},"title":"Ucrania depende de Starlink para su guerra de drones. Rusia parece estar evadiendo las sanciones para usar los dispositivos tambi\u00e9n","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Las tropas ucranianas en la primera l\u00ednea dicen que est\u00e1n experimentando problemas de conexi\u00f3n con el vital servicio de internet Starlink, propiedad de Elon Musk, que es utilizado para operar la flota de drones de ataque de Kyiv, al tiempo que informan un aumento en el uso ruso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473324,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/20\/ucrania-maquinas-batalla-robots-soldados-trax\/","url_meta":{"origin":1470774,"position":2},"title":"&#171;Los robots no sangran&#187;: Ucrania env\u00eda m\u00e1quinas al campo de batalla en lugar de soldados humanos","author":"","date":"abril 20, 2026","format":false,"excerpt":"La escena es tan antigua como la propia guerra. Dos soldados, con las manos en alto, rindi\u00e9ndose y siguiendo cuidadosamente las \u00f3rdenes que les grita la otra parte.Solo que en este caso no hab\u00eda captores humanos a la vista. En su lugar, los dos rusos se estaban entregando a robots\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466489,"url":"https:\/\/noticiasya.com\/boston\/2025\/09\/15\/drones-fuerzas-armadas-batalla-moderno-trax\/","url_meta":{"origin":1470774,"position":3},"title":"El dilema de los drones en EE.UU.: c\u00f3mo las Fuerzas Armadas m\u00e1s avanzadas intentan mantenerse al d\u00eda","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"El futuro de la guerra se parec\u00eda mucho a jugar un videojuego. Los soldados se pusieron gafas de realidad virtual y luego con sus dedos movieron los controles que ten\u00edan en las manos. Un peque\u00f1o dron despeg\u00f3 para responder.El mes pasado, en una base militar en Texas, soldados estadounidenses se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461959,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/04\/ucrania-caza-ruso-dron-maritimo-trax\/","url_meta":{"origin":1470774,"position":4},"title":"Ucrania afirma que destruy\u00f3 un caza ruso utilizando por primera vez un dron mar\u00edtimo","author":"","date":"mayo 4, 2025","format":false,"excerpt":"Ucrania afirm\u00f3 que derrib\u00f3 un caza ruso Su-30 en el mar Negro utilizando un dron mar\u00edtimo por primera vez.\u201cEsta es la primera vez en el mundo que un avi\u00f3n de combate ha sido destruido por un dron marino\u201d, dijo la Inteligencia de Defensa de Ucrania en un comunicado este s\u00e1bado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465996,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/30\/rusia-ataques-masivos-ucrania-putin-china-trax\/","url_meta":{"origin":1470774,"position":5},"title":"Rusia lanza ataques &#171;masivos&#187; contra Ucrania mientras Putin se prepara para visitar China","author":"","date":"agosto 30, 2025","format":false,"excerpt":"Rusia lanz\u00f3 un ataque a gran escala contra Ucrania durante la madrugada, seg\u00fan informaron las autoridades ucranianas este s\u00e1bado.La Fuerza A\u00e9rea de Ucrania afirm\u00f3 que Rusia lanz\u00f3 un \u201cataque masivo\u201d con 537 drones y 45 misiles durante la noche del viernes al s\u00e1bado, de los cuales 548 fueron derribados.Al menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1470774"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470774\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1470774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1470774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1470774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}