{"id":1470798,"date":"2026-02-03T04:03:44","date_gmt":"2026-02-03T12:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/"},"modified":"2026-02-03T04:03:44","modified_gmt":"2026-02-03T12:03:44","slug":"registran-oficinas-x-musk-paris-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","title":{"rendered":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk"},"content":{"rendered":"<p>Se est\u00e1 llevando a cabo un registro en las oficinas francesas de la plataforma de redes sociales X, propiedad de Elon Musk, como parte de una investigaci\u00f3n iniciada en enero de 2025, seg\u00fan inform\u00f3 el martes la fiscal\u00eda de Par\u00eds.<\/p>\n<p>La unidad de ciberdelincuencia de la fiscal\u00eda est\u00e1 a cargo del registro, seg\u00fan un comunicado, y en la operaci\u00f3n participa Europol.<\/p>\n<p>Tanto el presidente de X, Elon Musk, como la exdirectora ejecutiva Linda Yaccarino han sido citados a comparecer en audiencias en abril, mientras que los empleados de X ser\u00e1n interrogados como testigos, seg\u00fan la fiscal\u00eda de Par\u00eds.<\/p>\n<p>CNN se ha puesto en contacto con X para obtener comentarios.<\/p>\n<p>La fiscal de Par\u00eds, Laure Beccuau, declar\u00f3 que la investigaci\u00f3n francesa, que inicialmente se centraba en el presunto uso indebido de algoritmos, se ha ampliado para incluir las \u201cim\u00e1genes falsas con contenido sexual de Grok\u201d.<\/p>\n<p>La semana pasada, la Comisi\u00f3n Europea inici\u00f3 una investigaci\u00f3n sobre Grok, el chatbot de inteligencia artificial de X, tras las cr\u00edticas por su capacidad para generar im\u00e1genes sexualmente expl\u00edcitas. El escrutinio de esta funci\u00f3n se intensific\u00f3 a finales del a\u00f1o pasado, cuando se descubri\u00f3 que el chatbot hab\u00eda producido una gran cantidad de im\u00e1genes de personas desnudas digitalmente, incluyendo mujeres y ni\u00f1os, a petici\u00f3n de los usuarios.<\/p>\n<p>Desde entonces, la gigante de las redes sociales ha impedido que los usuarios de Grok creen im\u00e1genes de personas con ropa reveladora.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se est\u00e1 llevando a cabo un registro en las oficinas francesas de la plataforma de redes sociales X, propiedad de Elon Musk, como parte de una investigaci\u00f3n iniciada en enero de 2025, seg\u00fan inform\u00f3 el martes la fiscal\u00eda de Par\u00eds. La unidad de ciberdelincuencia de la fiscal\u00eda est\u00e1 a cargo del registro, seg\u00fan un comunicado, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470798","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se est\u00e1 llevando a cabo un registro en las oficinas francesas de la plataforma de redes sociales X, propiedad de Elon Musk, como parte de una investigaci\u00f3n iniciada en enero de 2025, seg\u00fan inform\u00f3 el martes la fiscal\u00eda de Par\u00eds. La unidad de ciberdelincuencia de la fiscal\u00eda est\u00e1 a cargo del registro, seg\u00fan un comunicado, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T12:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk\",\"datePublished\":\"2026-02-03T12:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\",\"name\":\"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T12:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias","og_description":"Se est\u00e1 llevando a cabo un registro en las oficinas francesas de la plataforma de redes sociales X, propiedad de Elon Musk, como parte de una investigaci\u00f3n iniciada en enero de 2025, seg\u00fan inform\u00f3 el martes la fiscal\u00eda de Par\u00eds. La unidad de ciberdelincuencia de la fiscal\u00eda est\u00e1 a cargo del registro, seg\u00fan un comunicado, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-03T12:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/"},"author":{"name":"","@id":""},"headline":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk","datePublished":"2026-02-03T12:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","name":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T12:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Unidad de cibercrimen de Par\u00eds registra las oficinas francesas de X, de Elon Musk","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/03\/registran-oficinas-x-musk-paris-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T12:03:44Z","datePublished":"2026-02-03T12:03:44Z","dateModified":"2026-02-03T12:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Unidad de cibercrimen de Par\\u00eds registra las oficinas francesas de X, de Elon Musk\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/03\\\/registran-oficinas-x-musk-paris-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/03\\\/registran-oficinas-x-musk-paris-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T12:03:44Z\",\"datePublished\":\"2026-02-03T12:03:44Z\",\"dateModified\":\"2026-02-03T12:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471314,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/17\/organismo-privacidad-europa-investigacion-x-elon-musk-trax\/","url_meta":{"origin":1470798,"position":0},"title":"El organismo de control de la privacidad de Europa lanza una investigaci\u00f3n &#171;a gran escala&#187; sobre X de Elon Musk","author":"","date":"febrero 17, 2026","format":false,"excerpt":"El organismo de control de privacidad de datos de la Uni\u00f3n Europea ha iniciado una investigaci\u00f3n sobre X de Elon Musk por im\u00e1genes sexualizadas generadas por el chatbot de inteligencia artificial del sitio de redes sociales, Grok.La medida se suma a la creciente presi\u00f3n regulatoria sobre X, que tambi\u00e9n enfrenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453279,"url":"https:\/\/noticiasya.com\/boston\/2024\/10\/02\/elon-musk-twitter-x-fidelity-trax\/","url_meta":{"origin":1470798,"position":1},"title":"El X de Elon Musk vale casi un 80% menos que cuando lo compr\u00f3, seg\u00fan estimaciones de Fidelity","author":"","date":"octubre 2, 2024","format":false,"excerpt":"(CNN) --\u00a0 La plataforma de medios sociales antes conocida como Twitter vale casi 80% menos que hace dos a\u00f1os cuando Elon Musk la compr\u00f3, seg\u00fan estimaciones del gigante de inversiones Fidelity.X ya no cotiza p\u00fablicamente despu\u00e9s de que Musk desembolsara US$ 44.000 millones para hacerla privada en octubre de 2022.Sin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452509,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/07\/cuales-son-intereses-elon-musk-america-latina-orix\/","url_meta":{"origin":1470798,"position":2},"title":"\u00bfCu\u00e1les son los intereses de Elon Musk en Am\u00e9rica Latina?","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El multimillonario Elon Musk, due\u00f1o de X y otras empresas, dedica buena parte de su actividad en redes sociales a lo que sucede en Am\u00e9rica Latina. En los \u00faltimos d\u00edas ha publicado varios mensajes sobre la suspensi\u00f3n de la red social de su propiedad en Brasil, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452662,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/13\/supremo-tribunal-brasil-confiscar-millones-empresas-elon-musk-orix\/","url_meta":{"origin":1470798,"position":3},"title":"El Supremo Tribunal de Brasil ordena confiscar US$ 3,3 millones a empresas de Musk para pagar multas; luego desbloquea sus cuentas","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Supremo Tribunal Federal de Brasil (STF) orden\u00f3 este viernes confiscar el equivalente a m\u00e1s de US$ 3,3 millones de la red social X y la empresa de servicios satelitales Starlink, as\u00ed como desbloquear las cuentas de las dos compa\u00f1\u00edas, controladas por Elon Musk.El Tribunal inform\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452412,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/03\/lula-mundo-no-tiene-soportar-ideologia-extrema-derecha-elon-musk-solo-es-rico-trax\/","url_meta":{"origin":1470798,"position":4},"title":"El presidente de Brasil dice que el mundo no tiene por qu\u00e9 soportar la ideolog\u00eda de \u201cextrema derecha\u201d de Elon Musk solo porque es rico","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) -- El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, dice que el mundo no est\u00e1 obligado a soportar la agenda de extrema derecha del multimillonario Elon Musk debido a su inmensa riqueza.Lula da Silva hizo estas declaraciones en una entrevista con CNN Brasil, afiliada de CNN, publicada este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470097,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/14\/grok-ai-restricciones-imagenes-desnudos-elon-musk-trax\/","url_meta":{"origin":1470798,"position":5},"title":"El chatbot Grok de Elon Musk parece modificar su funci\u00f3n de generaci\u00f3n de im\u00e1genes tras pol\u00e9mica","author":"","date":"enero 14, 2026","format":false,"excerpt":"Grok, el chatbot de inteligencia artificial desarrollado por Elon Musk, parece haber implementado nuevas salvaguardas en su sistema de generaci\u00f3n de im\u00e1genes. Esta medida surge como respuesta a una ola de indignaci\u00f3n global tras revelarse que la herramienta permit\u00eda a los usuarios \u201cdesvestir\u201d digitalmente a personas, afectando incluso a menores\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1470798"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470798\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1470798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1470798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1470798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}