{"id":1470826,"date":"2026-02-03T18:03:50","date_gmt":"2026-02-04T02:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/"},"modified":"2026-02-03T18:03:50","modified_gmt":"2026-02-04T02:03:50","slug":"trump-estados-agentes-gobierno-federal-elecciones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","title":{"rendered":"Trump dice que los estados son agentes del Gobierno federal en las elecciones"},"content":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 este martes que \u201cun estado es un agente del Gobierno federal en las elecciones\u201d, en defensa de su llamado a los republicanos para que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/03\/eeuu\/trump-pide-republicanos-nacionalizar-futuras-elecciones-trax\">nacionalicen las elecciones.<\/a><\/p>\n<p>\u201cQuiero que las elecciones sean honestas \u2014y si un estado no puede administrar una elecci\u00f3n, creo que las personas detr\u00e1s de m\u00ed deber\u00edan hacer algo al respecto\u201d, dijo Trump a Kaitlan Collins de CNN durante una ceremonia de firma en el Sal\u00f3n Oval con legisladores republicanos.<\/p>\n<p>\u201cUn estado es un agente del Gobierno federal en las elecciones. No s\u00e9 por qu\u00e9 el Gobierno federal no las hace de todos modos\u201d, a\u00f1adi\u00f3, agregando que es una \u201cverg\u00fcenza\u201d lo \u201chorriblemente\u201d que algunos estados administran las elecciones.<\/p>\n<p>A las elecciones las administran los funcionarios estatales y locales, y en ellas el Gobierno federal solo juega un papel limitado. Pero eso no ha impedido que Trump intente cambiar la manera en la que se llevan a cabo los comicios, ya que su Gobierno impulsa una reforma de las reglas antes de las elecciones de mitad de mandato.<\/p>\n<p>El presidente mencion\u00f3 Atlanta, donde hace menos de una semana el FBI r<a href=\"https:\/\/www.cnn.com\/2026\/01\/28\/politics\/fulton-county-election-office-fbi-warrant\">egistr\u00f3 una oficina electoral <\/a>como parte de una investigaci\u00f3n del Departamento de Justicia sobre presunto fraude electoral, y otras ciudades con fortines dem\u00f3cratas como lugares donde se ve \u201ccorrupci\u00f3n horrible en las elecciones\u201d.<\/p>\n<p>\u201cEl Gobierno federal no deber\u00eda permitir eso\u201d, dijo el martes. \u201cEl Gobierno federal deber\u00eda involucrarse. Estos son agentes del Gobierno federal para contar los votos. Si no pueden contar los votos legal y honestamente, entonces alguien m\u00e1s deber\u00eda hacerse cargo\u201d.<\/p>\n<p>Al ser interrogado por Collins sobre las <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/03\/eeuu\/analisis-trump-amenazas-electorales-trax\">disposiciones en la Constituci\u00f3n <\/a>que establecen que los funcionarios locales administren las elecciones, Trump dijo \u201cellos pueden administrar la elecci\u00f3n, pero tienen que hacerlo honestamente\u201d.<\/p>\n<p>M\u00e1s temprano ese d\u00eda, la secretaria de Prensa de la Casa Blanca, Karoline Leavitt, dijo a los periodistas que Trump estaba hablando sobre la necesidad de un requisito nacional de identificaci\u00f3n de votantes cuando llam\u00f3 a los republicanos a \u201cnacionalizar el voto\u201d en una entrevista que se emiti\u00f3 el lunes.<\/p>\n<p>\u201cA lo que se refer\u00eda el presidente es a la Ley SAVE\u201d, dijo Leavitt a los periodistas, en referencia a la legislaci\u00f3n que requerir\u00eda una prueba de ciudadan\u00eda para registrarse para votar. \u201cProporciona medidas de sentido com\u00fan para votar en nuestro pa\u00eds, como la identificaci\u00f3n de votantes\u201d. Quienes no son ciudadanos tienen prohibido votar en elecciones federales.<\/p>\n<p>En varias ocasiones, Trump se ha comprometido a cambiar la forma en la que el pa\u00eds vota, centrando su atenci\u00f3n en los m\u00e9todos que \u00e9l afirma, falsamente, que conducen al fraude electoral,. Adem\u00e1s, ha puesto en marcha una inusual campa\u00f1a de<a href=\"https:\/\/www.cnn.com\/2025\/11\/12\/politics\/redistricting-trump-democrats\"> redistribuci\u00f3n de distritos<\/a> a mitad de d\u00e9cada destinada a ayudar a los republicanos a ganar esca\u00f1os adicionales en la C\u00e1mara de Representantes de EE.UU.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 este martes que \u201cun estado es un agente del Gobierno federal en las elecciones\u201d, en defensa de su llamado a los republicanos para que nacionalicen las elecciones. \u201cQuiero que las elecciones sean honestas \u2014y si un estado no puede administrar una elecci\u00f3n, creo que las personas detr\u00e1s de m\u00ed deber\u00edan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470826","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump afirm\u00f3 este martes que \u201cun estado es un agente del Gobierno federal en las elecciones\u201d, en defensa de su llamado a los republicanos para que nacionalicen las elecciones. \u201cQuiero que las elecciones sean honestas \u2014y si un estado no puede administrar una elecci\u00f3n, creo que las personas detr\u00e1s de m\u00ed deber\u00edan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T02:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump dice que los estados son agentes del Gobierno federal en las elecciones\",\"datePublished\":\"2026-02-04T02:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\"},\"wordCount\":528,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\",\"name\":\"Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-04T02:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump dice que los estados son agentes del Gobierno federal en las elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias","og_description":"El presidente Donald Trump afirm\u00f3 este martes que \u201cun estado es un agente del Gobierno federal en las elecciones\u201d, en defensa de su llamado a los republicanos para que nacionalicen las elecciones. \u201cQuiero que las elecciones sean honestas \u2014y si un estado no puede administrar una elecci\u00f3n, creo que las personas detr\u00e1s de m\u00ed deber\u00edan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-04T02:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/"},"author":{"name":"","@id":""},"headline":"Trump dice que los estados son agentes del Gobierno federal en las elecciones","datePublished":"2026-02-04T02:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/"},"wordCount":528,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","name":"Trump dice que los estados son agentes del Gobierno federal en las elecciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-04T02:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump dice que los estados son agentes del Gobierno federal en las elecciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump dice que los estados son agentes del Gobierno federal en las elecciones","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/03\/trump-estados-agentes-gobierno-federal-elecciones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-04T02:03:50Z","datePublished":"2026-02-04T02:03:50Z","dateModified":"2026-02-04T02:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump dice que los estados son agentes del Gobierno federal en las elecciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/03\\\/trump-estados-agentes-gobierno-federal-elecciones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/03\\\/trump-estados-agentes-gobierno-federal-elecciones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-04T02:03:50Z\",\"datePublished\":\"2026-02-04T02:03:50Z\",\"dateModified\":\"2026-02-04T02:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470835,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/04\/trump-republicanos-nacionalicen-elecciones-ee-uu-trax\/","url_meta":{"origin":1470826,"position":0},"title":"Trump quiere que los republicanos &#171;nacionalicen&#187; las elecciones en EE.UU. La Constituci\u00f3n podr\u00eda evitarlo","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Una amplia gama de expertos electorales afirman que el llamado del presidente Donald Trump a los republicanos a \u201cnacionalizar el voto\u201d es una escalada alarmante y potencialmente peligrosa de sus continuos esfuerzos por transformar el modo en que se administran las elecciones en EE.UU.Los comentarios de Trump fueron notables tanto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470788,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/trump-pide-republicanos-nacionalizar-futuras-elecciones-trax\/","url_meta":{"origin":1470826,"position":1},"title":"Trump pide a los republicanos &#171;nacionalizar&#187; las futuras elecciones","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente Donald Trump pidi\u00f3 a los republicanos que \u201cnacionalicen el voto\u201d en una entrevista que se emiti\u00f3 este lunes, mientras su administraci\u00f3n presiona para revisar las reglas b\u00e1sicas electorales antes de los cruciales comicios intermedios de este a\u00f1o\u201cLos republicanos deber\u00edan decir: \u2018Queremos tomar el control, deber\u00edamos tomar el control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465630,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/19\/voto-por-correo-trump-falso-trax\/","url_meta":{"origin":1470826,"position":2},"title":"CNN verifica: Trump afirma falsamente que EE.UU. es el \u00fanico pa\u00eds que utiliza el voto por correo","author":"","date":"agosto 19, 2025","format":false,"excerpt":"El presidente Donald Trump hizo una serie de afirmaciones falsas sobre las elecciones en una publicaci\u00f3n en redes sociales el lunes, en la que se comprometi\u00f3 a \u201cliderar un movimiento para eliminar las papeletas de voto por correo\u201d y las m\u00e1quinas de votaci\u00f3n, incluyendo una aseveraci\u00f3n err\u00f3nea sobre que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471659,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/ice-centros-votacion-elecciones-intermedias-designada-trump-trax\/","url_meta":{"origin":1470826,"position":3},"title":"ICE no estar\u00e1 en centros de votaci\u00f3n en elecciones intermedias, dice designada de Trump a funcionarios electorales estatales","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Una persona designada por Donald Trump en el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) dijo este mi\u00e9rcoles a funcionarios electorales estatales de todo el pa\u00eds que los agentes federales de inmigraci\u00f3n no ser\u00e1n desplegados en los lugares de votaci\u00f3n durante las elecciones intermedias de 2026, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470190,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/17\/trump-cancelar-elecciones-medio-termino-trax\/","url_meta":{"origin":1470826,"position":4},"title":"No, Trump no puede cancelar las elecciones de mitad de mandato. En cambio, esto es lo que est\u00e1 haciendo","author":"","date":"enero 17, 2026","format":false,"excerpt":"Preocupado por perder el poder republicano unificado en Washington y desconcertado por su falta de apoyo entre el p\u00fablico, el presidente de Estados Unidos, Donald Trump, sigue hablando de no celebrar las elecciones de mitad de mandato de noviembre, en las que los republicanos podr\u00edan perder el control de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465073,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/02\/trump-aliados-presion-elecciones-legislativas-trax\/","url_meta":{"origin":1470826,"position":5},"title":"Trump y sus aliados lanzan una campa\u00f1a de presi\u00f3n contra las elecciones de EE.UU. antes de las legislativas","author":"","date":"agosto 2, 2025","format":false,"excerpt":"Hace unas semanas, funcionarios electorales republicanos en Colorado comenzaron a recibir llamadas y mensajes de texto no solicitados de un consultor del Partido Republicano que aseguraba trabajar con la administraci\u00f3n Trump en \u201cintegridad electoral\u201d.En un mensaje a uno de los funcionarios, el consultor, Jeff Small, indic\u00f3 que actuaba por solicitud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1470826"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1470826\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1470826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1470826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1470826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}