{"id":1471555,"date":"2026-02-23T08:03:44","date_gmt":"2026-02-23T16:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/"},"modified":"2026-02-23T08:03:44","modified_gmt":"2026-02-23T16:03:44","slug":"que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","title":{"rendered":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3"},"content":{"rendered":"<p>En 48 horas, la larga misi\u00f3n de dar con el paradero de Nemesio \u201cEl Mencho\u201d Oseguera, l\u00edder y cofundador del Cartel Jalisco Nueva Generaci\u00f3n, pas\u00f3 de una ansiada pista concreta a realizar el operativo que este domingo result\u00f3 en la muerte del temido l\u00edder narco en el oeste de M\u00e9xico.<\/p>\n<p>El seguimiento de la red de v\u00ednculos del Mencho, uno de los criminales m\u00e1s buscados desde hace a\u00f1os por las autoridades de M\u00e9xico y de Estados Unidos, dio con una persona clave con llegada hasta su guarida.<\/p>\n<p>\u201cEl 20 de febrero, mediante trabajos de inteligencia militar central, se ubic\u00f3 un hombre de confianza de una de las parejas sentimentales del Mencho, que la traslad\u00f3 a una instalaci\u00f3n en Tapalpa\u201d, explic\u00f3 en conferencia de prensa el general Ricardo Trevilla Trejo, secretario de la Defensa Nacional de M\u00e9xico.<\/p>\n<p>El s\u00e1bado 21, la mujer se retir\u00f3 del inmueble, pero la informaci\u00f3n recabada se\u00f1al\u00f3 que el capo permanec\u00eda en el lugar con un c\u00edrculo de seguridad, agreg\u00f3 Trevilla.<\/p>\n<p>Con esa confirmaci\u00f3n, la Fuerza A\u00e9rea y la Fuerza Especial de Reacci\u00f3n Inmediata de la Guardia Nacional pas\u00f3 a dise\u00f1ar el operativo para realizarlo antes que se le vuelva a perder el rastro.<\/p>\n<p>La misi\u00f3n fue llevada a cabo por componentes terrestres; una fuerza aerom\u00f3vil, con helic\u00f3pteros que no llegaron a Jalisco para no desatar sospechas; y una fuerza de apoyo a\u00e9reo.<\/p>\n<p>Trevilla narr\u00f3 que las fuerzas trazaron un cerco con el objetivo de detener al Mencho en flagrancia y sus lugartenientes abrieron fuego. \u201cEl Mencho sale, deja un grupo con una gran cantidad de armamento, fue un ataque muy violento el que realiz\u00f3 el personal de la delincuencia organizada. Las fuerzas militares repelen la acci\u00f3n\u201d, explic\u00f3.<\/p>\n<p>En ese momento murieron ocho integrantes del cartel, cuatro m\u00e1s que los reportados el domingo, y dos militares resultaron heridos. Adem\u00e1s, fueron incautadas siete armas largas y dos lanzacohetes.<\/p>\n<p>Oseguera, con otro grupo de seguridad, intent\u00f3 escapar.<\/p>\n<p>El complejo de caba\u00f1as estaba en las orillas de Tapalpa y, tras la incursi\u00f3n, el Mencho trat\u00f3 de huir hacia una zona boscosa.<\/p>\n<p>\u201cSe estableci\u00f3 un cerco, los persigue el personal de las Fuerzas Especiales y lo ubican oculto entre la maleza\u201d, dijo Trevilla.<\/p>\n<p>Los escoltas abrieron fuego, pero el general afirm\u00f3 que, gracias a la presi\u00f3n de los militares, no pudieron usar el lanzacohetes que llevaban con ellos. Las fuerzas de seguridad repelieron la agresi\u00f3n y pudieron acercarse al lugar.<\/p>\n<p>\u201cResulta herido el Mencho con dos de sus escoltas y se detienen a dos m\u00e1s\u201d, afirm\u00f3.<\/p>\n<p>\u201cUna vez que se controla la situaci\u00f3n, personal de sanidad militar acude al lugar donde estaba el Mencho y su escolta, determinan que es necesario evacuarlos, estaban muy graves\u201d, explic\u00f3 Trevilla. Por ello, llamaron a un helic\u00f3ptero, al que fueron subidos el l\u00edder narco, dos lugartenientes y un oficial herido.<\/p>\n<p>Inicialmente, iban a ser trasladados a Guadalajara para recibir atenci\u00f3n m\u00e9dica, pero murieron en el trayecto, por lo que cambiaron el rumbo hacia el aeropuerto internacional de Morelia, donde esperaba un caza de la Fuerza A\u00e9rea para llevarlos a Ciudad de M\u00e9xico.<\/p>\n<p>\u201cYa no era conveniente llegar a Guadalajara por el riesgo que pod\u00eda correrse con que este grupo delictivo hiciera acciones m\u00e1s violentas en la capital de Jalisco\u201d, dijo Trevilla.<\/p>\n<p>En la conferencia, la presidenta Claudia Sheinbaum explic\u00f3 que no hubo una participaci\u00f3n de fuerzas de Estados Unidos, sino que apoyaron con el intercambio de informaci\u00f3n. \u201cToda la operaci\u00f3n es responsabilidad de la Secretar\u00eda de la Defensa Nacional\u201d, enfatiz\u00f3.<\/p>\n<p>Por su lado, Trevilla dijo que EE.UU. comparti\u00f3 \u201cinformaci\u00f3n adicional\u201d que ayud\u00f3 a las fuerzas de seguridad y militares mexicanas a \u201cdar con la ubicaci\u00f3n exacta\u201d del l\u00edder del CJNG. Sin embargo, aclar\u00f3 que la pista sobre la pareja sentimental fue producto de las tareas de inteligencia de M\u00e9xico.<\/p>\n<p>El domingo, un funcionario de Defensa de EE.UU. dijo a CNN que un grupo de trabajo interinstitucional de Estados Unidos \u201ctuvo un papel\u201d en la operaci\u00f3n. \u201c(Joint Interagency Task Force-Counter Cartel) tuvo un papel, ya que JIATF-CC trabaja regularmente con (las fuerzas armadas mexicanas) a trav\u00e9s de USNORTHCOM\u201d, dijo el funcionario, en referencia al Comando Norte de EE.UU. \u201cSin embargo, quiero enfatizar que esta fue una operaci\u00f3n de (las fuerzas armadas mexicanas), as\u00ed que el m\u00e9rito es de ellos\u201d.<\/p>\n<p>El operativo desat\u00f3 una respuesta de violencia casi inmediata. En varias partes del sur de Jalisco comenzaron los llamados \u201cnarcobloqueos\u201d, cerrando carreteras y quemando veh\u00edculos.<\/p>\n<p>Esto se extendi\u00f3 a otros estados, como Colima, Nayarit, Michoac\u00e1n, Guanajuato, Aguascalientes, Tamaulipas, Baja California, Quintana Roo y Guerrero. Diversas situaciones de robos, quema de veh\u00edculos y otros hechos violentos fueron reportados en varios puntos del pa\u00eds. Esto llev\u00f3 a que se suspendieran el transporte p\u00fablico y las clases en algunas de las zonas m\u00e1s afectadas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 48 horas, la larga misi\u00f3n de dar con el paradero de Nemesio \u201cEl Mencho\u201d Oseguera, l\u00edder y cofundador del Cartel Jalisco Nueva Generaci\u00f3n, pas\u00f3 de una ansiada pista concreta a realizar el operativo que este domingo result\u00f3 en la muerte del temido l\u00edder narco en el oeste de M\u00e9xico. El seguimiento de la red [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471555","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias\" \/>\n<meta property=\"og:description\" content=\"En 48 horas, la larga misi\u00f3n de dar con el paradero de Nemesio \u201cEl Mencho\u201d Oseguera, l\u00edder y cofundador del Cartel Jalisco Nueva Generaci\u00f3n, pas\u00f3 de una ansiada pista concreta a realizar el operativo que este domingo result\u00f3 en la muerte del temido l\u00edder narco en el oeste de M\u00e9xico. El seguimiento de la red [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T16:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3\",\"datePublished\":\"2026-02-23T16:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\"},\"wordCount\":883,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\",\"name\":\"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-23T16:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias","og_description":"En 48 horas, la larga misi\u00f3n de dar con el paradero de Nemesio \u201cEl Mencho\u201d Oseguera, l\u00edder y cofundador del Cartel Jalisco Nueva Generaci\u00f3n, pas\u00f3 de una ansiada pista concreta a realizar el operativo que este domingo result\u00f3 en la muerte del temido l\u00edder narco en el oeste de M\u00e9xico. El seguimiento de la red [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-23T16:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3","datePublished":"2026-02-23T16:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/"},"wordCount":883,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","name":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-23T16:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3","url":"http:\/\/noticiasya.com\/boston\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-23T16:03:44Z","datePublished":"2026-02-23T16:03:44Z","dateModified":"2026-02-23T16:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 est\\u00e1 pasando en M\\u00e9xico? As\\u00ed fue el operativo en el que muri\\u00f3 el Mencho y la ola de violencia que le sigui\\u00f3\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/23\\\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/02\\\/23\\\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-23T16:03:44Z\",\"datePublished\":\"2026-02-23T16:03:44Z\",\"dateModified\":\"2026-02-23T16:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471635,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/operacion-capturar-mencho-sheinbaum-trump-se-atribuyera-operativo-orix\/","url_meta":{"origin":1471555,"position":0},"title":"Trump se atribuy\u00f3 la ca\u00edda del Mencho. Sheinbaum insisti\u00f3 en que el operativo lo hizo M\u00e9xico","author":"","date":"febrero 25, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, recalc\u00f3 este mi\u00e9rcoles que toda la operaci\u00f3n militar para capturar a Nemesio Oseguera Cervantes, alias el Mencho, l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n (CJNG), fue llevada a cabo por las fuerzas de seguridad mexicanas, refutando as\u00ed las declaraciones que hizo el presidente de Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471572,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/23\/operativo-mencho-gobierno-sheinbaum-ahora-orix\/","url_meta":{"origin":1471555,"position":1},"title":"\u00bfPor qu\u00e9 Sheinbaum aprob\u00f3 ahora un operativo de este nivel contra un capo del narcotr\u00e1fico?","author":"","date":"febrero 23, 2026","format":false,"excerpt":"Fuerzas federales de M\u00e9xico realizaron este domingo un fuerte operativo en el estado de Jalisco, en el occidente del pa\u00eds, con el objetivo de detener a Nemesio Oseguera Cervantes, el Mencho, considerado l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n (CJNG) y uno de los hombres m\u00e1s buscados de todo el continente.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471646,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/familiares-mencho-piden-entrega-cuerpo-orix\/","url_meta":{"origin":1471555,"position":2},"title":"Familiares del Mencho ya pidieron que se les entregue su cuerpo, dice la Fiscal\u00eda General de M\u00e9xico","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Familiares de Nemesio Oseguera Cervantes, el Mencho, el se\u00f1alado l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n (CJNG) y quien muri\u00f3 el domingo en un operativo federal en el occidente de M\u00e9xico, ya pidieron a la Fiscal\u00eda General de la Rep\u00fablica (FGR) que les entregue el cuerpo, inform\u00f3 este mi\u00e9rcoles la propia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471632,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/eeuu-zar-antidrogas-felicita-operativo-mencho-mexico-efe\/","url_meta":{"origin":1471555,"position":3},"title":"En M\u00e9xico, la &#171;zar antidrogas&#187; de EE.UU. felicit\u00f3 a las autoridades por el operativo contra El Mencho","author":"","date":"febrero 25, 2026","format":false,"excerpt":"La directora de la Oficina Nacional de Pol\u00edtica de Control de Drogas (ONDCP) de Estados Unidos, Sara Carter, afirm\u00f3 que su pa\u00eds trabaja \u201cd\u00eda y noche\u201d con M\u00e9xico para \u201celiminar\u201d a los carteles y el tr\u00e1fico de drogas, tras una reuni\u00f3n con autoridades militares y de seguridad en Palacio Nacional.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471648,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/detencion-hacha-operador-cjng-tlaxcala-mencho-orix\/","url_meta":{"origin":1471555,"position":4},"title":"M\u00e9xico captura a &#171;El Hacha&#187;, supuesto operador clave del CJNG en Tlaxcala, d\u00edas despu\u00e9s de la muerte del Mencho","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Las autoridades mexicanas detuvieron este mi\u00e9rcoles a Isaac Moreno Romero, alias \u201cEl Hacha\u201d, se\u00f1alado como l\u00edder de una c\u00e9lula del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG) con presencia en el estado de Tlaxcala, en el centro de M\u00e9xico, y vinculado con secuestros, extorsiones, homicidios y tr\u00e1fico ilegal de combustibles, confirm\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473543,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/27\/detencion-jardinero-cjng-mencho-orix\/","url_meta":{"origin":1471555,"position":5},"title":"M\u00e9xico detiene a alias &#171;El Jardinero&#187;, posible sucesor del &#171;Mencho&#187; en el Cartel Jalisco Nueva Generaci\u00f3n","author":"","date":"abril 27, 2026","format":false,"excerpt":"Fuerzas especiales de la Secretar\u00eda de Marina de M\u00e9xico detuvieron en el estado de Nayarit a Audias Flores Silva, alias \u201cEl Jardinero\u201d, identificado como uno de los presuntos l\u00edderes del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG), dos meses despu\u00e9s de la ca\u00edda de Nemesio Rub\u00e9n Oseguera Cervantes, alias \u201cEl Mencho\u201d, considerado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1471555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1471555"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1471555\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1471555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1471555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1471555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}