{"id":1473068,"date":"2026-04-11T17:03:46","date_gmt":"2026-04-12T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/"},"modified":"2026-04-11T17:03:46","modified_gmt":"2026-04-12T00:03:46","slug":"tribunal-construccion-salon-baile-casa-blanca-continua-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","title":{"rendered":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora"},"content":{"rendered":"<p>Un tribunal federal de apelaciones dijo este s\u00e1bado que el presidente Donald Trump puede seguir adelante durante otra semana con la construcci\u00f3n de un enorme nuevo sal\u00f3n de baile en la Casa Blanca mientras los jueces consideran el proyecto.<\/p>\n<p>La orden 2-1 del Tribunal de Apelaciones del Circuito del Distrito de Columbia es una victoria temporal para Trump en una prolongada batalla legal sobre si tiene autoridad para construir el sal\u00f3n de baile en el sitio del antiguo Ala Este sin la aprobaci\u00f3n expresa del Congreso.<\/p>\n<p>El tribunal de apelaciones dijo que el trabajo en el proyecto puede continuar al menos hasta el 17 de abril. El tribunal devolvi\u00f3 el caso a un juez federal que inicialmente fall\u00f3 en contra, diciendo que necesitaba examinar m\u00e1s de cerca el argumento de la Casa Blanca de que la construcci\u00f3n debe continuar por razones de seguridad nacional y seguridad, y agregando que el tribunal de apelaciones no pod\u00eda escrutar la idea sobre un \u201cexpediente apresurado\u201d.<\/p>\n<p>\u201cSigue sin estar claro si y en qu\u00e9 medida el desarrollo de ciertos aspectos del sal\u00f3n de baile propuesto es necesario para garantizar la seguridad de las mejoras de seguridad nacional subterr\u00e1neas o, en general, para asegurar la protecci\u00f3n de la Casa Blanca y sus ocupantes mientras el proceso de apelaci\u00f3n contin\u00faa\u201d, escribieron los jueces de la mayor\u00eda.<\/p>\n<p>Los dos jueces que decidieron devolver el caso fueron designados por los expresidentes Barack Obama y Joe Biden. El juez disidente fue nombrado por Trump durante su primer mandato.<\/p>\n<p>La decisi\u00f3n de este s\u00e1bado es el m\u00e1s reciente punto de tensi\u00f3n en una disputa de meses sobre el intento de Trump de avanzar con el proyecto del sal\u00f3n de baile con poca o ninguna supervisi\u00f3n externa.<\/p>\n<p>Despu\u00e9s de que Trump demoliera el Ala Este el a\u00f1o pasado para iniciar la construcci\u00f3n, el principal grupo de preservaci\u00f3n hist\u00f3rica del pa\u00eds acudi\u00f3 a los tribunales para impugnar la legalidad del proyecto. Argument\u00f3, entre otras cosas, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/25\/eeuu\/analisis-demolicion-ala-este-presidencia-trump\">que el Congreso deb\u00eda aprobarlo<\/a>.<\/p>\n<p>El juez federal de distrito Richard Leon dio la raz\u00f3n al grupo a finales del mes pasado, al se\u00f1alar en un contundente fallo que Trump estaba llevando a cabo la construcci\u00f3n de manera ilegal, ya que no hab\u00eda solicitado permiso a los legisladores para construir la nueva y ambiciosa ampliaci\u00f3n de la Casa Blanca.<\/p>\n<p>Leon, designado por el expresidente George W. Bush, se\u00f1al\u00f3 que gran parte del trabajo deb\u00eda detenerse en espera de la aprobaci\u00f3n del Congreso, pero que las cuadrillas pod\u00edan continuar con la \u201cconstrucci\u00f3n necesaria para garantizar la seguridad de la Casa Blanca\u201d.<\/p>\n<p>\u201cEl presidente de Estados Unidos es el custodio de la Casa Blanca para las futuras generaciones de primeras familias. Sin embargo, \u00a1no es el propietario!\u201d, escribi\u00f3 Leon en la resoluci\u00f3n de 35 p\u00e1ginas.<\/p>\n<p>Trump y sus abogados se apresuraron a aprovechar esa laguna jur\u00eddica para argumentar que la decisi\u00f3n carec\u00eda, en esencia, de sentido.<\/p>\n<p>\u201cEso significa: \u2018puedo continuar construyendo seg\u00fan sea necesario\u2019\u201d, dijo Trump poco despu\u00e9s de que Leon emitiera su fallo. \u201cAs\u00ed que, en ese aspecto, estamos bien\u201d.<\/p>\n<p>Tras apelar la decisi\u00f3n de Leon ante el Circuito del Distrito de Columbia, los abogados de Trump dijeron al tribunal en un escrito de tono contundente que el juez se excedi\u00f3 al emitir una \u201corden judicial impactante, sin precedentes e impropia\u201d que, seg\u00fan afirmaron, \u201cpondr\u00eda en peligro al presidente y a otras personas que viven y trabajan en la Casa Blanca\u201d.<\/p>\n<p>Al argumentar que todo el proyecto \u201cavanza objetivos cr\u00edticos de seguridad nacional\u201d, los abogados del Departamento de Justicia pidieron al tribunal suspender el fallo de Leon mientras el caso sigue su curso.<\/p>\n<p>\u201cLas mejoras en el Ala Este no son cosm\u00e9ticas; incluyen el uso de columnas y vigas de acero resistentes a misiles, materiales de techo a prueba de drones y ventanas resistentes a balas, impactos bal\u00edsticos y explosiones\u201d, escribieron en documentos judiciales. \u201cTambi\u00e9n incluyen la instalaci\u00f3n de refugios antibombas, instalaciones hospitalarias y m\u00e9dicas, divisiones protectoras y sistemas militares ultrasecretos, adem\u00e1s de aire acondicionado, calefacci\u00f3n, ventilaci\u00f3n y m\u00e1s\u201d.<\/p>\n<p>Sin embargo, el National Trust for Historic Preservation <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/19\/eeuu\/bunker-secreto-casa-blanca-trax\">dijo a la corte de apelaciones<\/a> que Trump estaba mezclando err\u00f3neamente el b\u00fanker que se construye bajo el sal\u00f3n de baile con la estructura sobre el nivel del suelo que reemplaza el Ala Este, que durante d\u00e9cadas alberg\u00f3 la oficina de la primera dama.<\/p>\n<p>\u201cComo es evidente, la ausencia de un gran sal\u00f3n de baile en los terrenos de la Casa Blanca no ha impedido que este, ni ning\u00fan otro, presidente resida all\u00ed o celebre eventos\u201d, dijeron los abogados del grupo en un escrito presentado esta semana. \u201cDetener temporalmente el proyecto hasta que cumpla con la ley no causar\u00e1 un da\u00f1o irreparable a los demandados ni a la naci\u00f3n\u201d.<\/p>\n<p>El proyecto del sal\u00f3n de baile ha sido una de las principales prioridades de Trump, quien durante a\u00f1os ha imaginado un gran espacio permanente para eventos en la Casa Blanca que sustituya las estructuras temporales que se instalan en el Jard\u00edn Sur para algunos actos presidenciales importantes.<\/p>\n<p>El proyecto tendr\u00eda una superficie aproximada de 8.300 metros cuadrados, seg\u00fan el arquitecto principal Shalom Baranes. En comparaci\u00f3n, la estructura principal de la Casa Blanca, la Mansi\u00f3n Ejecutiva, tiene unos 5.100 metros cuadrados.<\/p>\n<p>A principios de este mes, una junta compuesta por aliados de Trump que supervisa la planificaci\u00f3n de edificios y terrenos federales <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/eeuu\/controvertido-salon-trump-resolver-problema-trax\">dio su aprobaci\u00f3n al proyecto<\/a>. No obstante, esa votaci\u00f3n pareci\u00f3 tener poco impacto en el avance del plan debido al fallo de Leon d\u00edas antes.<\/p>\n<p>En la \u00faltima reuni\u00f3n de la Comisi\u00f3n Nacional de Planificaci\u00f3n de la Capital, la junta escuch\u00f3 a decenas de expertos, incluidos arquitectos, historiadores, conservacionistas y exfuncionarios de la Casa Blanca; representantes de grupos clave como el National Trust for Historic Preservation, la DC Preservation League y el American Institute of Architects; as\u00ed como ciudadanos que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/05\/eeuu\/retrasan-aprobacion-salon-baile-casa-blanca-criticas-trax\">expresaron su oposici\u00f3n al proyecto<\/a>. Solo una persona, el propietario de un recinto hist\u00f3rico local para eventos, manifest\u00f3 su apoyo.<\/p>\n<p>El presidente de la comisi\u00f3n, Will Scharf, un alto asesor de Trump, elogi\u00f3 el proyecto durante la reuni\u00f3n y dijo que el sal\u00f3n de baile \u201cser\u00e1 considerado tanto un tesoro nacional como los dem\u00e1s componentes clave de la Casa Blanca\u201d.<\/p>\n<p>Trump ha prometido que estar\u00e1 terminado en el verano de 2028, meses antes de que deje el cargo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tribunal federal de apelaciones dijo este s\u00e1bado que el presidente Donald Trump puede seguir adelante durante otra semana con la construcci\u00f3n de un enorme nuevo sal\u00f3n de baile en la Casa Blanca mientras los jueces consideran el proyecto. La orden 2-1 del Tribunal de Apelaciones del Circuito del Distrito de Columbia es una victoria [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473068","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un tribunal federal de apelaciones dijo este s\u00e1bado que el presidente Donald Trump puede seguir adelante durante otra semana con la construcci\u00f3n de un enorme nuevo sal\u00f3n de baile en la Casa Blanca mientras los jueces consideran el proyecto. La orden 2-1 del Tribunal de Apelaciones del Circuito del Distrito de Columbia es una victoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-12T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora\",\"datePublished\":\"2026-04-12T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\"},\"wordCount\":1156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\",\"name\":\"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-12T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias","og_description":"Un tribunal federal de apelaciones dijo este s\u00e1bado que el presidente Donald Trump puede seguir adelante durante otra semana con la construcci\u00f3n de un enorme nuevo sal\u00f3n de baile en la Casa Blanca mientras los jueces consideran el proyecto. La orden 2-1 del Tribunal de Apelaciones del Circuito del Distrito de Columbia es una victoria [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-12T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/"},"author":{"name":"","@id":""},"headline":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora","datePublished":"2026-04-12T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/"},"wordCount":1156,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","name":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-12T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tribunal de apelaciones dice que la construcci\u00f3n del sal\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/11\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-12T00:03:46Z","datePublished":"2026-04-12T00:03:46Z","dateModified":"2026-04-12T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tribunal de apelaciones dice que la construcci\\u00f3n del sal\\u00f3n de baile de la Casa Blanca de Trump puede continuar por ahora\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/11\\\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/11\\\/tribunal-construccion-salon-baile-casa-blanca-continua-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-12T00:03:46Z\",\"datePublished\":\"2026-04-12T00:03:46Z\",\"dateModified\":\"2026-04-12T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473245,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/16\/juez-trump-salon-baile-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":0},"title":"Trump no puede decir que el sal\u00f3n de baile de la Casa Blanca responde a motivos de seguridad nacional, dice juez","author":"","date":"abril 16, 2026","format":false,"excerpt":"Un juez federal ha ordenado nuevamente al presidente Donald Trump que suspenda la construcci\u00f3n de un nuevo y gigante sal\u00f3n de baile en la Casa Blanca, al rechazar el intento \u201cpoco sincero\u201d del mandatario de eludir una resoluci\u00f3n anterior argumentando que el proyecto deb\u00eda continuar por razones de seguridad nacional.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473609,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/28\/solicitud-construccion-salon-baile-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":1},"title":"Con tono muy Trump, abogados piden a tribunal que anule el fallo que detuvo las obras del sal\u00f3n de baile de la Casa Blanca","author":"","date":"abril 28, 2026","format":false,"excerpt":"En una presentaci\u00f3n judicial inusualmente mordaz que imit\u00f3 el tono cl\u00e1sico del presidente Donald Trump, el Departamento de Justicia pidi\u00f3 a un juez federal a \u00faltima hora del lunes que anule un fallo que habr\u00eda detenido la construcci\u00f3n de un enorme nuevo sal\u00f3n de baile de la Casa Blanca.La solicitud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471697,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/26\/fallo-juez-salon-baile-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":2},"title":"Juez permite que contin\u00fae el proyecto de sal\u00f3n de baile de la Casa Blanca; grupo de preservaci\u00f3n presentar\u00e1 una nueva demanda","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Un juez federal rechaz\u00f3 este jueves el intento del principal grupo nacional de preservaci\u00f3n hist\u00f3rica de bloquear el proyecto de sal\u00f3n de baile de la Casa Blanca del presidente Donald Trump, pero tambi\u00e9n sugiri\u00f3 una posible hoja de ruta para que el grupo presente un nuevo desaf\u00edo.El National Trust for\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465017,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/31\/construccion-salon-baile-trump-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":3},"title":"La construcci\u00f3n del sal\u00f3n de baile de US$ 200 millones de Trump en la Casa Blanca comenzar\u00e1 en septiembre","author":"","date":"julio 31, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump ha so\u00f1ado con un nuevo sal\u00f3n de baile en la Casa Blanca durante d\u00e9cada y media.Ese sue\u00f1o est\u00e1 a punto de hacerse realidad.En septiembre comenzar\u00e1 la construcci\u00f3n de un sal\u00f3n de baile de US$ 200 millones y 8.400 metros cuadrados, anunci\u00f3 su secretaria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468981,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/04\/nuevo-arquitecto-salon-baile-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":4},"title":"Trump contrata a nuevo arquitecto para el sal\u00f3n de baile de la Casa Blanca en medio de enfrentamientos sobre el proyecto","author":"","date":"diciembre 4, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump contrat\u00f3 a un nuevo arquitecto para el sal\u00f3n de baile de la Casa Blanca en medio de disputas entre el mandatario y el arquitecto originalmente contratado para completar el proyecto, dijeron varias fuentes a CNN.Un alto funcionario de la Casa Blanca dijo que McCrery\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473553,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/27\/enfoque-trump-salon-baile-casa-blanca-trax\/","url_meta":{"origin":1473068,"position":5},"title":"El extra\u00f1o enfoque de Trump en su sal\u00f3n de baile tras el tiroteo en la Cena de Corresponsales de la Casa Blanca","author":"","date":"abril 27, 2026","format":false,"excerpt":"Tras el asesinato de Charlie Kirk el a\u00f1o pasado, el Gobierno de Trump se puso de inmediato a citar la tragedia para justificar una gran ofensiva contra grupos de izquierda. (Esto a pesar de no haber pruebas de que dichos grupos desempe\u00f1aran alg\u00fan papel.)Despu\u00e9s de que este fin de semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473068"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473068\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}