{"id":1473101,"date":"2026-04-13T11:03:38","date_gmt":"2026-04-13T18:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/"},"modified":"2026-04-13T11:03:38","modified_gmt":"2026-04-13T18:03:38","slug":"festival-cannes-2026-estados-unidos-espana-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","title":{"rendered":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica"},"content":{"rendered":"<p>El festival de cine de Cannes, famoso por su pompa y circunstancia, present\u00f3 el jueves la lista oficial de las pel\u00edculas invitadas a participar en 2026 en la competencia por su m\u00e1ximo galard\u00f3n: la Palma de Oro. Y si bien hay muchos directores de renombre mundial, lo que brilla casi por su ausencia total es la participaci\u00f3n de producciones estadounidenses.<\/p>\n<p>Es bien sabido que la presencia de estrellas de Hollywood \u2013por su relevancia mundial\u2013 en las alfombras rojas de este y otros encuentros de su tipo, son un gancho para atraer la curiosidad del p\u00fablico y la cobertura de la prensa internacional.<\/p>\n<p>Pero este a\u00f1o, solo una pel\u00edcula estadounidense, \u201cThe Man I Love\u201d del realizador Ira Sachs, figura en el grupo de 21 competidoras.<\/p>\n<p>Espa\u00f1a, en cambio, celebra el que este a\u00f1o tenga tres pel\u00edculas de su m\u00e1s reciente cosecha en tan selecto grupo. De igual manera, el a\u00f1o pasado, este pa\u00eds hispanoamericano celebraba el que, tambi\u00e9n por primera vez en 37 a\u00f1os, dos de sus producciones fueran invitadas a la competencia oficial: \u201cRomer\u00eda\u201d, de Carla Sim\u00f3n, y \u201cSir\u0101t\u201d, de Oliver Laxe. Esta \u00faltima, recibi\u00f3 el Premio del Jurado, algo as\u00ed como el tercer reconocimiento m\u00e1s importante de la competencia.<\/p>\n<p>En esta ocasi\u00f3n, las pel\u00edculas espa\u00f1olas en competencia son \u201cAmarga Navidad\u201d, de Pedro Almod\u00f3var y la \u00fanica que ya est\u00e1 siendo exhibida en las salas de cine de su pa\u00eds, y las dos pr\u00f3ximas a estrenarse \u201cEl ser querido\u201d, de Rodrigo Sorogoyen, y \u201cLa bola negra\u201d, del d\u00fao creativo conocido como \u201cLos Javis\u201d: Javier Ambrossi y Javier Calvo. (\u201cAmarga Navidad\u201d es distribuida por Warner Bros. Pictures, que, al igual que CNN en Espa\u00f1ol, forma parte de Warner Bros. Discovery).<\/p>\n<p>Con el anuncio oficial de las pel\u00edculas que aspiran a la Palma de Oro, tambi\u00e9n se revelaron los nombres de obras que integran secciones especiales como \u201cUna cierta mirada\u201d o que simplemente tendr\u00e1n su <em>premiere<\/em> mundial en esta ciudad costera del sur de Francia, como \u201cDiamond\u201d, un nuevo proyecto como director del m\u00fasico y actor Andy Garc\u00eda, o \u201cPropeller One-Way Night Coach\u201d, la \u00f3pera prima de John Travolta como realizador.<\/p>\n<p>Gracias a Garc\u00eda y a Travolta, la prensa de Hollywood tendr\u00e1 entonces m\u00e1s caras de Hollywood a las cuales fotografiar, y no solo tendr\u00e1 que conformarse con el reparto de la pel\u00edcula en competencia \u201cThe Man I Love\u201d, encabezado por Rami Malek.<\/p>\n<p>Adem\u00e1s, las directivas del festival de Cannes anunciaron el jueves que a\u00fan faltan algunos t\u00edtulos por revelarse y entre ellos, creemos, podr\u00eda haber m\u00e1s pel\u00edculas <em>Made in the USA<\/em>.<\/p>\n<ul>\n<li>\u201cAmarga Navidad\u201d, de Pedro Almod\u00f3var<\/li>\n<li>\u201cParallel Tales\u201d, de Asghar Farhadi<\/li>\n<li>\u201cA Woman\u2019s Life\u201d, de Charline Bourgeois-Tacquet<\/li>\n<li>\u201cLa bola negra\u201d; de Javier Calvo &#038; Javier Ambrossi<\/li>\n<li>\u201cCoward\u201d, de Lukas Dhont<\/li>\n<li>\u201cDas Getr\u00e4umte Abenteuer\u201d, de Valeska Grisebach<\/li>\n<li>\u201cAll of Sudden\u201d, de Ry\u00fbsuke Hamaguchi<\/li>\n<li>\u201cThe Unknown\u201d, de Arthur Harari<\/li>\n<li>\u201cAnother Day\u201d, de Jeanne Herry<\/li>\n<li>\u201cSheep in the Box\u201d, de Hirokazu Kore-eda<\/li>\n<li>\u201cHope\u201d, de Na Hong-jin<\/li>\n<li>\u201cNagi Notes\u201d, de Koji Fukada<\/li>\n<li>\u201cGentle Monster\u201d, de Marie Kreutzer<\/li>\n<li>\u201cNotre salut\u201d, de Emmanuel Marre<\/li>\n<li>\u201cFjord\u201d, de Cristian Mungiu<\/li>\n<li>\u201cThe Birthday Party\u201d, de L\u00e9a Mysius<\/li>\n<li>\u201cMoulin\u201d, de L\u00e1szl\u00f3 Nemes<\/li>\n<li>\u201cFatherland\u201d, de Pawel Pawlikowski<\/li>\n<li>\u201cThe Man I Love\u201d, de Ira Sachs<\/li>\n<li>\u201cEl ser querido\u201d, de Rodrigo Sorogoyen<\/li>\n<li>\u201cMinotaur\u201d, de Andrey Zvyagintsev<\/li>\n<\/ul>\n<p>El Festival de Cine de Cannes se inicia este a\u00f1o el 12 de mayo y culmina el 23 de mayo. Para m\u00e1s informaci\u00f3n, se puede consultar su <a href=\"https:\/\/www.festival-cannes.com\/en\/press\/press-releases\/the-films-of-the-official-selection-2026\/\">sitio web oficial<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El festival de cine de Cannes, famoso por su pompa y circunstancia, present\u00f3 el jueves la lista oficial de las pel\u00edculas invitadas a participar en 2026 en la competencia por su m\u00e1ximo galard\u00f3n: la Palma de Oro. Y si bien hay muchos directores de renombre mundial, lo que brilla casi por su ausencia total es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473101","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias\" \/>\n<meta property=\"og:description\" content=\"El festival de cine de Cannes, famoso por su pompa y circunstancia, present\u00f3 el jueves la lista oficial de las pel\u00edculas invitadas a participar en 2026 en la competencia por su m\u00e1ximo galard\u00f3n: la Palma de Oro. Y si bien hay muchos directores de renombre mundial, lo que brilla casi por su ausencia total es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T18:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica\",\"datePublished\":\"2026-04-13T18:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\"},\"wordCount\":636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\",\"name\":\"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-13T18:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias","og_description":"El festival de cine de Cannes, famoso por su pompa y circunstancia, present\u00f3 el jueves la lista oficial de las pel\u00edculas invitadas a participar en 2026 en la competencia por su m\u00e1ximo galard\u00f3n: la Palma de Oro. Y si bien hay muchos directores de renombre mundial, lo que brilla casi por su ausencia total es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-13T18:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/"},"author":{"name":"","@id":""},"headline":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica","datePublished":"2026-04-13T18:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","name":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-13T18:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estados Unidos casi ausente en Cannes, pero Espa\u00f1a tendr\u00e1 una presencia hist\u00f3rica","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/13\/festival-cannes-2026-estados-unidos-espana-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-13T18:03:38Z","datePublished":"2026-04-13T18:03:38Z","dateModified":"2026-04-13T18:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estados Unidos casi ausente en Cannes, pero Espa\\u00f1a tendr\\u00e1 una presencia hist\\u00f3rica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/13\\\/festival-cannes-2026-estados-unidos-espana-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/13\\\/festival-cannes-2026-estados-unidos-espana-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-13T18:03:38Z\",\"datePublished\":\"2026-04-13T18:03:38Z\",\"dateModified\":\"2026-04-13T18:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472113,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/11\/barbra-streisand-palma-de-oro-festival-cine-cannes-orix\/","url_meta":{"origin":1473101,"position":0},"title":"Barbra Streisand recibir\u00e1 la Palma de Oro honor\u00edfica en la edici\u00f3n 79 del Festival de Cine de Cannes","author":"","date":"marzo 11, 2026","format":false,"excerpt":"La actriz, cantante y directora Barbra Streisand recibir\u00e1 la Palma de Oro honor\u00edfica en la edici\u00f3n n\u00famero 79 del Festival de Cine de Cannes. El sitio oficial del prestigioso certamen inform\u00f3 que la artista ser\u00e1 homenajeada el pr\u00f3ximo 23 de mayo, cuando recibir\u00e1 este galard\u00f3n que reconoce toda su trayectoriaStreisand\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462124,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/08\/cine-peliculas-aranceles-trump-hollywood-cannes-orix\/","url_meta":{"origin":1473101,"position":1},"title":"Trump, los aranceles y el futuro del cine global: la tensi\u00f3n de Hollywood llega al Festival de Cannes","author":"","date":"mayo 8, 2025","format":false,"excerpt":"A pocos d\u00edas de que la ciudad mediterr\u00e1nea de Cannes (Francia) extienda la alfombra roja de su fiesta anual cinematogr\u00e1fica, el acostumbrado runr\u00fan sobre las pel\u00edculas m\u00e1s esperadas de esta edici\u00f3n se est\u00e1 viendo eclipsado por otro tipo de discusi\u00f3n: la guerra arancelaria.Despu\u00e9s de que el presidente Donald Trump anunciara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462445,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/16\/tiempo-ovaciones-de-pie-aplausos-cannes-orix\/","url_meta":{"origin":1473101,"position":2},"title":"Las ovaciones de pie en Cannes no significan lo que crees: la verdad de los elogios en el festival de cine","author":"","date":"mayo 16, 2025","format":false,"excerpt":"\u00a1Saquen sus cron\u00f3metros! Ahora que arranc\u00f3 una nueva edici\u00f3n del festival de cine de Cannes, la prensa y otros asistentes miden cuidadosamente los minutos y segundos que dura cada una de las ovaciones de pie para las pel\u00edculas en competencia. \u00a1Pero ojo que eso no se traduce en un eventual\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462356,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/14\/celebridades-desafian-nuevo-codigo-vestimenta-alfombra-roja-festival-cannes-trax\/","url_meta":{"origin":1473101,"position":3},"title":"Celebridades desaf\u00edan el nuevo c\u00f3digo de vestimenta de la alfombra roja del Festival de Cannes","author":"","date":"mayo 14, 2025","format":false,"excerpt":"La alfombra roja se despleg\u00f3 oficialmente por el Paseo de la Croisette para dar la bienvenida a la Riviera Francesa a las estrellas del Festival de Cine de Cannes.En su 78\u00aa edici\u00f3n, este acontecimiento es una joya en el calendario tanto de los cin\u00e9filos m\u00e1s exquisitos como de los amantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467699,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/24\/favoritos-nominaciones-premios-oscar-2026-trax\/","url_meta":{"origin":1473101,"position":4},"title":"As\u00ed est\u00e1 la carrera por las nominaciones a los premios Oscar 2026. Estas son las favoritas","author":"","date":"octubre 24, 2025","format":false,"excerpt":"\u00bfD\u00f3nde se ha ido el 2025? Una forma de marcar el vertiginoso paso del tiempo: la carrera por los premios Oscar ya est\u00e1 cobrando protagonismo, ahora que estamos \u2014\u00a1uf!\u2014 a tres meses de las nominaciones.La competencia a\u00fan tiene mucho tiempo para tomar forma, pero hay algunos favoritos emergentes, empezando por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462339,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/14\/robert-de-niro-contra-trump-discurso-cannes-trax\/","url_meta":{"origin":1473101,"position":5},"title":"Robert De Niro arremete contra Trump en su discurso en Cannes","author":"","date":"mayo 14, 2025","format":false,"excerpt":"El actor de Hollywood Robert De Niro aprovech\u00f3 su discurso de aceptaci\u00f3n de premios en el Festival de Cine de Cannes para criticar al presidente estadounidense Donald Trump.De Niro, de 81 a\u00f1os, recib\u00eda la Palma de Oro a la trayectoria en el evento celebrado el martes en el sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473101"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473101\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}