{"id":1473197,"date":"2026-04-15T07:03:48","date_gmt":"2026-04-15T14:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/"},"modified":"2026-04-15T07:03:48","modified_gmt":"2026-04-15T14:03:48","slug":"embajada-eeuu-venezuela-laura-dogu-john-barrett-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","title":{"rendered":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala"},"content":{"rendered":"<p>La recientemente reabierta embajada de Estados Unidos en Venezuela tendr\u00e1 un cambio de representaci\u00f3n. La administraci\u00f3n de Donald Trump design\u00f3 al diplom\u00e1tico John Barrett como encargado de negocios en el pa\u00eds sudamericano, en reemplazo de Laura Dogu.<\/p>\n<p>La propia Dogu confirm\u00f3 el cambio. \u201cMi asignaci\u00f3n temporal en Caracas est\u00e1 llegando a su fin\u201d, public\u00f3 la diplom\u00e1tica <a href=\"https:\/\/x.com\/usembassyve\/status\/2044385747931693253?s=20\">en la cuenta de X <\/a>de la embajada estadounidense. All\u00ed tambi\u00e9n anunci\u00f3 que el designado para su reemplazo es Barrett, actual encargado de negocios en Guatemala, y que llegar\u00e1 \u201cpr\u00f3ximamente\u201d a Venezuela.<\/p>\n<p>CNN contact\u00f3 al Departamento para solicitar comentarios.<\/p>\n<p>Estados Unidos reabri\u00f3 formalmente su embajada en Caracas el pasado 30 de marzo, casi tres meses despu\u00e9s del operativo militar en el que capturaron al depuesto presidente Nicol\u00e1s Maduro.<\/p>\n<p>El Departamento de Estado de EE.UU. dijo entonces que la reapertura significaba \u201cun nuevo cap\u00edtulo\u201d en las relaciones diplom\u00e1ticas entre ambos pa\u00edses. Estos v\u00ednculos se hab\u00edan interrumpido en 2019, luego de que Trump, en su primera administraci\u00f3n, rechazara reconocer a Maduro como presidente tras unas cuestionadas elecciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La recientemente reabierta embajada de Estados Unidos en Venezuela tendr\u00e1 un cambio de representaci\u00f3n. La administraci\u00f3n de Donald Trump design\u00f3 al diplom\u00e1tico John Barrett como encargado de negocios en el pa\u00eds sudamericano, en reemplazo de Laura Dogu. La propia Dogu confirm\u00f3 el cambio. \u201cMi asignaci\u00f3n temporal en Caracas est\u00e1 llegando a su fin\u201d, public\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473197","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias\" \/>\n<meta property=\"og:description\" content=\"La recientemente reabierta embajada de Estados Unidos en Venezuela tendr\u00e1 un cambio de representaci\u00f3n. La administraci\u00f3n de Donald Trump design\u00f3 al diplom\u00e1tico John Barrett como encargado de negocios en el pa\u00eds sudamericano, en reemplazo de Laura Dogu. La propia Dogu confirm\u00f3 el cambio. \u201cMi asignaci\u00f3n temporal en Caracas est\u00e1 llegando a su fin\u201d, public\u00f3 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T14:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala\",\"datePublished\":\"2026-04-15T14:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\",\"name\":\"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-15T14:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias","og_description":"La recientemente reabierta embajada de Estados Unidos en Venezuela tendr\u00e1 un cambio de representaci\u00f3n. La administraci\u00f3n de Donald Trump design\u00f3 al diplom\u00e1tico John Barrett como encargado de negocios en el pa\u00eds sudamericano, en reemplazo de Laura Dogu. La propia Dogu confirm\u00f3 el cambio. \u201cMi asignaci\u00f3n temporal en Caracas est\u00e1 llegando a su fin\u201d, public\u00f3 la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-15T14:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/"},"author":{"name":"","@id":""},"headline":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala","datePublished":"2026-04-15T14:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","name":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-15T14:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/15\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-15T14:03:48Z","datePublished":"2026-04-15T14:03:48Z","dateModified":"2026-04-15T14:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cambios en la embajada de EE.UU. en Venezuela: sale Dogu y llega John Barrett, actual encargado de negocios en Guatemala\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/15\\\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/15\\\/embajada-eeuu-venezuela-laura-dogu-john-barrett-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-15T14:03:48Z\",\"datePublished\":\"2026-04-15T14:03:48Z\",\"dateModified\":\"2026-04-15T14:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470390,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/22\/gobierno-trump-embajadora-laura-dogu-encargada-venezuela-orix\/","url_meta":{"origin":1473197,"position":0},"title":"Trump nombra a Laura Dogu como encargada de Negocios para Venezuela en &#171;el per\u00edodo de transici\u00f3n&#187;. Esto sabemos sobre ella","author":"","date":"enero 22, 2026","format":false,"excerpt":"El Gobierno del presidente de Estados Unidos, Donald Trump, design\u00f3 a la embajadora Laura F. Dogu como encargada de Negocios de la Oficina Externa de EE.UU. para asuntos de Venezuela, confirm\u00f3 a CNN un alto funcionario del Departamento de Estado.\u201cLa administraci\u00f3n Trump contin\u00faa trabajando con las autoridades interinas para estabilizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472693,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/30\/eeuu-reabre-embajada-caracas-orix\/","url_meta":{"origin":1473197,"position":1},"title":"Estados Unidos anunci\u00f3 que reanuda operaciones de su Embajada en Caracas","author":"","date":"marzo 30, 2026","format":false,"excerpt":"El Departamento de Estado de EE.UU. anunci\u00f3 este lunes la reanudaci\u00f3n de las operaciones de su embajada en Caracas, como parte del restablecimiento de las relaciones diplom\u00e1ticas que estaban rotas desde 2019.La medida parece tener un car\u00e1cter principalmente simb\u00f3lico. Seg\u00fan la nota de prensa del Departamento de Estado de EE.UU.,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470711,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/31\/enviada-ee-uu-venezuela-llega-caracas-trax\/","url_meta":{"origin":1473197,"position":2},"title":"La nueva enviada de EE.UU. a Venezuela llega a Caracas mientras el Gobierno de Trump busca reabrir la embajada","author":"","date":"enero 31, 2026","format":false,"excerpt":"Laura F. Dogu, la nueva enviada de Estados Unidos a Venezuela, lleg\u00f3 a Caracas el s\u00e1bado, en un momento en que la administraci\u00f3n Trump busca reabrir la embajada por primera vez en casi siete a\u00f1os.\u201cAcabo de llegar a Venezuela. Mi equipo y yo estamos listos para trabajar\u201d, \u200b\u200bdijo Dogu en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472190,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/14\/izan-bandera-eeuu-embajada-caracas-primera-vez-7-anios-orix\/","url_meta":{"origin":1473197,"position":3},"title":"Izan la bandera estadounidense en la Embajada de EE.UU. en Caracas por primera vez en 7 a\u00f1os","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Por primera vez en siete a\u00f1os, el Gobierno de Estados Unidos iz\u00f3 este s\u00e1bado la bandera de su pa\u00eds en la Embajada estadounidense en Caracas, apenas unos d\u00edas despu\u00e9s de que Venezuela y EE.UU. restablecieran relaciones diplom\u00e1ticas.\u201cEn la ma\u00f1ana del 14 de marzo de 2019, la bandera estadounidense fue arriada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470515,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/27\/ee-uu-planifica-presencia-cia-maduro-trax\/","url_meta":{"origin":1473197,"position":4},"title":"Exclusivo: EE.UU. planifica la presencia de la CIA en la Venezuela pos-Maduro","author":"","date":"enero 27, 2026","format":false,"excerpt":"La CIA est\u00e1 trabajando discretamente para establecer una presencia permanente de Estados Unidos en Venezuela, encabezando los planes del Gobierno de Trump para ejercer su nueva influencia sobre el futuro del pa\u00eds, seg\u00fan m\u00faltiples fuentes familiarizadas con la planificaci\u00f3n.Las conversaciones de planificaci\u00f3n entre la CIA y el Departamento de Estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470783,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/02\/delcy-rodriguez-reunion-encargada-negocios-eeuu-laura-dogu-orix\/","url_meta":{"origin":1473197,"position":5},"title":"Delcy Rodr\u00edguez se re\u00fane por primera vez con la nueva encargada de negocios de EE.UU. desde su llegada a Caracas","author":"","date":"febrero 2, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, se reuni\u00f3 este lunes con Laura Dogu, la nueva encargada de negocios de Estados Unidos, en su primer encuentro oficial desde la llegada de Dogu a Caracas este s\u00e1bado para reabrir la misi\u00f3n diplom\u00e1tica estadounidense, cerrada tras la ruptura de relaciones entre ambos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473197"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473197\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}