{"id":1473611,"date":"2026-04-28T14:03:46","date_gmt":"2026-04-28T21:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/"},"modified":"2026-04-28T14:03:46","modified_gmt":"2026-04-28T21:03:46","slug":"anant-ambani-hipopotamos-escobar-sacrificio-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","title":{"rendered":"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar"},"content":{"rendered":"<p>El magnate indio <a href=\"https:\/\/www.cnn.com\/2024\/07\/11\/style\/anant-ambani-wedding-events-intl-hnk\">Anant Ambani<\/a>, hijo del millonario Mukesh Ambani, propuso recibir en su centro de conservaci\u00f3n de fauna silvestre en India a los 80 \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2023\/11\/03\/colombia-plan-hipopotamos-cocaina-pablo-escobar-trax\">hipop\u00f3tamos de la coca\u00edna\u201d<\/a> que el Gobierno de Colombia autoriz\u00f3 sacrificar para, seg\u00fan se anunci\u00f3, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/13\/colombia\/hipopotamos-pablo-escobar-eutanasia-colombia-orix\">preservar el ecosistema<\/a> del pa\u00eds.<\/p>\n<p>Se trata de los famosos ejemplares de una especie que lleg\u00f3 al pa\u00eds en la d\u00e9cada del 1980 introducida por el fallecido Pablo Escobar, uno de los m\u00e1ximos jefes del narcotr\u00e1fico en Colombia, quien buscaba tener uno de los zool\u00f3gicos privados m\u00e1s grandes de Am\u00e9rica Latina con una gran variedad de animales.<\/p>\n<p>Desde entonces, la poblaci\u00f3n de hipop\u00f3tamos africanos en la cuenca del r\u00edo Magdalena, que asciende a cerca de 160 ejemplares, no ha dejado de crecer, al punto de poner en riesgo a especies nativas y la biodiversidad del pa\u00eds, que semanas atr\u00e1s anunci\u00f3 que avanzar\u00eda en sacrificar a 80 de estos animales, una medida que desde hace tiempo genera debates.<\/p>\n<p>Ambani pidi\u00f3 al Gobierno de Colombia que reconsidere la decisi\u00f3n sobre los hipop\u00f3tamos y propone recibirlos en su centro de rescate. \u201cEstos ochenta hipop\u00f3tamos no eligieron d\u00f3nde nacer, ni crearon las circunstancias que ahora enfrentan\u201d, dijo en <a href=\"https:\/\/www.instagram.com\/vantara\/p\/DXqvik-jx58\/?img_index=2\">una publicaci\u00f3n<\/a> en redes sociales. Estos animales \u201cson seres vivos y sintientes, y si tenemos la capacidad de salvarlos mediante una soluci\u00f3n segura y humana, tenemos la responsabilidad de intentarlo\u201d.<\/p>\n<p>En la ciudad de Jamnagar, en el estado de Guyarat, Ambani fund\u00f3 el centro de conservaci\u00f3n Vantara, que re\u00fane a m\u00e1s de 150.000 animales de m\u00e1s de 2.000 especies de fauna silvestre, seg\u00fan se\u00f1ala <a href=\"https:\/\/vantara.in\/en\">su sitio oficial<\/a>.<\/p>\n<p>All\u00ed es donde propone relocalizar a 80 de los hipop\u00f3tamos colombianos, que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/13\/colombia\/hipopotamos-pablo-escobar-eutanasia-colombia-orix#:~:text=Los%20animales%20viven%20en%20los%20alrededores%20de%20la%20llamada%20Hacienda%20N%C3%A1poles%2C%20un%20predio%20rural%20ubicado%20en%20Puerto%20Triunfo%2C%20departamento%20de%20Antioquia%2C%20que%20perteneci%C3%B3%20a%20Escobar%20y%20hoy%20est%C3%A1%20dedicado%20a%20actividades%20tur%C3%ADsticas.\">hoy viven<\/a> en los alrededores de la llamada Hacienda N\u00e1poles, un predio rural ubicado en Puerto Triunfo, departamento de Antioquia, que perteneci\u00f3 a Escobar y actualmente est\u00e1 destinado a actividades tur\u00edsticas.<\/p>\n<p>\u201cEstamos dispuestos a recibir y cuidar a estos hipop\u00f3tamos en un entorno especialmente dise\u00f1ado y enriquecido, concebido para garantizar su bienestar y, al mismo tiempo, reflejar las caracter\u00edsticas clave de su h\u00e1bitat actual\u201d, dice <a href=\"https:\/\/www.instagram.com\/vantara\/p\/DXqvik-jx58\/?img_index=3\">un comunicado<\/a> publicado el lunes que lleva la firma del director ejecutivo de Vantara, Vivaan Karani, en representaci\u00f3n de Ambani.<\/p>\n<p>En el escrito, dirigido a la ministra de Ambiente y Desarrollo Sustentable de Colombia, Irene V\u00e9lez Torres, los ejecutivos de Vantara hacen un llamado para \u201capelar respetuosamente\u201d a la decisi\u00f3n del Gobierno colombiano y suspender la muerte de los animales, una medida que las autoridades <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/13\/colombia\/hipopotamos-pablo-escobar-eutanasia-colombia-orix\">autorizaron el 13 de abril pasado<\/a>.<\/p>\n<p>CNN se contact\u00f3 con las autoridades de Vantara para obtener m\u00e1s detalles sobre la propuesta.<\/p>\n<p>En caso de que el Gobierno de Colombia est\u00e9 dispuesto a considerar la iniciativa, la implementaci\u00f3n se llevar\u00eda a cabo \u201cen estricta conformidad con las aprobaciones, permisos, procesos de debida diligencia, requisitos de bioseguridad y planificaci\u00f3n log\u00edstica necesarios\u201d, explic\u00f3 Karani en el comunicado, en el que ofrece el cuidado \u201cde por vida\u201d a los animales bajo el principio de \u201cno causar da\u00f1o a ning\u00fan ser vivo\u201d.<\/p>\n<p>CNN consult\u00f3 al Ministerio de Ambiente y Desarrollo Sostenible de Colombia y a la ministra V\u00e9lez sobre la recepci\u00f3n de la propuesta y su viabilidad, y est\u00e1 a la espera de respuesta.<\/p>\n<p>Las autoridades de Vantara dijeron estar a \u201centera disposici\u00f3n\u201d para dialogar con el Gobierno colombiano para analizar la iniciativa y manifestaron la intenci\u00f3n de reunirse con los funcionionarios del Gobierno del presidente Gustavo Petro, a quienes extendieron una invitaci\u00f3n para visitar las instalaciones del centro de rescate.<\/p>\n<p>Ambani, fundador de Vantara e hijo del presidente y director general de Reliance Industries Limited (RIL), considerada la <a href=\"https:\/\/www.cnn.com\/2024\/07\/11\/style\/anant-ambani-wedding-events-intl-hnk#:~:text=El%20viernes%2C%20Anant,semanas%20en%20promedio.\">mayor corporaci\u00f3n privada<\/a> de la India, dice ser un amante de los animales. \u201cEn los animales veo a Dios y Vantara es templo\u201d, dice. Su nombre fue noticia internacional en 2024 al casarse con Radhika Merchant, en una boda precedida por <a href=\"https:\/\/www.cnn.com\/2024\/07\/11\/style\/anant-ambani-wedding-events-intl-hnk\">lujosas celebraciones<\/a> que se extendieron durante meses.<\/p>\n<p>La medida de autorizar el sacrificio 80 de estos ejemplares se debe al crecimiento descontrolado de esta especie invasora en la cuenca del r\u00edo Magdalena, dijo la ministra V\u00e9lez al comunicar la decisi\u00f3n.<\/p>\n<p>\u201cSin esa acci\u00f3n es imposible controlar la poblaci\u00f3n, y, como ya vimos, en las estimaciones implicar\u00eda que a 2030 tendr\u00edamos al menos 500 hipop\u00f3tamos afectando nuestros ecosistemas y a nuestras especies nativas, como el manat\u00ed y como la tortuga de r\u00edo. Es con responsabilidad con nuestro ecosistema que tenemos que tomar estas acciones\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/13\/colombia\/hipopotamos-pablo-escobar-eutanasia-colombia-orix#:~:text=%E2%80%9CSin%20esa%20acci%C3%B3n,conferencia%20de%20prensa.\">dijo <\/a>la funcionaria en conferencia de prensa el pasado 13 de abril.<\/p>\n<p>Semanas atr\u00e1s, el ministerio de Ambiente colombiano dijo que <a href=\"https:\/\/x.com\/MinAmbienteCo\/status\/2043718788902748505\/photo\/1\">exploraba alternativas<\/a> como la reubicaci\u00f3n de algunos de los animales en pa\u00edses como Ecuador, Per\u00fa, Filipinas, India, M\u00e9xico, Rep\u00fablica Dominicana, Sud\u00e1frica y Chile; pero que esas opciones no hab\u00edan prosperado \u201cdebido a restricciones internacionales y limitaciones operativas\u201d.<\/p>\n<p>La decisi\u00f3n, que responde a una crisis ecol\u00f3gica evaluada desde hace a\u00f1os por diferentes sectores cient\u00edficos y de defensa del medio ambiente, ha generado cuestionamientos y debates tanto a favor como en contra de la medida, que tiene opiniones divididas entre ambientalistas y proteccionistas de animales.<\/p>\n<p>Se trata de un debate entre la protecci\u00f3n del ecosistema global y el derecho a la vida de animales individuales, muy presente durante los \u00faltimos a\u00f1os en Colombia.<\/p>\n<p>\u201cLa ciencia nos pide actuar. Las acciones son indispensables para evitar un desastre ecol\u00f3gico irreversible en nuestros r\u00edos\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/13\/colombia\/hipopotamos-pablo-escobar-eutanasia-colombia-orix#:~:text=La%20ciencia%20nos%20pide%20actuar.%20Las%20acciones%20son%20indispensables%20para%20evitar%20un%20desastre%20ecol%C3%B3gico%20irreversible%20en%20nuestros%20r%C3%ADos%E2%80%9D%2C%20afirm%C3%B3%20la%20ministra%20V%C3%A9lez%20durante%20la%20presentaci%C3%B3n%20de%20una%20circular%20t%C3%A9cnica%20sobre%20el%20tema.\">dijo<\/a> la ministra V\u00e9lez, que no dio precisiones de cu\u00e1ndo podr\u00eda llevarse a cabo la medida.<\/p>\n<p>El hipop\u00f3tamo <a href=\"https:\/\/www.minambiente.gov.co\/el-minambiente-declara-al-hipopotamo-especie-invasora-en-colombia\/\">fue incluido en la lista de especies ex\u00f3ticas invasoras<\/a> de Colombia en marzo de 2022, lo que permiti\u00f3 luego al Gobierno dise\u00f1ar medidas para controlar la especie, que vive <a href=\"https:\/\/www.minambiente.gov.co\/el-minambiente-declara-al-hipopotamo-especie-invasora-en-colombia\/#:~:text=vive%20alrededor%20de%2040%20a%C3%B1os%20en%20estado%20silvestre%20y%20hasta%2050%20a%C3%B1os%20en%20cautividad%2C\">alrededor de 40 y 50 a\u00f1os<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El magnate indio Anant Ambani, hijo del millonario Mukesh Ambani, propuso recibir en su centro de conservaci\u00f3n de fauna silvestre en India a los 80 \u201chipop\u00f3tamos de la coca\u00edna\u201d que el Gobierno de Colombia autoriz\u00f3 sacrificar para, seg\u00fan se anunci\u00f3, preservar el ecosistema del pa\u00eds. Se trata de los famosos ejemplares de una especie que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473611","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Millonario indio Anant Ambani ofrece acoger a los 80 &quot;hipop\u00f3tamos de la coca\u00edna&quot; que Colombia quiere sacrificar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Millonario indio Anant Ambani ofrece acoger a los 80 &quot;hipop\u00f3tamos de la coca\u00edna&quot; que Colombia quiere sacrificar - Noticias\" \/>\n<meta property=\"og:description\" content=\"El magnate indio Anant Ambani, hijo del millonario Mukesh Ambani, propuso recibir en su centro de conservaci\u00f3n de fauna silvestre en India a los 80 \u201chipop\u00f3tamos de la coca\u00edna\u201d que el Gobierno de Colombia autoriz\u00f3 sacrificar para, seg\u00fan se anunci\u00f3, preservar el ecosistema del pa\u00eds. Se trata de los famosos ejemplares de una especie que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T21:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar\",\"datePublished\":\"2026-04-28T21:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\"},\"wordCount\":1026,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\",\"name\":\"Millonario indio Anant Ambani ofrece acoger a los 80 \\\"hipop\u00f3tamos de la coca\u00edna\\\" que Colombia quiere sacrificar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-28T21:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Millonario indio Anant Ambani ofrece acoger a los 80 \"hipop\u00f3tamos de la coca\u00edna\" que Colombia quiere sacrificar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Millonario indio Anant Ambani ofrece acoger a los 80 \"hipop\u00f3tamos de la coca\u00edna\" que Colombia quiere sacrificar - Noticias","og_description":"El magnate indio Anant Ambani, hijo del millonario Mukesh Ambani, propuso recibir en su centro de conservaci\u00f3n de fauna silvestre en India a los 80 \u201chipop\u00f3tamos de la coca\u00edna\u201d que el Gobierno de Colombia autoriz\u00f3 sacrificar para, seg\u00fan se anunci\u00f3, preservar el ecosistema del pa\u00eds. Se trata de los famosos ejemplares de una especie que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-28T21:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/"},"author":{"name":"","@id":""},"headline":"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar","datePublished":"2026-04-28T21:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/"},"wordCount":1026,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","name":"Millonario indio Anant Ambani ofrece acoger a los 80 \"hipop\u00f3tamos de la coca\u00edna\" que Colombia quiere sacrificar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-28T21:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\u00f3tamos de la coca\u00edna&#187; que Colombia quiere sacrificar","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/28\/anant-ambani-hipopotamos-escobar-sacrificio-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-28T21:03:46Z","datePublished":"2026-04-28T21:03:46Z","dateModified":"2026-04-28T21:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Millonario indio Anant Ambani ofrece acoger a los 80 &#171;hipop\\u00f3tamos de la coca\\u00edna&#187; que Colombia quiere sacrificar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/28\\\/anant-ambani-hipopotamos-escobar-sacrificio-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/28\\\/anant-ambani-hipopotamos-escobar-sacrificio-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-28T21:03:46Z\",\"datePublished\":\"2026-04-28T21:03:46Z\",\"dateModified\":\"2026-04-28T21:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473623,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/29\/5-cosas-29-de-abril-orix\/","url_meta":{"origin":1473611,"position":0},"title":"Las 5 cosas que debes saber este 29 de abril","author":"","date":"abril 29, 2026","format":false,"excerpt":"Golpe para la OPEP y Arabia Saudita: Emiratos \u00c1rabes Unidos se retirar\u00e1 de la organizaci\u00f3n. Las teor\u00edas conspirativas del tiroteo en la Cena de Corresponsales. El PSG vence al Bayern Munich en hist\u00f3rica semifinal de la Champions. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473106,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/13\/hipopotamos-pablo-escobar-eutanasia-colombia-orix\/","url_meta":{"origin":1473611,"position":1},"title":"Colombia autoriza sacrificar a 80 de los &#171;hipop\u00f3tamos de la coca\u00edna&#187; de Pablo Escobar","author":"","date":"abril 13, 2026","format":false,"excerpt":"La utop\u00eda animal del difunto Pablo Escobar, uno de los m\u00e1s sanguinarios jefes del narcotr\u00e1fico en Colombia, termin\u00f3 convirti\u00e9ndose en una verdadera pesadilla ecol\u00f3gica. Este lunes, el Gobierno de Colombia oficializ\u00f3 una de las decisiones m\u00e1s complejas y debatidas en materia de biodiversidad: la autorizaci\u00f3n para aplicar la eutanasia a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451235,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/18\/boda-india-ambani-merchant-jets-bendicion-modi-kardashian-trax\/","url_meta":{"origin":1473611,"position":2},"title":"As\u00ed fue la boda del a\u00f1o en la India de Ambani y Merchant: jets privados, la bendici\u00f3n de Modi y cameo de las Kardashian","author":"","date":"julio 18, 2024","format":false,"excerpt":"(CNN) -- La boda m\u00e1s esperada del a\u00f1o en la India lleg\u00f3 a su fin el domingo, despu\u00e9s de tres d\u00edas de celebraciones repletas de estrellas en las que incluso el primer ministro del pa\u00eds bendijo a la joven pareja.El multimillonario heredero Anant Ambani se cas\u00f3 en Mumbai con su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450858,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/03\/ambani-asia-boda-india-lujo-trax\/","url_meta":{"origin":1473611,"position":3},"title":"El hijo del hombre m\u00e1s rico de Asia se casar\u00e1 en una de las bodas m\u00e1s lujosas y esperadas del a\u00f1o en la India","author":"","date":"julio 3, 2024","format":false,"excerpt":"(CNN) -- El multimillonario heredero Anant Ambani se casar\u00e1 con su novia Radhika Merchant a finales de este mes, en una fastuosa ceremonia descrita como la boda del a\u00f1o en el pa\u00eds.Las extravagantes celebraciones previas a la boda ya han desatado el frenes\u00ed en los medios de comunicaci\u00f3n de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450975,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/09\/boda-ambani-paraliza-india-trax\/","url_meta":{"origin":1473611,"position":4},"title":"De Justin Bieber a las joyas mogoles: la boda de Ambani paraliza a la India","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN) -- La boda del a\u00f1o ya est\u00e1 aqu\u00ed.En menos de una semana, Anant Ambani, hijo del multimillonario indio Mukesh Ambani, se casar\u00e1 con su novia Radhika Merchant. No es la primera vez que se celebra una boda opulenta en la India, pero los preparativos y las fiestas para esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452236,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/28\/namibia-sacrificar-700-animales-elefantes-hambruna-sequia-trax\/","url_meta":{"origin":1473611,"position":5},"title":"Namibia planea sacrificar m\u00e1s de 700 animales, incluidos elefantes e hipop\u00f3tamos, y distribuir la carne","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN) -- Namibia planea sacrificar m\u00e1s de 700 animales salvajes, incluidos elefantes, cebras e hipop\u00f3tamos, y distribuir la carne entre la poblaci\u00f3n que lucha contra la inseguridad alimentaria mientras el pa\u00eds se enfrenta a su peor sequ\u00eda en 100 a\u00f1os.Los animales que ser\u00e1n sacrificados incluyen 83 elefantes, 30 hipop\u00f3tamos, 60\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473611"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473611\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}