{"id":1473666,"date":"2026-04-30T04:03:51","date_gmt":"2026-04-30T11:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/"},"modified":"2026-04-30T04:03:51","modified_gmt":"2026-04-30T11:03:51","slug":"cronologia-caso-d4vd-presunto-homicidio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","title":{"rendered":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven"},"content":{"rendered":"<p>Los fiscales expusieron el mi\u00e9rcoles una cronolog\u00eda detallada y macabra en el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/eeuu\/tiempo-cargos-d4vd-celeste-rivas-trax\">caso contra el cantante d4vd<\/a>, acusado de matar a <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/24\/eeuu\/quien-fue-celeste-rivas-hernandez-d4vd-muerte-trax\">Celeste Rivas Hern\u00e1ndez<\/a>, de 14 a\u00f1os, incluidas acusaciones de que comenz\u00f3 a abusar sexualmente de ella cuando ten\u00eda 13 a\u00f1os y luego la apu\u00f1al\u00f3 mortalmente cuando ella amenaz\u00f3 con exponer su relaci\u00f3n.<\/p>\n<p>Se cree que Celeste <a href=\"https:\/\/www.cnn.com\/2026\/04\/20\/us\/d4vd-case-update-celeste-rivas-hernandez\">fue muerta el 23 de abril de 2025<\/a>, un d\u00eda despu\u00e9s de que ella y d4vd \u2014cuyo nombre legal es David Anthony Burke\u2014 tuvieran una discusi\u00f3n durante la cual ella amenaz\u00f3 con revelar informaci\u00f3n perjudicial sobre su relaci\u00f3n \u201cpara acabar con su carrera y destruir su vida\u201d, seg\u00fan un escrito de la Fiscal\u00eda del condado de Los \u00c1ngeles.<\/p>\n<p>El cantante, cuyo primer \u00e1lbum de estudio se public\u00f3 d\u00edas despu\u00e9s, tom\u00f3 \u201cmedidas horribles para destruir y deshacerse del cuerpo de la v\u00edctima\u201d, se\u00f1al\u00f3 el escrito.<\/p>\n<p>Celeste muri\u00f3 por \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/23\/eeuu\/d4vd-celeste-rivas-hernandez-autopsia-trax\">m\u00faltiples lesiones penetrantes<\/a>\u201d, seg\u00fan un informe de autopsia publicado a principios de este mes. Ten\u00eda heridas en el pecho y el abdomen que \u201cpodr\u00edan representar lesiones por fuerza cortante\u201d, indic\u00f3 la oficina del m\u00e9dico forense del condado de Los \u00c1ngeles en el informe, que fue firmado en diciembre pero permaneci\u00f3 sellado durante meses a solicitud de las fuerzas del orden.<\/p>\n<p>Su cuerpo fue descubierto en el maletero de un veh\u00edculo incautado el pasado septiembre, un d\u00eda despu\u00e9s de lo que habr\u00eda sido su 15.\u00ba cumplea\u00f1os. Fue reportada como desaparecida por familiares y amigos en varias ocasiones, a principios de 2024, y fue vista con vida por \u00faltima vez cuando se dirig\u00eda a la casa de d4vd en abril de 2025.<\/p>\n<p>El cantante, ahora de 21 a\u00f1os, fue arrestado a principios de este mes y <a href=\"https:\/\/www.cnn.com\/2026\/04\/20\/us\/d4vd-case-update-celeste-rivas-hernandez\">se declar\u00f3 inocente<\/a> de cargos que incluyen homicidio premeditado. La abogada de d4vd, Blair Berk, dijo tras la lectura de cargos que su cliente es inocente y que las pruebas \u201cdemostrar\u00e1n que David Burke no mat\u00f3 a Celeste Rivas Hernandez y que \u00e9l no fue la causa de su muerte\u201d.<\/p>\n<p>Berk pidi\u00f3 el mi\u00e9rcoles al tribunal que sellara el escrito probatorio, diciendo que era \u201cunilateral\u201d y \u201crepleto de testimonios de o\u00eddas\u201d y que podr\u00eda potencialmente contaminar a un futuro grupo de jurados. El juez deneg\u00f3 la solicitud. CNN se comunic\u00f3 con Berk para solicitar comentarios el mi\u00e9rcoles por la noche.<\/p>\n<p>La noche anterior a la que las autoridades dicen que probablemente fue muerta Celeste, ella tuvo una larga discusi\u00f3n con d4vd, descrita posteriormente en mensajes de texto que \u201crevelan los celos de la v\u00edctima por las relaciones del acusado con otras mujeres, ya que el acusado la llev\u00f3 a creer que ten\u00edan un futuro juntos\u201d, seg\u00fan el documento judicial.<\/p>\n<p>\u201cSe puso extremadamente alterada y amenaz\u00f3 con revelar informaci\u00f3n perjudicial sobre su relaci\u00f3n con el acusado para acabar con su carrera y destruir su vida\u201d, escribieron los fiscales, se\u00f1alando que la fecha de lanzamiento del primer \u00e1lbum de estudio del cantante era el 25 de abril de 2025.<\/p>\n<p>El 23 de abril de 2025, el cantante envi\u00f3 un Uber para recoger a Celeste en su casa en Lake Elsinore alrededor de las 8:40 p.m. y llevarla a su casa en Hollywood Hills alrededor de las 10:10 p.m., seg\u00fan el documento judicial.<\/p>\n<p>Alrededor de las 10:30 p.m. de esa noche, d4vd le envi\u00f3 un mensaje de texto a Celeste, en lo que los fiscales describieron como parte de su \u201cplan premeditado para encubrir el homicidio, ya que para ese momento ella ya estaba muerta\u201d.<\/p>\n<p>\u201cSabiendo que ten\u00eda que silenciar a la v\u00edctima antes de que arruinara su carrera musical, como ella hab\u00eda amenazado, muy poco despu\u00e9s de su llegada a su casa, el acusado apu\u00f1al\u00f3 a la v\u00edctima en m\u00faltiples ocasiones hasta matarla y se qued\u00f3 all\u00ed mientras ella se desangraba\u201d, dijo el escrito. \u201cEn ning\u00fan momento llam\u00f3 a las fuerzas del orden ni al 911 ni la llev\u00f3 a una sala de emergencias para intentar salvarle la vida\u201d.<\/p>\n<p>Los <a href=\"https:\/\/www.cnn.com\/2026\/04\/21\/us\/d4vd-murder-charge-timing\">restos desmembrados<\/a> de Celeste fueron hallados en el Tesla de d4vd en Los \u00c1ngeles el 8 de septiembre de 2025. Al parecer, el veh\u00edculo fue abandonado en Hollywood Hills y remolcado a un dep\u00f3sito policial, donde un empleado not\u00f3 un olor f\u00e9tido que proven\u00eda del maletero y alert\u00f3 a las autoridades.<\/p>\n<p>Los fiscales escribieron que d4vd compr\u00f3 en l\u00ednea dos motosierras que utiliz\u00f3 para desmembrar el cuerpo de Celeste en una piscina inflable. Seg\u00fan los fiscales, se encontr\u00f3 ADN de ella en su garaje y dijeron que su cuerpo fue cortado en partes. El cantante tambi\u00e9n realiz\u00f3 compras en l\u00ednea de una bolsa para cad\u00e1veres y bolsas de lavander\u00eda de alta resistencia, seg\u00fan el documento judicial.<\/p>\n<p>\u201cEl acusado tom\u00f3 medidas horribles para destruir y deshacerse del cuerpo de la v\u00edctima\u201d, dijeron los fiscales en el documento.<\/p>\n<p>D4vd \u201cle amput\u00f3 el dedo anular y el me\u00f1ique de la mano izquierda porque el dedo anular ten\u00eda un tatuaje con su nombre\u201d, se\u00f1al\u00f3 el documento judicial. \u201cSus dedos no han sido recuperados\u201d.<\/p>\n<p>Peque\u00f1os fragmentos de pl\u00e1stico azul estaban incrustados en los restos de la v\u00edctima, y un experto del Departamento de Polic\u00eda de Los \u00c1ngeles (LAPD, por sus siglas en ingl\u00e9s) realiz\u00f3 \u201cuna coincidencia f\u00edsica de encaje entre los fragmentos azules y la piscina inflable azul\u201d en la que Celeste fue desmembrada, seg\u00fan el documento.<\/p>\n<p>Antes de partir para una gira de conciertos a finales de julio, dice el documento, el artista estacion\u00f3 su Tesla en la calle, a la vuelta de la esquina de su casa.<\/p>\n<p>Las pruebas expuestas por el estado incluyen fotos de Celeste y el cantante participando en actividad sexual, que los investigadores dicen que comenz\u00f3 cuando ella ten\u00eda 13 a\u00f1os y \u00e9l 18. Los investigadores creen que ambos se conocieron cuando Celeste ten\u00eda 11 a\u00f1os, seg\u00fan el escrito.<\/p>\n<p>Los mensajes de texto hasta marzo de 2025 muestran c\u00f3mo d4vd presuntamente manipul\u00f3 a la v\u00edctima. Celeste escribi\u00f3 en un mensaje, seg\u00fan los fiscales: \u201cTodo lo que hacemos es tener sexo y simplemente pasar el rato, amigo; quiero m\u00e1s que eso para m\u00ed\u201d.<\/p>\n<p>Los padres de Celeste reportaron su desaparici\u00f3n en febrero de 2024. Detectives del Departamento del Sheriff del condado de Riverside se pusieron en contacto con d4vd, quien les dijo que solo la hab\u00eda conocido una vez y que no sab\u00eda su edad, seg\u00fan el documento judicial.<\/p>\n<p>Cuando la adolescente regres\u00f3 a casa ese febrero, sus padres le quitaron el tel\u00e9fono celular. Los fiscales dijeron que el acusado luego condujo hasta Lake Elsinore y le pag\u00f3 a un compa\u00f1ero de clase de Celeste US$ 1.000 para que le diera un tel\u00e9fono.<\/p>\n<p>Celeste y d4vd pasaron mucho tiempo juntos durante 2024, incluidos viajes de fin de semana a su casa en Hollywood Hills y visitas a Las Vegas, Londres y Texas para conocer a la familia del cantante, seg\u00fan el documento judicial. Los mensajes de texto entre ambos supuestamente inclu\u00edan referencias al sexo, el embarazo, el aborto y el anticonceptivo de emergencia Plan B.<\/p>\n<p>\u201cLa familia Rivas Hernandez est\u00e1 absolutamente devastada por los hallazgos\u201d, dijo la familia de Celeste en un comunicado tras la publicaci\u00f3n del informe de la autopsia. \u201cRespetuosamente piden privacidad, comprensi\u00f3n y paciencia mientras procesan esta informaci\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los fiscales expusieron el mi\u00e9rcoles una cronolog\u00eda detallada y macabra en el caso contra el cantante d4vd, acusado de matar a Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, incluidas acusaciones de que comenz\u00f3 a abusar sexualmente de ella cuando ten\u00eda 13 a\u00f1os y luego la apu\u00f1al\u00f3 mortalmente cuando ella amenaz\u00f3 con exponer su relaci\u00f3n. Se cree [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473666","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los fiscales expusieron el mi\u00e9rcoles una cronolog\u00eda detallada y macabra en el caso contra el cantante d4vd, acusado de matar a Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, incluidas acusaciones de que comenz\u00f3 a abusar sexualmente de ella cuando ten\u00eda 13 a\u00f1os y luego la apu\u00f1al\u00f3 mortalmente cuando ella amenaz\u00f3 con exponer su relaci\u00f3n. Se cree [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T11:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven\",\"datePublished\":\"2026-04-30T11:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\"},\"wordCount\":1300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\",\"name\":\"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T11:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias","og_description":"Los fiscales expusieron el mi\u00e9rcoles una cronolog\u00eda detallada y macabra en el caso contra el cantante d4vd, acusado de matar a Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, incluidas acusaciones de que comenz\u00f3 a abusar sexualmente de ella cuando ten\u00eda 13 a\u00f1os y luego la apu\u00f1al\u00f3 mortalmente cuando ella amenaz\u00f3 con exponer su relaci\u00f3n. Se cree [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T11:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/"},"author":{"name":"","@id":""},"headline":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven","datePublished":"2026-04-30T11:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/"},"wordCount":1300,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","name":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T11:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los fiscales presentan una cronolog\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/30\/cronologia-caso-d4vd-presunto-homicidio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T11:03:51Z","datePublished":"2026-04-30T11:03:51Z","dateModified":"2026-04-30T11:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los fiscales presentan una cronolog\\u00eda detallada en el caso contra el cantante d4vd por el presunto homicidio de una joven\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/30\\\/cronologia-caso-d4vd-presunto-homicidio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/30\\\/cronologia-caso-d4vd-presunto-homicidio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T11:03:51Z\",\"datePublished\":\"2026-04-30T11:03:51Z\",\"dateModified\":\"2026-04-30T11:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473449,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/23\/pornografia-infantil-d4vd-asesinato-trax\/","url_meta":{"origin":1473666,"position":0},"title":"Hallan pornograf\u00eda infantil entre las pruebas en el caso contra el cantante d4vd, acusado de asesinar a una ni\u00f1a de 14 a\u00f1os","author":"","date":"abril 23, 2026","format":false,"excerpt":"La pornograf\u00eda infantil figura entre las pruebas clave que, seg\u00fan los fiscales de Los \u00c1ngeles, reforzar\u00e1n su caso contra el cantante de alt-pop d4vd, quien ha sido acusado de asesinato y abuso sexual prolongado de una ni\u00f1a en edad de escuela secundaria cuyos restos fueron hallados el a\u00f1o pasado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473337,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","url_meta":{"origin":1473666,"position":1},"title":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista","author":"","date":"abril 20, 2026","format":false,"excerpt":"David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473426,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/23\/d4vd-celeste-rivas-hernandez-autopsia-trax\/","url_meta":{"origin":1473666,"position":2},"title":"Autopsia de Celeste Rivas Hern\u00e1ndez confirma que muri\u00f3 por m\u00faltiples heridas penetrantes. El cantante d4vd est\u00e1 acusado","author":"","date":"abril 23, 2026","format":false,"excerpt":"La joven de 14 a\u00f1os que, seg\u00fan la acusaci\u00f3n, fue asesinada y desmembrada por el cantante d4vd muri\u00f3 por \u201cm\u00faltiples heridas penetrantes\u201d, seg\u00fan una autopsia publicada el mi\u00e9rcolesLos hallazgos arrojan m\u00e1s luz sobre la muerte de Celeste Rivas Hern\u00e1ndez, meses despu\u00e9s de que la adolescente fuera encontrada en el maletero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473297,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/18\/d4vd-asesinato-celeste-rivas-hernandez-trax\/","url_meta":{"origin":1473666,"position":3},"title":"Un autom\u00f3vil abandonado, una fotograf\u00eda y una ni\u00f1a desaparecida: \u00bfQu\u00e9 llev\u00f3 al arresto de d4vd bajo sospecha de asesinato?","author":"","date":"abril 18, 2026","format":false,"excerpt":"Meses despu\u00e9s de que el cuerpo de una ni\u00f1a fuera hallado en el maletero de su coche abandonado, el cantante d4vd fue arrestado cerca del dep\u00f3sito de veh\u00edculos de Los \u00c1ngeles donde se descubrieron sus restos.La fiscal\u00eda ahora evaluar\u00e1 si presenta cargos penales contra el artista de pop alternativo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473486,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/24\/quien-fue-celeste-rivas-hernandez-d4vd-muerte-trax\/","url_meta":{"origin":1473666,"position":4},"title":"\u00bfQui\u00e9n fue Celeste Rivas Hern\u00e1ndez, la chica de 14 a\u00f1os por cuya muerte se acusa al cantante d4vid?","author":"","date":"abril 24, 2026","format":false,"excerpt":"La unida y familiar ciudad de Lake Elsinore, en el condado de Riverside, se encuentra a unos 110 kil\u00f3metros al sureste, un mundo aparte del brillo y el glamour de Hollywood Hills.Celeste Rivas Hern\u00e1ndez creci\u00f3 en Lake Elsinore, donde era una habitual de la tienda de la esquina calle abajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467425,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/16\/esposo-separado-sia-quiere-manutencion-mensual-trax\/","url_meta":{"origin":1473666,"position":5},"title":"El esposo separado de la cantante Sia quiere una manutenci\u00f3n mensual de US$ 250.000","author":"","date":"octubre 16, 2025","format":false,"excerpt":"El esposo separado de Sia est\u00e1 solicitando m\u00e1s de US$ 250.000 en pagos mensuales de manutenci\u00f3n conyugal.La cantante australiana, cuyo nombre completo es Sia Furler, present\u00f3 una petici\u00f3n de disoluci\u00f3n de matrimonio de su segundo esposo, Daniel Bernad, en marzo. La pareja se cas\u00f3 en 2022 y dio la bienvenida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473666"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473666\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}