{"id":1473683,"date":"2026-04-30T13:03:38","date_gmt":"2026-04-30T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/"},"modified":"2026-04-30T13:03:38","modified_gmt":"2026-04-30T20:03:38","slug":"congreso-ice-dhs-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/04\/30\/congreso-ice-dhs-trax\/","title":{"rendered":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE"},"content":{"rendered":"<p>El Congreso vot\u00f3 este jueves para reabrir partes clave del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), incluida la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s), despu\u00e9s de semanas de disputas internas republicanas que prolongaron un cierre r\u00e9cord de la agencia.<\/p>\n<p>El proyecto de ley para financiar el departamento, que llevaba 75 d\u00edas sin fondos, pasa ahora al presidente Donald Trump para su firma.<\/p>\n<p>Los l\u00edderes republicanos de la C\u00e1mara cedieron en una disputa de semanas sobre la financiaci\u00f3n del DHS, en un importante retroceso para el presidente de la C\u00e1mara de Representantes, Mike Johnson, mientras enfrentaba una creciente rebeli\u00f3n de centristas de su partido, dijeron m\u00faltiples fuentes a CNN. La C\u00e1mara aprob\u00f3 abruptamente el paquete \u2014que no incluye dinero para la aplicaci\u00f3n federal de leyes migratorias, en una importante victoria para los dem\u00f3cratas\u2014 mediante votaci\u00f3n por voz este jueves por la tarde.<\/p>\n<p>La medida pone fin a un cierre hist\u00f3rico que provoc\u00f3 largas filas en aeropuertos de todo el pa\u00eds y llega justo antes de que los salarios de los empleados del DHS volvieran a quedar en riesgo. El Gobierno de Trump hab\u00eda advertido que el departamento estaba por quedarse sin fondos de emergencia utilizados para pagar al personal afectado por el cierre.<\/p>\n<p>La decisi\u00f3n culmina semanas de drama en el Capitolio, con republicanos optando por no realizar una votaci\u00f3n registrada sobre la medida que ha dividido fuertemente al partido. Algunos republicanos de la C\u00e1mara insist\u00edan en que sus l\u00edderes no deb\u00edan ceder, aunque el liderazgo argument\u00f3 que sus miembros dieron un paso clave un d\u00eda antes para desbloquear fondos para la aplicaci\u00f3n de leyes migratorias, lo que allana el camino para poner fin al estancamiento sobre el resto del DHS.<\/p>\n<p>\u201cCreo que es absurdo que estemos financiando al Gobierno de esta manera\u201d, dijo el representante de Texas Chip Roy poco antes de la votaci\u00f3n.<\/p>\n<p>Y no es el fin del drama para el Congreso esta semana. Los l\u00edderes republicanos tambi\u00e9n necesitan convencer a esos mismos miembros descontentos de respaldar otro proyecto de ley impopular: una extensi\u00f3n temporal de los poderes de vigilancia extranjera sin orden judicial del Gobierno. Los debates simult\u00e1neos sobre gasto y poderes de espionaje han subrayado que Johnson y los republicanos han perdido efectivamente su capacidad de gobernar en una C\u00e1mara plagada de divisiones y disputas internas.<\/p>\n<p>Durante casi un mes, Johnson se neg\u00f3 a aprobar la misma medida parcial de financiaci\u00f3n ya aprobada por el Senado debido a miembros como Roy. Los republicanos de la C\u00e1mara detestan ampliamente el proyecto parcial de financiaci\u00f3n del DHS del Senado, porque temen que siente un precedente que los dem\u00f3cratas puedan explotar en futuras disputas presupuestarias.<\/p>\n<p>Incluso el representante de Florida Mario Diaz-Balart, un importante l\u00edder en temas de gasto que rara vez confronta a su propio partido, insisti\u00f3 en que la C\u00e1mara no deb\u00eda permitir que los dem\u00f3cratas del Senado decidieran simplemente no financiar una parte de un departamento fuera del proceso anual de asignaciones presupuestarias.<\/p>\n<p>\u201cEl Senado est\u00e1 m\u00e1s preocupado por preservar el filibusterismo que por preservar la Constituci\u00f3n. El filibusterismo no est\u00e1 en la Constituci\u00f3n. Los proyectos de ley de asignaciones presupuestarias s\u00ed\u201d, dijo, se\u00f1alando adem\u00e1s que es \u201crealmente muy peligroso\u201d que el DHS siga cerrado.<\/p>\n<p>Muchos republicanos de la C\u00e1mara tienen objeciones espec\u00edficas sobre un aspecto del proyecto: incluye lenguaje que elimina espec\u00edficamente fondos para ICE, algo que muchos republicanos temen que los exponga a desaf\u00edos en elecciones primarias en sus estados bajo acusaciones de haber dejado sin fondos a ICE. (Johnson ha intentado en privado modificar el lenguaje, pero encontr\u00f3 resistencia de l\u00edderes republicanos del Senado encargados del gasto, seg\u00fan personas familiarizadas con las conversaciones).<\/p>\n<p>Pero mientras la C\u00e1mara se preparaba para salir a un receso de una semana, Johnson y su equipo de liderazgo decidieron en una reuni\u00f3n privada este jueves temprano que ten\u00edan pocas opciones m\u00e1s que avanzar con el proyecto. No solo sus propios miembros les advert\u00edan que actuaran: el secretario del DHS, Markwayne Mullin, ex integrante de la C\u00e1mara, hab\u00eda se\u00f1alado p\u00fablicamente que estaba casi sin dinero.<\/p>\n<p>Johnson tambi\u00e9n enfrentaba una presi\u00f3n creciente de republicanos centristas, incluidos importantes presidentes de comit\u00e9s y miembros vulnerables pol\u00edticamente, para resolver el estancamiento antes de que la C\u00e1mara abandonara Washington por el receso de la pr\u00f3xima semana. Muchos cre\u00edan que los votantes probablemente culpar\u00edan a su partido por m\u00e1s caos, incluido el relacionado con TSA.<\/p>\n<p>El representante republicano Zach Nunn, un centrista que representa un distrito competitivo, fue directo con el liderazgo sobre no abandonar Washington hasta aprobar la financiaci\u00f3n del DHS.<\/p>\n<p>\u201cEsto debi\u00f3 hacerse hace mucho tiempo\u201d, dijo Nunn a CNN. \u201cQuiero ver una soluci\u00f3n hoy para asegurar que estas personas reciban su pago\u201d.<\/p>\n<p>Hasta ahora, Johnson se hab\u00eda negado a llevar al pleno el proyecto de compromiso del DHS aprobado por el Senado, argumentando que los miembros no financiar\u00edan ciertas partes del departamento sin garantizar dinero para ICE y la patrulla fronteriza.<\/p>\n<p>En cambio, Johnson presion\u00f3 a l\u00edderes republicanos del Senado para avanzar r\u00e1pidamente hacia el desbloqueo de un poder especial que permite aprobar ciertos proyectos presupuestarios sin votos dem\u00f3cratas. Los republicanos de la C\u00e1mara insistieron en que solo avanzar\u00edan con la medida parcial de financiaci\u00f3n del DHS una vez estuvieran listos los fondos para ICE y la patrulla fronteriza, aunque reconocen que el proceso, conocido como reconciliaci\u00f3n presupuestaria, probablemente tomar\u00eda semanas.<\/p>\n<p>Subrayando la dificultad de la tarea, un alto republicano de la C\u00e1mara dijo a CNN esta semana que simplemente no exist\u00edan los votos para poner fin parcialmente al cierre del DHS sin tener \u201cen mano\u201d fondos para la aplicaci\u00f3n de leyes migratorias.<\/p>\n<p>\u201cNadie va a votar para financiar Seguridad Nacional sin dinero para ICE y CBP\u201d, dijo el representante de Texas Jodey Arrington, quien lidera el Comit\u00e9 de Presupuesto de la C\u00e1mara, el martes cuando se le pregunt\u00f3 cu\u00e1ndo avanzar\u00eda la C\u00e1mara con el proyecto parcial de financiaci\u00f3n del DHS que llevaba semanas detenido.<\/p>\n<p>Arrington \u2014un republicano pr\u00f3ximo a retirarse y respetado entre el ala ultraconservadora del partido\u2014 no estaba solo.<\/p>\n<p>Pero el representante republicano Nick Langworthy inst\u00f3 el mi\u00e9rcoles a sus colegas a no \u201cseguir jugando\u201d mientras segu\u00eda sin estar claro el camino para poner fin al cierre r\u00e9cord del DHS.<\/p>\n<p>\u201cDebe haber un sentido de urgencia\u201d, dijo a CNN al ser consultado sobre el manejo de Johnson del tema.<\/p>\n<p>Johnson hab\u00eda expresado resistencia a llevar al pleno un proyecto bipartidista aprobado por el Senado para financiar agencias cr\u00edticas del DHS, como FEMA y TSA, citando desacuerdos con el \u201clenguaje\u201d del proyecto. Pero Langworthy, un centrista que normalmente no critica al liderazgo, dijo que Johnson necesita actuar.<\/p>\n<p>\u201cYa no hay tiempo para seguir jugando con esto. Hay demasiada gente preocupada por las tarjetas de puntuaci\u00f3n de Washington y por qui\u00e9n gana, qui\u00e9n pierde o de qui\u00e9n fue la idea\u201d, dijo. \u201cNo veo c\u00f3mo podemos irnos de aqu\u00ed sin aprobarlo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso vot\u00f3 este jueves para reabrir partes clave del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), incluida la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s), despu\u00e9s de semanas de disputas internas republicanas que prolongaron un cierre r\u00e9cord de la agencia. El proyecto de ley para financiar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473683","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Congreso vot\u00f3 este jueves para reabrir partes clave del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), incluida la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s), despu\u00e9s de semanas de disputas internas republicanas que prolongaron un cierre r\u00e9cord de la agencia. El proyecto de ley para financiar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE\",\"datePublished\":\"2026-04-30T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\"},\"wordCount\":1271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\",\"name\":\"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias","og_description":"El Congreso vot\u00f3 este jueves para reabrir partes clave del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), incluida la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s), despu\u00e9s de semanas de disputas internas republicanas que prolongaron un cierre r\u00e9cord de la agencia. El proyecto de ley para financiar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/"},"author":{"name":"","@id":""},"headline":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE","datePublished":"2026-04-30T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/"},"wordCount":1271,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/","name":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/congreso-ice-dhs-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/04\/30\/congreso-ice-dhs-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE","url":"http:\/\/noticiasya.com\/boston\/2026\/04\/30\/congreso-ice-dhs-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/04\/30\/congreso-ice-dhs-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T20:03:38Z","datePublished":"2026-04-30T20:03:38Z","dateModified":"2026-04-30T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Congreso vota para reabrir partes del DHS tras semanas de disputa por fondos de ICE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/30\\\/congreso-ice-dhs-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/04\\\/30\\\/congreso-ice-dhs-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T20:03:38Z\",\"datePublished\":\"2026-04-30T20:03:38Z\",\"dateModified\":\"2026-04-30T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470690,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/30\/senado-proyecto-ley-financiamiento-trump-fin-al-cierre-trax\/","url_meta":{"origin":1473683,"position":0},"title":"El Senado aprueba ley de financiamiento respaldada por Trump y presiona a la C\u00e1mara para poner fin al cierre del Gobierno","author":"","date":"enero 30, 2026","format":false,"excerpt":"El Senado ha dado un paso para que el Congreso evite otro cierre prolongado del Gobierno, al aprobar un importante acuerdo presupuestario alcanzado con la Casa Blanca que financia temporalmente al Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), permitiendo as\u00ed negociaciones a largo plazo sobre la pol\u00edtica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472794,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/02\/senado-proyecto-reabrir-dhs-camara-trax\/","url_meta":{"origin":1473683,"position":1},"title":"Senado manda proyecto de ley para reabrir parcialmente el DHS nuevamente a la C\u00e1mara","author":"","date":"abril 2, 2026","format":false,"excerpt":"El Senado de Estados Unidos aprob\u00f3 por unanimidad este jueves un proyecto de ley destinado a reabrir parcialmente el Departamento de Seguridad Nacional, que excluye la financiaci\u00f3n para la aplicaci\u00f3n de las leyes de inmigraci\u00f3n y la Patrulla Fronteriza.La medida regresa ahora a la C\u00e1mara de Representantes, que la semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473378,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/21\/plan-migratorio-fin-cierre-dhs-trax\/","url_meta":{"origin":1473683,"position":2},"title":"Republicanos del Senado presentan plan migratorio de US$ 70.000 millones para poner fin al cierre del DHS","author":"","date":"abril 21, 2026","format":false,"excerpt":"Los l\u00edderes republicanos del Senado declararon formalmente este martes que intentar\u00e1n sortear a los dem\u00f3cratas en el estancamiento de meses sobre el financiamiento del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y aprobar por su cuenta hasta US$ 70.000 millones para la aplicaci\u00f3n de leyes migratorias.Tras meses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472623,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/27\/orden-trump-pagar-trabajadores-tsa-trax\/","url_meta":{"origin":1473683,"position":3},"title":"\u00bfQu\u00e9 sabemos de la orden de Trump para pagar a los trabajadores de la TSA sin esperar al Congreso?","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Con el debate del Congreso sobre la financiaci\u00f3n del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) ahora probablemente extendi\u00e9ndose por al menos varios d\u00edas m\u00e1s, el presidente Donald Trump emiti\u00f3 este viernes una acci\u00f3n ejecutiva prometida para que los empleados de la Administraci\u00f3n de Seguridad en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473547,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/27\/republicanos-congreso-financiacion-dhs-trax\/","url_meta":{"origin":1473683,"position":4},"title":"Los republicanos del Congreso se preparan para una &#171;semana de pesadilla&#187; en la discusi\u00f3n sobre el financiamiento del DHS","author":"","date":"abril 27, 2026","format":false,"excerpt":"Los principales republicanos en el Capitolio han pasado 10 semanas luchando por poner fin al amargo estancamiento en el financiamiento del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s).Ahora, mientras los trabajadores federales \u2014incluidos agentes del Servicio Secreto de EE.UU. que protegieron al presidente en el tiroteo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470498,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/26\/negociaciones-financiamiento-gobierno-ice-minneapolis-trax\/","url_meta":{"origin":1473683,"position":5},"title":"C\u00f3mo van las negociaciones sobre el financiamiento del Gobierno tras el tiroteo en Minneapolis","author":"","date":"enero 26, 2026","format":false,"excerpt":"La posibilidad de un cierre parcial del Gobierno para el final de la semana est\u00e1 creciendo, ya que el destino del financiamiento para el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y otras agencias gubernamentales clave est\u00e1 en juego.Tras otro tiroteo mortal por parte de un agente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473683"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473683\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}