{"id":1473753,"date":"2026-05-03T07:03:40","date_gmt":"2026-05-03T14:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/"},"modified":"2026-05-03T07:03:40","modified_gmt":"2026-05-03T14:03:40","slug":"corte-suprema-sigue-revocando-precedentes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","title":{"rendered":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed"},"content":{"rendered":"<p>Mientras la Corte Suprema se precipitaba hacia las \u00faltimas semanas de su per\u00edodo el a\u00f1o pasado, el presidente del Tribunal Supremo, John Roberts, hizo una rara aparici\u00f3n p\u00fablica para defender a sus colegas de las cr\u00edticas de que estaban demasiado dispuestos a mandar a la basura precedentes de d\u00e9cadas.<\/p>\n<p>A\u00fan magullado por la ira de la izquierda por la monumental decisi\u00f3n del tribunal tres a\u00f1os antes de revocar el fallo del caso Roe v. Wade, Roberts enumer\u00f3 una serie de estad\u00edsticas que subrayaban que su tribunal \u2014el tribunal de Roberts\u2014 hab\u00eda apuntado contra muchos menos precedentes que cualquiera de sus predecesores modernos, un promedio de menos de dos \u201crevocaciones\u201d cada a\u00f1o.<\/p>\n<p>\u201cCreo que la gente tiene un malentendido sobre cu\u00e1nto el tribunal actual est\u00e1 revocando precedentes\u201d, dijo Roberts a una audiencia en el Centro de Derecho de la Universidad de Georgetown.<\/p>\n<p>Pero apenas 10 d\u00edas despu\u00e9s de que se bajara del escenario, la Corte Suprema dej\u00f3 en pie el despido por parte del presidente Donald Trump de dos altos funcionarios laborales pese a un precedente de 1935 conocido como Humphrey\u2019s Executor que durante d\u00e9cadas ha protegido a los l\u00edderes de agencias independientes de ser destituidos si causa por un presidente.<\/p>\n<p>Los cr\u00edticos de la decisi\u00f3n de gran impacto de la Corte Suprema del mi\u00e9rcoles, que desmantel\u00f3 una disposici\u00f3n clave de la Ley de Derecho al Voto de 1965 y anul\u00f3 un mapa congresional de Louisiana, dicen que el tribunal hizo lo mismo: efectivamente revoc\u00f3 un precedente de d\u00e9cadas sin decir expl\u00edcitamente que lo estaba haciendo.<\/p>\n<p>\u201cEl resultado es que la mayor\u00eda, sin ninguna buena raz\u00f3n, ha revocado la determinaci\u00f3n ponderada del Congreso \u2014junto con los precedentes de este tribunal que la respaldan\u2014 sobre c\u00f3mo rectificar las desigualdades raciales en la pol\u00edtica electoral\u201d, escribi\u00f3 la jueza Elena Kagan en un voto disidente en nombre de los tres jueces liberales.<\/p>\n<p>Las cifras que cit\u00f3 Roberts eran precisas, lo que le permiti\u00f3 argumentar que el tribunal se est\u00e1 moviendo deliberadamente en lugar de arrasar con casos anteriores. Pero esas cifras no tienen en cuenta los casos en los que el tribunal ha vapuleado un precedente sin eliminarlo expl\u00edcitamente. En apenas los \u00faltimos a\u00f1os, la mayor\u00eda conservadora tambi\u00e9n se ha apartado de precedentes relacionados con la libertad religiosa.<\/p>\n<p>\u201cPara m\u00ed, Callais es el ejemplo m\u00e1s reciente de un fallo del tribunal de Roberts que, en el mismo aliento, en gran medida neutraliza un precedente sin revocarlo formalmente\u201d, dijo Steve Vladeck, analista de la Corte Suprema de CNN y profesor en el Centro de Derecho de la Universidad de Georgetown, refiri\u00e9ndose al caso del mi\u00e9rcoles por su t\u00edtulo, Louisiana v. Callais.<\/p>\n<p>La distinci\u00f3n entre revocar precedentes formalmente y hacerlo en la pr\u00e1ctica es importante, dijo Vladeck.<\/p>\n<p>\u201cCuando solo los abogados entienden qu\u00e9 queda y qu\u00e9 no queda de una decisi\u00f3n anterior, eso hace mucho m\u00e1s dif\u00edcil construir el argumento de por qu\u00e9 la Corte, el Congreso o cualquier otro actor deber\u00eda responder\u201d.<\/p>\n<p>Tanto los jueces conservadores como los liberales, ostensiblemente, desaprueban revocar precedentes porque puede socavar la estabilidad del derecho y puede hacer que el tribunal parezca pol\u00edtico, dispuesto a cambiar de postura seg\u00fan qu\u00e9 jueces est\u00e9n sentados en el estrado.<\/p>\n<p>En el caso de derechos de voto del mi\u00e9rcoles, el juez Samuel Alito, el juez conservador que escribi\u00f3 la opini\u00f3n del tribunal, rechaz\u00f3 en\u00e9rgicamente lo dicho por Kagan.<\/p>\n<p>En su fallo 6-3, la primera decisi\u00f3n sobre el fondo del a\u00f1o que dividi\u00f3 limpiamente a los bloques conservador y liberal, el tribunal dijo que los votantes que alegan discriminaci\u00f3n racial en la redistribuci\u00f3n de distritos ahora deben demostrar una \u201cfuerte inferencia\u201d de que los legisladores redibujaron intencionalmente los l\u00edmites de los distritos para perjudicar a los votantes de minor\u00edas.<\/p>\n<p>Pero hace apenas tres a\u00f1os, en un caso que involucraba el mapa congresional de Alabama llamado Allen v. Milligan, la Corte Suprema rechaz\u00f3 en gran medida ese mismo argumento.<\/p>\n<p>\u201cContrariamente a lo que afirma el disenso, no hemos revocado Allen\u201d, escribi\u00f3 Alito, refiri\u00e9ndose a la decisi\u00f3n sobre Alabama de 2023.<\/p>\n<p>Alito dijo que el tribunal en Allen \u201cadjudic\u00f3 el caso bas\u00e1ndose en los argumentos de las partes\u201d. El argumento del estado era, esencialmente, que hab\u00eda trazado un mapa que dio como resultado solo un distrito de mayor\u00eda negra sin considerar la raza en absoluto. \u00bfC\u00f3mo pod\u00eda ser discriminatorio ese mapa, pregunt\u00f3 Alabama, si los legisladores nunca consideraron la raza?<\/p>\n<p>Por una votaci\u00f3n de 5-4, el tribunal rechaz\u00f3 esa idea y se atuvo en cambio a una revisi\u00f3n de 1982 de la Ley de Derecho al Voto que permit\u00eda a los grupos presentar esas demandas basadas en los efectos discriminatorios de una redistribuci\u00f3n de distritos. En otras palabras, no importaba si los legisladores pretend\u00edan discriminar si el nuevo distrito, en la pr\u00e1ctica, privaba a los votantes negros de una voz igual en la elecci\u00f3n.<\/p>\n<p>\u201cComo este tribunal ha reconocido desde hace mucho tiempo \u2014y como todos los miembros de este tribunal hoy coinciden\u2014 el texto del \u00a72 establece una prueba de efectos, no una prueba de intenci\u00f3n\u201d, escribi\u00f3 el juez Brett Kavanaugh en una opini\u00f3n concurrente en Allen.<\/p>\n<p>Pero en la opini\u00f3n mayoritaria del mi\u00e9rcoles, a la que se sumaron tanto Kavanaugh como Roberts, Alito dijo que la ley se aplica \u201csolo cuando la evidencia respalda una fuerte inferencia de que el estado traz\u00f3 intencionalmente sus distritos para otorgar a los votantes minoritarios menos oportunidad debido a su raza\u201d.<\/p>\n<p>\u201cEl tribunal puede reescribir dr\u00e1sticamente los precedentes, y lo ha hecho, sin anularlos formalmente\u201d, dijo a CNN Richard Pildes, profesor de Derecho en la Universidad de Nueva York y experto en Derecho Electoral.<\/p>\n<p>Un colega de la Facultad de Derecho, se\u00f1al\u00f3, acu\u00f1\u00f3 una frase para el fen\u00f3meno: \u201canulaciones encubiertas\u201d.<\/p>\n<p>\u201cDeterminar si el tribunal ha hecho esto m\u00e1s en ciertos per\u00edodos que en otros puede ser dif\u00edcil\u201d, dijo Pildes. \u201cPero en Callais, no hay duda de que el Tribunal ha reescrito por completo el marco que los casos anteriores hab\u00edan establecido para interpretar la VRA [la Ley de derecho del voto]\u201d.<\/p>\n<p>Cuando la mayor\u00eda conservadora de la Corte Suprema en 2022 anul\u00f3 el fallo del caso Roe v. Wade, la decisi\u00f3n de 1973 que estableci\u00f3 un derecho constitucional al aborto, lo dijo expl\u00edcitamente en las primeras p\u00e1ginas de su opini\u00f3n.<\/p>\n<p>\u201cRoe fue atrozmente err\u00f3nea desde el principio\u201d, escribi\u00f3 Alito.<\/p>\n<p>Fue igualmente claro dos a\u00f1os despu\u00e9s, cuando el tribunal anul\u00f3 Chevron v. Natural Resources Defense Council, una decisi\u00f3n de 1984 que facultaba a las agencias federales a interpretar leyes vagas y que se hab\u00eda convertido en un objetivo para los conservadores legales.<\/p>\n<p>\u201cChevron\u201d, escribi\u00f3 Roberts en esa opini\u00f3n, \u201cqueda anulada\u201d.<\/p>\n<p>Pero apartarse del precedente \u2014a veces de una manera que lo deja vivo, pero con soporte vital\u2014 es m\u00e1s com\u00fan y menos claro. Las sentencias que anulan expl\u00edcitamente un precedente ocurrieron en solo el 4 % de los 558 casos estudiados de 2005 a 2013, en los que los defensores apuntaron a una decisi\u00f3n previa, seg\u00fan datos recopilados por Lee Epstein, profesora de Derecho y polit\u00f3loga en la Universidad Washington en St. Louis.<\/p>\n<p>Pero las desviaciones, dijo Epstein, ocurrieron en alrededor del 28 % de esos casos.<\/p>\n<p>A finales de abril, la Corte Suprema acept\u00f3 revisar una ley de Colorado que exige que los preescolares que reciben dinero de los contribuyentes inscriban a los hijos de parejas del mismo sexo, preparando un importante enfrentamiento de la Primera Enmienda a finales de este a\u00f1o que enfrenta los derechos religiosos contra las familias LGBTQ.<\/p>\n<p>Al aceptar el caso, los jueces declinaron espec\u00edficamente abordar una cuesti\u00f3n sobre si deber\u00edan anular un precedente clave de 1990, Employment Division v. Smith, que los grupos religiosos consideran que da al Gobierno demasiada libertad para vulnerar la religi\u00f3n. Una interpretaci\u00f3n de la decisi\u00f3n de la Corte de dejar de lado esa cuesti\u00f3n es que una mayor\u00eda de jueces no se ha aglutinado en torno a qu\u00e9 reemplazar por Smith. Otra es que el precedente ya ha sido despojado de gran parte de su fuerza a lo largo de la \u00faltima d\u00e9cada, por lo que tiene poco sentido.<\/p>\n<p>Los magistrados se enfrentan a una situaci\u00f3n similar mientras revisan el intento de Trump de destituir a los l\u00edderes de agencias independientes como la Comisi\u00f3n Federal de Comercio. Durante los alegatos orales, en diciembre, una mayor\u00eda de magistrados indic\u00f3 que se pondr\u00eda del lado de Trump, a pesar del precedente de 1935. Durante su alegato ante el tribunal en diciembre, el procurador general D. John Sauer se\u00f1al\u00f3 que el tribunal ya hab\u00eda socavado el llamado fallo Humphrey en una serie de otros casos que cuestionaban esa noci\u00f3n de agencias independientes como la Oficina de Protecci\u00f3n Financiera del Consumidor.<\/p>\n<p>\u201cEl tribunal ha repudiado el razonamiento del caso Humphrey y lo ha limitado a sus hechos\u201d, dijo Sauer a los magistrados.<\/p>\n<p>En otras palabras, que la Corte anule o no de manera expl\u00edcita el fallo Humphrey Executor este a\u00f1o podr\u00eda tener un impacto limitado. El precedente ya hab\u00eda sido debilitado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la Corte Suprema se precipitaba hacia las \u00faltimas semanas de su per\u00edodo el a\u00f1o pasado, el presidente del Tribunal Supremo, John Roberts, hizo una rara aparici\u00f3n p\u00fablica para defender a sus colegas de las cr\u00edticas de que estaban demasiado dispuestos a mandar a la basura precedentes de d\u00e9cadas. A\u00fan magullado por la ira de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473753","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mientras la Corte Suprema se precipitaba hacia las \u00faltimas semanas de su per\u00edodo el a\u00f1o pasado, el presidente del Tribunal Supremo, John Roberts, hizo una rara aparici\u00f3n p\u00fablica para defender a sus colegas de las cr\u00edticas de que estaban demasiado dispuestos a mandar a la basura precedentes de d\u00e9cadas. A\u00fan magullado por la ira de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-03T14:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed\",\"datePublished\":\"2026-05-03T14:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\"},\"wordCount\":1613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\",\"name\":\"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-03T14:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias","og_description":"Mientras la Corte Suprema se precipitaba hacia las \u00faltimas semanas de su per\u00edodo el a\u00f1o pasado, el presidente del Tribunal Supremo, John Roberts, hizo una rara aparici\u00f3n p\u00fablica para defender a sus colegas de las cr\u00edticas de que estaban demasiado dispuestos a mandar a la basura precedentes de d\u00e9cadas. A\u00fan magullado por la ira de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-03T14:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/"},"author":{"name":"","@id":""},"headline":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed","datePublished":"2026-05-03T14:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/"},"wordCount":1613,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","name":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-03T14:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\u00ed","url":"http:\/\/noticiasya.com\/boston\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2026\/05\/03\/corte-suprema-sigue-revocando-precedentes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-03T14:03:40Z","datePublished":"2026-05-03T14:03:40Z","dateModified":"2026-05-03T14:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Corte Suprema de EE.UU. sigue revocando sus propios precedentes. Jura que no es as\\u00ed\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/05\\\/03\\\/corte-suprema-sigue-revocando-precedentes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2026\\\/05\\\/03\\\/corte-suprema-sigue-revocando-precedentes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-03T14:03:40Z\",\"datePublished\":\"2026-05-03T14:03:40Z\",\"dateModified\":\"2026-05-03T14:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457145,"url":"https:\/\/noticiasya.com\/boston\/2025\/01\/02\/roberts-advierte-contra-ignorar-fallos-de-la-corte-tension-trump-trax\/","url_meta":{"origin":1473753,"position":0},"title":"Roberts advierte contra ignorar fallos de la Corte Suprema mientras se avecina tensi\u00f3n con Trump","author":"","date":"enero 2, 2025","format":false,"excerpt":"El presidente de la Corte Suprema de EE.UU., John Roberts, critic\u00f3 lo que describi\u00f3 como declaraciones \u201cpeligrosas\u201d de algunos funcionarios sobre ignorar los fallos de los tribunales federales, utilizando un informe anual semanas antes de que el presidente electo Donald Trump asuma el cargo para destacar la importancia de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471517,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/21\/john-roberts-trump-corte-suprema-trax\/","url_meta":{"origin":1473753,"position":1},"title":"John Roberts pone fin a la racha de victorias de Trump en la Corte Suprema","author":"","date":"febrero 21, 2026","format":false,"excerpt":"El presidente del Tribunal Supremo, John Roberts, aport\u00f3 dramatismo el viernes al subir al estrado del tribunal para declarar, por fin, que los aranceles del presidente Donald Trump son ilegales.Durante 10 apasionantes minutos, expuso met\u00f3dicamente los argumentos contra la emblem\u00e1tica iniciativa econ\u00f3mica de Trump, que ha generado miles de millones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457608,"url":"https:\/\/noticiasya.com\/boston\/2025\/01\/17\/conclusiones-decision-corte-suprema-tiktok-primera-enmienda-trax\/","url_meta":{"origin":1473753,"position":2},"title":"Conclusiones de la decisi\u00f3n de la Corte Suprema sobre TikTok y lo que puede significar para la Primera Enmienda","author":"","date":"enero 17, 2025","format":false,"excerpt":"La decisi\u00f3n notablemente r\u00e1pida de la Corte Suprema el viernes de permitir que una pol\u00e9mica prohibici\u00f3n de TikTok entre en vigor tendr\u00e1 un impacto enorme en las decenas de millones de estadounidenses que usan la aplicaci\u00f3n todos los d\u00edas y amplias implicaciones pol\u00edticas para el presidente electo Donald Trump.Pero la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471506,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/21\/corte-suprema-ee-uu-enfrenta-trump-aranceles-trax\/","url_meta":{"origin":1473753,"position":3},"title":"La Corte Suprema de EE.UU. se enfrenta a Trump en materia de aranceles de emergencia. Conclusiones sobre un fallo clave","author":"","date":"febrero 21, 2026","format":false,"excerpt":"La Corte Suprema de Justicia de EE.UU. anul\u00f3 este viernes los amplios aranceles de emergencia del presidente Donald Trump, una decisi\u00f3n importante que podr\u00eda reorientar el curso de la agenda econ\u00f3mica y de pol\u00edtica exterior de la administraci\u00f3n.La decisi\u00f3n de 6-3, que incluy\u00f3 a jueces tanto conservadores como liberales en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458812,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/16\/administracion-trump-primera-apelacion-corte-suprema-dellinger-trax\/","url_meta":{"origin":1473753,"position":4},"title":"Gobierno de Trump critica un &#171;ataque sin precedentes&#187; a su poder en la primera apelaci\u00f3n ante la Corte Suprema","author":"","date":"febrero 16, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump pedir\u00e1 a la Corte Suprema que le permita despedir al director de una agencia de vigilancia de la \u00e9tica gubernamental en la primera apelaci\u00f3n de su segundo mandato que llega al tribunal m\u00e1s alto del pa\u00eds.En el centro de la apelaci\u00f3n est\u00e1 Hampton Dellinger,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471631,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/25\/trump-corte-suprema-aranceles-trax\/","url_meta":{"origin":1473753,"position":5},"title":"Trump critica el &#171;fallo desafortunado&#187; de la Corte Suprema sobre aranceles mientras los jueces guardan silencio","author":"","date":"febrero 25, 2026","format":false,"excerpt":"El presidente Donald Trump utiliz\u00f3 su discurso sobre el Estado de la Uni\u00f3n el martes para criticar la decisi\u00f3n de la Corte Suprema contra sus amplios aranceles de emergencia, calificando repetidamente el fallo de \u201cdesafortunado\u201d, aunque sugiri\u00f3 que su administraci\u00f3n lo superar\u00eda r\u00e1pidamente.Con cuatro jueces sentados a escasos metros de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1473753"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1473753\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1473753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1473753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1473753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}