{"id":1443730,"date":"2024-01-15T09:33:41","date_gmt":"2024-01-15T17:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443730"},"modified":"2024-01-15T09:33:41","modified_gmt":"2024-01-15T17:33:41","slug":"quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","title":{"rendered":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional de la Esperanza, fue una sorpresa para muchos.<\/p>\n<p>Ar\u00e9valo prest\u00f3 juramento como presidente de Guatemala la madrugada de este lunes despu\u00e9s de que su toma de posesi\u00f3n se retrasara m\u00e1s de nueve horas mientras el Congreso controlado por la oposici\u00f3n debat\u00eda la admisi\u00f3n de los legisladores entrantes, quienes deb\u00edan prestar juramento ante el presidente.<\/p>\n<p>Pero \u00bfqui\u00e9n es Ar\u00e9valo? Naci\u00f3 en Montevideo, Uruguay, durante el exilio de sus padres y regres\u00f3 a Guatemala en 2013. Fue viceministro de Relaciones Exteriores y embajador en Espa\u00f1a. Es hijo del presidente Juan Jos\u00e9 Ar\u00e9valo (1945-1951) y este 20 de agosto obtuvo el 58,01% de los votos en la elecci\u00f3n para el sucesor en el cargo que ocupa actualmente Alejandro Giammattei.<\/p>\n<p>Simpatizantes de Bernardo Ar\u00e9valo festejan el resultado de las elecciones en Guatemala<\/p>\n<p>Ar\u00e9valo derrot\u00f3 a Sandra Torres, quien perdi\u00f3 el balotaje en 2015 y 2019, y quien este domingo obtuvo el 37,24% de los votos. La principal bandera del candidato ganador fue la lucha contra la corrupci\u00f3n. Solo as\u00ed, dice, podr\u00e1 llegar el desarrollo a Guatemala, pa\u00eds centroamericano con m\u00e1s de 17,6 millones de habitantes, seg\u00fan la proyecci\u00f3n para 2023 del Instituto Nacional de Estad\u00edstica.<\/p>\n<p>\u201cGuatemala se merece una nueva primavera, porque Guatemala se merece un futuro digno y para poder hacerlo hay que arrancarles las instituciones a esos corruptos\u201d, dijo Ar\u00e9valo frente a un grupo de seguidores en un acto pol\u00edtico en el municipio de Jutiapa, ubicado a unos 123 kil\u00f3metros de Ciudad de Guatemala, la capital.<\/p>\n<p>Las propuestas de Bernardo Ar\u00e9valo<\/p>\n<p>Ar\u00e9valo, doctor en filosof\u00eda y licenciado en sociolog\u00eda, dice que para generar desarrollo para las grandes mayor\u00edas en Guatemala \u201clo m\u00e1s importante\u201d es atender \u00e1reas como la salud, educaci\u00f3n, infraestructura, entre otros. Sin embargo, considera que \u201clo m\u00e1s urgente\u201d es frenar la corrupci\u00f3n, porque de lo contrario las instituciones no har\u00e1n un buen trabajo.<\/p>\n<p>&#171;T\u00edo Bernie&#187;, como lo llaman con cari\u00f1o sus seguidores, dice que desde el ejecutivo impulsar\u00e1 acciones para evitar que se mal utilicen los fondos p\u00fablicos. \u201cDesde el ejecutivo comenzar un desmontaje de las distintas formas, de la manera como se han desarrollado estos procesos de acoso a las distintas instituciones\u201d, explica en entrevista con CNN.<\/p>\n<p>Bernardo Ar\u00e9valo es el ganador de las elecciones presidenciales de Guatemala<\/p>\n<p>El candidato del partido Semilla incluso hizo p\u00fablico diez medidas que ser\u00edan implementadas para el combate a la corrupci\u00f3n, entre las que destaca la creaci\u00f3n de un \u201cGabinete Espec\u00edfico Anticorrupci\u00f3n\u201d, a cargo de formular propuestas para reformar leyes y acuerdos a fin de potenciar la transparencia.<\/p>\n<p>Las reformas incluir\u00e1n la \u201cmuerte civil\u201d a fin de que las personas que sean condenadas por actos de corrupci\u00f3n sean inhabilitadas para ejercer cargos p\u00fablicos.<\/p>\n<p>Adem\u00e1s, la creaci\u00f3n de la Comisi\u00f3n de Vigilancia Anticorrupci\u00f3n estar\u00eda integrada por funcionarios p\u00fablicos y miembros de la Sociedad civil cuya funci\u00f3n ser\u00e1 la recomendar acciones para el cumplimiento de la ley de acceso a la informaci\u00f3n, compras o contrataciones.<\/p>\n<p>En materia de seguridad, Ar\u00e9valo dice que se requieren de tres acciones puntuales y de manera inmediata: Controlar los territorios, para lo que se necesita fortalecer a la Polic\u00eda Nacional Civil y al Ej\u00e9rcito; controlar las c\u00e1rceles, algo que requiere una reforma integral que permita reducir el hacinamiento y evitar que desde su interior se ordenen extorsiones, homicidios y otros delitos.<\/p>\n<p>El tercer eje, seg\u00fan Ar\u00e9valo, es el uso de la inteligencia policial para la prevenci\u00f3n de delitos y desbaratar las bandas criminales antes de que se fortalezcan.<\/p>\n<p>El candidato del partido Movimiento Semilla dice que su plan responde a los problemas de Guatemala y prefiere no compararlo con las medidas de seguridad que implementa en El Salvador, el presidente Nayib Bukele, que asegura haber reducido los homicidios y encarcelado a m\u00e1s de 71.000 personas con el r\u00e9gimen de excepci\u00f3n, aunque eso tambi\u00e9n le ha causado fuertes cr\u00edticas por considerar que viola derechos humanos.<\/p>\n<p>El plan de gobierno tambi\u00e9n incluye las denominadas \u201cdiez semillas para recuperar el futuro\u201d que incluyen reformas para mejorar la educaci\u00f3n e infraestructura en educaci\u00f3n, salud y cultura; el fortalecimiento de las instituciones para mejorar la seguridad social de los guatemaltecos; la lucha contra la desnutrici\u00f3n, as\u00ed como el apoyo al sector agr\u00edcola o programas para emprendedores, entre otros.<\/p>\n<p>Esta noticia fue publicada originalmente el domingo 14 de enero y actualizada este lunes 15 de enero<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443730","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-15T17:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?\",\"datePublished\":\"2024-01-15T17:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\"},\"wordCount\":857,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\",\"name\":\"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-15T17:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","og_site_name":"Noticias","article_published_time":"2024-01-15T17:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","datePublished":"2024-01-15T17:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/"},"wordCount":857,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","name":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-15T17:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-15T17:33:41Z","datePublished":"2024-01-15T17:33:41Z","dateModified":"2024-01-15T17:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es y qu\\u00e9 propone Bernardo Ar\\u00e9valo, el presidente electo de Guatemala?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/15\\\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/15\\\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-15T17:33:41Z\",\"datePublished\":\"2024-01-15T17:33:41Z\",\"dateModified\":\"2024-01-15T17:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443724,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-2\/","url_meta":{"origin":1443730,"position":0},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443728,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-3\/","url_meta":{"origin":1443730,"position":1},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443691,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/14\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala\/","url_meta":{"origin":1443730,"position":2},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, gan\u00f3 en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional de la Esperanza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444036,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","url_meta":{"origin":1443730,"position":3},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444040,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-3\/","url_meta":{"origin":1443730,"position":4},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala, en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en la que fue su primera entrevista desde su toma de posesi\u00f3n, y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444043,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-4\/","url_meta":{"origin":1443730,"position":5},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala, en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en la que fue su primera entrevista desde su toma de posesi\u00f3n, y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1443730"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443730\/revisions"}],"predecessor-version":[{"id":1443748,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443730\/revisions\/1443748"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1443730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1443730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1443730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}