{"id":1443969,"date":"2024-01-16T23:33:31","date_gmt":"2024-01-17T07:33:31","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443969"},"modified":"2024-01-16T23:33:31","modified_gmt":"2024-01-17T07:33:31","slug":"presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","title":{"rendered":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d"},"content":{"rendered":"<p>(CNN) &#8212; Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds.<\/p>\n<p>En declaraciones a Christiane Amanpour de CNN el martes, el presidente de Ecuador Daniel Noboa dijo que era necesaria una \u201ccooperaci\u00f3n internacional\u201d ya que el tema es un \u201cproblema global\u201d.<\/p>\n<p>\u201cAceptar\u00eda con mucho gusto la cooperaci\u00f3n de Estados Unidos. Necesitamos equipos, necesitamos armas, necesitamos inteligencia y creo que este es un problema global. No es s\u00f3lo en Ecuador, este es un problema que va m\u00e1s all\u00e1 de las fronteras\u201d, afirm\u00f3.<\/p>\n<p>As\u00ed funciona el estado de excepci\u00f3n en Ecuador: restricciones, horarios y duraci\u00f3n<\/p>\n<p>\u201cAlrededor del 35, 40% de la droga que sale del Ecuador va a Estados Unidos y otro porcentaje similar a Europa. Por eso hay que tratar esto como un problema internacional\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Un miembro del Ej\u00e9rcito patrulla un barrio en el sur de Quito, el 12 de enero de 2024. Cr\u00e9dito: STRINGER\/AFP v\u00eda Getty Images<\/p>\n<p>El presidente Noboa dice que conf\u00eda en que Ecuador eventualmente restaurar\u00e1 la paz en todo el pa\u00eds.<\/p>\n<p>\u201cEstoy seguro de que podemos ganar esta guerra. Estoy seguro de que podemos restaurar la paz y restaurar la estabilidad en un pa\u00eds que tiene todos los recursos naturales, que tiene una econom\u00eda dolarizada estable y que podemos generar empleo y atraer inversiones en el futuro cercano\u201d, dijo Noboa.<\/p>\n<p>Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado<\/p>\n<p>Amanpour pregunt\u00f3 al mandatario ecuatoriano sobre los m\u00e1s de 40 presos escaparon de prisi\u00f3n en el norte de Ecuador. Noboa dijo que su equipo trabaja de &#171;manera ordenada&#187; para resolver el problema despu\u00e9s de haber liberado ya a 270 rehenes.<\/p>\n<p>Grupo de 48 reos se fug\u00f3 de la c\u00e1rcel Esmeraldas 2 de Ecuador; 5 fueron recapturados y uno muri\u00f3, seg\u00fan el Gobierno<\/p>\n<p>&#171;Restauramos la estabilidad en las c\u00e1rceles en este momento&#187;, dijo Noboa, y agreg\u00f3 que &#171;en este momento el ej\u00e9rcito y la polic\u00eda trabajan juntos y toda la naci\u00f3n est\u00e1 unida para eliminar esta amenaza&#187;.<\/p>\n<p>\u201cLa gente quiere la paz. La gente quiere poder caminar libremente por la calle, tener su propio negocio, tener estabilidad para que sus hijos puedan ir a los parques, ir a la escuela y tambi\u00e9n a la universidad\u201d.<\/p>\n<p>\u201cCreo que nuestra operaci\u00f3n tiene \u00e9xito en este momento. Estamos progresando y estoy seguro de que al final obtendremos una victoria total\u201d, a\u00f1adi\u00f3.<\/p>\n<p>M\u00e1s sobre la crisis en Ecuador:<\/p>\n<p>\u00bfQui\u00e9n es Fito, el pr\u00f3fugo m\u00e1s buscado de Ecuador?<br \/>\n\u00bfQui\u00e9nes son Los Lobos, la banda criminal de &#171;Capit\u00e1n Pico&#187;<br \/>\n\u00bfPor qu\u00e9 los c\u00e1rteles mexicanos est\u00e1n presentes en Ecuador?<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds. En declaraciones a Christiane Amanpour de CNN el martes, el presidente de Ecuador [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443969","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds. En declaraciones a Christiane Amanpour de CNN el martes, el presidente de Ecuador [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T07:33:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d\",\"datePublished\":\"2024-01-17T07:33:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\",\"name\":\"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-17T07:33:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias","og_description":"(CNN) &#8212; Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds. En declaraciones a Christiane Amanpour de CNN el martes, el presidente de Ecuador [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","og_site_name":"Noticias","article_published_time":"2024-01-17T07:33:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/"},"author":{"name":"","@id":""},"headline":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d","datePublished":"2024-01-17T07:33:31+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","name":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-17T07:33:31+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-17T07:33:31Z","datePublished":"2024-01-17T07:33:31Z","dateModified":"2024-01-17T07:33:31Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Presidente Noboa advierte que escalada de violencia en Ecuador \\u201ctrasciende fronteras\\u201d y requiere \\u201ccooperaci\\u00f3n internacional\\u201d\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/16\\\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/16\\\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-17T07:33:31Z\",\"datePublished\":\"2024-01-17T07:33:31Z\",\"dateModified\":\"2024-01-17T07:33:31Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443966,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional\/","url_meta":{"origin":1443969,"position":0},"title":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d","author":"","date":"enero 16, 2024","format":false,"excerpt":"(CNN) -- Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds.En declaraciones a Christiane Amanpour de CNN el martes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452732,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/09\/16\/noboa-prohibicion-bases-militares-extranjeras-ecuador-orix\/","url_meta":{"origin":1443969,"position":1},"title":"Daniel Noboa propone que se levante la prohibici\u00f3n de bases militares extranjeras en Ecuador","author":"","date":"septiembre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de Ecuador, Daniel Noboa, presentar\u00e1 un proyecto de reforma parcial a la Constituci\u00f3n para que la Asamblea Nacional modifique un art\u00edculo que proh\u00edbe \u201cla existencia de bases militares extranjeras e instalaciones con prop\u00f3sitos militares\u201d en el pa\u00eds, anunci\u00f3 este lunes el gobierno en un comunicado.A la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461241,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/04\/15\/ecuador-noboa-espera-ayuda-eeuu-combatir-criminalidad-orix\/","url_meta":{"origin":1443969,"position":2},"title":"En exclusiva con CNN, el presidente Noboa dice que espera recibir &#171;ayuda real&#187; de EE.UU. para combatir la criminalidad","author":"","date":"abril 15, 2025","format":false,"excerpt":"Daniel Noboa esperaba ganar la segunda vuelta de la elecci\u00f3n presidencial en Ecuador, pero le sorprendi\u00f3 el margen de once puntos porcentuales con el que lo hizo. \u201cNo ten\u00edamos proyectada esa diferencia, pero la campa\u00f1a y la estrategia buscaba captar mucho voto indeciso al final y, bueno, hizo efecto\u201d, afirm\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459743,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/03\/10\/noboa-ecuador-contara-fuerzas-especiales-exterior-crimen-organizado-orix\/","url_meta":{"origin":1443969,"position":3},"title":"Noboa dice que pr\u00f3ximamente Ecuador contar\u00e1 con &#171;fuerzas especiales del exterior&#187; para combatir el crimen organizado","author":"","date":"marzo 10, 2025","format":false,"excerpt":"El presidente de Ecuador, Daniel Noboa, afirm\u00f3 en una entrevista radial que el pa\u00eds contar\u00e1 en los pr\u00f3ximos d\u00edas con asistencia y apoyo internacional a trav\u00e9s de \u201cfuerzas especiales en el exterior\u201d que llegar\u00edan al pa\u00eds, seg\u00fan dijo, para unirse al combate contra el crimen organizado.\u201cPara Guayas, para Santa Elena,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460578,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/03\/29\/ecuador-trump-noboa-pandillas-trax\/","url_meta":{"origin":1443969,"position":4},"title":"Ecuador se prepara para la llegada de fuerzas estadounidenses, mientras Noboa pide ayuda para combatir las pandillas","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Ecuador est\u00e1 sentando las bases para la llegada de las fuerzas estadounidenses, seg\u00fan planes obtenidos por CNN, mientras su presidente pide al presidente de Estados Unidos, Donald Trump, que ayude a combatir las poderosas pandillas en un pa\u00eds que alguna vez fue conocido como la \u201cisla de la paz\u201d.Seg\u00fan un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463897,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/06\/24\/daniel-noboa-inversiones-china-temu-ecuador-orix\/","url_meta":{"origin":1443969,"position":5},"title":"Daniel Noboa busca inversiones en China y el posible ingreso de Temu a Ecuador. \u00bfC\u00f3mo est\u00e1n las relaciones bilaterales?","author":"","date":"junio 24, 2025","format":false,"excerpt":"Las relaciones diplom\u00e1ticas entre Ecuador y China cumplieron 45 a\u00f1os a inicios de 2025 bajo la consigna de ambos pa\u00edses de fortalecer los lazos comerciales, la confianza pol\u00edtica y la cooperaci\u00f3n.En estos d\u00edas el presidente de China, Xi Jinping y el de Ecuador, Daniel Noboa, intentan reforzar sus relaciones en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1443969"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443969\/revisions"}],"predecessor-version":[{"id":1443984,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1443969\/revisions\/1443984"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1443969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1443969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1443969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}