{"id":1444036,"date":"2024-01-18T04:33:30","date_gmt":"2024-01-18T12:33:30","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444036"},"modified":"2024-01-18T04:33:30","modified_gmt":"2024-01-18T12:33:30","slug":"bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","title":{"rendered":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.<\/p>\n<p>Durante su conversaci\u00f3n con Fernando del Rinc\u00f3n, se\u00f1al\u00f3 que &#171;el compromiso nuestro contra la corrupci\u00f3n es fundamental. Pero adem\u00e1s es fundamental porque entendemos que si no combatimos a la corrupci\u00f3n nunca vamos a lograr el desarrollo que necesita el pa\u00eds. El combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187;.<\/p>\n<p>Despu\u00e9s, en referencia al Ministerio P\u00fablico \u2013\u2013al que le ha hecho frente desde que result\u00f3 electo\u2013\u2013 y a otras instituciones a\u00f1adi\u00f3 que &#171;lo m\u00e1s importante es lograr el desarrollo, lo m\u00e1s importante es hacer que esas instituciones que han sido perdidas y convertidas en tramitadoras de negocios turbios se conviertan en instituciones que comienzan a llevar resultados concretos expresados en bienestar en las distintas \u00e1reas de la gesti\u00f3n p\u00fablica a la poblaci\u00f3n: en salud, en escuelas, en carreteras, en cr\u00e9ditos, es esa visi\u00f3n de desarrollo&#187;.<\/p>\n<p>La dif\u00edcil relaci\u00f3n de Ar\u00e9valo con el Ministerio P\u00fablico se debe a que la instituci\u00f3n ha presentado dos solicitudes para retirarle la inmunidad. La primera, por su presunta responsabilidad en promover la toma y posteriores protestas en la Universidad San Carlos; la segunda, por las posibles irregularidades en la formaci\u00f3n del partido Movimiento Semilla. Ar\u00e9valo ha rechazado ambos se\u00f1alamientos y acusado a las autoridades de promover un golpe de Estado.<\/p>\n<p>Sobre la fiscal general Consuelo Porras, quien lidera el Ministerio P\u00fablico, Ar\u00e9valo ya hab\u00eda anticipado que le pedir\u00eda la renuncia. Este mi\u00e9rcoles, en la entrevista reiter\u00f3 esa intenci\u00f3n al se\u00f1alar que citar\u00e1 a la funcionaria pr\u00f3ximamente a su despacho para &#171;pedirle la renuncia. Lo he dicho p\u00fablicamente y lo reitero. En esa cita ser\u00e1 en cuesti\u00f3n de d\u00edas le solicitar\u00e9 la renuncia. Y espero que tenga el buen sentido de entregarla&#187;.<\/p>\n<p>Bernardo Ar\u00e9valo exigir\u00e1 la renuncia de la fiscal general de Guatemala tras asumir la presidencia<\/p>\n<p>Adem\u00e1s, advirti\u00f3 que si no hay renuncia &#171;empezaremos a emprender toda acci\u00f3n legal posible dentro del marco constitucional vigente, para alcanzar la remoci\u00f3n de la fiscal&#187;. Aunque destac\u00f3 que &#171;la realidad pol\u00edtica que exist\u00eda en Guatemala y que era la que le permit\u00eda al Ministerio P\u00fablico actuar con impunidad, con abuso, hacer esa persecuci\u00f3n pol\u00edtica de cualquier forma de oposici\u00f3n y en el caso nuestro tratar de burlar el resultado electoral, esa realidad pol\u00edtica cambi\u00f3 dram\u00e1ticamente, la correlaci\u00f3n de fuerzas que hay ahora es totalmente distinta&#187;.<\/p>\n<p>Una complicada toma de posesi\u00f3n<\/p>\n<p>Bernardo Ar\u00e9valo, presidente de Guatemala, despu\u00e9s de asumir el cargo el pasado 15 de enero. (Cr\u00e9dito: JOHAN ORDONEZ\/AFP via Getty Images)<\/p>\n<p>El retraso en la toma de posesi\u00f3n de Ar\u00e9valo se debi\u00f3 a que el Congreso, controlado por la oposici\u00f3n, debati\u00f3 durante esas nueve horas la admisi\u00f3n de los legisladores entrantes, que deb\u00edan jurar antes que el presidente.<\/p>\n<p>El retraso termin\u00f3 despu\u00e9s de que los nuevos legisladores prestaran finalmente juramento y eligieran una mesa directiva del Congreso para investir formalmente al presidente.<\/p>\n<p>La legislatura tambi\u00e9n revoc\u00f3 una decisi\u00f3n del Congreso anterior que hab\u00eda designado como independientes a los miembros del partido Semilla de Ar\u00e9valo, una medida que les imped\u00eda formar parte de la junta directiva del Congreso y debilitaba el poder de Ar\u00e9valo.<\/p>\n<p>Sin embargo, dicha junta directiva electa sufri\u00f3 un rev\u00e9s momentos antes de que Ar\u00e9valo le diera su entrevista a CNN en Espa\u00f1ol. La Corte de Constitucionalidad de Guatemala resolvi\u00f3 este mi\u00e9rcoles otorgar un amparo provisional que invalida la elecci\u00f3n como presidente del Congreso al diputado Samuel P\u00e9rez, perteneciente al partido en el poder, Movimiento Semilla, argumentando una ilegalidad, seg\u00fan inform\u00f3 el \u00f3rgano en un comunicado difundido en X.<\/p>\n<p>El amparo fue solicitado por la Fundaci\u00f3n Contra el Terrorismo, una organizaci\u00f3n de extrema derecha. Ricardo M\u00e9ndez Ruiz, presidente de esa fundaci\u00f3n, argumentaba en su solicitud ante los magistrados que la elecci\u00f3n fue ilegal porque contravino una orden de la propia Corte, que hab\u00eda establecido que un diputado independiente no puede integrar la Junta Directiva del Congreso.<\/p>\n<p>Corte de Constitucionalidad de Guatemala suspende integraci\u00f3n de la Junta Directiva del Congreso<\/p>\n<p>Ante esta situaci\u00f3n, Ar\u00e9valo sostuvo en Conclusiones: &#171;La Corte de Constitucionalidad al final ha indicado que hay que repetir las elecciones (de la Junta Directiva), lo que habr\u00e1 que hacerlo en la medida en que estas resoluciones se deben acatar&#187;. Sin embargo, destac\u00f3 que &#171;lo que es importante se\u00f1alar es que lo que se ha logrado en el camino es estructurar una alianza, un acuerdo entre una serie de partidos que demostraron que tienen la capacidad y la fuerza para ganar la presidencia del Congreso. Ser\u00e1n estos mismos partidos los que participar\u00e1n en la nueva elecci\u00f3n del Congreso que ha decretado la Corte de Constitucionalidad&#187;.<\/p>\n<p>Y luego se\u00f1al\u00f3 que, &#171;independientemente de si Semilla aparece o no como miembro de la Junta Directiva o de si Samuel P\u00e9rez queda electo como presidente&#187;, hay un &#171;recurso de inconstitucionalidad&#187; ante esa corte que &#171;cuestiona la aplicaci\u00f3n de la ley de crimen organizado para el caso de las firmas y las supuestas firmas falsas que el Ministerio P\u00fablico ha inventado. Estamos seguros que cuando la Corte de Constitucionalidad d\u00e9 la resoluci\u00f3n esto va a permitir revertir todo este desprop\u00f3sito que ha hecho el Ministerio P\u00fablico y se le restablecer\u00e1n los plenos derechos a la bancada dentro del Congreso de la Rep\u00fablica&#187;.<\/p>\n<p>En su toma de posesi\u00f3n, Ar\u00e9valo sostuvo que lo que ocurre en Guatemala, como en otras partes del mundo, es la lucha contra el autoritarismo, y que su pa\u00eds est\u00e1 luchando con &#171;convicci\u00f3n y resiliencia&#187;.<\/p>\n<p>Ar\u00e9valo prometi\u00f3 impulsar acciones para generar desarrollo para las grandes mayor\u00edas en Guatemala en la salud, educaci\u00f3n, infraestructura, entre otros.<\/p>\n<p>El presidente deber\u00e1 lograr el apoyo del Congreso, un desaf\u00edo.<\/p>\n<p>Con informaci\u00f3n de Merl\u00edn Delcid<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n. Durante su conversaci\u00f3n con Fernando [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444036","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bernardo Ar\u00e9valo asegura que &quot;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&quot; en Guatemala en su primera entrevista luego de asumir como presidente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bernardo Ar\u00e9valo asegura que &quot;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&quot; en Guatemala en su primera entrevista luego de asumir como presidente - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n. Durante su conversaci\u00f3n con Fernando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T12:33:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente\",\"datePublished\":\"2024-01-18T12:33:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\"},\"wordCount\":1124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\",\"name\":\"Bernardo Ar\u00e9valo asegura que \\\"el combate a la corrupci\u00f3n es lo m\u00e1s urgente\\\" en Guatemala en su primera entrevista luego de asumir como presidente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-18T12:33:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bernardo Ar\u00e9valo asegura que \"el combate a la corrupci\u00f3n es lo m\u00e1s urgente\" en Guatemala en su primera entrevista luego de asumir como presidente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","og_locale":"es_ES","og_type":"article","og_title":"Bernardo Ar\u00e9valo asegura que \"el combate a la corrupci\u00f3n es lo m\u00e1s urgente\" en Guatemala en su primera entrevista luego de asumir como presidente - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n. Durante su conversaci\u00f3n con Fernando [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","og_site_name":"Noticias","article_published_time":"2024-01-18T12:33:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/"},"author":{"name":"","@id":""},"headline":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente","datePublished":"2024-01-18T12:33:30+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/"},"wordCount":1124,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","name":"Bernardo Ar\u00e9valo asegura que \"el combate a la corrupci\u00f3n es lo m\u00e1s urgente\" en Guatemala en su primera entrevista luego de asumir como presidente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-18T12:33:30+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-18T12:33:30Z","datePublished":"2024-01-18T12:33:30Z","dateModified":"2024-01-18T12:33:30Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bernardo Ar\\u00e9valo asegura que &#171;el combate a la corrupci\\u00f3n es lo m\\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/18\\\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/18\\\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-18T12:33:30Z\",\"datePublished\":\"2024-01-18T12:33:30Z\",\"dateModified\":\"2024-01-18T12:33:30Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444034,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente\/","url_meta":{"origin":1444036,"position":0},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en los que fue su primera entrevista desde su toma de posesi\u00f3n y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444040,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-3\/","url_meta":{"origin":1444036,"position":1},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala, en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en la que fue su primera entrevista desde su toma de posesi\u00f3n, y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444043,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/18\/bernardo-arevalo-asegura-que-el-combate-a-la-corrupcion-es-lo-mas-urgente-en-guatemala-en-su-primera-entrevista-luego-de-asumir-como-presidente-4\/","url_meta":{"origin":1444036,"position":2},"title":"Bernardo Ar\u00e9valo asegura que &#171;el combate a la corrupci\u00f3n es lo m\u00e1s urgente&#187; en Guatemala, en su primera entrevista luego de asumir como presidente","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Guatemala, Bernardo Ar\u00e9valo, quien asumi\u00f3 el cargo despu\u00e9s de un retraso de nueve horas, habl\u00f3 este mi\u00e9rcoles con CNN en Espa\u00f1ol en la que fue su primera entrevista desde su toma de posesi\u00f3n, y reiter\u00f3 la lucha que ha asumido en combatir la corrupci\u00f3n.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443724,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-2\/","url_meta":{"origin":1444036,"position":3},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443728,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-3\/","url_meta":{"origin":1444036,"position":4},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443730,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","url_meta":{"origin":1444036,"position":5},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1444036"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444036\/revisions"}],"predecessor-version":[{"id":1444052,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444036\/revisions\/1444052"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1444036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1444036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1444036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}