{"id":1444142,"date":"2024-01-19T23:33:33","date_gmt":"2024-01-20T07:33:33","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444142"},"modified":"2024-01-19T23:33:33","modified_gmt":"2024-01-20T07:33:33","slug":"biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","title":{"rendered":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes"},"content":{"rendered":"<p>(CNN) \u2013\u2013 El presidente de Estados Unidos, Joe Biden, dijo que es optimista con respecto a que la pr\u00f3xima semana surgir\u00e1 en el Senado un paquete de inmigraci\u00f3n bipartidista que, en \u00faltima instancia, podr\u00eda desbloquear el punto muerto en el que se encuentra su solicitud de financiamiento m\u00e1s amplio para ayuda a Ucrania.<\/p>\n<p>Durante sus declaraciones un grupo de alcaldes de todo el pa\u00eds en la Casa Blanca este viernes, Biden dijo que busca \u201ccambios masivos\u201d en las normas de inmigraci\u00f3n de EE.UU. El presidente ha sostenido que est\u00e1 abierto a cambios radicales en las pol\u00edticas relacionadas con la inmigraci\u00f3n para lograr que el acuerdo se apruebe. Los republicanos en el Congreso han bloqueado la solicitud de Biden de decenas de miles de millones en asistencia adicional para Ucrania mientras buscan endurecer las nuevas reglas fronterizas.<\/p>\n<p>\u201cMi equipo ha estado en la mesa durante semanas con un grupo bipartidista de senadores para negociar un acuerdo, que incluye la frontera, porque creo que necesitamos cambios pol\u00edticos significativos en la frontera, entre ellos cambios en nuestro sistema de asilo para garantizar que tengamos las autoridades que necesitamos para controlar la frontera. Y estoy listo para actuar\u201d, dijo Biden a los alcaldes.<\/p>\n<p>Sus comentarios representan la nota m\u00e1s optimista hasta el momento de que un avance en materia de inmigraci\u00f3n \u2013un tema al que Biden se ha enfrentado durante toda su presidencia\u2013 podr\u00eda ser inminente. El asunto se ha extendido al Congreso y a los presidentes \u2013dem\u00f3cratas y republicanos\u2013 durante d\u00e9cadas.<\/p>\n<p>Los alcaldes de Texas est\u00e1n hartos de las disputas por la frontera entre el presidente Biden y el gobernador Abbott<\/p>\n<p>El grupo de alcaldes estaba en Washington para la reuni\u00f3n de invierno de la Conferencia de Alcaldes de Estados Unidos. En el evento, varios alcaldes de Texas dijeron a CNN que estaban frustrados por el constante enfrentamiento entre el gobierno federal y el gobernador del estado, Greg Abbott, sobre el tema, que describieron como una verdadera crisis humanitaria.<\/p>\n<p>Si bien la migraci\u00f3n desde la frontera sur de Estados Unidos se ha desacelerado en las \u00faltimas semanas, el n\u00famero de migrantes el a\u00f1o pasado en ocasiones sobrecarg\u00f3 las ciudades fronterizas. La afluencia llev\u00f3 a Abbott a tomar medidas cada vez m\u00e1s dr\u00e1sticas. Entre ellas, la instalaci\u00f3n de alambre de p\u00faas a lo largo de la frontera y la firma de una ley que convierte la inmigraci\u00f3n ilegal en un delito estatal, usurpando la t\u00edpica autoridad federal sobre las normas de inmigraci\u00f3n y su cumplimiento.<\/p>\n<p>Biden se reuni\u00f3 este mi\u00e9rcoles con los principales l\u00edderes del Congreso para discutir el impacto que tendr\u00eda en el campo de batalla en Ucrania el hecho de que se agotara la financiaci\u00f3n estadounidense.<\/p>\n<p>El viernes, el mandatario parec\u00eda optimista de que pronto se podr\u00eda llegar a un acuerdo, al igual que los principales l\u00edderes del Congreso de ambos partidos.<\/p>\n<p>\u201cCreo que la pr\u00f3xima semana deber\u00edamos poder resolver algo, al menos en el Senado. Y tengo la esperanza de que sea un paquete bipartidista de senadores el que lo apruebe, si Dios quiere\u201d, dijo Biden.<\/p>\n<p>Y a\u00f1adi\u00f3 que la cuesti\u00f3n segu\u00eda siendo si el presidente de la C\u00e1mara de Representantes, Mike Johnson, estar\u00eda de acuerdo con el paquete.<\/p>\n<p>\u201cAhora la pregunta para el presidente y los republicanos de la C\u00e1mara: \u00bfest\u00e1n ellos tambi\u00e9n preparados para actuar? Tienen que elegir si quieren resolver un problema o seguir utilizando el tema como arma para ganar puntos pol\u00edticos contra el presidente. Estoy listo para resolver el problema\u201d, asever\u00f3 Biden.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 El presidente de Estados Unidos, Joe Biden, dijo que es optimista con respecto a que la pr\u00f3xima semana surgir\u00e1 en el Senado un paquete de inmigraci\u00f3n bipartidista que, en \u00faltima instancia, podr\u00eda desbloquear el punto muerto en el que se encuentra su solicitud de financiamiento m\u00e1s amplio para ayuda a Ucrania. Durante sus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444142","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &quot;cambios masivos&quot; en las leyes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &quot;cambios masivos&quot; en las leyes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 El presidente de Estados Unidos, Joe Biden, dijo que es optimista con respecto a que la pr\u00f3xima semana surgir\u00e1 en el Senado un paquete de inmigraci\u00f3n bipartidista que, en \u00faltima instancia, podr\u00eda desbloquear el punto muerto en el que se encuentra su solicitud de financiamiento m\u00e1s amplio para ayuda a Ucrania. Durante sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T07:33:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes\",\"datePublished\":\"2024-01-20T07:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\",\"name\":\"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca \\\"cambios masivos\\\" en las leyes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-20T07:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca \"cambios masivos\" en las leyes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","og_locale":"es_ES","og_type":"article","og_title":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca \"cambios masivos\" en las leyes - Noticias","og_description":"(CNN) \u2013\u2013 El presidente de Estados Unidos, Joe Biden, dijo que es optimista con respecto a que la pr\u00f3xima semana surgir\u00e1 en el Senado un paquete de inmigraci\u00f3n bipartidista que, en \u00faltima instancia, podr\u00eda desbloquear el punto muerto en el que se encuentra su solicitud de financiamiento m\u00e1s amplio para ayuda a Ucrania. Durante sus [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","og_site_name":"Noticias","article_published_time":"2024-01-20T07:33:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/"},"author":{"name":"","@id":""},"headline":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes","datePublished":"2024-01-20T07:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","url":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","name":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca \"cambios masivos\" en las leyes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-20T07:33:33+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Biden dice que conf\u00eda en lograr un acuerdo sobre inmigraci\u00f3n la pr\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/19\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-20T07:33:33Z","datePublished":"2024-01-20T07:33:33Z","dateModified":"2024-01-20T07:33:33Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Biden dice que conf\\u00eda en lograr un acuerdo sobre inmigraci\\u00f3n la pr\\u00f3xima semana, mientras busca &#171;cambios masivos&#187; en las leyes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/19\\\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/19\\\/biden-dice-que-confia-en-lograr-un-acuerdo-sobre-inmigracion-la-proxima-semana-mientras-busca-cambios-masivos-en-las-leyes\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-20T07:33:33Z\",\"datePublished\":\"2024-01-20T07:33:33Z\",\"dateModified\":\"2024-01-20T07:33:33Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449283,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/05\/08\/gobierno-biden-prepara-norma-rechazar-migrantes-trax\/","url_meta":{"origin":1444142,"position":0},"title":"El Gobierno de Joe Biden prepara una norma para rechazar r\u00e1pidamente a migrantes que no son elegibles para solicitar asilo","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN) --\u00a0Se prev\u00e9 que el Gobierno de Biden proponga este jueves una norma que tome medidas m\u00e1s en\u00e9rgicas contra los migrantes que no cumplen con los requisitos para solicitar asilo, seg\u00fan dos fuentes familiarizadas con el asunto. No se espera que el cambio sea radical, sino m\u00e1s bien un endurecimiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444113,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/19\/los-alcaldes-de-texas-estan-hartos-de-las-disputas-por-la-frontera-entre-el-presidente-biden-y-el-gobernador-abbott\/","url_meta":{"origin":1444142,"position":1},"title":"Los alcaldes de Texas est\u00e1n hartos de las disputas por la frontera entre el presidente Biden y el gobernador Abbott","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- Varios alcaldes de Texas dicen que est\u00e1n hartos de la hiperpolarizaci\u00f3n sobre la inmigraci\u00f3n a medida que las tensiones entre el presidente Joe Biden y el gobernador Greg Abbott contin\u00faan escalando y la frontera se convierte en un tema pol\u00edtico intratable para ambos.Los l\u00edderes de Texas que asistieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445935,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/02\/22\/biden-donantes-democratas-frontera-caos-trax\/","url_meta":{"origin":1444142,"position":2},"title":"Biden afirma a donantes dem\u00f3cratas que &#171;la frontera es un caos&#187;","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN) --\u00a0El presidente Joe Biden dijo a los donantes el jueves que \"la frontera es un caos\", mientras sigue arremetiendo contra los republicanos por frenar la legislaci\u00f3n que habr\u00eda proporcionado financiaci\u00f3n adicional y endurecido las normas de migraci\u00f3n.\"La frontera es un caos. No tienen personal\", dijo Biden a los donantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446504,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/04\/ley-inmigracion-texas-corte-suprema-biden-trax\/","url_meta":{"origin":1444142,"position":3},"title":"Gobierno de Biden pide a la Corte Suprema suspender la implementaci\u00f3n de la pol\u00e9mica ley de inmigraci\u00f3n de Texas","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El Gobierno de Biden present\u00f3 este lunes una solicitud de emergencia ante la Corte Suprema para que suspendan la implementaci\u00f3n de la controvertida ley de inmigraci\u00f3n de Texas, la cual permite a las autoridades estatales arrestar y detener a personas sospechosas de haber ingresado ilegalmente al pa\u00eds.Sin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451191,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/07\/17\/medidas-inmigracion-latinos-biden-ee-uu-trax\/","url_meta":{"origin":1444142,"position":4},"title":"Biden anunciar\u00e1 nuevas medidas sobre inmigraci\u00f3n y oportunidades educativas para los latinos en su discurso de este mi\u00e9rcoles ante Unidos","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN) --\u00a0 El presidente Joe Biden reanuda su visita de tres d\u00edas a Las Vegas con un discurso este mi\u00e9rcoles ante la mayor organizaci\u00f3n latina de defensa de los derechos civiles y continuar\u00e1 su acercamiento a este grupo demogr\u00e1fico crucial dando a conocer nuevas medidas sobre inmigraci\u00f3n y sobre la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455825,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/11\/14\/funcionarios-biden-rapida-anulacion-politicas-inmigracion-trax\/","url_meta":{"origin":1444142,"position":5},"title":"Los funcionarios de Biden se preparan para la r\u00e1pida anulaci\u00f3n de las pol\u00edticas de inmigraci\u00f3n, dejando a los inmigrantes en el limbo","author":"","date":"noviembre 14, 2024","format":false,"excerpt":"(CNN) --\u00a0Altos funcionarios del gobierno se preparan para que la administraci\u00f3n entrante de Trump deseche las pol\u00edticas de inmigraci\u00f3n establecidas bajo la presidencia de Joe Biden, muchas de las cuales pueden deshacerse con tan solo una firma, dejando a muchos inmigrantes en el limbo.M\u00faltiples funcionarios del gobierno que hablaron con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1444142"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444142\/revisions"}],"predecessor-version":[{"id":1444159,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444142\/revisions\/1444159"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1444142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1444142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1444142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}