{"id":1444168,"date":"2024-01-20T11:33:42","date_gmt":"2024-01-20T19:33:42","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444168"},"modified":"2024-01-20T11:33:42","modified_gmt":"2024-01-20T19:33:42","slug":"se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","title":{"rendered":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue"},"content":{"rendered":"<p>(CNN) &#8212; El futbolista Jordan Henderson anunci\u00f3 que regresa a Europa para fichar por el Ajax, seis meses despu\u00e9s de su pol\u00e9mico traspaso a Arabia Saud\u00ed.<\/p>\n<p>El jueves, el internacional ingl\u00e9s dijo que dejaba el club Al-Ettifaq de la Liga Profesional Saud\u00ed (SPL) &#171;con efecto inmediato&#187;, y a\u00f1adi\u00f3: &#171;No ha sido una decisi\u00f3n f\u00e1cil, pero creo que es la mejor para m\u00ed y mi familia&#187;.<\/p>\n<p>El Ajax, actualmente quinto en la Eredivisie holandesa, tambi\u00e9n confirm\u00f3 el traspaso el jueves, publicando fotos y videos de la llegada de Henderson en las cuentas de las redes sociales del club.<\/p>\n<p>&#171;Sigo queriendo rendir a un alto nivel sobre el terreno de juego y eso es lo m\u00e1s importante. Tengo que venir a rendir e intentar ayudar al equipo a tener \u00e9xito&#187;, dijo el jugador de 33 a\u00f1os en un video en X, antes Twitter.<\/p>\n<p>Un comunicado del Al-Ettifaq describi\u00f3 la decisi\u00f3n de rescindir el contrato de Henderson como &#171;amistosa&#187;, mientras que el presidente del club, Samer Al Misehal, dijo que la &#171;decisi\u00f3n r\u00e1pida, sin demora ni m\u00e1s distracciones, se ha tomado tanto por el bien general del club como por el de Jordania&#187;.<\/p>\n<p>El acuerdo de Henderson con el Al-Ettifaq era por tres a\u00f1os, seg\u00fan ESPN.<\/p>\n<p>&#171;Jordan es un buen tipo y es una pena que las cosas no hayan funcionado para \u00e9l, pero ser\u00eda el primero en admitir que se le ha dado todo el apoyo y se le ha mostrado respeto&#187;, declar\u00f3 Saad Allazeez, director general interino de la SPL.<\/p>\n<p>El traspaso de Henderson del Liverpool al Al-Ettifaq fue objeto de escrutinio dado el apoyo previo del centrocampista a los derechos LGBTQ. Henderson ha apoyado p\u00fablicamente la campa\u00f1a Rainbow Laces, respaldada por Stonewall, y ha hablado de la necesidad de apoyar &#171;hombro con hombro&#187; a quienes sufren exclusi\u00f3n.<\/p>\n<p>Pero al trasladarse a Arabia Saudita \u2014donde la actividad sexual entre personas del mismo sexo es un delito, seg\u00fan Human Rights Watch\u2014 surgieron cr\u00edticas contra Henderson por parte de grupos de la campa\u00f1a LGBTQ y de la comunidad futbol\u00edstica en general.<\/p>\n<p>Kop Outs, un grupo de aficionados LGBTQ del Liverpool, se declar\u00f3 &#171;horrorizado y preocupado&#187; por el traslado, mientras que 3LionsPride, un grupo similar de aficionados ingleses, se declar\u00f3 &#171;decepcionado&#187;.<\/p>\n<p>En una entrevista con The Athletic publicada el a\u00f1o pasado, Henderson dijo que cre\u00eda que su traslado a Arabia Saudita era &#171;algo positivo&#187;, y explic\u00f3 que comprend\u00eda la frustraci\u00f3n de la comunidad LGBTQ.<\/p>\n<p>&#171;Puedo entender el enfado. Lo entiendo&#187;, dijo. &#171;Todo lo que puedo decir al respecto es que lamento que se sientan as\u00ed. Mi intenci\u00f3n nunca, nunca fue hacer da\u00f1o a nadie&#187;.<\/p>\n<p>Henderson gan\u00f3 la Liga de Campeones y la Premier League durante sus 12 temporadas en el Liverpool antes de fichar por el Al-Ettifaq el a\u00f1o pasado, uni\u00e9ndose as\u00ed a una serie de jugadores de alto nivel \u2014como Cristiano Ronaldo, Karim Benzema y Neymar\u2014 en Arabia Saudita.<\/p>\n<p>Durante los seis meses que jug\u00f3 en el Al Ettifaq, dirigido por Steven Gerrard, gran jugador del Liverpool, disput\u00f3 17 partidos de liga. El jueves, el club anunci\u00f3 que hab\u00eda ampliado el contrato de Gerrard hasta 2027.<\/p>\n<p>Amy Woodyatt y David Close, de CNN, contribuyeron a este reporte.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El futbolista Jordan Henderson anunci\u00f3 que regresa a Europa para fichar por el Ajax, seis meses despu\u00e9s de su pol\u00e9mico traspaso a Arabia Saud\u00ed. El jueves, el internacional ingl\u00e9s dijo que dejaba el club Al-Ettifaq de la Liga Profesional Saud\u00ed (SPL) &#171;con efecto inmediato&#187;, y a\u00f1adi\u00f3: &#171;No ha sido una decisi\u00f3n f\u00e1cil, pero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444168","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El futbolista Jordan Henderson anunci\u00f3 que regresa a Europa para fichar por el Ajax, seis meses despu\u00e9s de su pol\u00e9mico traspaso a Arabia Saud\u00ed. El jueves, el internacional ingl\u00e9s dijo que dejaba el club Al-Ettifaq de la Liga Profesional Saud\u00ed (SPL) &#171;con efecto inmediato&#187;, y a\u00f1adi\u00f3: &#171;No ha sido una decisi\u00f3n f\u00e1cil, pero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T19:33:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue\",\"datePublished\":\"2024-01-20T19:33:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\",\"name\":\"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-20T19:33:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","og_locale":"es_ES","og_type":"article","og_title":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias","og_description":"(CNN) &#8212; El futbolista Jordan Henderson anunci\u00f3 que regresa a Europa para fichar por el Ajax, seis meses despu\u00e9s de su pol\u00e9mico traspaso a Arabia Saud\u00ed. El jueves, el internacional ingl\u00e9s dijo que dejaba el club Al-Ettifaq de la Liga Profesional Saud\u00ed (SPL) &#171;con efecto inmediato&#187;, y a\u00f1adi\u00f3: &#171;No ha sido una decisi\u00f3n f\u00e1cil, pero [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","og_site_name":"Noticias","article_published_time":"2024-01-20T19:33:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/"},"author":{"name":"","@id":""},"headline":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue","datePublished":"2024-01-20T19:33:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","name":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-20T19:33:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-20T19:33:42Z","datePublished":"2024-01-20T19:33:42Z","dateModified":"2024-01-20T19:33:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se uni\\u00f3 a la liga de f\\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\\u00e9s, tuvo suficiente y se fue\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/20\\\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/20\\\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-20T19:33:42Z\",\"datePublished\":\"2024-01-20T19:33:42Z\",\"dateModified\":\"2024-01-20T19:33:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444166,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/se-unio-a-la-liga-de-futbol-de-arabia-saudita-con-un-gran-contrato-seis-meses-despues-tuvo-suficiente-y-se-fue\/","url_meta":{"origin":1444168,"position":0},"title":"Se uni\u00f3 a la liga de f\u00fatbol de Arabia Saudita con un gran contrato. Seis meses despu\u00e9s, tuvo suficiente y se fue","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN) -- El futbolista Jordan Henderson anunci\u00f3 que regresa a Europa para fichar por el Ajax, seis meses despu\u00e9s de su pol\u00e9mico traspaso a Arabia Saud\u00ed.El jueves, el internacional ingl\u00e9s dijo que dejaba el club Al-Ettifaq de la Liga Profesional Saud\u00ed (SPL) \"con efecto inmediato\", y a\u00f1adi\u00f3: \"No ha sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458325,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/06\/neymar-debut-santos-regreso-club-brasileno-trax\/","url_meta":{"origin":1444168,"position":1},"title":"Neymar se qued\u00f3 sin palabras tras debutar con el Santos en su regreso al f\u00fatbol brasile\u00f1o","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Neymar dijo que se qued\u00f3 sin palabras despu\u00e9s de hacer su primera aparici\u00f3n con el Santos desde que regres\u00f3 al club brasile\u00f1o donde comenz\u00f3 su ilustre carrera.Neymar confirm\u00f3 en enero que regresaba al club de su infancia, 12 a\u00f1os despu\u00e9s de que se marchara por primera vez para unirse al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457307,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/07\/reunion-neymar-messi-suarez-futbol-trax\/","url_meta":{"origin":1444168,"position":2},"title":"Neymar insin\u00faa una posible reuni\u00f3n con Messi y Su\u00e1rez en exclusiva para CNN mientras apunta a la Copa del Mundo","author":"","date":"enero 7, 2025","format":false,"excerpt":"\u00bfPodr\u00eda estar en juego un resurgimiento de uno de los tr\u00edos m\u00e1s famosos del f\u00fatbol mundial?Durante tres temporadas, la delantera del FC Barcelona formada por Lionel Messi, Luis Su\u00e1rez y Neymar domin\u00f3 el f\u00fatbol de clubes.Forjando una era de \u00e9xito sin precedentes, la ic\u00f3nica \u201cMSN\u201d (como se la conoci\u00f3) logr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470584,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/28\/lucas-paqueta-flamengo-traspaso-record-orix\/","url_meta":{"origin":1444168,"position":3},"title":"Lucas Paquet\u00e1 regresa al Flamengo en la mayor transferencia de la historia del f\u00fatbol sudamericano","author":"","date":"enero 28, 2026","format":false,"excerpt":"Dinero m\u00e1s nostalgia m\u00e1s Mundial 2026, igual a: Brasil a la vista. Ese GPS interno es el que activ\u00f3 Lucas Paquet\u00e1, un excepcional futbolista brasile\u00f1o, para generar un tsunami financiero con su regreso al Flamengo desde el West Ham de Inglaterra. La transferencia confirmada por ambos clubes est\u00e1 valuada en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444752,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/02\/01\/el-contrato-de-servilleta-de-papel-para-sellar-el-traspaso-de-lionel-messi-al-fc-barcelona-se-subastara-con-una-oferta-inicial-de-us-380-000\/","url_meta":{"origin":1444168,"position":4},"title":"El &#8216;contrato&#8217; de servilleta de papel para sellar el traspaso de Lionel Messi al FC Barcelona se subastar\u00e1 con una oferta inicial de US$ 380.000","author":"","date":"febrero 1, 2024","format":false,"excerpt":"(CNN) -- La servilleta de papel que contiene el acuerdo por el que Lionel Messi se uni\u00f3 al FC Barcelona saldr\u00e1 a subasta con un precio inicial de US$ 380.000.La servilleta, que se firm\u00f3 para adquirir el talento de Messi, que entonces ten\u00eda 13 a\u00f1os, en 2000, ser\u00e1 vendida por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461863,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/01\/dudas-futuro-lebron-james-retiro-nba-lakers-trax\/","url_meta":{"origin":1444168,"position":5},"title":"Surgen dudas sobre el futuro de LeBron James tras el decepcionante final de la temporada de los Lakers","author":"","date":"mayo 1, 2025","format":false,"excerpt":"Los Lakers de Los \u00c1ngeles se quedan con m\u00e1s preguntas que respuestas tras su impactante eliminaci\u00f3n en la primera ronda a manos de los Timberwolves de Minnesota.A pesar de los informes de que los Lakers \u201cesperan\u201d el regreso del alero superestrella LeBron James la pr\u00f3xima temporada, a\u00fan persisten dudas sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1444168"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444168\/revisions"}],"predecessor-version":[{"id":1444184,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444168\/revisions\/1444184"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1444168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1444168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1444168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}