{"id":1444176,"date":"2024-01-20T15:33:32","date_gmt":"2024-01-20T23:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444176"},"modified":"2024-01-20T15:33:32","modified_gmt":"2024-01-20T23:33:32","slug":"estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","title":{"rendered":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza"},"content":{"rendered":"<p>Nota del editor:\u00a0Llamado a la Tierra es una serie editorial de CNN comprometida con reportar los desaf\u00edos ambientales que enfrenta nuestro planeta, adem\u00e1s de mostrar las soluciones a esos retos. La iniciativa Perpetual Planet de Rolex se ha asociado con CNN para crear conciencia y educaci\u00f3n sobre los asuntos de sostenibilidad claves y para inspirar acciones positivas.<\/p>\n<p>(CNN) &#8212; Fotos fascinantes de hormigas disparando \u00e1cido, un camar\u00f3n flotando sobre una estrella de mar con colores del arco iris y una mariposa observando la fiesta de una boda se encuentran entre las im\u00e1genes ganadoras del concurso Close-up Photographer of the Year 2023.<\/p>\n<p>La competencia, que llega a su quinta edici\u00f3n, celebra la micro y la macrofotograf\u00eda, en un esfuerzo por revelar las maravillas ocultas del mundo natural, desde hongos microsc\u00f3picos hasta animales majestuosos. Micro es el t\u00e9rmino utilizado para la fotograf\u00edas de elementos peque\u00f1os que requieren ampliaci\u00f3n, mientras que macro implica capturar im\u00e1genes en primer plano de criaturas m\u00e1s grandes.<\/p>\n<p>Este inusualmente colorido pedazo de pasto marino gan\u00f3 la categor\u00eda de microfotograf\u00e1. (Gerhard Vlcek\/cupoty.com)<\/p>\n<p>Tracy Calder, cofundadora del concurso y miembro del jurado, cont\u00f3 a CNN c\u00f3mo las fotograf\u00edas revelan interacciones inusuales entre animales y plantas, demostrando c\u00f3mo todo en el mundo natural est\u00e1 interconectado y es interdependiente. &#171;Celebran los animales y el comportamiento que la gente nunca ha visto o encontrado antes&#187;, asegur\u00f3.<\/p>\n<p>El gran premio de este a\u00f1o fue para el fot\u00f3grafo h\u00fangaro Csaba Dar\u00f3czi, por su imagen en blanco y negro de un trepador azul euroasi\u00e1tico volando a trav\u00e9s de un bosque. Tomada con una GoPro desde el interior de un tronco de un \u00e1rbol ahuecado, la impactante imagen ofrece una nueva perspectiva del p\u00e1jaro en contraste con el fondo lleno de \u00e1rboles alargados.<\/p>\n<p>La fotograf\u00eda de Csaba Dar\u00f3czi se titula &#171;El p\u00e1jaro del bosque&#187;. (cupoty.com)<\/p>\n<p>El t\u00edtulo de joven fot\u00f3grafo de primeros planos de este a\u00f1o fue para el espa\u00f1ol Carlos P\u00e9rez Naval, de 17 a\u00f1os, por su imagen de un gecko morisco en una pared cubierta de cristales de pirolusita. &#171;Estos minerales de magnesio crean formaciones impresionantes, que parecen \u00e1rboles petrificados, pero son tan peque\u00f1os que son dif\u00edciles de detectar&#187;, dijo en un comunicado de prensa.<\/p>\n<p>Carlos P\u00e9rez Naval, de 17 a\u00f1os, tom\u00f3 esta foto en Calamacha, Espa\u00f1a, el pueblo donde vive. (Carlos P\u00e9rez Naval\/cupoty.com)<\/p>\n<p>\u201cHac\u00eda mucho tiempo que quer\u00eda capturar un gecko en el \u201cbosque petrificado\u201d, pero apareci\u00f3 recientemente en mi pueblo, probablemente tra\u00eddo en cestas de frutas desde zonas m\u00e1s c\u00e1lidas. Debido al cambio clim\u00e1tico ahora pueden sobrevivir aqu\u00ed\u201d, a\u00f1adi\u00f3.<\/p>\n<p>En la categor\u00eda de plantas, la ganadora es esta fotograf\u00eda que recuerda a una pintura de Monet del reflejo de un \u00e1rbol de magnolia sobre el agua, capturada por Ria Bloemendaal. (cupoty.com)<\/p>\n<p>El jurado, conformado por 23 fot\u00f3grafos, cient\u00edficos y naturalistas, eligi\u00f3 los ganadores de cada categor\u00eda entre un total de 12.000 candidatas procedentes de 67 pa\u00edses. Muchas fueron tomadas en \u00e1reas locales de los fot\u00f3grafos, mostrando la belleza de lo que se puede observar en su propio patio trasero, asegur\u00f3 Calder.<\/p>\n<p>Hormigas carpinteras que disparan secreci\u00f3n \u00e1cida, en una fotograf\u00eda de Ren\u00e9 Krekels. (cupoty.com)<\/p>\n<p>Calder y su esposo Daniel fundaron el concurso en 2018. Ambos son fot\u00f3grafos profesionales. Si bien muchos otros premios de fotograf\u00eda cuentan con categor\u00edas de primeros planos, cre\u00edan que era necesario un concurso completo dedicado a la fotograf\u00eda macro y micro.<\/p>\n<p>&#171;Invitada a la boda&#187;, fotograf\u00eda tambi\u00e9n de Csaba Dar\u00f3czi. (cupoty.com)<\/p>\n<p>\u201cA menudo es m\u00e1s f\u00e1cil para las personas respaldar historias de conservaci\u00f3n que presentan animales y plantas \u201clindos\u201d o m\u00e1s obvios: rinocerontes, pandas, orqu\u00eddeas. Pero los insectos y plantas menos conocidos que con frecuencia consideramos plagas tienen un papel muy importante para mantener todo en equilibrio. Las fotograf\u00edas en primer plano a menudo muestran estos animales y plantas\u201d, dijo.<\/p>\n<p>Una fotograf\u00eda de un &#171;Stiphra&#187;, parte insecto y parte grillo, gan\u00f3 la categor\u00eda de invertebrados. Tomada por Tibor Molnar en Ecuador. (cupoty.com)<\/p>\n<p>\u201cTambi\u00e9n es un placer mostrarle a la gente cosas que no podr\u00edan ver sin una lente macro o un microscopio. Muchas de las criaturas y plantas que mostramos est\u00e1n a nuestro alrededor pero nunca son observadas. El concurso es una forma de darse a conocer\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Un hongo de 1 mil\u00edmetro de altura con un trozo de hielo encima gan\u00f3 en la categor\u00eda de hongos. Capturado por Barry Webb en Reino Unido. (cupoty.com)<\/p>\n<p>En la categor\u00eda de hecho por el hombre gan\u00f3 Elizabeth Kazda, que fotografi\u00f3 hilos utilizando una larga exposici\u00f3n. (cupoty.com)<\/p>\n<p>Este art\u00edculo fue publicado el 12 de enero y ha sido actualizado<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor:\u00a0Llamado a la Tierra es una serie editorial de CNN comprometida con reportar los desaf\u00edos ambientales que enfrenta nuestro planeta, adem\u00e1s de mostrar las soluciones a esos retos. La iniciativa Perpetual Planet de Rolex se ha asociado con CNN para crear conciencia y educaci\u00f3n sobre los asuntos de sostenibilidad claves y para inspirar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444176","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nota del editor:\u00a0Llamado a la Tierra es una serie editorial de CNN comprometida con reportar los desaf\u00edos ambientales que enfrenta nuestro planeta, adem\u00e1s de mostrar las soluciones a esos retos. La iniciativa Perpetual Planet de Rolex se ha asociado con CNN para crear conciencia y educaci\u00f3n sobre los asuntos de sostenibilidad claves y para inspirar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T23:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza\",\"datePublished\":\"2024-01-20T23:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\"},\"wordCount\":859,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\",\"name\":\"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-20T23:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","og_locale":"es_ES","og_type":"article","og_title":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias","og_description":"Nota del editor:\u00a0Llamado a la Tierra es una serie editorial de CNN comprometida con reportar los desaf\u00edos ambientales que enfrenta nuestro planeta, adem\u00e1s de mostrar las soluciones a esos retos. La iniciativa Perpetual Planet de Rolex se ha asociado con CNN para crear conciencia y educaci\u00f3n sobre los asuntos de sostenibilidad claves y para inspirar [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","og_site_name":"Noticias","article_published_time":"2024-01-20T23:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/"},"author":{"name":"","@id":""},"headline":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza","datePublished":"2024-01-20T23:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/"},"wordCount":859,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","name":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-20T23:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-20T23:33:32Z","datePublished":"2024-01-20T23:33:32Z","dateModified":"2024-01-20T23:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estas impactantes fotograf\\u00edas en primer plano revelan las maravillas ocultas de la naturaleza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/20\\\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/20\\\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-20T23:33:32Z\",\"datePublished\":\"2024-01-20T23:33:32Z\",\"dateModified\":\"2024-01-20T23:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451003,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/07\/10\/investigacion-cnn-airbnb-camaras-ocultas-privacidad-trax\/","url_meta":{"origin":1444176,"position":0},"title":"Conclusiones de la investigaci\u00f3n de CNN: C\u00f3mo Airbnb no protege a sus hu\u00e9spedes de las c\u00e1maras ocultas","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN) -- Desde hace a\u00f1os, Airbnb sabe que algunos de sus anfitriones utilizan c\u00e1maras ocultas para espiar en secreto a sus hu\u00e9spedes, e invaden sus momentos m\u00e1s privados e \u00edntimos. Aunque Airbnb reconoci\u00f3 repetidamente el problema en sus informes financieros, se esforz\u00f3 por mantener el alcance del problema fuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458976,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/20\/los-estrenos-en-cine-y-series-con-catalina-dlugi-en-cnn-radio\/","url_meta":{"origin":1444176,"position":1},"title":"Los estrenos en cine y series con Catalina Dlugi en CNN Radio","author":"","date":"febrero 20, 2025","format":false,"excerpt":"La reconocida periodista y columnista de CNN Radio Argentina Catalina Dlugi realiz\u00f3 este jueves sus recomendaciones sobre cine y series.Estrenos en los cinesMARIA CALLAS. El director termina con esta pel\u00edcula una trilog\u00eda. Tiene momentos esot\u00e9ricos. Mar\u00eda Callas se mete con una diva de canto l\u00edrico en la \u00faltima semana de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466526,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/16\/machu-picchu-riesgo-siete-maravillas-mundo-orix\/","url_meta":{"origin":1444176,"position":2},"title":"Machu Picchu est\u00e1 en riesgo de perder su designaci\u00f3n como una de las Nuevas Siete Maravillas del Mundo. \u00bfQu\u00e9 pas\u00f3?","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Fue en 2007 cuando se anunci\u00f3 que, tras un concurso mundial y m\u00e1s de 100 millones de votos, Machu Picchu se hab\u00eda convertido en una de las Nuevas Siete Maravillas del Mundo.Ahora, el proyecto New7Wonders, que organiz\u00f3 la votaci\u00f3n, advierte que \u201cla permanencia, justificable y cre\u00edble, de Machu Picchu\u201d en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462464,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/17\/primeros-planos-naturaleza-cte-llamado-tierra\/","url_meta":{"origin":1444176,"position":3},"title":"Los secretos (y la ferocidad) de la naturaleza a trav\u00e9s de 12 fotograf\u00edas premiadas","author":"","date":"mayo 17, 2025","format":false,"excerpt":"Dos escarabajos ciervo enfrascados en una lucha \u00e9pica por el derecho a aparearse, una viuda negra d\u00e1ndose un fest\u00edn con su \u00faltima v\u00edctima y un pez arrebatando la vida de las fauces de la muerte: estas im\u00e1genes del concurso Fot\u00f3grafo de primeros planos del a\u00f1o 2024 muestran la belleza y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464194,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/07\/03\/malas-ocultas-informe-empleo-junio-trax\/","url_meta":{"origin":1444176,"position":4},"title":"Estas son las malas noticias ocultas en el informe de empleo de junio","author":"","date":"julio 3, 2025","format":false,"excerpt":"A simple vista, el informe de empleo de junio presenta un panorama s\u00f3lido de la econom\u00eda estadounidense, con una tasa de desempleo hist\u00f3ricamente baja, una cantidad saludable de empleos creados y un crecimiento salarial que supera la inflaci\u00f3n. Sin embargo, un an\u00e1lisis m\u00e1s detallado de los datos revela aspectos negativos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447727,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/04\/increible-cascada-sagrada-angola-kalandula-trax\/","url_meta":{"origin":1444176,"position":5},"title":"La incre\u00edble cascada &#171;sagrada&#187; de Angola de la que probablemente nunca hayas o\u00eddo hablar","author":"","date":"abril 4, 2024","format":false,"excerpt":"Nota del editor: Esta serie de CNN Travel est\u00e1, o estuvo, patrocinada por el pa\u00eds que destaca. CNN retiene el control editorial total sobre los temas, reportajes y frecuencia de los art\u00edculos y videos dentro del patrocinio, en cumplimiento de nuestra pol\u00edtica.(CNN) -- \"Nadie puede decir que Dios no existe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1444176"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444176\/revisions"}],"predecessor-version":[{"id":1444191,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444176\/revisions\/1444191"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1444176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1444176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1444176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}