{"id":1444262,"date":"2024-01-22T10:33:29","date_gmt":"2024-01-22T18:33:29","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444262"},"modified":"2024-01-22T10:33:29","modified_gmt":"2024-01-22T18:33:29","slug":"guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","title":{"rendered":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido"},"content":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed<\/p>\n<p>Obuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images)<\/p>\n<p>Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en Khan Younis, Gaza, el 17 de enero. (Cr\u00e9dito: Ahmed Zakot\/Reuters)<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Obuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images) Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en Khan Younis, Gaza, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444262","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Obuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images) Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en Khan Younis, Gaza, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T18:33:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido\",\"datePublished\":\"2024-01-22T18:33:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\"},\"wordCount\":99,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\",\"name\":\"Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-22T18:33:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias","og_description":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Obuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images) Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en Khan Younis, Gaza, [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","og_site_name":"Noticias","article_published_time":"2024-01-22T18:33:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/"},"author":{"name":"","@id":""},"headline":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido","datePublished":"2024-01-22T18:33:29+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/"},"wordCount":99,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","name":"Guerra Israel - Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-22T18:33:29+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-22T18:33:29Z","datePublished":"2024-01-22T18:33:29Z","dateModified":"2024-01-22T18:33:29Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/22\\\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/01\\\/22\\\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-29\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-22T18:33:29Z\",\"datePublished\":\"2024-01-22T18:33:29Z\",\"dateModified\":\"2024-01-22T18:33:29Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444710,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-54\/","url_meta":{"origin":1444262,"position":0},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Una imagen satelital muestra las tiendas de campa\u00f1a en Khan Younis el 19 de enero. (Cr\u00e9dito: PlanetLabs)La misma zona, fotografiada el 29 de enero, ya no tiene las tiendas. (Cr\u00e9dito: PlanetLabs)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444714,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-55\/","url_meta":{"origin":1444262,"position":1},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Una imagen satelital muestra las tiendas de campa\u00f1a en Khan Younis el 19 de enero. (Cr\u00e9dito: PlanetLabs)La misma zona, fotografiada el 29 de enero, ya no tiene las tiendas. (Cr\u00e9dito: PlanetLabs)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444716,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-56\/","url_meta":{"origin":1444262,"position":2},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Una imagen satelital muestra las tiendas de campa\u00f1a en Khan Younis el 19 de enero. (Cr\u00e9dito: PlanetLabs)La misma zona, fotografiada el 29 de enero, ya no tiene las tiendas. (Cr\u00e9dito: PlanetLabs)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444265,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-30\/","url_meta":{"origin":1444262,"position":3},"title":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido","author":"","date":"enero 22, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edObuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images)Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444266,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-31\/","url_meta":{"origin":1444262,"position":4},"title":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido","author":"","date":"enero 22, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edObuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images)Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444268,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/22\/guerra-israel-hamas-en-vivo-noticias-y-ataques-en-yemen-de-ee-uu-y-reino-unido-32\/","url_meta":{"origin":1444262,"position":5},"title":"Guerra Israel &#8211; Hamas en vivo: noticias y ataques en Yemen de EE.UU. y Reino Unido","author":"","date":"enero 22, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edObuses de artiller\u00eda autopropulsados ruedan en el sur de Israel a lo largo de la frontera con la Franja de Gaza el 19 de enero. (Cr\u00e9dito: Jack Guez\/AFP\/Getty Images)Palestinos revisan las tumbas da\u00f1adas en un cementerio tras una incursi\u00f3n israel\u00ed en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1444262"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444262\/revisions"}],"predecessor-version":[{"id":1444279,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1444262\/revisions\/1444279"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1444262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1444262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1444262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}