{"id":1456600,"date":"2024-12-14T12:03:49","date_gmt":"2024-12-14T20:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/"},"modified":"2024-12-14T12:03:49","modified_gmt":"2024-12-14T20:03:49","slug":"fundador-mango-muere-accidente-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","title":{"rendered":"Fundador del gigante de la moda Mango muere en un aparente accidente"},"content":{"rendered":"<p>El fundador del gigante de la moda Mango, Isak Andic, muri\u00f3 inesperadamente en un accidente este s\u00e1bado, anunci\u00f3 la compa\u00f1\u00eda <a href=\"https:\/\/www.mangofashiongroup.com\/en\/w\/fallecimiento-isak-andic\">en un comunicado.<\/a><\/p>\n<p>Andic se desempe\u00f1aba como presidente no ejecutivo de la compa\u00f1\u00eda, seg\u00fan el comunicado firmado por el CEO de Mango, Toni Ruiz.<\/p>\n<p>\u201cDedic\u00f3 su vida a Mango, dejando una marca indeleble gracias a su visi\u00f3n estrat\u00e9gica, su liderazgo inspirador y su compromiso inquebrantable con los valores que \u00e9l mismo inculc\u00f3 en nuestra empresa\u201d, dec\u00eda el comunicado.<\/p>\n<p>La Polic\u00eda regional de Catalu\u00f1a inform\u00f3 a CNN que fueron notificados la tarde de este s\u00e1bado de que un hombre de 71 a\u00f1os hab\u00eda ca\u00eddo por un barranco de m\u00e1s de 320 pies (unos 97.5 metros) en la zona de las cuevas de Salnitre en Collbat\u00f3, un popular destino tur\u00edstico cerca de Barcelona.<\/p>\n<p>Una fuente en Catalu\u00f1a con conocimiento de los hechos declar\u00f3 a CNN que la v\u00edctima era Isak Andic.<\/p>\n<p>Unidades policiales fueron desplegadas a las cuevas y pudieron recuperar el cuerpo, a\u00f1adi\u00f3 la Polic\u00eda.<\/p>\n<p>El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, reaccion\u00f3 a la muerte de Andic, diciendo: \u201cTodo mi cari\u00f1o y reconocimiento por tu gran trabajo y visi\u00f3n empresarial, que ha convertido esta marca espa\u00f1ola en un referente mundial en moda\u201d, <a href=\"https:\/\/x.com\/sanchezcastejon\/status\/1867982142283882632\">escribi\u00f3 S\u00e1nchez en X.<\/a><\/p>\n<p>El presidente regional de Catalu\u00f1a, Salvador Illa, escribi\u00f3 en X que Andic hab\u00eda dejado \u201cuna marca indeleble en el sector de la moda catal\u00e1n y global\u201d, y elogi\u00f3 su trabajo por contribuir a \u201chacer grande a Catalu\u00f1a y proyectarla al mundo\u201d.<\/p>\n<p>Andic ten\u00eda un patrimonio neto de US$ 4.500 millones,<a href=\"https:\/\/www.forbes.com\/profile\/isak-andic\/\"> seg\u00fan Forbes.<\/a> Fund\u00f3 la marca Mango en Barcelona, Espa\u00f1a, en 1984.<\/p>\n<p>Mango es uno de los principales grupos de moda de Europa, de acuerdo con el sitio web de la compa\u00f1\u00eda, con tiendas en m\u00e1s de 120 mercados. En 2023, las ventas de la compa\u00f1\u00eda superaron los US$ 3.200 millones.<\/p>\n<p>La compa\u00f1\u00eda actualmente opera 40 tiendas en EE.UU. y planea abrir 20 m\u00e1s el pr\u00f3ximo a\u00f1o, seg\u00fan el sitio web de Mango.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fundador del gigante de la moda Mango, Isak Andic, muri\u00f3 inesperadamente en un accidente este s\u00e1bado, anunci\u00f3 la compa\u00f1\u00eda en un comunicado. Andic se desempe\u00f1aba como presidente no ejecutivo de la compa\u00f1\u00eda, seg\u00fan el comunicado firmado por el CEO de Mango, Toni Ruiz. \u201cDedic\u00f3 su vida a Mango, dejando una marca indeleble gracias a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456600","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias\" \/>\n<meta property=\"og:description\" content=\"El fundador del gigante de la moda Mango, Isak Andic, muri\u00f3 inesperadamente en un accidente este s\u00e1bado, anunci\u00f3 la compa\u00f1\u00eda en un comunicado. Andic se desempe\u00f1aba como presidente no ejecutivo de la compa\u00f1\u00eda, seg\u00fan el comunicado firmado por el CEO de Mango, Toni Ruiz. \u201cDedic\u00f3 su vida a Mango, dejando una marca indeleble gracias a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T20:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fundador del gigante de la moda Mango muere en un aparente accidente\",\"datePublished\":\"2024-12-14T20:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\"},\"wordCount\":389,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\",\"name\":\"Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T20:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundador del gigante de la moda Mango muere en un aparente accidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias","og_description":"El fundador del gigante de la moda Mango, Isak Andic, muri\u00f3 inesperadamente en un accidente este s\u00e1bado, anunci\u00f3 la compa\u00f1\u00eda en un comunicado. Andic se desempe\u00f1aba como presidente no ejecutivo de la compa\u00f1\u00eda, seg\u00fan el comunicado firmado por el CEO de Mango, Toni Ruiz. \u201cDedic\u00f3 su vida a Mango, dejando una marca indeleble gracias a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T20:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/"},"author":{"name":"","@id":""},"headline":"Fundador del gigante de la moda Mango muere en un aparente accidente","datePublished":"2024-12-14T20:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/"},"wordCount":389,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","name":"Fundador del gigante de la moda Mango muere en un aparente accidente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T20:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fundador del gigante de la moda Mango muere en un aparente accidente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fundador del gigante de la moda Mango muere en un aparente accidente","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/14\/fundador-mango-muere-accidente-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T20:03:49Z","datePublished":"2024-12-14T20:03:49Z","dateModified":"2024-12-14T20:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fundador del gigante de la moda Mango muere en un aparente accidente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/14\\\/fundador-mango-muere-accidente-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/14\\\/fundador-mango-muere-accidente-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T20:03:49Z\",\"datePublished\":\"2024-12-14T20:03:49Z\",\"dateModified\":\"2024-12-14T20:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450669,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","url_meta":{"origin":1456600,"position":0},"title":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, anunci\u00f3 este lunes que llegaron a un acuerdo con las autoridades de Estados Unidos para implementar un modelo para proteger la labor de los inspectores de sanidad agr\u00edcola que certifican el aguacate y mango de exportaci\u00f3n a ese pa\u00eds, suspendida durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452422,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/09\/04\/muere-ciudadana-mexicana-accidente-cataluna-orix\/","url_meta":{"origin":1456600,"position":1},"title":"Muere ciudadana mexicana en un accidente en Catalu\u00f1a","author":"","date":"septiembre 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una ciudadana mexicana falleci\u00f3 el lunes en la localidad de Tossa de Mar, Catalu\u00f1a, Espa\u00f1a, inform\u00f3 la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico este martes a trav\u00e9s de un comunicado.La Secretar\u00eda agreg\u00f3 que, la polic\u00eda local de Tossa de Mar fue quien notific\u00f3 al Consulado de M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448227,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/17\/arroz-glutinoso-mango-verano-tailandia-trax\/","url_meta":{"origin":1456600,"position":2},"title":"\u00bfPor qu\u00e9 el arroz glutinoso con mango es uno de los platos veraniegos m\u00e1s aclamados en Tailandia?","author":"","date":"abril 17, 2024","format":false,"excerpt":"Nota del editor: esta serie de viajes de CNN est\u00e1, o estuvo, patrocinada por el pa\u00eds que destaca. CNN conserva el control editorial total sobre el tema, los informes y la frecuencia de los art\u00edculos y videos patrocinados, en conformidad con nuestra pol\u00edtica.Bangkok (CNN) -- Se dice que en Tailandia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470303,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","url_meta":{"origin":1456600,"position":3},"title":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a","author":"","date":"enero 20, 2026","format":false,"excerpt":"Al menos una persona muri\u00f3 y 20 resultaron heridas este martes a causa del descarrilamiento de un tren de cercan\u00edas en Catalu\u00f1a, en el noroeste de Espa\u00f1a, confirm\u00f3 a CNN un portavoz de la Generalitat.El accidente involucr\u00f3 a un convoy de la l\u00ednea R4 del servicio de cercan\u00edas (llamado Rodalies\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451683,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/08\/08\/dispositivo-policial-encontrar-carles-puigdemont-orix\/","url_meta":{"origin":1456600,"position":4},"title":"Despliegan un dispositivo policial para encontrar a Carles Puigdemont, que se encuentra en paradero desconocido","author":"","date":"agosto 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de la Generalitat de Catalu\u00f1a Carles Puigdemont ha vuelto a desaparecer del espacio p\u00fablico tras hacer una breve aparici\u00f3n en Barcelona a primera hora de la ma\u00f1ana en un acto preparado por la formaci\u00f3n que lidera, Junts per Catalunya.Ante la expectativa que generaba su llegada,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449385,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/05\/10\/elecciones-cataluna-2024-que-hay-en-juego-orix\/","url_meta":{"origin":1456600,"position":5},"title":"Elecciones en Catalu\u00f1a 2024: \u00bfqu\u00e9 hay en juego y por qu\u00e9 son importantes en Espa\u00f1a?","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este domingo, m\u00e1s de 5,7 millones de personas est\u00e1n llamadas a acudir a las urnas para participar en las elecciones al Parlamento de Catalu\u00f1a, en la que los electores escoger\u00e1n a los 135 miembros de esta c\u00e1mara auton\u00f3mica.Para atraer la simpat\u00eda de los votantes, las diferentes formaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456600"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456600\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}