{"id":1456654,"date":"2024-12-16T10:03:48","date_gmt":"2024-12-16T18:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/"},"modified":"2024-12-16T10:03:48","modified_gmt":"2024-12-16T18:03:48","slug":"scholz-perdio-voto-confianza-alemania-que-sigue-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","title":{"rendered":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue"},"content":{"rendered":"<p>Alemania, la mayor econom\u00eda de Europa y normalmente un pilar de estabilidad, se enfrentar\u00e1 a unas <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/12\/alemania-elecciones-anticipadas-febrero-trax\">elecciones anticipadas el pr\u00f3ximo a\u00f1o<\/a> despu\u00e9s de que el canciller del pa\u00eds, Olaf Scholz, perdiera una votaci\u00f3n de confianza.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/07\/olaf-scholz-canciller-alemania-coalicion-colpaso-trax\">Su gobierno colaps\u00f3<\/a> en noviembre por una disputa presupuestaria, pero su coalici\u00f3n llevaba meses tambale\u00e1ndose.<\/p>\n<p>Scholz perdi\u00f3 la votaci\u00f3n, que \u00e9l mismo convoc\u00f3 como un paso para asegurar unas elecciones nacionales anticipadas, con 394 papeletas en su contra, 207 a su favor y 116 abstenciones.<\/p>\n<p>Con la fecha de las elecciones fijada para el 23 de febrero de 2025, esto es lo que est\u00e1 en juego.<\/p>\n<p>Habr\u00e1 siete grandes partidos por los que votar\u00e1n los alemanes. Cuatro de ellos ya anunciaron oficialmente sus <em>Kanzlerkandidaten<\/em> (candidatos a canciller).<\/p>\n<p>Los dos partidos dominantes de la pol\u00edtica alemana, la Uni\u00f3n Dem\u00f3crata Cristiana (CDU) y la Uni\u00f3n Social Cristiana (CSU), conocidos extraoficialmente como la Uni\u00f3n, forman una agrupaci\u00f3n. Los socialdem\u00f3cratas, o SPD, forman otra.<\/p>\n<p>Dado el sistema alem\u00e1n de representaci\u00f3n proporcional, el gobierno tiende a formarse en coalici\u00f3n, normalmente encabezada por la CDU\/CSU o el SPD.<\/p>\n<p>El ganador busca un socio para formar mayor\u00eda. Desde 2021, el SPD de Scholz gobern\u00f3 en una inc\u00f3moda coalici\u00f3n con el liberal Partido de los Dem\u00f3cratas Libres (FDP) y el Partido Verde. En los 16 a\u00f1os anteriores a la coalici\u00f3n tripartita de Scholz, la CDU, encabezada por Angela Merkel, cont\u00f3 tanto con el SPD como con el FDP como socios en diferentes gobiernos.<\/p>\n<p>En esta ocasi\u00f3n, la CDU\/CSU estar\u00e1 dirigida por Friedrich Merz, y el SPD por Scholz, canciller en funciones pero profundamente impopular.<\/p>\n<p>El partido de extrema derecha <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/09\/02\/afd-gana-elecciones-estatales-alemania-extrema-derecha-trax\">Alternativa para Alemania<\/a> (AfD) vio c\u00f3mo sus buenos resultados en las elecciones regionales le daban un impulso nacional. Alice Weidel, col\u00edder del partido, es su candidata a la Canciller\u00eda. Es conocida por su discurso ingenioso y sus pol\u00edticas populistas, sobre todo en materia de inmigraci\u00f3n. Es una ferviente defensora de la conservaci\u00f3n de los valores tradicionales alemanes, y es famosa por su frase \u201c\u00a1que nadie toque mi schnitzel!\u201d, una referencia al popular plato.<\/p>\n<p>Tambi\u00e9n hay que tener en cuenta al Partido Verde. Es poco probable que re\u00fana suficientes votos para ser el partido m\u00e1s grande, pero podr\u00eda desempe\u00f1ar un papel importante en la formaci\u00f3n del pr\u00f3ximo gobierno. Los verdes estar\u00e1n liderados por Robert Habeck, actual ministro de Econom\u00eda de la naci\u00f3n.<\/p>\n<p>Los otros tres grandes partidos ser\u00e1n los Dem\u00f3cratas Libres; el BSW, un grupo socialista de izquierdas que lleva el nombre de su l\u00edder, Sahra Wagenknecht; y por \u00faltimo Die Linke, un partido pol\u00edtico de izquierdas. Los tres a\u00fan no anunciaron oficialmente a sus candidatos.<\/p>\n<p>Salvo un giro inesperado en las encuestas, Merz, de la CDU\/CSU, tiene muchas probabilidades de ser el nuevo canciller de Alemania.<\/p>\n<p><a href=\"https:\/\/www.infratest-dimap.de\/umfragen-analysen\/bundesweit\/sonntagsfrage\/\">Los sondeos nacionales<\/a> sit\u00faan actualmente a la CDU\/CSU muy por delante de los dem\u00e1s, con un 32% de apoyo de los encuestados. La AfD se sit\u00faa en segundo lugar con un 18%, el SPD en tercero con un 16% y el Partido Verde con un 14%.<\/p>\n<p>Merz no es un reci\u00e9n llegado a la pol\u00edtica alemana, pero esta es su segunda etapa como pol\u00edtico.<\/p>\n<p>Entre 1989 y 1994, Merz fue diputado del Parlamento Europeo (MEP) por Alemania. Posteriormente fue miembro del Bundestag (Parlamento alem\u00e1n) donde represent\u00f3 a la CDU hasta 2009. Despu\u00e9s dej\u00f3 la pol\u00edtica para trabajar como abogado de empresa, donde form\u00f3 parte de numerosos consejos de supervisi\u00f3n, incluido el del gigante de la inversi\u00f3n BlackRock.<\/p>\n<p>Merz representa en el Bundestag a la circunscripci\u00f3n de Hochsauerlandkreis, la regi\u00f3n en la que naci\u00f3, y actualmente vive en Brilon, su ciudad natal. Tambi\u00e9n tiene fama de ser millonario y posee licencia de piloto privado.<\/p>\n<p>Merz hizo dos intentos fallidos de convertirse en l\u00edder de la CDU en 2018 y 2020. En 2021 regres\u00f3 como diputado al Bundestag, por primera vez en 12 a\u00f1os, y posteriormente consigui\u00f3 el nombramiento como jefe de la CDU, asumiendo oficialmente el cargo en septiembre de 2022.<\/p>\n<p>Es conocido por haber dado un giro a la CDU hacia la derecha, con una postura m\u00e1s dura en materia de inmigraci\u00f3n y una fuerte mentalidad econ\u00f3mica. Durante su campa\u00f1a para convertirse en l\u00edder del partido, defendi\u00f3 no ser un heredero del estilo de Merkel, a diferencia de sus contrincantes, marcando as\u00ed el fin de las pol\u00edticas centristas de la CDU durante su etapa como canciller.<\/p>\n<p>Leonie von Randow, reportera pol\u00edtica de la cadena alemana WELT TV que cubrir\u00e1 la campa\u00f1a electoral, dijo a CNN que Merz \u201csabe un par de cosas sobre econom\u00eda, y eso es algo que obviamente preocupa a mucha gente. Mucha gente espera que pueda hacer avanzar las cosas\u201d.<\/p>\n<p>Merz es un firme partidario de apoyar a Ucrania en su lucha contra la invasi\u00f3n a gran escala de Rusia. Ha sido un firme partidario de suministrar a Ucrania misiles Taurus de fabricaci\u00f3n alemana, armas que podr\u00edan utilizarse para atacar objetivos rusos mucho <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/19\/que-son-misiles-atacms-ucrania-rusia-orix\">m\u00e1s all\u00e1 de las l\u00edneas del frente ucraniano<\/a>. Scholz, por el contrario, se ha negado sistem\u00e1ticamente a suministrarlos a Kyiv.<\/p>\n<p>Merz viaj\u00f3 por sorpresa a la capital ucraniana anteriormente este mes, donde inst\u00f3 a las naciones europeas a formar una \u201cvisi\u00f3n com\u00fan\u201d para la paz en Ucrania, especialmente ante la inminente llegada a la Casa Blanca del presidente electo de Estados Unidos, Donald Trump.<\/p>\n<p>La econom\u00eda va a desempe\u00f1ar un papel central en las elecciones, sobre todo teniendo en cuenta sus flojos resultados bajo el mandato de Scholz.<\/p>\n<p>En los \u00faltimos d\u00edas, el Banco Central alem\u00e1n <a href=\"https:\/\/publikationen.bundesbank.de\/publikationen-en\/reports-studies\/monthly-reports\/monthly-report-december-2024-947276?article=forecast--947278\">revis\u00f3<\/a> a la baja las previsiones de crecimiento en un 0,2%, afirmando que \u201cla econom\u00eda alemana se estancar\u00e1 en el semestre de invierno de 2024-25 y solo empezar\u00e1 a recuperarse lentamente a lo largo de 2025\u201d.<\/p>\n<p>En relaci\u00f3n con el debate sobre la econom\u00eda, se prestar\u00e1 especial atenci\u00f3n a la reactivaci\u00f3n de la importante industria automovil\u00edstica del pa\u00eds. El Banco Central dijo que los problemas de la industria son \u201cestructurales\u201d y, por tanto, est\u00e1n agravando el lastre de la econom\u00eda.<\/p>\n<p>Grandes empresas como Volkswagen, uno de los mayores fabricantes de autom\u00f3viles del mundo, se enfrentan a <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/01\/problemas-volkswagen-trabajadores-huelgas-alemania-trax\">importantes despidos y cierres de f\u00e1bricas<\/a>.<\/p>\n<p>Los argumentos sobre la inmigraci\u00f3n tambi\u00e9n ser\u00e1n cruciales en estas elecciones, en especial porque los partidos buscan arrebatar votos a una AfD en auge, que lo convirti\u00f3 en uno de sus temas centrales.<\/p>\n<p>\u201cLas elecciones llegan probablemente en un momento muy bueno para la AfD\u2026 Es un momento en el que mucha gente est\u00e1 en general muy descontenta con el Gobierno, as\u00ed que quieren demostrar su descontento votando a un partido extremista\u201d, dijo von Randow a CNN.<\/p>\n<p>En los \u00faltimos meses, Scholz <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/09\/22\/adios-cultura-bienvenida-alemania-cede-presion-extrema-derecha-estrecha-fronteras-trax\">volvi\u00f3 a introducir controles en las fronteras<\/a> con las naciones europeas vecinas, una medida que muchos vieron como un intento de ganarse el favor de los votantes que podr\u00edan estar volvi\u00e9ndose hacia el partido populista AfD.<\/p>\n<p>La ca\u00edda del r\u00e9gimen de Assad en Siria tambi\u00e9n influir\u00e1 en el debate nacional. Alemania acogi\u00f3 a m\u00e1s inmigrantes sirios que cualquier otra naci\u00f3n europea durante su guerra civil. Ya comenz\u00f3 la campa\u00f1a en torno a c\u00f3mo manejar\u00eda cada partido a los inmigrantes.<\/p>\n<p>Es muy dif\u00edcil prever un resultado en el que la CDU\/CSU y Friedrich Merz no salgan victoriosos.<\/p>\n<p>Su ventaja parece consolidada e indiscutible, pero la principal inc\u00f3gnita gira en torno a la formaci\u00f3n de un gobierno estable. Es poco probable que la CDU\/CSU consiga la mayor\u00eda absoluta de los 630 esca\u00f1os en juego. Eso significa que tendr\u00e1n que formar una coalici\u00f3n con uno (o m\u00e1s) de los otros partidos. La pregunta es \u00bfcon qui\u00e9n?<\/p>\n<p>Si la AfD obtuviera los resultados que sugieren las encuestas, supondr\u00eda un cambio radical en la pol\u00edtica alemana. Desde su formaci\u00f3n en 2013, el partido nunca ha obtenido m\u00e1s de 94 esca\u00f1os. Fue el quinto partido m\u00e1s grande en 2021 y el tercero en 2017.<\/p>\n<p>Mientras que la AfD se ve a s\u00ed misma como potencial impulsora de l\u00edderes, la CDU\/CSU puede no estar dispuesta a darles una voz tan prominente en la gesti\u00f3n del pa\u00eds.<\/p>\n<p>Queda el SPD, con el que ya trabajaron anteriormente, sobre todo en la era Merkel. O podr\u00edan mirar m\u00e1s a la izquierda, hacia el Partido Verde, pero eso tambi\u00e9n podr\u00eda suponer un choque de principios y pol\u00edticas, dada su naturaleza m\u00e1s izquierdista.<\/p>\n<p>En cualquier caso, es probable que las elecciones federales dejen al SPD y a Scholz profundamente humillados, y que entren en un periodo de autorreflexi\u00f3n. \u201cProbablemente sea el final de su carrera pol\u00edtica\u201d, dijo von Randow a CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alemania, la mayor econom\u00eda de Europa y normalmente un pilar de estabilidad, se enfrentar\u00e1 a unas elecciones anticipadas el pr\u00f3ximo a\u00f1o despu\u00e9s de que el canciller del pa\u00eds, Olaf Scholz, perdiera una votaci\u00f3n de confianza. Su gobierno colaps\u00f3 en noviembre por una disputa presupuestaria, pero su coalici\u00f3n llevaba meses tambale\u00e1ndose. Scholz perdi\u00f3 la votaci\u00f3n, que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456654","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias\" \/>\n<meta property=\"og:description\" content=\"Alemania, la mayor econom\u00eda de Europa y normalmente un pilar de estabilidad, se enfrentar\u00e1 a unas elecciones anticipadas el pr\u00f3ximo a\u00f1o despu\u00e9s de que el canciller del pa\u00eds, Olaf Scholz, perdiera una votaci\u00f3n de confianza. Su gobierno colaps\u00f3 en noviembre por una disputa presupuestaria, pero su coalici\u00f3n llevaba meses tambale\u00e1ndose. Scholz perdi\u00f3 la votaci\u00f3n, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T18:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue\",\"datePublished\":\"2024-12-16T18:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\"},\"wordCount\":1545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\",\"name\":\"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T18:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias","og_description":"Alemania, la mayor econom\u00eda de Europa y normalmente un pilar de estabilidad, se enfrentar\u00e1 a unas elecciones anticipadas el pr\u00f3ximo a\u00f1o despu\u00e9s de que el canciller del pa\u00eds, Olaf Scholz, perdiera una votaci\u00f3n de confianza. Su gobierno colaps\u00f3 en noviembre por una disputa presupuestaria, pero su coalici\u00f3n llevaba meses tambale\u00e1ndose. Scholz perdi\u00f3 la votaci\u00f3n, que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-16T18:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/"},"author":{"name":"","@id":""},"headline":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue","datePublished":"2024-12-16T18:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/"},"wordCount":1545,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","name":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T18:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El canciller Olaf Scholz perdi\u00f3 el voto de confianza en Alemania. Esto es lo que sigue","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T18:03:48Z","datePublished":"2024-12-16T18:03:48Z","dateModified":"2024-12-16T18:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El canciller Olaf Scholz perdi\\u00f3 el voto de confianza en Alemania. Esto es lo que sigue\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/16\\\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/16\\\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T18:03:48Z\",\"datePublished\":\"2024-12-16T18:03:48Z\",\"dateModified\":\"2024-12-16T18:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455631,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/11\/07\/olaf-scholz-canciller-alemania-coalicion-colpaso-trax\/","url_meta":{"origin":1456654,"position":0},"title":"El canciller alem\u00e1n Olaf Scholz despidi\u00f3 a su ministro de Finanzas y la coalici\u00f3n de gobierno colaps\u00f3. Esto es lo que puede pasar ahora","author":"","date":"noviembre 7, 2024","format":false,"excerpt":"(CNN) -- La coalici\u00f3n gobernante de Alemania ha colapsado despu\u00e9s de desacuerdos sobre la d\u00e9bil econom\u00eda del pa\u00eds que llevaron al canciller Olaf Scholz a despedir a su ministro de Finanzas.El despido de Christian Lindner lo llev\u00f3 a retirar su Partido de los Dem\u00f3cratas Libres (FDP) de una coalici\u00f3n con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459066,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/22\/alemania-elecciones-nacionales-europa-trax\/","url_meta":{"origin":1456654,"position":1},"title":"Alemania celebra elecciones nacionales. Esto es lo que est\u00e1 en juego","author":"","date":"febrero 22, 2025","format":false,"excerpt":"Los alemanes acuden a las urnas este domingo en las elecciones nacionales. Los sondeos de opini\u00f3n sugieren que el resultado ser\u00e1 probablemente un nuevo canciller y una nueva coalici\u00f3n de gobierno.Esta campa\u00f1a electoral, que suele ser \u00e1rida y predecible, ha sido, en comparaci\u00f3n, muy agitada.El pasado noviembre, el canciller Olaf\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457977,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/28\/elon-musk-partidos-derecha-canciller-alemania-trax\/","url_meta":{"origin":1456654,"position":2},"title":"El apoyo de Elon Musk a los partidos de derecha &#171;es realmente repugnante&#187;, dice el canciller de Alemania a CNN","author":"","date":"enero 28, 2025","format":false,"excerpt":"El canciller de Alemania, Olaf Scholz, aprovech\u00f3 una oportunidad en la campa\u00f1a electoral de este martes para criticar a Elon Musk, diciendo a CNN que el multimillonario estadounidense \u201cest\u00e1 interviniendo a favor de pol\u00edticos de derecha en toda Europa. Y esto es realmente repugnante\u201d.Antes de las elecciones de febrero en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459108,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/23\/resultados-elecciones-alemania-friedrich-merz-conservadores-ultraderecha-trax\/","url_meta":{"origin":1456654,"position":3},"title":"Friedrich Merz reivindica la victoria de los conservadores alemanes y ser\u00eda el pr\u00f3ximo canciller","author":"","date":"febrero 23, 2025","format":false,"excerpt":"La Uni\u00f3n Dem\u00f3crata Cristiana (CDU) de centroderecha de Alemania est\u00e1 lista para volver al poder con la ultraderechista Alternativa para Alemania como segundo partido m\u00e1s grande, seg\u00fan muestran las encuestas de salida, despu\u00e9s de unas elecciones anticipadas dominadas por las preocupaciones sobre la inmigraci\u00f3n, la econom\u00eda y el regreso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462038,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/06\/friedrich-merz-nombrado-canciller-aleman-trax\/","url_meta":{"origin":1456654,"position":4},"title":"Friedrich Merz nombrado canciller de Alemania tras ganar la votaci\u00f3n parlamentaria en su segundo intento","author":"","date":"mayo 6, 2025","format":false,"excerpt":"El alem\u00e1n Friedrich Merz se convirti\u00f3 formalmente en canciller tras la aprobaci\u00f3n de su nombramiento por parte del presidente. Ahora se trasladar\u00e1 al Bundestag para prestar juramento.Merz fue elegido canciller en una segunda votaci\u00f3n parlamentaria, horas despu\u00e9s de una derrota sin precedentes que evidenci\u00f3 un profundo descontento dentro de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457076,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/30\/alemania-acusa-elon-musk-influir-elecciones-trax\/","url_meta":{"origin":1456654,"position":5},"title":"Alemania acusa a Elon Musk de intentar influir en sus elecciones","author":"","date":"diciembre 30, 2024","format":false,"excerpt":"El Gobierno de Alemania acus\u00f3 este lunes al multimillonario estadounidense Elon Musk de intentar influir en sus elecciones previstas para febrero con art\u00edculos de apoyo al partido de extrema derecha Alternativa para Alemania (AfD), aunque sugiri\u00f3 que equival\u00edan a \u201ctonter\u00edas\u201d.Musk, que est\u00e1 listo para servir al nuevo Gobierno de Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456654"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456654\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}