{"id":1456658,"date":"2024-12-16T10:03:48","date_gmt":"2024-12-16T18:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/"},"modified":"2024-12-16T10:03:48","modified_gmt":"2024-12-16T18:03:48","slug":"el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","title":{"rendered":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000"},"content":{"rendered":"<p>Hace dos a\u00f1os, Elizabeth Grantham decidi\u00f3 que no quer\u00eda seguir alquilando mucho m\u00e1s tiempo, as\u00ed que se mud\u00f3 de su ciudad natal, en la costosa zona de la bah\u00eda de San Francisco, al estado de Washington, para ahorrar y comprar una casa<\/p>\n<p>\u201cCada a\u00f1o nos sub\u00edan el alquiler. Incluso sub\u00eda el precio del aparcamiento en nuestro complejo de apartamentos\u201d, declar\u00f3 recientemente Grantham, de 31 a\u00f1os, a CNN. \u201cLuego, con el tiempo, te mudas y pronto ese alquiler empieza a subir. As\u00ed ha sido durante la mayor parte de mi vida adulta\u201d.<\/p>\n<p>La historia del mercado de la vivienda en los \u00faltimos a\u00f1os se ha caracterizado por una creciente divisi\u00f3n entre \u201clos que tienen\u201d y \u201clos que no tienen\u201d, los que alquilan y los que son propietarios de una vivienda. Los propietarios de vivienda han visto c\u00f3mo su riqueza se disparaba a medida que<a href=\"https:\/\/www.cnn.com\/2024\/11\/13\/economy\/home-buyer-salary-household-income\/index.html\"> los precios de la vivienda sub\u00edan por todo el pa\u00eds<\/a>. Al mismo tiempo, tras un ligero descenso de los alquileres despu\u00e9s del inicio de la pandemia de covid-19, los alquileres tambi\u00e9n se han disparado, mermando los ahorros de muchas personas.<\/p>\n<p>Un informe reciente del Aspen Institute pone de relieve el enorme abismo de riqueza que se ha formado entre los propietarios de viviendas y los inquilinos en Estados Unidos. El propietario medio de una vivienda en Estados Unidos ten\u00eda un patrimonio neto de US$ 400.000 en 2022, los datos m\u00e1s recientes disponibles, mientras que el patrimonio neto del inquilino medio era solo de US$ 10.400, seg\u00fan el informe. Esto significa que el propietario t\u00edpico tiene casi 40 veces m\u00e1s riqueza que el inquilino t\u00edpico.<\/p>\n<p>El mes que viene, Grantham probablemente alcanzar\u00e1 por fin su objetivo de ser propietaria de una vivienda cuando ella y su pareja cierren en enero la compra de una casa inicial de dos dormitorios y un ba\u00f1o en Tacoma (Washington). Se decidieron por este lugar, a una hora de Seattle, porque los precios de las viviendas eran m\u00e1s razonables que en las grandes ciudades.<\/p>\n<p>Grantham afirma que su objetivo a largo plazo es acumular capital inmobiliario.<\/p>\n<p>\u201cPagaremos un poco m\u00e1s por la hipoteca que por el alquiler, pero nos parece bien, porque al menos en cierta manera nos estamos pagando a nosotros mismos\u201d, afirma.<\/p>\n<p>Para otros, el sue\u00f1o de ser propietarios de una vivienda parece muy lejano.<\/p>\n<p>\u201cTengo tantas ganas de ser propietario\u201d, dijo Jordan Swanson, creador de contenido en TikTok, en un video reciente. \u201cEn esta econom\u00eda es literalmente imposible\u201d.<\/p>\n<p>Los que quieren comprar su primera casa se han enfrentado al doble golpe del aumento de los precios de la vivienda y las tasas hipotecarias obstinadamente altas. El precio medio de venta de las viviendas existentes fue de US$ 407.200 en octubre, seg\u00fan la Asociaci\u00f3n Nacional de Agentes Inmobiliarios. Es el decimosexto mes consecutivo de subidas de precios interanuales.<\/p>\n<p>Al mismo tiempo, los d\u00edas de tasas hipotecarias que se situaban por debajo del 4% parecen haber quedado atr\u00e1s, despu\u00e9s de que la Reserva Federal comenzara a subir los tipos de inter\u00e9s para hacer frente a la inflaci\u00f3n en 2022. El mi\u00e9rcoles, se espera que la Fed anuncie que bajar\u00e1 las tasas de inter\u00e9s por tercera vez este a\u00f1o. Aun as\u00ed, el tipo medio de las hipotecas fijas a 30 a\u00f1os fue del 6,6% la semana pasada, seg\u00fan Freddie Mac.<\/p>\n<p>Ser propietario de una vivienda se considera desde hace tiempo una de las mejores formas de acumular riqueza en Estados Unidos. A medida que el propietario va pagando su hipoteca, aumenta su patrimonio inmobiliario y el valor de su propiedad puede revalorizarse.<\/p>\n<p>Sin embargo, Katherine Lucas McKay, directora asociada del Programa de Seguridad Financiera del Instituto Aspen, se mostr\u00f3 sorprendida por las conclusiones del informe.<\/p>\n<p>\u201cRealmente demuestra cu\u00e1n adelantados est\u00e1n los propietarios de viviendas en t\u00e9rminos de riqueza\u201d, afirm\u00f3.<\/p>\n<p>El informe del Instituto Aspen -que utiliz\u00f3 principalmente datos de dos encuestas, la Encuesta sobre Finanzas de los Consumidores de la Reserva Federal y la Encuesta sobre Econom\u00eda Dom\u00e9stica y Toma de Decisiones- concluy\u00f3 que, en cada quintil de ingresos, los inquilinos, que constituyen m\u00e1s de un tercio de los hogares estadounidenses, tienen menos flujo de caja positivo, m\u00e1s deudas onerosas y menos ahorros que los propietarios de viviendas. Los inquilinos tambi\u00e9n son m\u00e1s propensos a tener deudas por pr\u00e9stamos estudiantiles.<\/p>\n<p>Sin embargo, algunas personas prefieren la flexibilidad que ofrece el alquiler, y la diferencia de riqueza entre inquilinos y propietarios no se debe \u00fanicamente al valor de la vivienda. Casi el 80% de los propietarios de vivienda poseen un activo potencialmente apreciable distinto de su residencia principal, que el Aspen Institute define como cuentas de jubilaci\u00f3n, acciones y bonos, capital de empresas, otros bienes inmuebles y otros activos financieros, incluidas las criptomonedas. Seg\u00fan el informe, solo el 48% de los inquilinos posee este tipo de activos.<\/p>\n<p>McKay dijo que la investigaci\u00f3n mostr\u00f3 que los inquilinos son menos propensos a abrir cuentas de inversi\u00f3n y de jubilaci\u00f3n.<\/p>\n<p>\u201cEsa es una de las cosas que la gente puede hacer para aumentar su riqueza fuera de la compra de una casa\u201d, dijo.<\/p>\n<p>En muchos sentidos, sin embargo, la baraja est\u00e1 en contra de los inquilinos, afirma Shane Phillips, investigador del Centro Lewis de Estudios de Pol\u00edtica Regional de la UCLA.<\/p>\n<p>\u201cHacemos mucho por incentivar la propiedad de la vivienda. Damos grandes exenciones fiscales en la hipoteca, la venta de la casa y cosas de esa naturaleza\u201d, dijo sobre los programas gubernamentales existentes. \u201cY las condiciones actuales dificultan el acceso a la vivienda a las personas que a\u00fan no son propietarias\u201d.<\/p>\n<p>Pero no todo son malas noticias para los inquilinos. Hay algunos indicios de que el mercado del alquiler podr\u00eda estar enfri\u00e1ndose, lo que supondr\u00eda un respiro muy necesario para los inquilinos cuyos presupuestos ya son escasos.<\/p>\n<p>Los precios de los alquileres bajaron m\u00e1s de lo habitual en noviembre, seg\u00fan un informe de Zillow publicado este mes, y la proporci\u00f3n de anuncios de alquiler en Zillow que ofrecen una concesi\u00f3n tambi\u00e9n marc\u00f3 un nuevo r\u00e9cord con un 38,6% el mes pasado.<\/p>\n<p>Tambi\u00e9n ha habido un auge de la construcci\u00f3n en el mercado del alquiler. Se espera que un mill\u00f3n de nuevas unidades multifamiliares que comenzaron a construirse en los \u00faltimos a\u00f1os lleguen al mercado este a\u00f1o y el pr\u00f3ximo, un m\u00e1ximo en m\u00e1s de 50 a\u00f1os. Este incremento de inmuebles podr\u00eda frenar el aumento de los alquileres en un futuro pr\u00f3ximo.<\/p>\n<p>A\u00fan as\u00ed, puede que no sea suficiente para que algunos inquilinos empiecen a buscar casa en un futuro pr\u00f3ximo. La subida vertiginosa de los precios de la vivienda no es la \u00fanica barrera de entrada: las tasas hipotecarias siguen siendo persistentemente altas. Grantham dijo que le aprobaron una hipoteca con una tasa del 7,2%, que est\u00e1 en el extremo superior de una t\u00edpica hipoteca a 30 a\u00f1os de tasa fija en este momento.<\/p>\n<p>\u201cEs posible que las tasas de inter\u00e9s no bajen tanto en un futuro pr\u00f3ximo, y est\u00e1bamos dispuestos a dejar de alquilar. As\u00ed que est\u00e1bamos dispuestos a comprometernos\u201d, dijo Grantham.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace dos a\u00f1os, Elizabeth Grantham decidi\u00f3 que no quer\u00eda seguir alquilando mucho m\u00e1s tiempo, as\u00ed que se mud\u00f3 de su ciudad natal, en la costosa zona de la bah\u00eda de San Francisco, al estado de Washington, para ahorrar y comprar una casa \u201cCada a\u00f1o nos sub\u00edan el alquiler. Incluso sub\u00eda el precio del aparcamiento en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456658","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace dos a\u00f1os, Elizabeth Grantham decidi\u00f3 que no quer\u00eda seguir alquilando mucho m\u00e1s tiempo, as\u00ed que se mud\u00f3 de su ciudad natal, en la costosa zona de la bah\u00eda de San Francisco, al estado de Washington, para ahorrar y comprar una casa \u201cCada a\u00f1o nos sub\u00edan el alquiler. Incluso sub\u00eda el precio del aparcamiento en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T18:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000\",\"datePublished\":\"2024-12-16T18:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\"},\"wordCount\":1258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\",\"name\":\"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T18:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","og_locale":"es_ES","og_type":"article","og_title":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias","og_description":"Hace dos a\u00f1os, Elizabeth Grantham decidi\u00f3 que no quer\u00eda seguir alquilando mucho m\u00e1s tiempo, as\u00ed que se mud\u00f3 de su ciudad natal, en la costosa zona de la bah\u00eda de San Francisco, al estado de Washington, para ahorrar y comprar una casa \u201cCada a\u00f1o nos sub\u00edan el alquiler. Incluso sub\u00eda el precio del aparcamiento en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","og_site_name":"Noticias","article_published_time":"2024-12-16T18:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/"},"author":{"name":"","@id":""},"headline":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000","datePublished":"2024-12-16T18:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/"},"wordCount":1258,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","name":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T18:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T18:03:48Z","datePublished":"2024-12-16T18:03:48Z","dateModified":"2024-12-16T18:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El inquilino medio de EE.UU. tiene un patrimonio neto de US$ 10.400. El del propietario medio es de US$ 400.000\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/16\\\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/16\\\/el-inquilino-medio-de-ee-uu-tiene-un-patrimonio-neto-de-ususd-10-400-el-del-propietario-medio-es-de-ususd-400-000\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T18:03:48Z\",\"datePublished\":\"2024-12-16T18:03:48Z\",\"dateModified\":\"2024-12-16T18:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473467,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/24\/viviendas-propietarios-inquilinos-batalla-politica-trax\/","url_meta":{"origin":1456658,"position":0},"title":"Propietarios contra inquilinos: la batalla pol\u00edtica por las viviendas unifamiliares en Estados Unidos","author":"","date":"abril 24, 2026","format":false,"excerpt":"La casa de Mona Gass se encuentra en medio de la compleja pol\u00edtica de la crisis de vivienda en Estados Unidos.Gass, de 72 a\u00f1os, paga US$ 2.500 al mes por una casa unifamiliar de tres habitaciones que comparte con su madre de 94 a\u00f1os. Es una de las decenas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1415600,"url":"https:\/\/noticiasya.com\/colorado-springs\/2022\/07\/26\/comision-de-vivienda-de-san-diego-ayudara-a-personas-mayores-sin-hogar-a-pagar-el-alquiler\/","url_meta":{"origin":1456658,"position":1},"title":"Comisi\u00f3n de Vivienda de San Diego ayudar\u00e1 a personas mayores sin hogar a pagar el alquiler","author":"agomez","date":"julio 26, 2022","format":false,"excerpt":"El condado de San Diego est\u00e1 apoyando el desarrollo con $7.5 millones en fondos estatales que administra del programa No Place Like Home","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458096,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/31\/londinenses-tutelas-evitar-alquileres-trax\/","url_meta":{"origin":1456658,"position":2},"title":"Los londinenses pagan por vivir en escuelas, oficinas y hasta en una catedral abandonada para evitar alquileres &#171;demenciales&#187;","author":"agomez","date":"enero 31, 2025","format":false,"excerpt":"Frente a una cama en el centro de Londres, la luz se filtra a trav\u00e9s de un ventanal en el que, en fragmentos de cobre y azul, est\u00e1 representado Jesucristo.Tres personas han vivido en la catedral abandonada en los \u00faltimos dos a\u00f1os, y cada ocupante (un electricista, un ingeniero de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450639,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/06\/23\/inquilinos-dificultades-propietarios-mercado-inmobiliario-ee-uu-trax\/","url_meta":{"origin":1456658,"position":3},"title":"Los inquilinos tienen m\u00e1s dificultades que los propietarios en el dif\u00edcil mercado inmobiliario de EE.UU., seg\u00fan informe","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN) --Los propietarios de viviendas en Estados Unidos no son los \u00fanicos que luchan contra un mercado inmobiliario inasequible. Los inquilinos se est\u00e1n llevando la peor parte.Un informe del Centro Conjunto de Estudios de la Vivienda de la Universidad de Harvard, publicado la semana pasada, mostr\u00f3 que tanto los propietarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472160,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/03\/13\/vivienda-asequible-senado-trax\/","url_meta":{"origin":1456658,"position":4},"title":"Senado de EE.UU. aprueba el mayor paquete de asequibilidad de vivienda en una generaci\u00f3n","author":"","date":"marzo 13, 2026","format":false,"excerpt":"Un grupo bipartidista de senadores en EE.UU. aprob\u00f3 el jueves un proyecto de ley destinado a mejorar la asequibilidad de la vivienda.La medida contiene aproximadamente 40 disposiciones para aumentar la oferta de vivienda y reducir los costos. A\u00fan est\u00e1 por verse si la C\u00e1mara de Representantes la aprobar\u00e1 tal como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449282,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/05\/08\/analisis-compra-vivienda-eeuu-tasas-trax\/","url_meta":{"origin":1456658,"position":5},"title":"AN\u00c1LISIS | Para las personas que alquilan en EE.UU., la posibilidad de tener una vivienda propia va de mal en peor","author":"","date":"mayo 8, 2024","format":false,"excerpt":"Nueva York (CNN) -- El \"sue\u00f1o americano\" de ser propietario de una vivienda se empieza a parecer cada vez m\u00e1s a una pesadilla.Con la inflaci\u00f3n subiendo de nuevo, la Reserva Federal no est\u00e1 en condiciones de plantearse bajar las tasas de inter\u00e9s en sus pr\u00f3ximas reuniones. Eso ha ayudado a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456658"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456658\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}