{"id":1456674,"date":"2024-12-17T04:03:48","date_gmt":"2024-12-17T12:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/"},"modified":"2024-12-17T04:03:48","modified_gmt":"2024-12-17T12:03:48","slug":"5-cosas-17-diciembre-assad-tiroteo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump"},"content":{"rendered":"<p>Difunden las primeras palabras de Bashar al-Assad desde que abandon\u00f3 Siria. Cinco Gobiernos latinoamericanos condenan el asedio a la embajada de Argentina en Caracas. Esto<em> es lo que debes saber para comenzar el d\u00eda.<\/em> <strong>Primero la verdad.<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.cnn.com\/newsletters\/5-cosas\"><strong>Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/5-cosas\"><strong>\ud83c\udf99 Escucha las 5 cosas de CNN<\/strong><\/a><\/li>\n<\/ul>\n<p>La salida del pa\u00eds del derrocado presidente de Siria, Bashar al-Assad, no fue planificada, seg\u00fan un comunicado publicado este lunes en la cuenta de Telegram de la Presidencia de Siria, supuestamente reportando declaraciones de Assad. No est\u00e1 claro si Assad todav\u00eda controla la cuenta de Telegram. Si la declaraci\u00f3n es aut\u00e9ntica, ser\u00eda la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/mundo\/siria-assad-salida-rusia-trax\">primera vez que comenta p\u00fablicamente los acontecimientos desde que huy\u00f3 de su naci\u00f3n.<\/a><\/p>\n<p>Colombia y la Alianza para el Desarrollo en Democracia, que integran Ecuador, Panam\u00e1, Costa Rica y Rep\u00fablica Dominicana, condenaron la situaci\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/latinoamerica\/gobiernos-condenan-asedio-embajada-argentina-caracas-orix\">que viven seis opositores asilados desde marzo en la embajada de Argentina en Caracas<\/a>, seg\u00fan comunicados oficiales.<\/p>\n<p>Esta semana se espera que haya un veredicto en el caso de Gis\u00e8le P\u00e9licot, cuyo esposo, Dominique, est\u00e1 acusado de haberla drogado con somn\u00edferos y ansiol\u00edticos y de haberla violado repetidamente, as\u00ed como de haber reclutado a decenas de hombres por internet para que tambi\u00e9n la violaran mientras estaba inconsciente. <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/mundo\/pelicot-caso-que-paso-juicio-violacion-francia-orix\">Esta es la historia judicial que ha sacudido a la sociedad francesa<\/a> y ha acaparado titulares en todo el mundo.<\/p>\n<p>Dos personas murieron y varias resultaron heridas <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/estados-unidos\/tiroteo-escuela-madison-wisconsin-trax\">en un tiroteo<\/a> en Abundant Life Christian School en Madison, Wisconsin, dijo la Polic\u00eda. Se cree que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/noticias-tiroteo-escuela-wisconsin-trax\/\">la persona atacante, de 15 a\u00f1os, muri\u00f3 por una herida autoinfligida<\/a>.<\/p>\n<p>El puerto de Chancay, inaugurado en noviembre por la presidenta de Per\u00fa y el de China, es una muestra del creciente inter\u00e9s del pa\u00eds asi\u00e1tico en Am\u00e9rica Latina. En medio de tensiones comerciales con Estados Unidos, China anunci\u00f3 medidas econ\u00f3micas para contrarrestar posibles aranceles anunciados por el presidente electo, Donald Trump, intensificando la rivalidad de ambos pa\u00edses por la<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/latinoamerica\/china-america-latina-historia-comercio-inversiones-orix\"> influencia en Latinoam\u00e9rica<\/a>.<\/p>\n<p><strong>La sonda Parker se prepara para una hist\u00f3rica aproximaci\u00f3n al Sol<\/strong><\/p>\n<p>La sonda Parker de la NASA har\u00e1 una hist\u00f3rica aproximaci\u00f3n al Sol. Se acercar\u00e1 a solo 6,1 millones de km de la superficie del astro, el pr\u00f3ximo 24 de diciembre. El f\u00edsico espacial de la NASA Cristian Ferradas<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/ciencia\/video\/sonda-parker-nasa-aproximacion-sol-cafe-tv\"> conversa en CNN sobre lo que esto implica para la comunidad cient\u00edfica.<\/a><\/p>\n<p><strong>Pron\u00f3stico del tiempo para Navidad en EE.UU., m\u00e1s caliente de lo normal en gran parte del pa\u00eds<\/strong><\/p>\n<p>La Navidad se acerca casi tan r\u00e1pido como el trineo de Pap\u00e1 Noel, pero quien en Estados Unidos fantasee <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/estados-unidos\/pronostico-tiempo-nochebuena-navidad-ee-uu-trax\">con una Navidad blanca digna de una pel\u00edcula quiz\u00e1 tenga que seguir so\u00f1ando.<\/a><\/p>\n<p><strong>A23a, el iceberg m\u00e1s grande del mundo, vuelve a moverse<\/strong><\/p>\n<p>El iceberg m\u00e1s grande del mundo est\u00e1 nuevamente en movimiento, a la deriva en el oc\u00e9ano Ant\u00e1rtico, despu\u00e9s de meses <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/mundo\/a23a-iceberg-mas-grande-mundo-vuelve-moverse-trax\">estancado girando en el mismo lugar, dijeron cient\u00edficos del British Antarctic Survey (BAS<\/a>).<\/p>\n<p><strong>Acusan al expresidente de Bolivia Evo Morales de trata y tr\u00e1fico de personas<\/strong><\/p>\n<p>El expresidente de Bolivia Evo Morales fue acusado penalmente de trata de personas agravado y se le gir\u00f3 una orden de captura y una alerta migratoria para evitar su salida del pa\u00eds,<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/latinoamerica\/acusan-evo-morales-trafico-de-personas-arresto-orix\"> dijo la fiscal departamental de Tarija, Sandra Guti\u00e9rrez.<\/a> El exmandatario ha dicho anteriormente que las acusaciones son una \u201cguerra sucia\u201d.<\/p>\n<p><strong>El canciller de Alemania, Olaf Scholz, pierde voto de confianza<\/strong><\/p>\n<p>Alemania, la mayor econom\u00eda de Europa y normalmente un pilar de estabilidad, se enfrentar\u00e1 a unas elecciones anticipadas el <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/mundo\/scholz-perdio-voto-confianza-alemania-que-sigue-trax\">pr\u00f3ximo a\u00f1o, despu\u00e9s de que el canciller del pa\u00eds, Olaf Scholz, perdi\u00f3 una votaci\u00f3n de confianza.<\/a><\/p>\n<p><strong>500<\/strong><\/p>\n<p>La Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/venezuela\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\"> m\u00e1s de 500 personas tras las protestas poselectorales<\/a>; pero la ONG Foro Penal solo registr\u00f3 155 excarcelaciones.<\/p>\n<p><strong>\u201cCuando muera, me van a quemar y me van a enterrar ah\u00ed\u201d <\/strong><\/p>\n<p>Jos\u00e9 \u201cPepe\u201d Mujica, expresidente de Uruguay, concedi\u00f3 una larga entrevista a CNN, en la que habl\u00f3 de la muerte que \u2013dice\u2013 se le avecina. <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/latinoamerica\/video\/jose-pepe-mujica-dios-muerte-orix\">Este es un adelanto de la entrevista.<\/a><\/p>\n<p><strong>El momento en el que un veh\u00edculo todoterreno choca contra una peluquer\u00eda<\/strong><\/p>\n<p>El video de vigilancia de una peluquer\u00eda en Houston muestra a una SUV estrell\u00e1ndose contra el edificio, dejando <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/estados-unidos\/video\/video-todoterreno-peluqueria-houston-heridos-ush-trax\">varios heridos, entre ellos un ni\u00f1o. <\/a><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Difunden las primeras palabras de Bashar al-Assad desde que abandon\u00f3 Siria. Cinco Gobiernos latinoamericanos condenan el asedio a la embajada de Argentina en Caracas. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456674","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Difunden las primeras palabras de Bashar al-Assad desde que abandon\u00f3 Siria. Cinco Gobiernos latinoamericanos condenan el asedio a la embajada de Argentina en Caracas. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T12:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump\",\"datePublished\":\"2024-12-17T12:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\",\"name\":\"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-17T12:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias","og_description":"Difunden las primeras palabras de Bashar al-Assad desde que abandon\u00f3 Siria. Cinco Gobiernos latinoamericanos condenan el asedio a la embajada de Argentina en Caracas. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-17T12:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump","datePublished":"2024-12-17T12:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","name":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-17T12:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/17\/5-cosas-17-diciembre-assad-tiroteo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-17T12:03:48Z","datePublished":"2024-12-17T12:03:48Z","dateModified":"2024-12-17T12:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 17 de diciembre: Assad, embajada argentina en Caracas, caso Pelicot, tiroteo escolar y Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/17\\\/5-cosas-17-diciembre-assad-tiroteo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/17\\\/5-cosas-17-diciembre-assad-tiroteo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-17T12:03:48Z\",\"datePublished\":\"2024-12-17T12:03:48Z\",\"dateModified\":\"2024-12-17T12:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456648,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/siria-assad-salida-rusia-trax\/","url_meta":{"origin":1456674,"position":0},"title":"El presidente derrocado Bashar al-Assad dice que no planeaba abandonar Siria, seg\u00fan su cuenta de Telegram","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"La salida del pa\u00eds del derrocado presidente de Sirio, Bashar al-Assad, no fue planificada, seg\u00fan un comunicado publicado este lunes en la cuenta de Telegram de la presidencia siria, supuestamente reportando declaraciones de Assad.No est\u00e1 claro si Assad todav\u00eda controla la cuenta de Telegram. Si la declaraci\u00f3n es aut\u00e9ntica, ser\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456393,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/09\/5-cosas-9-diciembre-assad-siria-orix\/","url_meta":{"origin":1456674,"position":1},"title":"Las 5 cosas que debes saber este 9 de diciembre: Siria, Assad, Milei, Cuba y migrantes","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Siria vive d\u00edas hist\u00f3ricos tras el fin del gobierno de Assad. Milei vuelve a la carga con una propuesta para extranjeros no residentes. Caravana migrante quiere llegar a EE.UU. antes de que asuma Trump. Termin\u00f3 la enorme gira de Taylor Swift. Aument\u00f3 el dengue en el continente. Esto es lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456365,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/07\/bashar-al-assad-quien-es-presidente-siria-trax\/","url_meta":{"origin":1456674,"position":2},"title":"\u00bfQui\u00e9n es Bashar al-Assad?","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"La guerra civil de Siria est\u00e1 de nuevo en el centro de atenci\u00f3n tras un nuevo ataque sorpresa de una coalici\u00f3n rebelde, que captur\u00f3 dos ciudades importantes y tiene en la mira la capital, Damasco, rompiendo el estancamiento de una guerra que nunca termin\u00f3 formalmente. Un grupo de facciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456428,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","url_meta":{"origin":1456674,"position":3},"title":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"Apenas un d\u00eda despu\u00e9s de la ca\u00edda del r\u00e9gimen sirio y la huida a Rusia de su l\u00edder, el presidente Bashar al-Assad, la bandera verde, blanca y negra que grupos rebeldes ondean desde el inicio de la guerra civil, en 2011, comenz\u00f3 a verse en las calles de Damasco.Esa misma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456369,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/08\/rusia-assad-abandono-siria\/","url_meta":{"origin":1456674,"position":4},"title":"Rusia afirma que Assad abandon\u00f3 Siria","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"El presidente Bashar al-Assad abandon\u00f3 Siria, dijo el ministerio de Relaciones Exteriores de Rusia en un comunicado este domingo.Assad \u201cdecidi\u00f3 dejar el cargo presidencial y abandon\u00f3 el pa\u00eds, dando instrucciones para transferir el poder de manera pac\u00edfica\u201d, dijo el comunicado, y a\u00f1adi\u00f3 que \u201cRusia no particip\u00f3 en estas negociaciones\u201d.\u201cLa Federaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456419,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/10\/5-cosas-10-diciembre-mangione-assad-orix\/","url_meta":{"origin":1456674,"position":5},"title":"Las 5 cosas que debes saber este 10 de diciembre: Mangione, Assad y Putin, Trump, Hait\u00ed y Edmundo Gonz\u00e1lez","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El arresto de Luigi Mangione. C\u00f3mo la ca\u00edda de Assad es un golpe para el Gobierno de Rusia. Juan Soto pasa de los Yankees a los Mets con un contrato hist\u00f3rico en la MLB. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456674"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456674\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}