{"id":1456699,"date":"2024-12-18T00:03:49","date_gmt":"2024-12-18T08:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/"},"modified":"2024-12-18T00:03:49","modified_gmt":"2024-12-18T08:03:49","slug":"adoctrinados-soldados-norcoreanos-rusia-expertos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","title":{"rendered":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos"},"content":{"rendered":"<p>Lejos de sus hogares, en uno de los Estados m\u00e1s aislados y herm\u00e9ticos del mundo, unos <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/22\/rusia-corea-del-norte-equipos-de-defensa-aerea-soldados-ucrania-trax\">11.000 soldados norcoreanos<\/a> se encuentran en el centro del mayor conflicto de Europa desde la Segunda Guerra Mundial.<\/p>\n<p>Poco se sabe de las tropas norcoreanas desplegadas para apoyar a Rusia en su devastadora guerra de un a\u00f1o en Ucrania; tampoco se sabe qu\u00e9 se les ordenar\u00e1 hacer exactamente. Su presencia ni siquiera fue reconocida oficialmente por Mosc\u00fa o Pyongyang.<\/p>\n<p>Los servicios de inteligencia estadounidenses, ucranianos y surcoreanos dicen que los norcoreanos ya participaron en operaciones de combate, uni\u00e9ndose a una <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2024\/11\/10\/europe\/russia-north-korea-forces-prepared-kursk-ukraine\/index.html\">fuerza rusa<\/a> de decenas de miles de soldados para llevar a cabo un asalto contra posiciones ucranianas en la regi\u00f3n occidental rusa de Kursk. Se ha especulado mucho sobre la actuaci\u00f3n de estas fuerzas militares.<\/p>\n<p>Corea del Norte <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/mundo\/ucrania-norcoreanos-bajas-ataque-kursk-trax\">sufri\u00f3 \u201cvarios cientos\u201d de bajas<\/a> \u2013entre muertos y heridos\u2013 en la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/03\/ucrania-rusia-kursk-soldados-incursion-trax\">regi\u00f3n de Kursk<\/a> desde que envi\u00f3 miles de efectivos a Rusia en octubre, seg\u00fan declar\u00f3 este martes un alto funcionario estadounidense.<\/p>\n<p>Seg\u00fan Ucrania, al menos <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2024\/12\/16\/europe\/north-koreans-kursk-losses-intl\/index.html\">30 soldados norcoreanos<\/a> murieron o resultaron heridos en combates librados solo durante el fin de semana cerca de aldeas de Kursk pr\u00f3ximas a la frontera ucraniana. Una unidad ucraniana inform\u00f3 que los norcoreanos \u2013con uniformes diferentes a los rusos\u2013 hab\u00edan lanzado ataques de infanter\u00eda utilizando \u201clas mismas t\u00e1cticas que hace 70 a\u00f1os\u201d, en una aparente referencia a la Guerra de Corea, en la que se utilizaron oleadas de infanter\u00eda.<\/p>\n<p>Los soldados de Pyongyang carecen de experiencia de combate en el mundo real y se enfrentar\u00e1n a un terreno desconocido en un escenario de guerra brutal y moderno, que ha sembrado el caos y el horror en ambos bandos mientras los muertos se amontonan en las l\u00edneas del frente.<\/p>\n<p>\u201cSi tuviera que describir su capacidad en t\u00e9rminos m\u00e1s generales y no pensar en el equipo que ten\u00edan, le dir\u00eda que no son tropas curtidas en la batalla, que no estuvieron en combate antes\u201d, dijo el funcionario estadounidense, a\u00f1adiendo que su evaluaci\u00f3n era que las bajas inclu\u00edan \u201ctodos los rangos\u201d, incluidos los l\u00edderes en los nodos de mando y control.<\/p>\n<p>Pero algunos analistas advirtieron que no se debe subestimar a los norcoreanos.<\/p>\n<p>El l\u00edder norcoreano Kim Jong Un enviar\u00e1 \u201clo mejor\u201d de una fuerza de \u00e9lite de soldados altamente entrenados y \u201cadoctrinados\u201d conocida como Cuerpo de Asalto (Storm Corps), seg\u00fan el teniente general retirado Chun In-bum, veterano del ej\u00e9rcito surcoreano.<\/p>\n<p>Algunos son fuerzas especiales, como los Navy Seals o los Rangers estadounidenses, o el SAS brit\u00e1nico. Otros son infanter\u00eda ligera y francotiradores.<\/p>\n<p>El Cuerpo de Asalto \u2013el 11\u00ba cuerpo del Ej\u00e9rcito norcoreano\u2013 est\u00e1n \u201cmejor entrenados, tienen mejor f\u00edsico y est\u00e1n mejor motivados que el soldado norcoreano medio\u201d, afirm\u00f3 Chun.<\/p>\n<p>El material propagand\u00edstico norcoreano difundido este a\u00f1o por los medios de comunicaci\u00f3n estatales mostr\u00f3 a Kim supervisando entrenamientos de operaciones especiales caracterizados por demostraciones extremas de fuerza, incluido el aplastamiento de bloques de hormig\u00f3n sobre los torsos desgarrados de soldados desnudos hasta la cintura.<\/p>\n<p>Michael Madden, miembro no residente del programa 38 North del Centro Stimson de Washington, afirma que este mayor despliegue de soldados norcoreanos desde la guerra de Vietnam est\u00e1 equipado con \u201cciertos trucos psicol\u00f3gicos\u201d para perseverar.<\/p>\n<p>\u201cEstos tipos est\u00e1n programados. Estos tipos est\u00e1n adoctrinados\u201d, dijo. \u201cPero la pregunta es, \u00bfQu\u00e9 tan bien adoctrinados? \u00bfQu\u00e9 tan bien programados est\u00e1n?\u201d.<\/p>\n<p>\u201cProbablemente est\u00e1n mejor posicionados que otros militares, u otros miembros de fuerzas armadas que van a un conflicto extranjero, en cuanto a la preparaci\u00f3n de sus mentes\u201d, dijo.<\/p>\n<p>La fortaleza mental, sin embargo, puede no ser suficiente para superar los peores desaf\u00edos a los que podr\u00edan enfrentarse los soldados norcoreanos.<\/p>\n<p>La guerra con drones ha transformado el campo de batalla en Ucrania, aportando nuevos niveles de vigilancia y <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2024\/09\/07\/europe\/ukraine-thermite-dragon-drones-intl-hnk-ml\/index.html\">destrucci\u00f3n<\/a> de objetivos militares, pero tambi\u00e9n de <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2024\/10\/22\/europe\/russia-deliberately-attacking-civilians-drones-kherson-intl-cmd\/index.html\">civiles e infraestructuras c\u00edvicas<\/a>.<\/p>\n<p>Las t\u00e1cticas de \u201cpicadora de carne\u201d de Rusia, particularmente en los combates por el este de Ucrania, han ofrecido esencialmente a los reclutas rusos como carne de ca\u00f1\u00f3n.<\/p>\n<p>Tambi\u00e9n existe la posibilidad muy real de que armas fabricadas en Estados Unidos maten a norcoreanos. La Casa Blanca dijo que los soldados son \u201cjuego limpio\u201d y \u201cblancos justos\u201d.<\/p>\n<p>Los legisladores surcoreanos afirman que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/10\/29\/soldados-norcoreanos-comandos-rusos-frente-ucrania-trax\">Rusia est\u00e1 ense\u00f1ando a los soldados unos 100 t\u00e9rminos militares b\u00e1sicos como \u201cfuego\u201d y \u201cen posici\u00f3n\u201d<\/a>, mientras surgen informes sobre problemas de mando y comunicaci\u00f3n.<\/p>\n<p>En Rusia, su entrenamiento incluy\u00f3 artiller\u00eda, manejo de veh\u00edculos a\u00e9reos no tripulados y operaciones b\u00e1sicas de infanter\u00eda, incluida la limpieza de trincheras, \u201cque son habilidades cr\u00edticas para las operaciones en primera l\u00ednea\u201d, seg\u00fan el Departamento de Estado estadounidense.<\/p>\n<p>Y las evaluaciones de los servicios de inteligencia sugieren que los norcoreanos se est\u00e1n integrando en las fuerzas armadas rusas.<\/p>\n<p>El \u00e9xito de Mosc\u00fa en la utilizaci\u00f3n de los soldados \u201cdepender\u00e1 en gran medida de lo bien que los rusos puedan integrarlas en sus fuerzas armadas\u201d, dijo el Departamento de Estado.<\/p>\n<p>A\u00fan no est\u00e1 claro si cavar\u00e1n trincheras, vigilar\u00e1n puestos o luchar\u00e1n en el frente.<\/p>\n<p>\u201cCuando los atrapemos o veamos un cad\u00e1ver, sabr\u00e9 con certeza que est\u00e1n aqu\u00ed\u201d, declar\u00f3 a CNN a principios de diciembre Oleksandr, comandante de unidad del 225\u00ba batall\u00f3n de asalto ucraniano.<\/p>\n<p>Corea del Norte es una de las naciones m\u00e1s militarizadas del mundo, con 1,2 millones de efectivos en las fuerzas armadas, seg\u00fan el <a href=\"https:\/\/www.cia.gov\/the-world-factbook\/countries\/korea-north\/#military-and-security\">CIA World Factbook,<\/a> y todos los ciudadanos deben cumplir el servicio militar obligatorio a partir de los 17 a\u00f1os.<\/p>\n<p>Este periodo suele durar 10 a\u00f1os para los hombres, aunque las \u00faltimas evaluaciones sugieren que Corea del Norte redujo el tiempo a la mitad.<\/p>\n<p>Seg\u00fan Chun, es probable que las fuerzas especiales norcoreanas tengan prioridad para recibir mejor comida y ropa, mientras que los reclutas regulares <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2018\/11\/19\/asia\/north-korean-defector-interview-intl\/index.html\">han tenido dificultades<\/a> en el pasado.<\/p>\n<p>Kim Seong-han, un desertor que vive en el Sur, recuerda sus 12 a\u00f1os en el Ej\u00e9rcito norcoreano como una \u00e9poca de poca comida, mal trato y agotadoras marchas invernales sin dormir.<\/p>\n<p>En 1989, se alist\u00f3 como soldado en Kaesong, ciudad cercana a la frontera surcoreana, y sirvi\u00f3 durante la catastr\u00f3fica hambruna norcoreana de los a\u00f1os 90, que acab\u00f3 con la vida de hasta un mill\u00f3n de personas.<\/p>\n<p>\u201cAntes de 1991, a\u00fan pod\u00edamos comer carne, pero a partir de ese a\u00f1o, la carne empez\u00f3 a escasear\u201d, dijo Kim, que pidi\u00f3 utilizar un seud\u00f3nimo por razones de seguridad. \u201cLa raci\u00f3n de arroz, que sol\u00eda ser de 800 gramos por comida, se redujo a 800 gramos diarios y, finalmente, solo nos daban harina de ma\u00edz sin arroz\u201d.<\/p>\n<p>La desnutrici\u00f3n era moneda corriente entre sus compa\u00f1eros, a\u00f1adi\u00f3.<\/p>\n<p>Durante el entrenamiento, Kim Seong-han dijo que hab\u00eda accidentes regulares \u201ccomo fallos de tiro, soldados que detonaban granadas accidentalmente y otros percances con las armas\u201d.<\/p>\n<p>\u201cUn ejemplo de nuestro entrenamiento ser\u00eda una marcha invernal: marchar 150 kil\u00f3metros durante tres d\u00edas sin dormir\u201d, dijo.<\/p>\n<p>Un punto positivo era la calefacci\u00f3n decente y la electricidad las 24 horas del d\u00eda en los barracones, a diferencia de las casas de muchos norcoreanos, a\u00f1adi\u00f3.<\/p>\n<p>Kim Seong-han escap\u00f3 a Corea del Sur en 2017. Aunque su experiencia militar norcoreana termin\u00f3 hace m\u00e1s de dos d\u00e9cadas, ofrece una visi\u00f3n de un mundo que rara vez entienden los forasteros.<\/p>\n<p>Relatos m\u00e1s recientes de la vida como soldado norcoreano tambi\u00e9n pintan un panorama sombr\u00edo.<\/p>\n<p>A un soldado, que recibi\u00f3 m\u00faltiples disparos cuando <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2017\/11\/22\/health\/north-korea-defector-parasites-health\/index.html\">desert\u00f3 al sur en 2017<\/a> corriendo a trav\u00e9s de la fuertemente fortificada zona desmilitarizada, se le encontraron <a href=\"https:\/\/archive.ph\/o\/LRgZt\/https:\/\/www.cnn.com\/2017\/11\/22\/health\/north-korea-defector-parasites-health\/index.html\">gusanos parasitarios<\/a> y una infecci\u00f3n hep\u00e1tica cr\u00f3nica.<\/p>\n<p>Algunos de los par\u00e1sitos extra\u00eddos med\u00edan hasta 27 cent\u00edmetros (m\u00e1s de 10 pulgadas), seg\u00fan los m\u00e9dicos surcoreanos que lo trataron. Un tipo de gusano que encontraron suele afectar a los perros.<\/p>\n<p>\u201cTodo el mundo ten\u00eda hambre, incluso los soldados\u201d, dijo entonces otro desertor norcoreano y exoficial del Ej\u00e9rcito, Kang Ri Hyuk. \u201cHay muchos soldados que tambi\u00e9n mueren de enfermedades porque no reciben tratamiento m\u00e9dico\u201d.<\/p>\n<p>Tambi\u00e9n hubo informes de soldados norcoreanos que roban alimentos de aldeas y granjas rurales.<\/p>\n<p>Corea del Norte tiene un largo historial de grave escasez de alimentos y hambrunas. Seg\u00fan el Programa Mundial de Alimentos de Naciones Unidas, m\u00e1s del 40% de la poblaci\u00f3n est\u00e1 desnutrida.<\/p>\n<p>Sin embargo, algunas unidades militares norcoreanas est\u00e1n bien abastecidas y \u201ctienen un suministro regular de alimentos y log\u00edstica\u201d, afirma Madden, de 38 North.<\/p>\n<p>\u201cTienen suficiente para comer. O, m\u00e1s para comer que el ciudadano norcoreano medio\u201d, dijo.<\/p>\n<p>\u201cEst\u00e1n bien equipados en cuanto a ropa. Hay calefacci\u00f3n en los barracones. Hay tiempo libre o actividades recreativas, y la propia unidad militar est\u00e1 bien abastecida en cuanto a materiales de construcci\u00f3n, materiales agr\u00edcolas\u201d.<\/p>\n<p>En la sociedad norcoreana, un miembro del 11\u00ba Cuerpo de Ej\u00e9rcito ocupar\u00eda probablemente una posici\u00f3n relativamente privilegiada.<\/p>\n<p>La divisi\u00f3n goza de gran estima, no muy por debajo de las unidades que proporcionan <a href=\"https:\/\/www.cnn.com\/videos\/world\/2019\/02\/26\/kim-jong-un-running-bodyguards-moos-pkg-ebof-vpx.cnn\">escolta de seguridad<\/a> al l\u00edder norcoreano Kim, y la lealtad al r\u00e9gimen es clave para ser admitido.<\/p>\n<p>\u201cInvestigan tus antecedentes familiares hasta el segundo grado; es decir, primos segundos, y saben qui\u00e9nes son tus padres, saben d\u00f3nde vives\u201d, explica Madden.<\/p>\n<p>\u201cSi lo haces bien en un entrenamiento espec\u00edfico o en un ejercicio de entrenamiento, puede que te recluten o te reasignen al 11\u00ba Cuerpo del Ej\u00e9rcito, pero est\u00e1 formado principalmente por soldados que tienen la agudeza f\u00edsica y las capacidades f\u00edsicas, adem\u00e1s de tener unos determinados antecedentes\u201d.<\/p>\n<p>Las fuerzas especiales est\u00e1n entrenadas para llevar a cabo misiones en el interior del territorio enemigo, recopilar informaci\u00f3n y lanzar ataques directos.<\/p>\n<p>\u201cEstas unidades norcoreanas, su misi\u00f3n principal es perturbar\u201d, dijo Chun, exoficial del Ej\u00e9rcito surcoreano.<\/p>\n<p>Parte del 11\u00ba Cuerpo de Ej\u00e9rcito es una divisi\u00f3n de comandos de 10.000 efectivos entrenados para saltar en paraca\u00eddas o penetrar en territorio enemigo y llevar a cabo asesinatos, da\u00f1os a infraestructuras y sabotajes, seg\u00fan Madden.<\/p>\n<p>Algunas unidades de comandos est\u00e1n entrenadas incluso para quitarse la vida antes que ser capturadas, afirm\u00f3.<\/p>\n<p>Chun dijo que la mayor\u00eda de los soldados norcoreanos que conoci\u00f3 durante su servicio tomar\u00edan esa fatal decisi\u00f3n.<\/p>\n<p>\u201cEsto se debe a que si uno se suicida, en Corea del Norte se ocupan de sus familias\u201d, explica. \u201cSer\u00edas considerado un h\u00e9roe para el resto de la eternidad\u201d.<\/p>\n<p>En los \u00faltimos a\u00f1os, Kim trat\u00f3 de hacer m\u00e1s eficiente el enorme Ej\u00e9rcito norcoreano.<\/p>\n<p>\u201cEst\u00e1 seleccionando a sus soldados, los est\u00e1 haciendo rotar por armamento espec\u00edfico\u2026 As\u00ed que est\u00e1 tratando de mantener la mayor eficiencia posible\u201d, dijo Chun.<\/p>\n<p>\u201cNo es capaz de tener un Ej\u00e9rcito que funcione al 100%, pero tiene un Ej\u00e9rcito dedicado e incluso con 200.000 hombres, es un n\u00famero considerable (mayor) que la mayor\u00eda de los pa\u00edses europeos\u201d.<\/p>\n<p>No est\u00e1 claro si los soldados norcoreanos enviados a Rusia pudieron elegir su despliegue, o si a ellos o a sus familias se les ofrecieron incentivos.<\/p>\n<p>Pero la perspectiva de dinero en efectivo y la oportunidad de ir al extranjero puede ser atractiva para muchos.<\/p>\n<p>Seg\u00fan el Centro de Estudios Estrat\u00e9gicos e Internacionales, con sede en Washington, Rusia \u201cprobablemente est\u00e1 pagando todos los costos de despliegue de los norcoreanos, as\u00ed como un estipendio para las propias tropas\u201d.<\/p>\n<p>La inteligencia surcoreana sugiere que los soldados norcoreanos en Rusia podr\u00edan estar recibiendo salarios de US$ 2.000 al mes.<\/p>\n<p>\u201cEl soldado norcoreano (medio) recibe un d\u00f3lar al mes\u201d, dijo Chun. \u201cNo va a recibir todo (el dinero ruso). Kim Jong Un se llevar\u00e1 al menos el 90%, pero (el soldado) seguir\u00e1 recibiendo US$ 300. Es mucho dinero para un norcoreano\u201d.<\/p>\n<p>En octubre, el proyecto ucraniano \u201cQuiero vivir\u201d, cuyo objetivo es incentivar y ayudar a los soldados rusos a desertar, public\u00f3 un <a href=\"https:\/\/t.me\/hochu_zhyt\/2017\">video en coreano<\/a> en el que promet\u00eda \u201ctres comidas calientes al d\u00eda\u201d, atenci\u00f3n m\u00e9dica y buen trato a las fuerzas norcoreanas que se rindieran.<\/p>\n<p>Pero los analistas dijeron que era poco probable que se produjeran deserciones masivas.<\/p>\n<p>\u201cUna cosa que hay que saber sobre los norcoreanos en el extranjero es que siempre est\u00e1n emparejados. Un soldado norcoreano que intente desertar a Ucrania recibir\u00e1 un disparo en la cabeza de su compa\u00f1ero o al rev\u00e9s\u201d, explic\u00f3 Madden.<\/p>\n<p>Chun advirti\u00f3 que \u201cnunca se sabe c\u00f3mo se comportar\u00e1n los soldados bajo el fuego\u201d. Y lo bien que se comporten tendr\u00e1 ramificaciones mucho m\u00e1s all\u00e1 de la guerra de Rusia.<\/p>\n<p>\u201cSi los norcoreanos fracasan en sus misiones, si son un pu\u00f1ado de soldados inexpertos, eso tiene muchas m\u00e1s implicaciones para la seguridad de la pen\u00ednsula coreana\u201d, dijo.<\/p>\n<p>\u201cPero si son buenos, si aprenden, y ya van a aprender incluso fracasando, seguir\u00e1 siendo una mala noticia para nosotros en la Pen\u00ednsula de Corea, e incluso para el mundo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lejos de sus hogares, en uno de los Estados m\u00e1s aislados y herm\u00e9ticos del mundo, unos 11.000 soldados norcoreanos se encuentran en el centro del mayor conflicto de Europa desde la Segunda Guerra Mundial. Poco se sabe de las tropas norcoreanas desplegadas para apoyar a Rusia en su devastadora guerra de un a\u00f1o en Ucrania; [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456699","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Lejos de sus hogares, en uno de los Estados m\u00e1s aislados y herm\u00e9ticos del mundo, unos 11.000 soldados norcoreanos se encuentran en el centro del mayor conflicto de Europa desde la Segunda Guerra Mundial. Poco se sabe de las tropas norcoreanas desplegadas para apoyar a Rusia en su devastadora guerra de un a\u00f1o en Ucrania; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T08:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos\",\"datePublished\":\"2024-12-18T08:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\"},\"wordCount\":2238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\",\"name\":\"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T08:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias","og_description":"Lejos de sus hogares, en uno de los Estados m\u00e1s aislados y herm\u00e9ticos del mundo, unos 11.000 soldados norcoreanos se encuentran en el centro del mayor conflicto de Europa desde la Segunda Guerra Mundial. Poco se sabe de las tropas norcoreanas desplegadas para apoyar a Rusia en su devastadora guerra de un a\u00f1o en Ucrania; [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T08:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/"},"author":{"name":"","@id":""},"headline":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos","datePublished":"2024-12-18T08:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/"},"wordCount":2238,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","name":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T08:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T08:03:49Z","datePublished":"2024-12-18T08:03:49Z","dateModified":"2024-12-18T08:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/18\\\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/18\\\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T08:03:49Z\",\"datePublished\":\"2024-12-18T08:03:49Z\",\"dateModified\":\"2024-12-18T08:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456871,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/22\/ucrania-afirma-soldados-norcoreanos-identificaciones-rusas-falsas-trax\/","url_meta":{"origin":1456699,"position":0},"title":"Ucrania afirma que soldados norcoreanos recibieron identificaciones militares rusas falsas","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"Los soldados norcoreanos que luchan por Rusia recibieron documentos militares falsos con nombres y lugares de nacimiento rusos, inform\u00f3 el ej\u00e9rcito ucraniano, en medio de afirmaciones de Kyiv de que Mosc\u00fa est\u00e1 tratando de ocultar la presencia de combatientes extranjeros en el campo de batalla.Las fuerzas de operaciones especiales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457465,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/12\/zelensky-liberar-soldados-norcoreanos-por-soldados-ucranianos-rusia-trax\/","url_meta":{"origin":1456699,"position":1},"title":"Zelensky ofrece liberar a soldados norcoreanos capturados a cambio de soldados ucranianos retenidos en Rusia","author":"","date":"enero 12, 2025","format":false,"excerpt":"El presidente de Ucrania, Volodymyr Zelensky, dijo que est\u00e1 dispuesto a liberar a los soldados norcoreanos capturados por Ucrania en la regi\u00f3n rusa de Kursk a cambio de los soldados ucranianos que permanezcan cautivos en Rusia.\u201cUcrania est\u00e1 dispuesta a entregarle los soldados a (el l\u00edder norcoreano) Kim Jong Un si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456911,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/23\/soldados-norcoreanos-muertos-heridos-kursk-zelensky-trax\/","url_meta":{"origin":1456699,"position":2},"title":"M\u00e1s de 3.000 soldados norcoreanos muertos o heridos en la regi\u00f3n rusa de Kursk, seg\u00fan Zelensky","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Ucrania estima que m\u00e1s de 3.000 soldados norcoreanos han muerto o han resultado heridos en la regi\u00f3n rusa de Kursk, al oeste del pa\u00eds, dijo el lunes el presidente de Ucrania Volodymyr Zelensky.Se cree que los soldados norcoreanos han sufrido grandes p\u00e9rdidas en la regi\u00f3n, seg\u00fan funcionarios estadounidenses y ucranianos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458098,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/01\/tropas-norcoreanas-retiran-bajas-trax\/","url_meta":{"origin":1456699,"position":3},"title":"Soldados norcoreanos se retiran del frente de batalla en Kursk tras fuertes p\u00e9rdidas, seg\u00fan funcionarios ucranianos","author":"","date":"febrero 1, 2025","format":false,"excerpt":"Los militares norcoreanas no fueron vistos en el frente en la regi\u00f3n rusa de Kursk durante varias semanas, dijo un funcionario militar ucraniano este viernes, en medio de informes de bajas masivas entre las fuerzas de Pyongyang.\u201cLa presencia de soldados de la Rep\u00fablica Popular De Corea (DPRK, en ingl\u00e9s) no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455417,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/10\/29\/soldados-norcoreanos-comandos-rusos-frente-ucrania-trax\/","url_meta":{"origin":1456699,"position":4},"title":"Los soldados norcoreanos aprenden comandos rusos y podr\u00edan ser enviados al frente de Ucrania, dicen legisladores surcoreanos","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN) -- Los soldados norcoreanos podr\u00edan estar siendo preparados para un traslado al frente de la guerra de Rusia contra Ucrania despu\u00e9s de que se les ense\u00f1aron comandos rusos b\u00e1sicos, dijeron este martes legisladores surcoreanos a la agencia de noticias Yonhap, citando a funcionarios de inteligencia del pa\u00eds.Unos 10.000 soldados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455339,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/10\/24\/avistan-tropas-corea-norte-rusia-ucrania-trax\/","url_meta":{"origin":1456699,"position":5},"title":"Avistan militares norcoreanos en la regi\u00f3n fronteriza entre Rusia y Ucrania, dice Kyiv","author":"","date":"octubre 24, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un grupo de soldados norcoreanos fue avistado en la regi\u00f3n rusa de Kursk, un \u00e1rea de operaciones militares en curso, seg\u00fan anunci\u00f3 este jueves el servicio de inteligencia militar de Ucrania.Despu\u00e9s de recibir entrenamiento en la zona oriental de Rusia, algunos militares se dirigieron ahora a la regi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456699"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456699\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}