{"id":1456715,"date":"2024-12-18T09:03:45","date_gmt":"2024-12-18T17:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/"},"modified":"2024-12-18T09:03:45","modified_gmt":"2024-12-18T17:03:45","slug":"playas-rusia-mar-negro-petroleo-naufragio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","title":{"rendered":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros"},"content":{"rendered":"<p>Largos tramos de la costa rusa del mar Negro est\u00e1n cubiertos de petr\u00f3leo derramado por el naufragio de dos petroleros rusos durante el fin de semana y el presidente ucraniano, Volodymyr Zelensky, advirti\u00f3 de un \u201cdesastre ambiental\u201d.<\/p>\n<p>Los videos geolocalizados por CNN muestran olas ennegrecidas que arrastran combustible pesado de baja calidad, conocido como mazut, hacia las costas de la regi\u00f3n rusa de Krasnodar, cerca del estrecho de Kerch, entre Rusia continental y Crimea ocupada.<\/p>\n<p>En un video, se ve a un p\u00e1jaro, con sus alas cubiertas de aceite, graznando angustiado mientras est\u00e1 sentado en la arena y es azotado por las olas, incapaz de levantar sus alas para volar.<\/p>\n<p>El derrame de petr\u00f3leo ha afectado al menos a 60 kil\u00f3metros de costa, seg\u00fan inform\u00f3 Greenpeace Ucrania el martes. \u201cVarias localidades han declarado la situaci\u00f3n de emergencia. Se ha registrado la muerte de aves contaminadas con mazut\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Los dos petroleros, el Volgoneft 212 y el Volgoneft 239, transportaban miles de toneladas de combustible en el estrecho de Kerch cuando se vieron en peligro el domingo, con vientos de hasta 70 km\/h. Un video de principios de esta semana mostr\u00f3 los restos del Volgoneft 212 arrastrados por la corriente a unos 10 kil\u00f3metros al sur del inicio del puente de Kerch en Rusia.<\/p>\n<p>Zelensky critic\u00f3 a Mosc\u00fa por enviar barcos \u201cviejos y mal mantenidos\u201d a condiciones tormentosas.<\/p>\n<p>\u201cEsos barcos ten\u00edan casi 50 a\u00f1os. No deber\u00edan haber estado en funcionamiento, especialmente en esta parte de las aguas y en esta temporada. En este momento, nuestro mar se enfrenta a otro desastre ambiental causado por Rusia\u201d, dijo Zelenski el martes.<\/p>\n<p>Ambrey, una empresa de seguridad mar\u00edtima, dijo que uno de los petroleros transportaba 4.300 toneladas de mazut. Dijo que estos buques de la era sovi\u00e9tica \u201cse han roto y hundido repetidamente en los \u00faltimos a\u00f1os durante el mal tiempo\u201d, se\u00f1alando el naufragio de un petrolero mientras estaba anclado en 2021. Ambrey dijo que Rusia estaba luchando por reemplazar su vieja flota debido a las sanciones occidentales.<\/p>\n<p>Zelensky dijo que el presidente ruso, Vladimir Putin, \u201cusa estos petroleros para financiar su guerra\u201d, enviando petr\u00f3leo desde el mar Negro.<\/p>\n<p>Veniamin Kondratiev, gobernador de la regi\u00f3n rusa de Krasnodar, dijo que los esfuerzos para limpiar los derrames de petr\u00f3leo arrastrados a la costa se estaban viendo obstaculizados por el clima tormentoso.<\/p>\n<p>\u201cEl clima est\u00e1 complicando la situaci\u00f3n, la tormenta en el mar no cesa, por lo que es dif\u00edcil predecir cu\u00e1nto tiempo llevar\u00e1 limpiar completamente la costa\u201d, dijo Kondratiev en una publicaci\u00f3n de Telegram el martes. Anteriormente hab\u00eda dicho que el petr\u00f3leo hab\u00eda llegado a decenas de kil\u00f3metros de la costa rusa.<\/p>\n<p>Videos geolocalizados por CNN muestran que una playa cercana a Anapa, al norte de la ciudad de Novorossiysk, se ha inundado de petr\u00f3leo. \u201cLos lugare\u00f1os dicen que el hedor es terrible\u201d, escribi\u00f3 en Telegram la ecologista rusa Zhora Kavanosyan.<\/p>\n<p>En un discurso ante la Fuerza Expedicionaria Conjunta, una alianza militar del norte de Europa liderada por el Reino Unido, que se reuni\u00f3 el martes en la capital de Estonia, Tallin, Zelensky pidi\u00f3 a la comunidad internacional que sancione la flota de petroleros \u201cen la sombra\u201d de Rusia.<\/p>\n<p>\u201cEsto no solo cortar\u00e1 la financiaci\u00f3n de la guerra por parte de Rusia, sino que tambi\u00e9n proteger\u00e1 la naturaleza\u201d, dijo.<\/p>\n<p><em>Catherine Nicholls de CNN contribuy\u00f3 con este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Largos tramos de la costa rusa del mar Negro est\u00e1n cubiertos de petr\u00f3leo derramado por el naufragio de dos petroleros rusos durante el fin de semana y el presidente ucraniano, Volodymyr Zelensky, advirti\u00f3 de un \u201cdesastre ambiental\u201d. Los videos geolocalizados por CNN muestran olas ennegrecidas que arrastran combustible pesado de baja calidad, conocido como mazut, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456715","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias\" \/>\n<meta property=\"og:description\" content=\"Largos tramos de la costa rusa del mar Negro est\u00e1n cubiertos de petr\u00f3leo derramado por el naufragio de dos petroleros rusos durante el fin de semana y el presidente ucraniano, Volodymyr Zelensky, advirti\u00f3 de un \u201cdesastre ambiental\u201d. Los videos geolocalizados por CNN muestran olas ennegrecidas que arrastran combustible pesado de baja calidad, conocido como mazut, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T17:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros\",\"datePublished\":\"2024-12-18T17:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\"},\"wordCount\":610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\",\"name\":\"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T17:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias","og_description":"Largos tramos de la costa rusa del mar Negro est\u00e1n cubiertos de petr\u00f3leo derramado por el naufragio de dos petroleros rusos durante el fin de semana y el presidente ucraniano, Volodymyr Zelensky, advirti\u00f3 de un \u201cdesastre ambiental\u201d. Los videos geolocalizados por CNN muestran olas ennegrecidas que arrastran combustible pesado de baja calidad, conocido como mazut, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T17:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/"},"author":{"name":"","@id":""},"headline":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros","datePublished":"2024-12-18T17:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/"},"wordCount":610,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","name":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T17:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las playas rusas del Mar Negro se inundan de petr\u00f3leo por el naufragio de dos buques petroleros","url":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/playas-rusia-mar-negro-petroleo-naufragio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T17:03:45Z","datePublished":"2024-12-18T17:03:45Z","dateModified":"2024-12-18T17:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las playas rusas del Mar Negro se inundan de petr\\u00f3leo por el naufragio de dos buques petroleros\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/18\\\/playas-rusia-mar-negro-petroleo-naufragio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2024\\\/12\\\/18\\\/playas-rusia-mar-negro-petroleo-naufragio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T17:03:45Z\",\"datePublished\":\"2024-12-18T17:03:45Z\",\"dateModified\":\"2024-12-18T17:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456959,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/25\/voluntarios-limpian-petroleo-mar-negro-ayuda-putin-trax\/","url_meta":{"origin":1456715,"position":0},"title":"&#171;Gente corriente con palas&#187;: voluntarios que limpian el vertido de petr\u00f3leo del mar Negro piden ayuda a Putin","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"Los voluntarios que ayudan a limpiar el derrame de petr\u00f3leo en la costa rusa del mar Negro est\u00e1n pidiendo m\u00e1s ayuda al presidente de Rusia, Vladimir Putin, mientras luchan contra el caos ambiental en m\u00e1s de 56 kil\u00f3metros de costa.Dos petroleros rusos que transportaban miles de toneladas de combustible resultaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456652,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/16\/buques-rusia-petroleo-mar-negro-trax\/","url_meta":{"origin":1456715,"position":1},"title":"Buques petroleros de Rusia derraman petr\u00f3leo cerca del Mar Negro tras resultar da\u00f1ados en una tormenta","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"Dos petroleros rusos que transportaban miles de toneladas de combustible resultaron gravemente da\u00f1ados durante una tormenta cerca del Mar Negro este fin de semana, lo que caus\u00f3 un derrame de petr\u00f3leo, seg\u00fan los medios estatales rusos.Los buques Volgoneft 212 y Volgoneft 239 se encontraban en el estrecho de Kerch, entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468824,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/29\/flota-encubierta-rusa-explosion-ucrania-trax\/","url_meta":{"origin":1456715,"position":2},"title":"Ucrania afirma que atac\u00f3 petroleros de la &#171;flota fantasma&#187; de Rusia con drones submarinos en el mar Negro","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Drones submarinos ucranianos atacaron a dos petroleros pertenecientes a la \u201cflota fantasma\u201d rusa en el mar Negro, seg\u00fan un funcionario de los servicios de seguridad ucranianos (SBU).Ucrania se atribuy\u00f3 los ataques tras las explosiones que alcanzaron a los dos buques entre el viernes y el s\u00e1bado.Una fuente de seguridad ucraniana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459670,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/03\/08\/concluye-desguace-petrolero-ruso-vertido-mar-negro-efe\/","url_meta":{"origin":1456715,"position":3},"title":"Concluye el desguace del petrolero ruso que caus\u00f3 un vertido de fuel en el mar Negro","author":"","date":"marzo 8, 2025","format":false,"excerpt":"Las autoridades rusas anunciaron este s\u00e1bado el fin del desguace de uno de los petroleros rusos que naufragaron en diciembre pasado en el mar Negro y causaron el vertido de miles de toneladas de fuel.\u201cVolgoneft-239 finalmente lev\u00f3 ancla. El 8 de marzo las \u00faltimas partes del petrolero -la h\u00e9lice y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457470,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/13\/rusia-grupo-trabajo-emergencia-derrame-petroleo-trax\/","url_meta":{"origin":1456715,"position":4},"title":"Rusia crea un grupo de trabajo de emergencia ante la propagaci\u00f3n del derrame de petr\u00f3leo en el estrecho de Kerch","author":"","date":"enero 13, 2025","format":false,"excerpt":"Un equipo de emergencia lleg\u00f3 el domingo a la regi\u00f3n sure\u00f1a rusa de Krasnodar mientras un derrame de petr\u00f3leo en el estrecho de Kerch proveniente de dos petroleros afectados por una tormenta contin\u00faa propag\u00e1ndose un mes despu\u00e9s de que fue detectado por primera vez, dijeron funcionarios.El grupo de trabajo, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470116,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/15\/cuantos-petroleros-incauto-eeuu-orix\/","url_meta":{"origin":1456715,"position":5},"title":"\u00bfCu\u00e1ntos petroleros vinculados a Venezuela ha incautado EE.UU.? Cronolog\u00eda de las acciones del Gobierno de Trump","author":"","date":"enero 15, 2026","format":false,"excerpt":"Estados Unidos inform\u00f3 este jueves que hab\u00eda incautado un barco petrolero en el mar Caribe, en un anuncio que se ha vuelto casi habitual en las \u00faltimas semanas: desde principios de diciembre, las fuerzas del pa\u00eds norteamericano se han hecho con el control de al menos seis petroleros vinculados de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1456715"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1456715\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1456715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1456715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1456715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}