{"id":1465724,"date":"2025-08-21T05:03:48","date_gmt":"2025-08-21T12:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/"},"modified":"2025-08-21T05:03:48","modified_gmt":"2025-08-21T12:03:48","slug":"streamer-frances-violencia-muerte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","title":{"rendered":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;"},"content":{"rendered":"<p>La polic\u00eda francesa est\u00e1 investigando la muerte de un popular streamer, que falleci\u00f3 durante una transmisi\u00f3n de casi 12 d\u00edas despu\u00e9s de sufrir aparentemente un trato abusivo y humillante mientras los espectadores miraban en vivo.<\/p>\n<p>Rapha\u00ebl Graven, de 46 a\u00f1os, conocido en l\u00ednea como Jean Pormanove o JP, es uno de los streamers m\u00e1s importantes de <a href=\"https:\/\/www.cnn.com\/world\/europe\/france\">Francia<\/a> en la plataforma Kick y muri\u00f3 este lunes.<\/p>\n<p>La fiscal\u00eda de Niza inform\u00f3 a CNN que se ha abierto una investigaci\u00f3n sobre su muerte y se ha ordenado una autopsia. Hasta el momento, las autoridades no han anunciado cargos relacionados con la muerte de Pormanove.<\/p>\n<p>El veterano militar de 46 a\u00f1os hab\u00eda conseguido m\u00e1s de un mill\u00f3n de seguidores en diferentes plataformas mientras se transmit\u00eda a s\u00ed mismo jugando videojuegos. A menudo aparec\u00eda en desaf\u00edos extremos donde otros streamers lo agred\u00edan o humillaban.<\/p>\n<p>Desde 2023, hab\u00eda aparecido con varios otros streamers, principalmente Owen Cenazandotti, conocido como Naruto online, y Safine Hamadi, quienes participaron en su \u00faltima transmisi\u00f3n en vivo.<\/p>\n<p>Cenazandotti anunci\u00f3 su fallecimiento el lunes en Instagram. En la transmisi\u00f3n en vivo que aparentemente mostr\u00f3 su fallecimiento, tras dejar de moverse, los espectadores donaron dinero para enviar mensajes alertando a los streamers que dorm\u00edan sobre el estado de Pormanove.<\/p>\n<p>En decenas de videos de transmisiones en vivo anteriores revisados \u200b\u200bpor CNN, Pormanove parece ser el blanco de bromas, acoso, ataques f\u00edsicos y acrobacias degradantes.<\/p>\n<p>Los videos de sus transmisiones en vivo conjuntas muestran a los compa\u00f1eros streamers de Pormanove compitiendo para ver cu\u00e1nto tiempo pod\u00edan estrangularlo, otros lo muestran recibiendo disparos de bolas de pintura o rociado con agua.<\/p>\n<p>No qued\u00f3 claro hasta qu\u00e9 punto Pormanove se someti\u00f3 voluntariamente a la violencia o si esta fue preparada en parte.<\/p>\n<p>Gracias a las donaciones de los suscriptores, el grupo gan\u00f3 dinero con las transmisiones en vivo. En la \u00faltima transmisi\u00f3n de Pormanove, un contador en la parte superior de la pantalla indicaba que el grupo hab\u00eda ganado unos 36.000 euros (US$ 42.000) gracias a la transmisi\u00f3n que dur\u00f3 varios d\u00edas.<\/p>\n<p>Durante la \u00faltima transmisi\u00f3n en vivo de Pormanove, que aparentemente dur\u00f3 casi 300 horas, los participantes se despertaron con el ruido de una motocicleta en su habitaci\u00f3n compartida o con un soplador de hojas. En un momento dado, Pormanove parece despertarse cuando le arrojan un cubo de agua encima.<\/p>\n<p>En una entrevista con BFMTV, afiliada de CNN, Yassin Sadouni, abogado de Cenazandotti, dijo que Pormanove sufr\u00eda de problemas cardiovasculares.<\/p>\n<p>En un video, Pormanove habl\u00f3 de tener que tomar medicamentos. En otro, Cenazandotti supuestamente lee mensajes que Pormanove le envi\u00f3 a su madre, en los que se queja de sentirse \u201cprisionero\u201d por sus compa\u00f1eros de transmisi\u00f3n.<\/p>\n<p>\u201cEl juego est\u00e1 yendo demasiado lejos\u201d, dijo Cenazandotti en su mensaje, durante la \u00faltima transmisi\u00f3n en vivo de Pormanove.<\/p>\n<p>\u201cMe siento como si estuviera prisionero de su concepto de mierda\u201d, dijo Cenazandotti que escribi\u00f3 Pormanove.<\/p>\n<p>No est\u00e1 claro a qui\u00e9n se refer\u00eda exactamente Pormanove y en un clip posterior le dice a Cenazandotti: \u201cYa sabes c\u00f3mo soy cuando estoy enojado\u201d en referencia a los mensajes.<\/p>\n<p>En otro clip, su madre reprende a Pormanove por tel\u00e9fono por dejar que los compa\u00f1eros de transmisi\u00f3n le afeiten partes del cabello.<\/p>\n<p>\u201c\u00bfEst\u00e1s orgulloso de tu pelo? \u00bfViste lo que te hizo?\u201d, dijo. \u201cTe est\u00e1n tratando fatal\u201d.<\/p>\n<p>Sadouni, abogado de Cenazandotti, dijo a BFMTV que la madre de Pormanove particip\u00f3 en escenas planificadas con los streamers.<\/p>\n<p>Un tema com\u00fan en las discusiones con sus compa\u00f1eros de transmisi\u00f3n fue el deseo de Pormanove de casarse y tener hijos, una esperanza que a menudo provoc\u00f3 burlas aparentes de los transmisores.<\/p>\n<p>En un video de 2024, se le pregunt\u00f3 a Pormanove c\u00f3mo esperaba ser recordado cuando muriera.<\/p>\n<p>\u201cSin esposa, sin hijos. \u00a1Pero qu\u00e9 buen tipo! \u2014dijo Pormanove\u2014. Yo, en lo que pienso ahora, es en dejar huella\u201d.<\/p>\n<p>Sadouni dijo que Cenazandotti, conocido por su nombre de usuario Naruto, no ten\u00eda nada que ver con la muerte de Pormanove y dijo que todos los incidentes contra Pormanove fueron planeados.<\/p>\n<p>\u201cMi cliente est\u00e1 dispuesto a ser escuchado y a proporcionar toda la informaci\u00f3n \u00fatil\u201d, declar\u00f3 este martes a BFMTV, afiliada de CNN. Cenazandotti tambi\u00e9n present\u00f3 una denuncia ante las autoridades por acoso en l\u00ednea desde la muerte de Pormanove, seg\u00fan Sadouni.<\/p>\n<p>CNN se comunic\u00f3 con la madre de Pormanove y con Hamadi para solicitar comentarios.<\/p>\n<p>Cenazandotti y Hamadi fueron detenidos brevemente como parte de una investigaci\u00f3n policial sobre la humillaci\u00f3n de personas vulnerables en enero de 2025, seg\u00fan BFMTV, afiliada de CNN.<\/p>\n<p>Seg\u00fan el fiscal de Niza, negaron haber cometido ning\u00fan delito y no fueron acusados \u200b\u200bde ning\u00fan delito.<\/p>\n<p>\u201cLa muerte de Jean Pormanove y la violencia que sufri\u00f3 son un horror absoluto\u201d, dijo la secretaria de Estado francesa de Inteligencia Artificial y Asuntos Digitales, Clara Chappaz, en una publicaci\u00f3n el martes X.<\/p>\n<p>\u201cJean Pormanove fue humillado y maltratado durante meses en directo en la plataforma Kick\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Kick, la plataforma de streaming que utilizaron los streamers, dijo que todos los involucrados en la transmisi\u00f3n hab\u00edan sido prohibidos \u201cen espera de la investigaci\u00f3n en curso\u201d, con la que el sitio cooperar\u00e1, seg\u00fan una declaraci\u00f3n a CNN este mi\u00e9rcoles.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda francesa est\u00e1 investigando la muerte de un popular streamer, que falleci\u00f3 durante una transmisi\u00f3n de casi 12 d\u00edas despu\u00e9s de sufrir aparentemente un trato abusivo y humillante mientras los espectadores miraban en vivo. Rapha\u00ebl Graven, de 46 a\u00f1os, conocido en l\u00ednea como Jean Pormanove o JP, es uno de los streamers m\u00e1s importantes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465724","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &quot;reto extremo&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &quot;reto extremo&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"La polic\u00eda francesa est\u00e1 investigando la muerte de un popular streamer, que falleci\u00f3 durante una transmisi\u00f3n de casi 12 d\u00edas despu\u00e9s de sufrir aparentemente un trato abusivo y humillante mientras los espectadores miraban en vivo. Rapha\u00ebl Graven, de 46 a\u00f1os, conocido en l\u00ednea como Jean Pormanove o JP, es uno de los streamers m\u00e1s importantes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-21T12:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;\",\"datePublished\":\"2025-08-21T12:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\"},\"wordCount\":939,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\",\"name\":\"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un \\\"reto extremo\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-21T12:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un \"reto extremo\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un \"reto extremo\" - Noticias","og_description":"La polic\u00eda francesa est\u00e1 investigando la muerte de un popular streamer, que falleci\u00f3 durante una transmisi\u00f3n de casi 12 d\u00edas despu\u00e9s de sufrir aparentemente un trato abusivo y humillante mientras los espectadores miraban en vivo. Rapha\u00ebl Graven, de 46 a\u00f1os, conocido en l\u00ednea como Jean Pormanove o JP, es uno de los streamers m\u00e1s importantes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-21T12:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/"},"author":{"name":"","@id":""},"headline":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;","datePublished":"2025-08-21T12:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/"},"wordCount":939,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","name":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un \"reto extremo\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-21T12:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Streamer franc\u00e9s muere durante una transmisi\u00f3n en vivo mientras hac\u00eda un &#171;reto extremo&#187;","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/streamer-frances-violencia-muerte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-21T12:03:48Z","datePublished":"2025-08-21T12:03:48Z","dateModified":"2025-08-21T12:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Streamer franc\\u00e9s muere durante una transmisi\\u00f3n en vivo mientras hac\\u00eda un &#171;reto extremo&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/21\\\/streamer-frances-violencia-muerte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/21\\\/streamer-frances-violencia-muerte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-21T12:03:48Z\",\"datePublished\":\"2025-08-21T12:03:48Z\",\"dateModified\":\"2025-08-21T12:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462363,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/14\/asesinan-influencer-tiktok-transmision-en-vivo-zapopan-trax\/","url_meta":{"origin":1465724,"position":0},"title":"Asesinan a influencer de TikTok durante transmisi\u00f3n en vivo en Zapopan, M\u00e9xico","author":"","date":"mayo 14, 2025","format":false,"excerpt":"Valeria M\u00e1rquez estaba dirigi\u00e9ndose a sus seguidores de TikTok en una transmisi\u00f3n en vivo desde su sal\u00f3n de belleza en Zapopan, M\u00e9xico, cuando alguien lleg\u00f3 a su puerta para entregar un peque\u00f1o paquete.\u201c\u00a1Es un cerdito!\u201d, exclam\u00f3 la influencer de belleza de 23 a\u00f1os a sus espectadores y desenvolv\u00eda el animal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473137,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/streaming-vida-twitch-247-trax\/","url_meta":{"origin":1465724,"position":1},"title":"Conoc\u00ed a la mujer que transmite su vida 24\/7 en streaming de Twitch y me impact\u00f3","author":"","date":"abril 14, 2026","format":false,"excerpt":"He estado cubriendo los extremos de internet y c\u00f3mo afectan nuestras vidas reales, fuera de l\u00ednea, desde hace m\u00e1s de una d\u00e9cada.He pasado incontables horas adentr\u00e1ndome en madrigueras de conejo en l\u00ednea. Pas\u00e9 meses en la carretera siguiendo a un culto itinerante. Incluso me vi arrastrado por la multitud en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473337,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","url_meta":{"origin":1465724,"position":2},"title":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista","author":"","date":"abril 20, 2026","format":false,"excerpt":"David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451395,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/07\/25\/ola-calor-valle-de-la-muerte-temperaturas-49c-turista-trax\/","url_meta":{"origin":1465724,"position":3},"title":"Un turista belga sufre quemaduras de tercer grado en los pies mientras caminaba por el Valle de la Muerte con temperaturas superiores a 49\u00b0C","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- Un turista belga de 42 a\u00f1os fue hospitalizado tras sufrir quemaduras de tercer grado en los pies este s\u00e1bado mientras caminaba por las dunas de arena de la parte californiana del Parque Nacional del Valle de la Muerte mientras las temperaturas superaban los 49\u00b0C, seg\u00fan el Servicio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473297,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/18\/d4vd-asesinato-celeste-rivas-hernandez-trax\/","url_meta":{"origin":1465724,"position":4},"title":"Un autom\u00f3vil abandonado, una fotograf\u00eda y una ni\u00f1a desaparecida: \u00bfQu\u00e9 llev\u00f3 al arresto de d4vd bajo sospecha de asesinato?","author":"","date":"abril 18, 2026","format":false,"excerpt":"Meses despu\u00e9s de que el cuerpo de una ni\u00f1a fuera hallado en el maletero de su coche abandonado, el cantante d4vd fue arrestado cerca del dep\u00f3sito de veh\u00edculos de Los \u00c1ngeles donde se descubrieron sus restos.La fiscal\u00eda ahora evaluar\u00e1 si presenta cargos penales contra el artista de pop alternativo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451070,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/07\/12\/velada-ano-iv-ibai-hora-participantes-como-ver-orix\/","url_meta":{"origin":1465724,"position":5},"title":"Velada del a\u00f1o IV de Ibai: a qu\u00e9 hora es, qui\u00e9nes son los participantes y c\u00f3mo ver","author":"","date":"julio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Ibai Llanos, el popular streamer espa\u00f1ol, organiza la Velada del a\u00f1o IV, un evento deportivo que re\u00fane cada a\u00f1o a reconocidos creadores de contenido del mundo digital, as\u00ed como a otros famosos, que se enfrentan en una serie de combates de boxeo transmitidos a trav\u00e9s de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465724"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465724\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}