{"id":1465738,"date":"2025-08-21T15:03:44","date_gmt":"2025-08-21T22:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/"},"modified":"2025-08-21T15:03:44","modified_gmt":"2025-08-21T22:03:44","slug":"atacante-armado-universidad-villanova-tiroteo-pensilvania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","title":{"rendered":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse"},"content":{"rendered":"<p>La polic\u00eda responde a un reporte de un atacante armado en la Universidad de Villanova, en Pensilvania, seg\u00fan inform\u00f3 el Departamento de Polic\u00eda de Radnor Township en su <a href=\"https:\/\/www.facebook.com\/radnorpolice\/posts\/pfbid02MLRwFEyJREnUxCU1TpMQRbdgc3BG8J3rbjdcngyMNsy3umWAo6FJZHfDvKQB5A4Hl\">p\u00e1gina de Facebook.<\/a><\/p>\n<p>Se pide a todos los estudiantes y residentes cercanos que permanezcan en resguardo.<\/p>\n<p>La universidad tambi\u00e9n public\u00f3 en <a href=\"https:\/\/www1.villanova.edu\/villanova\/alerts\/current-alert.html\">su sitio web<\/a> que las personas en el campus deben mantenerse alejadas de la Facultad de Derecho Scarpa Hall, trasladarse a un lugar seguro y cerrar o bloquear las puertas.<\/p>\n<p>Las autoridades est\u00e1n realizando una inspecci\u00f3n en la Facultad de Derecho para buscar posibles v\u00edctimas o un sospechoso, pero la naturaleza exacta del incidente a\u00fan no est\u00e1 clara, de acuerdo con una fuente policial.<\/p>\n<p>Polic\u00edas armados pod\u00edan verse en el techo mientras decenas de agentes y bomberos respond\u00edan en el campus, seg\u00fan mostr\u00f3 un video de la afiliada de CNN WPVI.<\/p>\n<p>La orientaci\u00f3n y el registro para nuevos estudiantes comenzaron este jueves y est\u00e1n programados hasta el s\u00e1bado, mientras que las clases inician el lunes, de acuerdo con el <a href=\"https:\/\/live-villanova-catalog.cleancatalog.io\/academic-calendar-20252026\">calendario acad\u00e9mico de la universidad.<\/a><\/p>\n<p>Los estudiantes recibieron un correo electr\u00f3nico sobre el tiroteo alrededor de las 4:35 p.m., hora de Miami, mientras se celebraba una <a href=\"https:\/\/www1.villanova.edu\/university\/student-life\/orientation\/schedule.html\">misa de apertura <\/a>en Rowen Campus Green. Despu\u00e9s de la misa estaba previsto un picnic familiar.<\/p>\n<p>Villanova es una universidad cat\u00f3lica privada en los suburbios de Filadelfia y es la alma mater del papa Le\u00f3n XIV.<\/p>\n<p>Estos reportes se producen horas despu\u00e9s de que la Universidad de Tennessee en Chattanooga emitiera una alerta de atacante armado y el campus fuera puesto en confinamiento. Posteriormente, la polic\u00eda inform\u00f3 que no se encontr\u00f3 evidencia de una amenaza. Una fuente policial dijo a CNN que las autoridades investigan el incidente en Tennessee como un posible caso de \u201cswatting\u201d, es decir, una falsa alarma a la polic\u00eda.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda responde a un reporte de un atacante armado en la Universidad de Villanova, en Pensilvania, seg\u00fan inform\u00f3 el Departamento de Polic\u00eda de Radnor Township en su p\u00e1gina de Facebook. Se pide a todos los estudiantes y residentes cercanos que permanezcan en resguardo. La universidad tambi\u00e9n public\u00f3 en su sitio web que las personas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465738","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias\" \/>\n<meta property=\"og:description\" content=\"La polic\u00eda responde a un reporte de un atacante armado en la Universidad de Villanova, en Pensilvania, seg\u00fan inform\u00f3 el Departamento de Polic\u00eda de Radnor Township en su p\u00e1gina de Facebook. Se pide a todos los estudiantes y residentes cercanos que permanezcan en resguardo. La universidad tambi\u00e9n public\u00f3 en su sitio web que las personas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-21T22:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse\",\"datePublished\":\"2025-08-21T22:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\"},\"wordCount\":357,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\",\"name\":\"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-21T22:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias","og_description":"La polic\u00eda responde a un reporte de un atacante armado en la Universidad de Villanova, en Pensilvania, seg\u00fan inform\u00f3 el Departamento de Polic\u00eda de Radnor Township en su p\u00e1gina de Facebook. Se pide a todos los estudiantes y residentes cercanos que permanezcan en resguardo. La universidad tambi\u00e9n public\u00f3 en su sitio web que las personas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-21T22:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/"},"author":{"name":"","@id":""},"headline":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse","datePublished":"2025-08-21T22:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/"},"wordCount":357,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","name":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-21T22:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Polic\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-21T22:03:44Z","datePublished":"2025-08-21T22:03:44Z","dateModified":"2025-08-21T22:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Polic\\u00eda atiende reporte de tiroteo en la Universidad de Villanova y estudiantes reciben orden de resguardarse\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/21\\\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/21\\\/atacante-armado-universidad-villanova-tiroteo-pensilvania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-21T22:03:44Z\",\"datePublished\":\"2025-08-21T22:03:44Z\",\"dateModified\":\"2025-08-21T22:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448457,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/24\/manifestantes-universidad-columbia-fecha-limite-desmantelar-campamento-trax\/","url_meta":{"origin":1465738,"position":0},"title":"Universidad de Columbia extiende negociaciones con estudiantes que protestan por el campamento despu\u00e9s del &#171;di\u00e1logo constructivo&#187; durante la noche","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --La Universidad de Columbia y los estudiantes que protestan continuar\u00e1n las negociaciones sobre el desmantelamiento del campamento propalestino durante las pr\u00f3ximas 48 horas, seg\u00fan un portavoz de la universidad.\"Estamos logrando avances importantes con los representantes del campamento de estudiantes en el c\u00e9sped oeste\", afirm\u00f3 un portavoz de la universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469121,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","url_meta":{"origin":1465738,"position":1},"title":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"Una persona muri\u00f3 y otra result\u00f3 herida tras un tiroteo en la Universidad Estatal de Kentucky que interrumpi\u00f3 los ex\u00e1menes finales del semestre de los estudiantes antes de que salieran de vacaciones de invierno, seg\u00fan la polic\u00eda.El sospechoso est\u00e1 bajo custodia, dijo la polic\u00eda.El gobernador Andy Beshear dijo que est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448359,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/21\/rabino-recomienda-judios-volver-casa-protestas-universidad-columbia-trax\/","url_meta":{"origin":1465738,"position":2},"title":"La Universidad de Columbia enfrenta una grave crisis mientras un rabino pide a los estudiantes jud\u00edos que \u201cregresen a casa\u201d","author":"","date":"abril 21, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia se enfrenta a una crisis en toda regla de cara a la Pascua, cuando un rabino vinculado a la escuela de la Ivy League inst\u00f3 a los estudiantes jud\u00edos a quedarse en casa y los tensos enfrentamientos en el campus generaron la condena de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445958,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/02\/23\/estudiante-muerta-universidad-georgia-laken-hope-riley-trax\/","url_meta":{"origin":1465738,"position":3},"title":"La Polic\u00eda identifica a una persona de inter\u00e9s en el caso de Laken Hope Riley, estudiante hallada muerta en la Universidad de Georgia","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) \u2014 La Polic\u00eda de la Universidad de Georgia identific\u00f3 a una persona relevante para la investigaci\u00f3n a la que interroga en relaci\u00f3n con la muerte de Laken Hope Riley, estudiante de enfermer\u00eda de 22 a\u00f1os cuyo cuerpo fue hallado en el campus este jueves, dijo un portavoz de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462957,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/29\/trump-marcha-atras-harvard-estudiantes-internacionales-trax\/","url_meta":{"origin":1465738,"position":4},"title":"El Gobierno de Trump da marcha atr\u00e1s: Harvard tiene 30 d\u00edas para defender su derecho de recibir estudiantes internacionales","author":"","date":"mayo 29, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 este mi\u00e9rcoles que le dar\u00e1 a Harvard un mes para presentar pruebas que impugnen su intento de despojar a la universidad de su capacidad para recibir estudiantes internacionales.La medida parece dise\u00f1ada para resolver una impugnaci\u00f3n legal que la universidad present\u00f3 la semana pasada contra esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448388,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/22\/tensiones-protestas-propalestina-campus-universidades-columbia-nyu-trax\/","url_meta":{"origin":1465738,"position":5},"title":"Clases del campus principal de la Universidad de Columbia ser\u00e1n h\u00edbridas hasta fin de semestre; estudiantes y profesores de NYU fueron detenidos durante protestas","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia, epicentro de las protestas propalestinas en los campus universitarios estadounidenses en los \u00faltimos d\u00edas, inform\u00f3 que todas las clases en su campus principal ser\u00e1n h\u00edbridas \u2014si la tecnolog\u00eda lo permite\u2014 hasta que finalice el semestre de primavera.\"La seguridad es nuestra m\u00e1xima prioridad mientras nos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465738"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465738\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}