{"id":1465793,"date":"2025-08-23T13:03:43","date_gmt":"2025-08-23T20:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/"},"modified":"2025-08-23T13:03:43","modified_gmt":"2025-08-23T20:03:43","slug":"trump-washington-detenciones-inmigrantes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","title":{"rendered":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes"},"content":{"rendered":"<p>Tras la toma de control de la fuerza policial de la ciudad de Washington y el despliegue de agentes federales y tropas en el distrito, la capital experiment\u00f3 una ca\u00edda moderada en los delitos reportados \u2014y un aumento mucho mayor en las detenciones de inmigrantes\u2014, seg\u00fan un an\u00e1lisis de CNN basado en datos gubernamentales.<\/p>\n<p>En la semana que comenz\u00f3 el 12 de agosto, el primer d\u00eda completo en que el Gobierno de Trump tom\u00f3 el control del Departamento de Polic\u00eda Metropolitana (MPD, por sus siglas en ingl\u00e9s), los delitos contra la propiedad bajaron aproximadamente un 19 % en comparaci\u00f3n con la semana anterior, y los delitos violentos disminuyeron alrededor de un 17 %, seg\u00fan los datos m\u00e1s recientes publicados por el MPD.<\/p>\n<p>Sin embargo, estas tendencias var\u00edan ampliamente seg\u00fan el tipo de delito. Mientras que los robos en general y los robos en veh\u00edculos disminuyeron en m\u00e1s del 40 %, otros hurtos se mantuvieron estables de una semana a otra y hubo un aumento del 6 % en los casos de allanamiento de morada y un incremento del 14 % en los casos de asalto con armas de fuego, seg\u00fan muestran los datos. Ha habido dos homicidios desde que el presidente Donald Trump firm\u00f3 su decreto para tomar el control del departamento, lo cual es consistente con lo que suced\u00eda en las \u00faltimas semanas en la ciudad de Washington, aunque ninguno desde el 13 de agosto.<\/p>\n<p>La disminuci\u00f3n general de la delincuencia se produce despu\u00e9s de que las agencias federales se hayan integrado con los agentes locales, colaborando en detenciones, registros, ejecuci\u00f3n de \u00f3rdenes judiciales y otras labores policiales locales mientras circulan por el distrito en veh\u00edculos que solo se identifican por sus luces azules y rojas intermitentes.<\/p>\n<p>Pero al mismo tiempo, la ola de agentes de ICE desplegados en el distrito ha impulsado un aumento mucho m\u00e1s dram\u00e1tico en las detenciones de inmigrantes.<\/p>\n<p>Desde el 7 de agosto, funcionarios federales han detenido a 300 personas en la ciudad de Washington que no tienen estatus migratorio legal, seg\u00fan inform\u00f3 la Administraci\u00f3n. Eso representa un incremento de m\u00e1s de diez veces respecto a las cifras habituales de detenciones de ICE en el distrito, seg\u00fan la revisi\u00f3n de CNN.<\/p>\n<p>Durante los primeros seis meses del mandato de Trump, la agencia detuvo en promedio a unos 12 inmigrantes por semana en la ciudad, seg\u00fan datos publicados por el Deportation Data Project, un grupo de investigaci\u00f3n vinculado a la Facultad de Derecho de la Universidad de California en Berkeley.<\/p>\n<p>Agentes de ICE siguen a los funcionarios del MPD, listos para intervenir si alguna persona detenida o interrogada ha excedido el tiempo de su visa o se encuentra en el pa\u00eds de manera ilegal, dijo un funcionario de las fuerzas del orden a CNN.<\/p>\n<p>En respuesta a los hallazgos de CNN, la portavoz de la Casa Blanca Abigail Jackson dijo que los medios estaban intentando restar importancia a los \u201cresultados excepcionales\u201d de la campa\u00f1a de Trump en Washington.<\/p>\n<p>\u201cLas ca\u00eddas en la criminalidad no son \u2018moderadas\u2019, son un cambio de vida para los incontables residentes y visitantes de la ciudad de Washington que no han sido asesinados, robados, v\u00edctimas de robo de autos o de delitos violentos en general en la \u00faltima semana\u201d, dijo Jackson. \u201cLa prioridad de esta operaci\u00f3n sigue siendo sacar a los criminales violentos de las calles, sin importar su estatus migratorio\u201d.<\/p>\n<p>Pero el notorio aumento en las cifras de inmigraci\u00f3n tambi\u00e9n dispara las preocupaciones de algunos l\u00edderes de la ciudad, incluida la alcaldesa Muriel Bowser, de que el verdadero prop\u00f3sito de la intervenci\u00f3n local de Trump es perseguir a inmigrantes indocumentados.<\/p>\n<p>Cuando se le pregunt\u00f3 el jueves si la declaraci\u00f3n de emergencia por crimen de Trump era un pretexto para aplicar su campa\u00f1a migratoria, Bowser dijo a los periodistas que una reciente orden de la secretaria de Justicia, Pam Bondi, \u201cse centr\u00f3 casi exclusivamente en la aplicaci\u00f3n de la ley migratoria y en el control de campamentos de personas sin hogar\u201d.<\/p>\n<p>\u201cAs\u00ed que los dejar\u00e9 sacar sus propias conclusiones\u201d, dijo Bowser.<\/p>\n<p>El fiscal de la ciudad de Washington ha presentado una demanda que impugna la orden de Bondi de ignorar las leyes de santuario vigentes en la capital, que hasta ahora limitaban la capacidad de la fuerza policial para cooperar con ICE en casos de inmigraci\u00f3n. Sin embargo, durante una audiencia la semana pasada, el juez federal que preside el caso indic\u00f3 que la autoridad de Trump bajo la Ley de Autonom\u00eda probablemente le permite ordenar a la Polic\u00eda que asista a ICE.<\/p>\n<p>Videos virales han circulado esta semana en la ciudad de Washington mostrando a agentes de ICE \u2014portando sus ahora caracter\u00edsticas mascarillas\u2014 mientras arrestaban a inmigrantes, incluidos algunos repartidores de comida, y en una ocasi\u00f3n rompiendo las ventanas de un auto para detener a dos hombres.<\/p>\n<p>Durante una noche de mayor presencia policial esta semana, CNN sigui\u00f3 a funcionarios que respond\u00edan a reportes de tiroteos, posesi\u00f3n de drogas y armas de fuego y un veh\u00edculo robado. Los federales se comunicaban por los canales de la polic\u00eda local mientras deten\u00edan y registraban veh\u00edculos y respond\u00edan a reportes de delitos, advirti\u00e9ndose mutuamente sobre las c\u00e1maras de velocidad de Washington.<\/p>\n<p>El MPD y sus socios federales tambi\u00e9n han establecido puntos de control de tr\u00e1fico durante la \u00faltima semana \u2014una herramienta policial poco com\u00fan en el distrito\u2014, incluido un gran ret\u00e9n con decenas de funcionarios y agentes en una autopista que sale de la ciudad.<\/p>\n<p>Se vio a agentes deteniendo a ciertos veh\u00edculos y realizando registros, aunque no estaba claro c\u00f3mo las fuerzas del orden determinaban a qui\u00e9n detener y a qui\u00e9n dejar pasar.<\/p>\n<p>Al caer la noche, la comunicaci\u00f3n policial se intensific\u00f3, con funcionarios locales y federales recorriendo juntos las calles en largas filas de luces intermitentes y autos sin identificar a alta velocidad.<\/p>\n<p>Pero algunos incidentes, como un tiroteo en una de las zonas de mayor delincuencia en el sureste de la ciudad, fueron atendidos \u00fanicamente por funcionarios del MPD.<\/p>\n<p>\u201cSolo vienen cuando pasa algo malo\u201d, dijo a CNN un residente que estaba afuera de la cinta policial tras el tiroteo. La noche del mi\u00e9rcoles, parec\u00eda haber relativamente pocos agentes federales patrullando las calles de Washington a pie, algo que era com\u00fan en los primeros d\u00edas desde la decisi\u00f3n de Trump. En lugar de eso, los agentes permanecieron en sus veh\u00edculos sin distintivos, esperando llamadas a trav\u00e9s de la radio.<\/p>\n<p>\u201cSimplemente parece una exageraci\u00f3n\u201d, dijo otro residente a CNN durante una salida nocturna en el popular corredor de U-Street, en la ciudad, lleno de restaurantes, clubes y tiendas de vapeo.<\/p>\n<p>Aproximadamente ocho de cada diez residentes de la ciudad de Washington se oponen a la toma de control policial de Trump y al despliegue de la Guardia Nacional y el FBI, seg\u00fan una encuesta de Washington Post-Schar School. El vicepresidente J. D. Vance y otras figuras del Gobierno han desestimado esos n\u00fameros, y afirmaron sin citar pruebas que el aumento de personal federal es popular entre los residentes locales.<\/p>\n<p>Es probable que el panorama completo del crimen en la ciudad de Washington bajo el control de Trump siga evolucionando. Las cifras analizadas por CNN se basan en los datos preliminares disponibles el viernes por la ma\u00f1ana y podr\u00edan cambiar con el tiempo, ya que algunos delitos tardan m\u00e1s en ser ingresados en la base de datos del Departamento. Adem\u00e1s, los datos no cubren todos los delitos de la ciudad.<\/p>\n<p>Las estad\u00edsticas tambi\u00e9n se han convertido en un factor de presi\u00f3n pol\u00edtica en la toma de control de Trump. El viernes, el presidente amenaz\u00f3 en redes sociales con \u201cuna toma federal completa y total de la ciudad\u201d, y acus\u00f3 a Bowser de promover \u201ccifras de criminalidad falsas y altamente inexactas\u201d.<\/p>\n<p>Mientras que funcionarios locales han se\u00f1alado una disminuci\u00f3n en la criminalidad en la ciudad de Washington en 2024 y 2025 tras un aumento en 2023, el Departamento de Justicia de Trump ahora est\u00e1 investigando si el MPD manipul\u00f3 los datos de criminalidad.<\/p>\n<p>La investigaci\u00f3n surge tras informes de que un comandante del MPD fue puesto en licencia administrativa en medio de acusaciones de que el Departamento estaba falsificando datos de criminalidad en un distrito, clasificando delitos como de menor gravedad de lo que realmente eran. La propia investigaci\u00f3n interna del MPD sobre el tema sigue en curso.<\/p>\n<p>Pero Trump tambi\u00e9n ha exagerado en lo relativo al impacto de la toma de control federal, al proclamar el viernes que hab\u00eda provocado un \u201cmilagro\u201d de seguridad p\u00fablica nunca visto en la memoria reciente: la capital del pa\u00eds pasando una semana sin un solo homicidio reportado.<\/p>\n<p>\u201cLa ciudad de Washington era un infierno, y ahora es segura\u201d, dijo Trump a los periodistas el viernes. \u201cOdio decir esto, porque no suena muy bien, pero no ha habido asesinatos en la ciudad de Washington en la \u00faltima semana. Es la primera vez en la memoria de cualquiera que no se ha tenido un asesinato en una semana\u201d.<\/p>\n<p>Es correcto que no ha habido asesinatos en la ciudad durante la \u00faltima semana, seg\u00fan los datos p\u00fablicos del MPD. Han ocurrido dos asesinatos desde que Trump firm\u00f3 su decreto asumiendo el control del Departamento de Polic\u00eda: uno en la noche del 11 de agosto, el mismo d\u00eda en que se firm\u00f3 la orden, y otro el 13 de agosto.<\/p>\n<p>Pero no es la primera semana reciente sin homicidios, como afirm\u00f3 Trump. No se reportaron asesinatos desde el 4 al 11 de mayo, del 11 al 17 de abril y tampoco en un periodo de m\u00e1s de dos semanas del 25 de febrero al 12 de marzo.<\/p>\n<p>Se han cometido un total de 89 homicidios hasta ahora en 2025, seg\u00fan los datos del distrito. En algunos casos, los asesinatos se confirman y se agregan a la base de datos p\u00fablica del MPD semanas o meses despu\u00e9s de ocurridos, por lo que es posible que se agreguen casos adicionales.<\/p>\n<p>Las protestas contra la represi\u00f3n han sido espor\u00e1dicas; algunos residentes en algunos vecindarios salieron a las calles despu\u00e9s de que se observara a agentes de ICE u otros funcionarios federales, a veces formando multitudes alrededor de los agentes y coreando para que se vayan.<\/p>\n<p>En el tribunal, los abogados del Departamento de Justicia dijeron que la autoridad de Trump sobre el MPD expirar\u00e1 al final del per\u00edodo de 30 d\u00edas establecido en la Ley de Autonom\u00eda, que el presidente ha citado como base de su medida.<\/p>\n<p>Pero ni el Departamento de Justicia ni la Casa Blanca han dicho si Trump continuar\u00e1 usando agentes federales y los cientos de miembros de la Guardia Nacional que ha desplegado despu\u00e9s de que expire su mes de control sobre el Departamento de Polic\u00eda. El propio presidente ha dicho que podr\u00eda mantenerlos all\u00ed \u201ctodo el tiempo que quiera\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la toma de control de la fuerza policial de la ciudad de Washington y el despliegue de agentes federales y tropas en el distrito, la capital experiment\u00f3 una ca\u00edda moderada en los delitos reportados \u2014y un aumento mucho mayor en las detenciones de inmigrantes\u2014, seg\u00fan un an\u00e1lisis de CNN basado en datos gubernamentales. En [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465793","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras la toma de control de la fuerza policial de la ciudad de Washington y el despliegue de agentes federales y tropas en el distrito, la capital experiment\u00f3 una ca\u00edda moderada en los delitos reportados \u2014y un aumento mucho mayor en las detenciones de inmigrantes\u2014, seg\u00fan un an\u00e1lisis de CNN basado en datos gubernamentales. En [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-23T20:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes\",\"datePublished\":\"2025-08-23T20:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\"},\"wordCount\":1896,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\",\"name\":\"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-23T20:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias","og_description":"Tras la toma de control de la fuerza policial de la ciudad de Washington y el despliegue de agentes federales y tropas en el distrito, la capital experiment\u00f3 una ca\u00edda moderada en los delitos reportados \u2014y un aumento mucho mayor en las detenciones de inmigrantes\u2014, seg\u00fan un an\u00e1lisis de CNN basado en datos gubernamentales. En [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-23T20:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/"},"author":{"name":"","@id":""},"headline":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes","datePublished":"2025-08-23T20:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/"},"wordCount":1896,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","name":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-23T20:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-23T20:03:43Z","datePublished":"2025-08-23T20:03:43Z","dateModified":"2025-08-23T20:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump tom\\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\\u00e9n aumentaron las detenciones de inmigrantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/23\\\/trump-washington-detenciones-inmigrantes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/23\\\/trump-washington-detenciones-inmigrantes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-23T20:03:43Z\",\"datePublished\":\"2025-08-23T20:03:43Z\",\"dateModified\":\"2025-08-23T20:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458230,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/04\/detienen-mas-8-700-migrantes-primeras-semanas-trump-trax\/","url_meta":{"origin":1465793,"position":0},"title":"Detienen a m\u00e1s de 8.700 migrantes durante las primeras dos semanas del Gobierno de Trump, informa el DHS","author":"","date":"febrero 4, 2025","format":false,"excerpt":"En las primeras dos semanas del Gobierno de Donald Trump, funcionarios federales han detenido a 8.768 inmigrantes y deportado a casi 6.000 personas, seg\u00fan las estad\u00edsticas publicadas este martes por el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s).En las cifras publicadas en X, el DHS dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457923,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","url_meta":{"origin":1465793,"position":1},"title":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones","author":"","date":"enero 27, 2025","format":false,"excerpt":"A las operaciones de b\u00fasqueda de inmigrantes del fin de semana llevadas a cabo por el Gobierno de Trump, que incluyeron casi 1.000 arrestos y que han asustado a muchas comunidades de inmigrantes, le sigui\u00f3 otra ofensiva: un aluvi\u00f3n de videos y fotos del gobierno federal que muestran a agentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471454,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/19\/exclusiva-dhs-sitio-web-plagado-errores-trax\/","url_meta":{"origin":1465793,"position":2},"title":"Exclusiva: el DHS admite que su sitio web que muestra a los &#171;peores de los peores&#187; inmigrantes estaba plagado de errores","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El Departamento de Seguridad Nacional de Estados Unidos (DHS, por sus siglas en ingl\u00e9s) admiti\u00f3 que su sitio web que presenta lo que denomina los \u201cpeores de los peores\u201d inmigrantes detenidos, estaba plagado de errores y modific\u00f3 la p\u00e1gina esta semana despu\u00e9s de recibir preguntas de CNN al respecto.El DHS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463599,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/06\/16\/menos-10-inmigrantes-detenidos-condenas-penales-graves-trax\/","url_meta":{"origin":1465793,"position":3},"title":"Menos del 10 % de los inmigrantes detenidos por el ICE desde octubre ten\u00edan condenas penales severas, seg\u00fan datos internos","author":"","date":"junio 16, 2025","format":false,"excerpt":"A medida que el Gobierno de Trump ha intensificado las redadas en Los \u00c1ngeles y otras partes del pa\u00eds, altos funcionarios han destacado la captura de inmigrantes condenados por delitos como asesinato, agresi\u00f3n y violaci\u00f3n, calific\u00e1ndolos de criminales \u201cb\u00e1rbaros\u201d que \u201csembraron el terror\u201d en comunidades estadounidenses.Pero documentos internos del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465661,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/19\/investigacion-estadisticas-crimen-washington-manipuladas-trax\/","url_meta":{"origin":1465793,"position":4},"title":"El Departamento de Justicia de Trump investiga si las estad\u00edsticas de cr\u00edmenes de Washington fueron manipuladas","author":"","date":"agosto 19, 2025","format":false,"excerpt":"El Departamento de Justicia de Trump est\u00e1 investigando si el Departamento de Polic\u00eda Metropolitana de Washington manipul\u00f3 datos sobre delitos, seg\u00fan dos fuentes.La investigaci\u00f3n, que est\u00e1 siendo dirigida por la oficina del fiscal federal en Washington, representa una escalada en la lucha de la ciudad contra una toma de control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465273,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/08\/irs-comparte-datos-contribuyentes-inmigrantes-indocumentados-trax\/","url_meta":{"origin":1465793,"position":5},"title":"IRS comparte datos confidenciales de contribuyentes con autoridades de inmigraci\u00f3n para encontrar inmigrantes indocumentados","author":"","date":"agosto 8, 2025","format":false,"excerpt":"El Servicio de Impuestos Internos (IRS, por sus siglas en ingl\u00e9s) comenz\u00f3 a compartir datos confidenciales de los contribuyentes esta semana con las autoridades de inmigraci\u00f3n que buscan inmigrantes indocumentados, seg\u00fan dos fuentes familiarizadas con el asunto.Como parte del masivo impulso de deportaci\u00f3n del presidente Donald Trump, el Departamento del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465793"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465793\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}