{"id":1465898,"date":"2025-08-27T06:03:48","date_gmt":"2025-08-27T13:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/"},"modified":"2025-08-27T06:03:48","modified_gmt":"2025-08-27T13:03:48","slug":"e-verify-inmigracion-gobierno-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","title":{"rendered":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n"},"content":{"rendered":"<p>Cuando se supo en el departamento de polic\u00eda de un peque\u00f1o pueblo tur\u00edstico de Maine que uno de sus <a href=\"https:\/\/www.cnn.com\/2025\/08\/19\/us\/maine-police-officer-immigration-arrest-hnk\">oficiales de reserva<\/a> estaba trabajando ilegalmente en EE.UU., el Departamento de Seguridad Nacional se asegur\u00f3 de que el caso apareciera en las primeras planas.<\/p>\n<p>\u201cEl hecho de que un departamento de polic\u00eda haya contratado a un extranjero ilegal y le haya entregado ilegalmente un arma de fuego ser\u00eda c\u00f3mico si no fuera tan tr\u00e1gico\u201d, dijo un funcionario de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en un <a href=\"https:\/\/www.ice.gov\/news\/releases\/ice-arrests-illegal-alien-serving-local-police-officer-after-attempting-unlawfully\">comunicado<\/a>.<\/p>\n<p>ICE acus\u00f3 al departamento de \u201cviolar conscientemente la misma ley que se le encarga hacer cumplir\u201d, pero la ciudad dijo que la falla estaba en el programa de verificaci\u00f3n federal que utiliz\u00f3 para confirmar que a Jon Luke Evans \u2014quien desde entonces acept\u00f3 abandonar el pa\u00eds voluntariamente despu\u00e9s de apenas un mes en el trabajo\u2014 ten\u00eda permiso para trabajar.<\/p>\n<p>\u201cSeguiremos confiando en el formulario de verificaci\u00f3n de elegibilidad de empleo I-9 y la base de datos del sistema de verificaci\u00f3n para confirmar la elegibilidad de empleo\u201d, dijo en ese momento la jefa de polic\u00eda de Old Orchard Beach, Elise Chard.<\/p>\n<p>Pero el Gobierno de Trump dijo que la luz verde de verificaci\u00f3n no era suficiente.<\/p>\n<p>\u201cLa confianza imprudente del Departamento de Polic\u00eda de Old Orchard Beach en el sistema de verificaci\u00f3n electr\u00f3nica para justificar armar a un extranjero ilegal, Jon Luke Evans, viola la ley federal y no los absuelve de su fracaso en realizar verificaciones de antecedentes b\u00e1sicas para verificar el estatus legal\u201d, dijo la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin.<\/p>\n<p>La declaraci\u00f3n de la agencia del gobierno federal encargada del sistema de verificaci\u00f3n llamado<em> E-Verify<\/em>, en la que afirma que es \u201cimprudente\u201d confiar en su propio sistema, atrajo la atenci\u00f3n a las debilidades del programa, incluso cuando el Gobierno de Trump hace de la expulsi\u00f3n de trabajadores indocumentados del pa\u00eds una de las principales prioridades en su agresiva y continua ofensiva contra la inmigraci\u00f3n.<\/p>\n<p>\u201cMe sorprendi\u00f3 much\u00edsimo\u201d, dijo Alexandra LaCombe, socia del bufete Fisher Phillips y especialista en derecho migratorio. \u201cYo les digo a todos que se puede confiar en estos sistemas. Para eso existen\u201d.<\/p>\n<p>Tras iniciarse como programa piloto bajo la presidencia de Bill Clinton, E-Verify se extendi\u00f3 a nivel nacional en 2004 y recibi\u00f3 su nombre cuando el presidente George W. Bush a\u00fan impulsaba una reforma migratoria integral. El Gobierno ayudar\u00eda con esto a los empleadores a que las verificaciones de antecedentes migratorios de los solicitantes de empleo sean m\u00e1s fiables, afirm\u00f3.<\/p>\n<p>\u201cNo podemos pedir a nuestros empleadores que verifiquen a alguien aqu\u00ed a menos que los ayudemos\u201d, <a href=\"https:\/\/georgewbush-whitehouse.archives.gov\/news\/releases\/2007\/05\/20070516-1.html\">dijo<\/a> Bush en una mesa redonda con l\u00edderes empresariales.<\/p>\n<p>Si bien la reforma migratoria integral <a href=\"https:\/\/www.cnn.com\/2007\/POLITICS\/06\/28\/immigration.vote.rollcall\/\">se vino abajo<\/a> por el fuerte rechazo de los conservadores, el programa de verificaci\u00f3n fue una de las medidas que se mantuvo vigente.<\/p>\n<p>En 2008, Bush emiti\u00f3 una orden para que las verificaciones de inmigraci\u00f3n con E-Verify fueran un requisito para los contratistas del gobierno federal.<\/p>\n<p>Desde entonces, diez estados la han hecho obligatoria para todos o la mayor\u00eda de los empleadores, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fworkforce.equifax.com%2Fe-verify-state-requirements&#038;data=05%7C02%7Cpeter.burn%40cnn.com%7Cda1e68795b4644b689ec08dde49d33a9%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918086058315072%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=8RD8B3Zwm9R%2BkuS%2FVkeLeJMuBdFV4tNJY99GR5i6IVU%3D&#038;reserved=0\">seg\u00fan Equifax<\/a>, pero sigue siendo opcional para la mayor\u00eda de las empresas privadas estadounidenses.<\/p>\n<p>Los \u00faltimos comentarios del Gobierno de Trump sobre E-Verify son marcadamente diferentes de lo que el DHS todav\u00eda dice en su propio <a href=\"https:\/\/www.e-verify.gov\/about-e-verify\/what-is-e-verify\">sitio web<\/a>.<\/p>\n<p>\u201cE-Verify funciona con rapidez y precisi\u00f3n\u201d, afirma el sitio.<\/p>\n<p>\u201cE-Verify es el \u00fanico servicio en l\u00ednea gratuito y r\u00e1pido de su tipo que confirma electr\u00f3nicamente la informaci\u00f3n de un empleado compar\u00e1ndola con millones de registros gubernamentales y brinda resultados en tan solo tres a cinco segundos\u201d, a\u00f1ade el texto.<\/p>\n<p>Los empleadores han confiado en que los ayudaba a cumplir con las leyes de inmigraci\u00f3n.<\/p>\n<p>\u201cEl sistema no es 100 % infalible\u201d, dijo LaCombe. \u201cNo elimina todo posible fraude, identificaciones falsas y cosas por el estilo, pero el empleador deber\u00eda tener la seguridad de creer sin reservas en la palabra del gobierno de que la persona est\u00e1 autorizada para trabajar\u201d.<\/p>\n<p>El jefe de polic\u00eda de Old Orchard Beach no es el \u00fanico que descubri\u00f3 que el sistema de verificaci\u00f3n del gobierno no ofrece garant\u00edas. Cuando agentes federales realizaron una <a href=\"https:\/\/www.cnn.com\/2025\/06\/11\/us\/immigration-raid-omaha-meat-plant-hnk\">redada<\/a> de alto perfil en una planta empacadora de carne en Nebraska a principios de este verano, la empresa propietaria tambi\u00e9n protest\u00f3 por el uso de E-Verify.<\/p>\n<p>\u201cEste es su sistema, administrado por el gobierno. \u00bfY me atacan a m\u00ed porque su sistema no funciona?\u201d, dijo <a href=\"https:\/\/www.cnn.com\/2025\/06\/11\/us\/immigration-raid-omaha-meat-plant-hnk\">Chad Hartmann<\/a>, presidente de Glen Valley Foods.<\/p>\n<p>Incluso algunas personas que han sido cr\u00edticas del sistema de verificaci\u00f3n se sorprendieron de que el Gobierno ahora parezca repudiarlo.<\/p>\n<p>\u201cMe impact\u00f3 o\u00edr al gobierno federal admitir que E-Verify no funciona lo suficientemente bien como para confiar en \u00e9l\u201d, dijo Alex Nowrasteh, vicepresidente de estudios de pol\u00edtica econ\u00f3mica y social del <a href=\"https:\/\/www.cato.org\/people\/alex-nowrasteh\">Cato Institute<\/a>, un centro de estudios libertario. \u201cEs la primera vez que oigo a empleados federales admitir que su programa es una p\u00e9rdida de tiempo para todos\u201d.<\/p>\n<p>Los cr\u00edticos de E-Verify se han quejado durante a\u00f1os de que el sistema es m\u00e1s un obst\u00e1culo para los trabajadores leg\u00edtimos que un elemento disuasorio para la inmigraci\u00f3n ilegal.<\/p>\n<p>\u201cEs muy f\u00e1cil enga\u00f1ar a E-Verify. Es muy sencillo\u201d, dijo Nowrasteh. \u201cSolo hay que darle los documentos de identidad de alguien que pueda trabajar. Eso es todo\u201d.<\/p>\n<p>Eso significa que los empleadores deben hacer m\u00e1s que simplemente ingresar informaci\u00f3n en la base de datos de E-Verify y cruzar los dedos, seg\u00fan un abogado de inmigraci\u00f3n que dice que las empresas necesitan recibir capacitaci\u00f3n sobre c\u00f3mo detectar licencias de conducir y tarjetas de Seguro Social falsas.<\/p>\n<p>\u201cEs trabajo del empleador asegurarse de no aceptar documentos fraudulentos, pero no se espera que sean detectives de documentos\u201d, dijo Dawn Lurie, asesora principal en derecho migratorio de Seyfarth Shaw LLP.<\/p>\n<p>Los empleadores deben tener cuidado de no sospechar de un solicitante de empleo sin una buena raz\u00f3n. \u201cNo conviene excederse y potencialmente discriminar a alguien al pedir m\u00e1s documentos o documentos diferentes\u201d, dijo Lurie.<\/p>\n<p>Los problemas con E-Verify van m\u00e1s all\u00e1 de no poder detectar a personas que no son elegibles para trabajar en EE.UU.<\/p>\n<p>M\u00e1s del 98 % de las personas verificadas por E-Verify durante los \u00faltimos 12 meses con datos disponibles fueron confirmadas como elegibles para trabajar en 24 horas, <a href=\"https:\/\/www.e-verify.gov\/about-e-verify\/e-verify-data\/e-verify-performance\">seg\u00fan<\/a> el DHS. Sin embargo, con m\u00e1s de 43 millones de verificaciones realizadas ese a\u00f1o, un peque\u00f1o error puede afectar a muchas personas.<\/p>\n<p>Los trabajadores elegibles en EE.UU. perdieron alrededor de 130.000 empleos en un per\u00edodo de 10 a\u00f1os porque fueron marcados incorrectamente por E-Verify, seg\u00fan un <a href=\"https:\/\/www.cato.org\/blog\/e-verify-has-held-or-cost-jobs-half-million-legal-workers\">estudio de Cato<\/a> de 2017 basado en estimaciones de datos del Gobierno.<\/p>\n<p>Seg\u00fan Lurie, los falsos positivos han disminuido considerablemente desde entonces. \u201cDir\u00eda que E-Verify ha mejorado much\u00edsimo en los \u00faltimos 10 a\u00f1os\u201d, afirm\u00f3. \u201cEs como la noche y el d\u00eda\u201d.<\/p>\n<p>Pero ser\u00eda imposible mejorar sustancialmente el programa ahora sin un documento de identidad nacional con informaci\u00f3n biom\u00e9trica para comprobar el estatus legal, argumenta Nowrasteh, algo que cree que nadie quiere realmente.<\/p>\n<p>\u201cLo que se dar\u00e1n cuenta muy pronto, y lo que todo el mundo se est\u00e1 dando cuenta, es que es una tarea in\u00fatil\u201d, dijo. \u201cEs demasiado caro. Es demasiado dif\u00edcil. Es demasiado invasivo\u201d.<\/p>\n<p>A pesar de las persistentes preocupaciones sobre la fiabilidad del programa, algunos congresistas desean un uso m\u00e1s amplio de E-Verify. El sistema debe renovarse cada dos a\u00f1os, pero los republicanos han propuesto reiteradamente que el programa sea permanente y que todos los empleadores lo utilicen.<\/p>\n<p>\u201cE-Verify es una forma comprobada y rentable de garantizar que las empresas cumplan con nuestras leyes y una herramienta para disuadir la inmigraci\u00f3n ilegal\u201d, <a href=\"https:\/\/www.grassley.senate.gov\/news\/news-releases\/grassley-colleagues-seek-to-permanently-authorize-expand-e-verify#:~:text=%E2%80%9CE%2Dverify%20is%20a%20proven%2C%20cost%2Deffective%20way,Find%20bill%20text%20HERE.\">declar\u00f3<\/a> la senadora republicana Joni Ernst de Iowa cuando se present\u00f3 la \u00faltima versi\u00f3n de la propuesta en marzo. Sin embargo, a pesar de la dura ret\u00f3rica migratoria de la mayor\u00eda republicana, dicho <a href=\"https:\/\/www.congress.gov\/bill\/119th-congress\/senate-bill\/1151\/all-actions\">proyecto de ley<\/a> a\u00fan no ha sido debatido en el Senado.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2023\/09\/07\/politics\/texas-water-barriers-migrants-appeal\">Proyectos de ley similares en Texas \u2014un estado cuyo gobernador, Greg Abbott, ha hecho de la inmigraci\u00f3n ilegal un tema tan fundamental que orden\u00f3 colocar barricadas<\/a> cubiertas con hojas de sierra en el r\u00edo Grande para disuadir los cruces fronterizos\u2014 han quedado en la nada en m\u00faltiples sesiones de la legislatura.<\/p>\n<p>A pesar de que el sistema pretende ser f\u00e1cil de utilizar para las empresas, el exdirector ejecutivo de la Asociaci\u00f3n de Negocios de Texas <a href=\"https:\/\/www.texastribune.org\/2025\/06\/05\/texas-e-verify-requirements-immigration\/\">dijo a The Texas Tribune<\/a> este verano que los l\u00edderes empresariales no quieren que se reduzca la fuerza laboral disponible.<\/p>\n<p>\u201c\u00bfQuieres ir a un restaurante y usar platos de papel porque nadie lava los platos?\u201d, pregunt\u00f3 Bill Hammond.<\/p>\n<p>Una <a href=\"https:\/\/www.cnn.com\/2025\/07\/20\/politics\/cnn-poll-trump-deportations\">encuesta de CNN<\/a> a principios de este verano mostr\u00f3 que el porcentaje de personas que creen que la campa\u00f1a de deportaci\u00f3n de Trump han ido \u201cdemasiado lejos\u201d aument\u00f3 en 10 puntos en cinco meses.<\/p>\n<p>Nowrasteh, quien se opone a la deportaci\u00f3n masiva de inmigrantes indocumentados, no le preocupa que E-Verify tenga problemas. Cree que los inmigrantes indocumentados que no cometen delitos, en general, benefician a Estados Unidos.<\/p>\n<p>\u201cLo mejor de E-Verify es que no funciona bien\u201d, dijo. \u201cSi funcionara, ser\u00eda devastador para nuestra econom\u00eda\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se supo en el departamento de polic\u00eda de un peque\u00f1o pueblo tur\u00edstico de Maine que uno de sus oficiales de reserva estaba trabajando ilegalmente en EE.UU., el Departamento de Seguridad Nacional se asegur\u00f3 de que el caso apareciera en las primeras planas. \u201cEl hecho de que un departamento de polic\u00eda haya contratado a un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465898","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando se supo en el departamento de polic\u00eda de un peque\u00f1o pueblo tur\u00edstico de Maine que uno de sus oficiales de reserva estaba trabajando ilegalmente en EE.UU., el Departamento de Seguridad Nacional se asegur\u00f3 de que el caso apareciera en las primeras planas. \u201cEl hecho de que un departamento de polic\u00eda haya contratado a un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-27T13:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n\",\"datePublished\":\"2025-08-27T13:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\"},\"wordCount\":1636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\",\"name\":\"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-27T13:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias","og_description":"Cuando se supo en el departamento de polic\u00eda de un peque\u00f1o pueblo tur\u00edstico de Maine que uno de sus oficiales de reserva estaba trabajando ilegalmente en EE.UU., el Departamento de Seguridad Nacional se asegur\u00f3 de que el caso apareciera en las primeras planas. \u201cEl hecho de que un departamento de polic\u00eda haya contratado a un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-27T13:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n","datePublished":"2025-08-27T13:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/"},"wordCount":1636,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","name":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-27T13:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno cuestiona el sistema de verificaci\u00f3n electr\u00f3nica usado para facilitar la aplicaci\u00f3n de leyes de inmigraci\u00f3n","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/27\/e-verify-inmigracion-gobierno-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-27T13:03:48Z","datePublished":"2025-08-27T13:03:48Z","dateModified":"2025-08-27T13:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno cuestiona el sistema de verificaci\\u00f3n electr\\u00f3nica usado para facilitar la aplicaci\\u00f3n de leyes de inmigraci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/27\\\/e-verify-inmigracion-gobierno-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/27\\\/e-verify-inmigracion-gobierno-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-27T13:03:48Z\",\"datePublished\":\"2025-08-27T13:03:48Z\",\"dateModified\":\"2025-08-27T13:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467445,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/10\/16\/ice-arresta-policia-chicago-estados-unidos-trax\/","url_meta":{"origin":1465898,"position":0},"title":"ICE arresta a un agente de polic\u00eda en un suburbio de Chicago y lo acusa de estar ilegalmente en Estados Unidos","author":"","date":"octubre 16, 2025","format":false,"excerpt":"Agentes de ICE arrestaron a un polic\u00eda la ma\u00f1ana de este jueves en el suburbio de Hanover Park, en Chicago, y lo acusaron de ser un inmigrante ilegal de Montenegro.El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) dijo que el oficial, Radule Bojovic, permaneci\u00f3 en el pa\u00eds\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462647,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/21\/fianza-inmigracion-ximena-arias-cristobal-arrestada-error-trax\/","url_meta":{"origin":1465898,"position":1},"title":"Juez otorga fianza a Ximena Arias, la inmigrante universitaria arrestada por una infracci\u00f3n de tr\u00e1nsito err\u00f3nea","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Un juez de la corte de inmigraci\u00f3n en Georgia otorg\u00f3 fianza a una adolescente cuya situaci\u00f3n gan\u00f3 atenci\u00f3n nacional despu\u00e9s de que un agente la detuvo por error a principios de este mes.La fianza para Ximena Arias Crist\u00f3bal fue fijada en US$ 1.500 el mi\u00e9rcoles por la tarde, seg\u00fan una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456891,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/23\/identifican-sospechoso-prender-fuego-mujer-metro-ny-trax\/","url_meta":{"origin":1465898,"position":2},"title":"Identifican al sospechoso de prender fuego a una mujer en el metro de Nueva York","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"El sospechoso de la muerte de una mujer en el metro de Nueva York tras prenderle fuego fue identificado como Sebasti\u00e1n Zapeta-Calil, un ciudadano guatemalteco de 33 a\u00f1os que entr\u00f3 ilegalmente a EE.UU. en alg\u00fan momento de los \u00faltimos seis a\u00f1os, seg\u00fan el portavoz del Servicio de Inmigraci\u00f3n y Control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468332,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/14\/exclusiva-arrestan-miles-padres-tutores-ninos-inmigrantes-trax\/","url_meta":{"origin":1465898,"position":3},"title":"Exclusiva: arrestan a miles de padres y tutores de ni\u00f1os inmigrantes en las redadas del Gobierno de Trump","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Cuando agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) arrestaron a una mujer en una guarder\u00eda de Chicago este mes, se desat\u00f3 una ola de indignaci\u00f3n local por las t\u00e1cticas de ICE.Pero tambi\u00e9n permiti\u00f3 vislumbrar la \u00faltima iniciativa de control inmigratorio del Gobierno de Trump: un esfuerzo intenso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466993,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/30\/renuncia-superintendente-iowa-ian-roberts-detenido-ice-trax\/","url_meta":{"origin":1465898,"position":4},"title":"Renuncia a su cargo el superintendente de Iowa Ian Roberts, detenido por ICE","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Ian Roberts, el l\u00edder de las escuelas de Des Moines que fue detenido por agentes de inmigraci\u00f3n la semana pasada, renunci\u00f3 a su cargo, dijo su abogado el martes.\u201cHoy enviaremos una carta a la junta escolar de Des Moines autorizada por el Dr. Roberts para renunciar a su cargo como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457010,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/27\/sospechoso-metro-nueva-york-audiencia-trax\/","url_meta":{"origin":1465898,"position":5},"title":"Sospechoso en el incendio fatal de una mujer en el metro de Nueva York comparece este viernes ante la corte","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"El hombre acusado de homicidio e incendio intencional por la muerte de una mujer dentro de un vag\u00f3n del metro en la ciudad de Nueva York tiene programada su comparecencia en la corte este viernes.Sebasti\u00e1n Zapeta-Calil, de 33 a\u00f1os, est\u00e1 acusado de prender fuego a una mujer no identificada que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465898"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465898\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}