{"id":1465946,"date":"2025-08-28T13:03:48","date_gmt":"2025-08-28T20:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/"},"modified":"2025-08-28T13:03:48","modified_gmt":"2025-08-28T20:03:48","slug":"casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","title":{"rendered":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;"},"content":{"rendered":"<p>La Casa Blanca \u201cseguir\u00e1 luchando\u201d contra la orden de una jueza de <a href=\"https:\/\/apnews.com\/article\/florida-alligator-alcatraz-trump-injunction-9dc2aa22f87a2a5ac8436918a8794d37\">cerrar<\/a> el centro de detenci\u00f3n de inmigrantes en Florida apodado Alligator Alcatraz, incluso mientras cumplen con una orden judicial para dejar de recibir nuevos detenidos y retirar la infraestructura a\u00f1adida al sitio, dijo la secretaria de prensa Karoline Leavitt.<\/p>\n<p>\u201cVamos a cumplir con las \u00f3rdenes judiciales, pero tambi\u00e9n vamos a combatirlas en cuanto al fondo legal. El DHS cumplir\u00e1, aunque no estamos de acuerdo con esta decisi\u00f3n, y seguiremos luchando en los tribunales\u201d, dijo Leavitt a los periodistas durante la rueda de prensa del jueves.<\/p>\n<p>La semana pasada, la jueza federal de distrito Kathleen Williams emiti\u00f3 una orden judicial preliminar en una demanda federal presentada por grupos ambientalistas y la Tribu ind\u00edgena Miccosukee de Florida, ordenando que el centro <a href=\"https:\/\/www.cnn.com\/2025\/08\/21\/us\/alligator-alcatraz-judge-restraining-order\">retire<\/a> la infraestructura a\u00f1adida al sitio y deje de recibir detenidos.<\/p>\n<p>La Tribu Miccosukee, una tribu nativa americana cuya reserva se encuentra a pocos kil\u00f3metros del centro, expres\u00f3 su preocupaci\u00f3n por el impacto que el centro tendr\u00e1 en su tierra y en el \u00e1rea ambientalmente sensible, incluyendo las plantas y animales que habitan los Everglades.<\/p>\n<p>\u201cEl proyecto causa un da\u00f1o irreparable en forma de p\u00e9rdida de h\u00e1bitat y aumento de la mortalidad de especies en peligro de extinci\u00f3n en el \u00e1rea\u201d, dijo Williams en la orden.<\/p>\n<p>El gobernador de Florida, Ron DeSantis, tambi\u00e9n ha dicho que su estado tiene la intenci\u00f3n de impugnar la orden, aunque un mensaje de un alto funcionario de Florida se\u00f1al\u00f3 que el centro probablemente estar\u00e1 vac\u00edo en cuesti\u00f3n de d\u00edas.<\/p>\n<p>\u201cNo vamos a dejarnos disuadir\u201d, dijo DeSantis. \u201cTenemos toda la raz\u00f3n en esto\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa Blanca \u201cseguir\u00e1 luchando\u201d contra la orden de una jueza de cerrar el centro de detenci\u00f3n de inmigrantes en Florida apodado Alligator Alcatraz, incluso mientras cumplen con una orden judicial para dejar de recibir nuevos detenidos y retirar la infraestructura a\u00f1adida al sitio, dijo la secretaria de prensa Karoline Leavitt. \u201cVamos a cumplir con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465946","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &quot;Alligator Alcatraz&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &quot;Alligator Alcatraz&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Casa Blanca \u201cseguir\u00e1 luchando\u201d contra la orden de una jueza de cerrar el centro de detenci\u00f3n de inmigrantes en Florida apodado Alligator Alcatraz, incluso mientras cumplen con una orden judicial para dejar de recibir nuevos detenidos y retirar la infraestructura a\u00f1adida al sitio, dijo la secretaria de prensa Karoline Leavitt. \u201cVamos a cumplir con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T20:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;\",\"datePublished\":\"2025-08-28T20:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\",\"name\":\"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar \\\"Alligator Alcatraz\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-28T20:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar \"Alligator Alcatraz\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar \"Alligator Alcatraz\" - Noticias","og_description":"La Casa Blanca \u201cseguir\u00e1 luchando\u201d contra la orden de una jueza de cerrar el centro de detenci\u00f3n de inmigrantes en Florida apodado Alligator Alcatraz, incluso mientras cumplen con una orden judicial para dejar de recibir nuevos detenidos y retirar la infraestructura a\u00f1adida al sitio, dijo la secretaria de prensa Karoline Leavitt. \u201cVamos a cumplir con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-28T20:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/"},"author":{"name":"","@id":""},"headline":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;","datePublished":"2025-08-28T20:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","name":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar \"Alligator Alcatraz\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-28T20:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Casa Blanca disputar\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-28T20:03:48Z","datePublished":"2025-08-28T20:03:48Z","dateModified":"2025-08-28T20:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Casa Blanca disputar\\u00e1 la orden de una jueza de cerrar &#171;Alligator Alcatraz&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/28\\\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/28\\\/casa-blanca-disputara-orden-cerrar-alligator-alcatraz-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-28T20:03:48Z\",\"datePublished\":\"2025-08-28T20:03:48Z\",\"dateModified\":\"2025-08-28T20:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466161,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/04\/tribunal-bloquea-orden-jueza-desmantelar-alligator-alcatraz-trax\/","url_meta":{"origin":1465946,"position":0},"title":"Un tribunal de apelaciones bloquea la orden de una jueza para desmantelar &#171;Alligator Alcatraz&#187;","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones bloque\u00f3 la orden de una jueza que exig\u00eda a Florida y al Gobierno federal cerrar y desmantelar un controvertido centro de detenci\u00f3n de inmigrantes construido en los Everglades, conocido popularmente como \u201cAlligator Alcatraz\u201d.Este jueves, el Tribunal de Apelaciones del 11\u00ba Circuito de EE.UU. acept\u00f3 las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465789,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/23\/alligator-alcatraz-cierre-florida-plan-b-trax\/","url_meta":{"origin":1465946,"position":1},"title":"Alligator Alcatraz podr\u00eda cerrarse antes de Halloween. Florida ya tiene un plan B","author":"","date":"agosto 23, 2025","format":false,"excerpt":"Casi dos meses despu\u00e9s del precipitado y controvertido nacimiento de \u201cAlligator Alcatraz\u201d, una jueza federal fren\u00f3 dr\u00e1sticamente la operaci\u00f3n al dictaminar que no se puede enviar a m\u00e1s personas al remoto campo de detenci\u00f3n de migrantes, ubicado en las profundidades de los pantanos de los Everglades.Construido en cuesti\u00f3n de d\u00edas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465744,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/21\/suspenden-detenidos-alligator-alcatraz-fallo-juez-trax\/","url_meta":{"origin":1465946,"position":2},"title":"No se pueden trasladar m\u00e1s detenidos a &#171;Alligator Alcatraz&#187; por ahora, dictamina un juez federal","author":"","date":"agosto 21, 2025","format":false,"excerpt":"Un juez federal orden\u00f3 que el remoto campo de detenci\u00f3n en los Everglades de Florida, conocido como \u201cAlligator Alcatraz\u201d, no reciba m\u00e1s detenidos y retire la infraestructura adicional agregada al sitio.El juez emiti\u00f3 la orden judicial preliminar despu\u00e9s de que grupos ambientalistas y una tribu nativa americana presentaran una demanda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464082,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/06\/30\/trump-visitara-alcatraz-trax\/","url_meta":{"origin":1465946,"position":3},"title":"Trump visitar\u00e1 &#171;Alligator Alcatraz&#187; con DeSantis, Noem y Donalds","author":"","date":"junio 30, 2025","format":false,"excerpt":"La secretaria de prensa de la Casa Blanca, Karoline Leavitt, confirm\u00f3 que el presidente Donald Trump visitar\u00e1 los Everglades de Florida para asistir a la apertura de \u201cAlligator Alcatraz\u201d, un nuevo centro de detenci\u00f3n de inmigraci\u00f3n en la regi\u00f3n.Trump estar\u00e1 acompa\u00f1ado en el aeropuerto de entrenamiento y transici\u00f3n Dade-Collier por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466188,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","url_meta":{"origin":1465946,"position":4},"title":"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"\u201cDeportation Depot\u201d, el nuevo centro de detenci\u00f3n de inmigrantes de Florida, ya alberga a detenidos, informaron este viernes funcionarios estatales.El centro, ubicado en la Instituci\u00f3n Correccional Baker del estado, alberga a 117 detenidos y tiene capacidad para recibir hasta 1.500 personas, seg\u00fan la oficina del gobernador Ron DeSantis. La prisi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464464,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/07\/12\/noem-promete-aumentar-deportaciones-impulso-fondos-trax\/","url_meta":{"origin":1465946,"position":5},"title":"Noem promete aumentar las deportaciones con el impulso de fondos de la &#171;gran y hermosa ley&#187; de pol\u00edtica interna de Trump","author":"","date":"julio 12, 2025","format":false,"excerpt":"La secretaria de Seguridad Nacional, Kristi Noem, prometi\u00f3 este s\u00e1bado que su departamento reforzar\u00e1 sus esfuerzos para combatir la inmigraci\u00f3n, gracias a un aumento de fondos proveniente de la ley de pol\u00edtica interna del presidente Donald Trump, que firm\u00f3 la semana pasada.\u201cAhora que se aprob\u00f3 el proyecto de ley de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465946"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465946\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}