{"id":1465956,"date":"2025-08-28T17:03:41","date_gmt":"2025-08-29T00:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/"},"modified":"2025-08-28T17:03:41","modified_gmt":"2025-08-29T00:03:41","slug":"gobierno-trump-gran-operativo-migratorio-chicago-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","title":{"rendered":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana"},"content":{"rendered":"<p>El Gobierno de Trump se est\u00e1 preparando para llevar a cabo una importante operaci\u00f3n de control migratorio en Chicago la pr\u00f3xima semana, seg\u00fan varias fuentes familiarizadas con los planes, lo que marca la \u00faltima escalada entre el presidente y una ciudad gobernada por dem\u00f3cratas.<\/p>\n<p>El presidente Donald Trump y sus asesores han criticado repetidamente a Chicago por las pol\u00edticas que limitan la cooperaci\u00f3n entre las autoridades locales y las autoridades federales de inmigraci\u00f3n. Chicago vivi\u00f3 una afluencia de migrantes durante el Gobierno de Biden, tras los aumentos repentinos de pasos en la frontera sur de Estados Unidos y la decisi\u00f3n del gobernador de Texas, Greg Abbott, de transportar migrantes a ciudades lideradas por los dem\u00f3cratas.<\/p>\n<p>Chicago fue una de las primeras ciudades en ser blanco de los operativos de control migratorio cuando Trump asumi\u00f3 el cargo en enero. El Gobierno tambi\u00e9n demand\u00f3 a la ciudad por sus llamadas pol\u00edticas de santuario, aunque el caso fue desestimado cuando un juez dictamin\u00f3 que el Gobierno federal no ten\u00eda legitimidad legal para presentar la demanda, y amenaz\u00f3 con retener fondos federales, lo que tambi\u00e9n fue bloqueado por un juez.<\/p>\n<p>Ahora, se espera que las operaciones previstas en Chicago sean de mayor escala, utilizando personal del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP), y posiblemente otras agencias. Las autoridades est\u00e1n <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/26\/eeuu\/guardia-nacional-los-angeles-washington-trump-trax\">preparando a la Guardia Nacional<\/a> para ayudar si se necesita una presencia de mantenimiento de la paz, similar a lo que ocurri\u00f3 en Los \u00c1ngeles tras las protestas, dijeron las fuentes.<\/p>\n<p>Los preparativos para Chicago ya est\u00e1n en marcha, incluyendo el env\u00edo de veh\u00edculos blindados a la ciudad en los pr\u00f3ximos d\u00edas y el aumento de agentes federales para el pr\u00f3ximo viernes 5 de septiembre, fecha en la que, seg\u00fan dos fuentes, se espera que comience la operaci\u00f3n. Sin embargo, las discusiones a\u00fan contin\u00faan y la planificaci\u00f3n est\u00e1 en proceso.<\/p>\n<p>Funcionarios de la Casa Blanca han dejado claro que estos planes son distintos de la idea que el presidente ha sugerido durante la \u00faltima semana de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/28\/eeuu\/analisis-represion-militarizada-crimen-trump-trax\">utilizar fuerzas del orden federales<\/a> y tropas de la Guardia Nacional para llevar a cabo una ofensiva m\u00e1s amplia contra el crimen en Chicago, similar a la actual en Washington.<\/p>\n<p>Esas conversaciones, que se centran en \u201climpiar el crimen dom\u00e9stico de Chicago\u201d, como lo expres\u00f3 uno de los funcionarios, contin\u00faan y no forman parte de esta operaci\u00f3n centrada en la inmigraci\u00f3n (aunque la iniciativa en Washington ha generado un gran aumento en arrestos relacionados con inmigraci\u00f3n).<\/p>\n<p>En cambio, el modelo para la operaci\u00f3n de Chicago se ha establecido en Los \u00c1ngeles.<\/p>\n<p>El Departamento de Seguridad Nacional ha promocionado las operaciones de seguridad all\u00ed, utilizando redes sociales para presumir de los arrestos y adoptando t\u00e1cticas agresivas. Esta semana, el departamento anunci\u00f3 que realiz\u00f3 5.000 arrestos en Los \u00c1ngeles desde junio.<\/p>\n<p>El zar de la frontera de la Casa Blanca, Tom Homan, dijo el jueves que la planificaci\u00f3n para Chicago segu\u00eda en marcha. Agreg\u00f3 que hay conversaciones en curso para usar una base naval al norte de Chicago como centro para el personal federal. La Marina se neg\u00f3 a comentar sobre los planes potenciales y remiti\u00f3 las preguntas al Departamento de Seguridad Nacional.<\/p>\n<p>Homan se neg\u00f3 a decir cu\u00e1ntas personas ser\u00edan desplegadas, pero sostuvo que \u201cser\u00e1 un contingente grande\u201d.<\/p>\n<p>\u201cSe puede ver un aumento gradual de las operaciones en Chicago, sin duda\u201d, afirm\u00f3.<\/p>\n<p>Gregory Bovino, quien ostenta el t\u00edtulo de jefe de patrulla del sector El Centro, ha estado a cargo de las operaciones en Los \u00c1ngeles y se espera que tambi\u00e9n lidere las operaciones en Chicago, seg\u00fan dos fuentes.<\/p>\n<p>\u201cEn todo el pa\u00eds, los funcionarios de seguridad nacional est\u00e1n arrestando y expulsando a lo peor de lo peor, incluyendo pandilleros, asesinos, ped\u00f3filos y violadores que han aterrorizado a las comunidades estadounidenses\u201d, dijo un alto funcionario de Seguridad Nacional en un comunicado a CNN al ser consultado sobre las pr\u00f3ximas operaciones en Chicago. \u201cBajo la secretaria Noem, ICE y CBP est\u00e1n trabajando arduamente para cumplir con el mandato del pueblo estadounidense de arrestar y deportar a inmigrantes criminales ilegales y hacer que Estados Unidos sea seguro de nuevo\u201d.<\/p>\n<p>El papel de la Guardia Nacional en Chicago ser\u00eda similar al que tuvo en Los \u00c1ngeles, donde las tropas estaban bajo \u00f3rdenes del T\u00edtulo 10, lo que significa que hab\u00edan sido federalizadas y la Ley Posse Comitatus les prohib\u00eda participar en actividades de aplicaci\u00f3n de la ley.<\/p>\n<p>La situaci\u00f3n es diferente en Washington, donde las tropas est\u00e1n bajo \u00f3rdenes del T\u00edtulo 32. Eso normalmente significa que reportan al gobernador \u2014 en el caso \u00fanico de Washington, esa autoridad recae en el presidente y normalmente se delega en el titular del Ej\u00e9rcito\u2014 y no est\u00e1n sujetas a la Ley Posse Comitatus.<br \/>Habr\u00eda inquietudes legales m\u00e1s amplias si la administraci\u00f3n Trump intentara algo similar en Illinois.<\/p>\n<p>Rachel VanLandingham, exasesora legal de la Fuerza A\u00e9rea y actual profesora de derecho en la Facultad de Derecho Southwestern, dijo previamente a CNN que ser\u00eda \u201cun mundo completamente nuevo para ellos intentar una maniobra similar a la de Washington en Chicago o cualquier otro lugar que no sea Washington, porque ah\u00ed es legalmente diferente a cualquier otra \u00e1rea\u201d.<\/p>\n<p>Sin embargo, el actual impulso contra la inmigraci\u00f3n ilegal est\u00e1 firmemente dentro de la autoridad ejecutiva del presidente, seg\u00fan funcionarios de la administraci\u00f3n.<\/p>\n<p>El gobernador de Illinois, J. B. Pritzker, arremeti\u00f3 el lunes contra Trump por sugerir que podr\u00eda desplegar un contingente mayor de fuerzas federales en Chicago, acusando a la administraci\u00f3n de \u201cbuscar formas de sentar las bases para eludir nuestra democracia, militarizar nuestras ciudades y acabar con las elecciones\u201d.<\/p>\n<p>Pritzker tambi\u00e9n afirm\u00f3 que el Gobierno no se hab\u00eda comunicado con su oficina ni con el alcalde antes del supuesto despliegue y critic\u00f3 duramente la falta de coordinaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Trump se est\u00e1 preparando para llevar a cabo una importante operaci\u00f3n de control migratorio en Chicago la pr\u00f3xima semana, seg\u00fan varias fuentes familiarizadas con los planes, lo que marca la \u00faltima escalada entre el presidente y una ciudad gobernada por dem\u00f3cratas. El presidente Donald Trump y sus asesores han criticado repetidamente a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465956","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Trump se est\u00e1 preparando para llevar a cabo una importante operaci\u00f3n de control migratorio en Chicago la pr\u00f3xima semana, seg\u00fan varias fuentes familiarizadas con los planes, lo que marca la \u00faltima escalada entre el presidente y una ciudad gobernada por dem\u00f3cratas. El presidente Donald Trump y sus asesores han criticado repetidamente a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T00:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana\",\"datePublished\":\"2025-08-29T00:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\"},\"wordCount\":1056,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\",\"name\":\"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-29T00:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias","og_description":"El Gobierno de Trump se est\u00e1 preparando para llevar a cabo una importante operaci\u00f3n de control migratorio en Chicago la pr\u00f3xima semana, seg\u00fan varias fuentes familiarizadas con los planes, lo que marca la \u00faltima escalada entre el presidente y una ciudad gobernada por dem\u00f3cratas. El presidente Donald Trump y sus asesores han criticado repetidamente a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-29T00:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana","datePublished":"2025-08-29T00:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/"},"wordCount":1056,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","name":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-29T00:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\u00f3xima semana","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/28\/gobierno-trump-gran-operativo-migratorio-chicago-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-29T00:03:41Z","datePublished":"2025-08-29T00:03:41Z","dateModified":"2025-08-29T00:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Trump planea un gran operativo de control migratorio en Chicago la pr\\u00f3xima semana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/28\\\/gobierno-trump-gran-operativo-migratorio-chicago-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/28\\\/gobierno-trump-gran-operativo-migratorio-chicago-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-29T00:03:41Z\",\"datePublished\":\"2025-08-29T00:03:41Z\",\"dateModified\":\"2025-08-29T00:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466242,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/07\/chicago-dia-independencia-mexico-inmigracion-trax\/","url_meta":{"origin":1465956,"position":0},"title":"En Chicago, las celebraciones del D\u00eda de la Independencia de M\u00e9xico se ven opacadas por amenazas de redadas del ICE","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"En el suroeste de Chicago, la m\u00fasica retumbaba y las banderas verde, blanca y roja ondeaban por las calles del barrio mayoritariamente latino de Pilsen, donde el s\u00e1bado multitudes se reunieron para dar inicio a las celebraciones del D\u00eda de la Independencia de M\u00e9xico.Artistas disfrazados y ni\u00f1os con canastas llenas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466231,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/07\/trump-operativo-migratorio-massachusetts-trax\/","url_meta":{"origin":1465956,"position":1},"title":"El Gobierno de Trump lanza operativo migratorio en Massachusetts","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"El Gobierno de Trump lanz\u00f3 un nuevo operativo federal de inmigraci\u00f3n en Massachusetts enfocado en deportar a delincuentes que ingresaron ilegalmente al pa\u00eds, seg\u00fan el Departamento de Seguridad Nacional (DHS).\u201cICE lanz\u00f3 \u2018Patriot 2.0\u2019 para atacar a lo peor de lo peor entre los extranjeros ilegales criminales que viven en Massachusetts,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466008,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/30\/chicago-trump-decreto-johnson-trax\/","url_meta":{"origin":1465956,"position":2},"title":"El alcalde de Chicago firm\u00f3 un decreto para resistir la ofensiva migratoria planeada por Trump","author":"","date":"agosto 30, 2025","format":false,"excerpt":"El alcalde de Chicago, Brandon Johnson, firm\u00f3 este s\u00e1bado un decreto que un plan sobre c\u00f3mo la ciudad intentar\u00e1 resistir la ofensiva migratoria planeada por el presidente Donald Trump en los pr\u00f3ximos d\u00edas.La medida del alcalde proporciona orientaci\u00f3n y directrices a las agencias y fuerzas del orden de la ciudad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460697,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/04\/01\/ciudades-santuario-eeuu-deportaciones-trump-orix\/","url_meta":{"origin":1465956,"position":3},"title":"Estos son los estados y ciudades &#171;santuario&#187; y as\u00ed responden a los planes de deportaci\u00f3n de Trump","author":"","date":"abril 1, 2025","format":false,"excerpt":"Las \u201cciudades santuario\u201d, aquellas con pol\u00edticas que limitan la colaboraci\u00f3n de sus autoridades locales con los agentes federales de inmigraci\u00f3n, est\u00e1n en la mira del presidente de Estados Unidos, Donald Trump, pues considera que son un obst\u00e1culo en sus planes de deportaci\u00f3n masiva.Durante una reuni\u00f3n con embajadores en la Casa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457752,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/22\/planes-deportacion-trump-inmigrantes-trax\/","url_meta":{"origin":1465956,"position":4},"title":"Estos son los planes de deportaci\u00f3n de Trump y los cambios que va a introducir para los inmigrantes","author":"","date":"enero 22, 2025","format":false,"excerpt":"Han pasado seis meses desde que Nedi, una venezolana de 35 a\u00f1os y madre de dos hijos, emprendi\u00f3 un peligroso viaje a trav\u00e9s del Tap\u00f3n del Dari\u00e9n para llegar a Estados Unidos.Con la esperanza de eventualmente establecerse en Miami, Nedi y su familia llegaron a San Diego hace 11 d\u00edas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466061,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/01\/chicago-operativo-control-inmigracion-trump-trax\/","url_meta":{"origin":1465956,"position":5},"title":"Chicago se prepara para un operativo federal de control inmigratorio mientras Trump critica a los funcionarios locales","author":"","date":"septiembre 1, 2025","format":false,"excerpt":"Las autoridades de Chicago se preparan para una importante operaci\u00f3n federal de control de inmigraci\u00f3n que podr\u00eda comenzar esta misma semana, y el alcalde de la ciudad firm\u00f3 un decreto durante el fin de semana destinado a resistir la represi\u00f3n planeada por el Gobierno de Trump.El gobernador de Illinois, JB\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1465956"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1465956\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1465956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1465956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1465956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}