{"id":1466014,"date":"2025-08-30T19:03:43","date_gmt":"2025-08-31T02:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/"},"modified":"2025-08-30T19:03:43","modified_gmt":"2025-08-31T02:03:43","slug":"zohran-mamdani-policia-nueva-york-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","title":{"rendered":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York"},"content":{"rendered":"<p>Meses antes de ganar las primarias dem\u00f3cratas para la alcald\u00eda de la ciudad de Nueva York, Zohran Mamdani se sent\u00f3 en un restaurante pakistan\u00ed en Queens junto a unas dos decenas de polic\u00edas fuera de servicio.<\/p>\n<p>Los agentes estaban familiarizados con los anteriores llamados del asamble\u00edsta de 33 a\u00f1os para recortar fondos a la mayor fuerza policial de Estados Unidos y con publicaciones en redes sociales en las que se refer\u00eda a la polic\u00eda como racista y malvada.<\/p>\n<p>Hab\u00edan sido invitados al encuentro privado por un agente retirado del Departamento de Polic\u00eda de Nueva York (NYPD, por sus siglas en ingl\u00e9s) que pas\u00f3 a\u00f1os ayudando a aumentar la matr\u00edcula de banglades\u00edes y surasi\u00e1ticos en el departamento. Les dijo a los agentes que le dieran una oportunidad a Mamdani.<\/p>\n<p>\u201cNo era seguidor de Mamdani en absoluto, pero a medida que lo conoc\u00ed m\u00e1s, empec\u00e9 a respetarlo y a agradarme m\u00e1s\u201d, dijo Shamsul Haque, organizador de la reuni\u00f3n y un estadounidense de origen banglades\u00ed que pas\u00f3 21 a\u00f1os en el departamento, lleg\u00f3 a convertirse en el primer musulm\u00e1n y surasi\u00e1tico del NYPD en alcanzar el rango de teniente comandante.<\/p>\n<p>Si gana las elecciones generales de noviembre, Mamdani supervisar\u00eda el mayor departamento de polic\u00eda municipal del pa\u00eds. Ser\u00e1 una gran prueba pol\u00edtica y de seguridad p\u00fablica para ambas partes: Mamdani, como socialista democr\u00e1tico que ha pedido cambios radicales en la aplicaci\u00f3n de la ley, y el NYPD, una fuerza de 36.000 agentes que desde hace tiempo enfrenta llamados a reformarse.<\/p>\n<p>Mientras sus oponentes lo acusan de intentar socavar la seguridad p\u00fablica, Mamdani ha rechazado sus anteriores llamados a recortar fondos a la polic\u00eda y se ha apoyado en figuras como Haque, quien afirm\u00f3 que pas\u00f3 de la aprensi\u00f3n a un apoyo total a Mamdani debido a la convicci\u00f3n de que si \u201cse le da la oportunidad\u201d, algunas de sus propuestas podr\u00edan \u201crevolucionar la aplicaci\u00f3n de la ley y la seguridad comunitaria de una manera que beneficiar\u00eda a la sociedad\u201d.<\/p>\n<p>Mamdani tambi\u00e9n est\u00e1 recibiendo apoyo de un veterano experimentado del NYPD: Rodney Harrison, quien se desempe\u00f1\u00f3 como jefe de departamento, el agente uniformado de m\u00e1s alto rango del departamento, antes de su retiro en 2021, se reuni\u00f3 recientemente con Mamdani y respald\u00f3 su campa\u00f1a.<\/p>\n<p>Sin embargo, el apoyo de Mamdani entre los l\u00edderes policiales sigue siendo escaso. Entre quienes cuestionan sus planes est\u00e1 Bill Bratton, quien fue comisionado de polic\u00eda bajo Bill de Blasio, un aliado de Mamdani a quien el candidato dem\u00f3crata ha llamado el mejor alcalde de su vida, as\u00ed como bajo Rudy Giuliani en la d\u00e9cada de 1990.<\/p>\n<p>\u201cSe le considera antipolic\u00eda, en contra del NYPD, as\u00ed que est\u00e1 empezando en una posici\u00f3n dif\u00edcil\u201d, dijo Bratton en una entrevista. \u201cSer\u00e1 interesante ver c\u00f3mo un novato pol\u00edtico que nunca ha dirigido nada maneja la mayor fuerza policial de Estados Unidos\u201d.<\/p>\n<p>Durante su tiempo en el NYPD, Harrison, cuyo apoyo a Mamdani no se hab\u00eda reportado previamente, ayud\u00f3 a implementar el Programa de Polic\u00eda Vecinal, una iniciativa de la era de Blasio que buscaba mejorar la relaci\u00f3n entre las comunidades y la polic\u00eda. Tras retirarse del NYPD, Harrison pas\u00f3 a liderar el Departamento de Polic\u00eda del Condado de Suffolk, donde encabez\u00f3 un exitoso esfuerzo para capturar a Rex Heuermann, sospechoso de los homicidios de Gilgo Beach.<\/p>\n<p>En un comunicado de la campa\u00f1a, Harrison elogi\u00f3 la idea de un Departamento de Seguridad Comunitaria, calific\u00e1ndola de \u201cplan reflexivo e impactante\u201d que, en su opini\u00f3n, podr\u00eda ayudar a reducir la carga de trabajo de los agentes al incorporar profesionales de la salud mental.<\/p>\n<p>\u201cS\u00e9 que la polic\u00eda est\u00e1 trabajando duro para mantenernos seguros, y tampoco podemos seguir usando el mismo manual para cada problema\u201d, dijo Harrison.<\/p>\n<p>La campa\u00f1a de Mamdani dijo que realiza reuniones para entender c\u00f3mo implementar las propuestas delineadas en su agenda de seguridad p\u00fablica, que buscan renovar la manera en que la ciudad de Nueva York trata a sus residentes m\u00e1s vulnerables.<\/p>\n<p>Una de sus principales propuestas es la creaci\u00f3n de un Departamento de Seguridad Comunitaria. Elle Bisgaard-Church, quien dirigi\u00f3 la campa\u00f1a primaria de Mamdani y ahora trabaja como su asesora principal, describi\u00f3 el departamento propuesto como una entidad que abordar\u00eda \u201cla violencia armada, la seguridad en el metro, las crisis de salud mental y otros problemas graves con soluciones basadas en evidencia\u201d.<\/p>\n<p>Mamdani se ha reunido con familias de neoyorquinos que sufren enfermedades mentales, incluida la familia de <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/05\/13\/joven-llamo-911-crisis-muerto-trax\">Win Rozario<\/a>, un joven de 19 a\u00f1os que estaba atravesando una crisis de salud mental cuando llam\u00f3 al 911 pidiendo ayuda en marzo del a\u00f1o pasado.<\/p>\n<p>Agentes de la polic\u00eda de Nueva York llegaron y encontraron a Rozario de pie en la cocina con su madre cerca. Cuando un agente se acerc\u00f3 a la cocina, Rozario pareci\u00f3 alterarse y tom\u00f3 un par de tijeras de cocina. Los agentes primero dispararon sus pistolas el\u00e9ctricas, pero cuando Rozario continu\u00f3 avanzando hacia ellos con las tijeras en la mano, los agentes abrieron fuego y lo mataron. Toda la situaci\u00f3n se desarroll\u00f3 en minutos, seg\u00fan ha dicho la familia de Rozario.<\/p>\n<p>Mamdani quiere centralizar y expandir parte del sistema que ya existe, triplicando el tama\u00f1o del programa de Equipos M\u00f3vil de Crisis de la ciudad, que permite un servicio de 24 horas, 7 d\u00edas de la semana, aumentando los salarios y creando un sistema m\u00f3vil de crisis independiente, similar al 911, al que los neoyorquinos podr\u00edan solicitar ayuda.<\/p>\n<p>Nueva York estar\u00eda lejos de ser la primera ciudad en intentar implementar cambios. La campa\u00f1a de Mamdani se inspira en ciudades m\u00e1s peque\u00f1as.<\/p>\n<p>En Eugene, Oreg\u00f3n, el programa de Asistencia en Crisis para Ayudar en las Calles (CAHOOTS, por sus siglas en ingl\u00e9s) gestiona un sistema de respuesta a crisis 24\/7 que conecta a trabajadores de salud mental y m\u00e9dicos para responder a llamadas no urgentes que involucran a personas con crisis de salud mental. Un estudio de 2020 sobre el programa encontr\u00f3 que, de aproximadamente 24.000 llamadas a las que respondi\u00f3 CAHOOTS en 2019, solo 311 requirieron apoyo policial.<\/p>\n<p>No obstante, el programa ha enfrentado importantes desaf\u00edos presupuestarios. A principios de este a\u00f1o, Eugene <strong>\ufeff<\/strong>\u2014una ciudad de 180.000 habitantes en comparaci\u00f3n con los 8 millones de Nueva York\u2014 anunci\u00f3 que dejar\u00eda de servir al \u00e1rea debido a problemas de contrato y financiamiento.<\/p>\n<p>Ben Struhl, director ejecutivo del Crime and Justice Policy Lab, de la Universidad de Pensilvania, dijo que Mamdani enfrentar\u00e1 un doble desaf\u00edo: reformar un sistema masivo que requiere una inversi\u00f3n igualmente masiva y superar el escepticismo general de que el Gobierno est\u00e1 cumpliendo con su labor.<\/p>\n<p>\u201cPara Nueva York, elegir algunos problemas que preocupan a las comunidades y demostrar que el Gobierno realmente est\u00e1 intentando resolverlos es lo que funcionar\u00e1 para intentar superar ese cinismo\u201d, dijo Struhl.<\/p>\n<p>Como miembro destacado de los Socialistas Democr\u00e1ticos de Am\u00e9rica, Mamdani ha pedido anteriormente cambios de pol\u00edtica y recortes presupuestarios que chocan frontalmente con las prioridades actuales del departamento y su l\u00edder, la comisionada de polic\u00eda Jessica Tisch.<\/p>\n<p>Aunque Mamdani ha elogiado el liderazgo de Tisch en la polic\u00eda de Nueva York, se\u00f1alando que ha sido efectiva al erradicar la corrupci\u00f3n dentro de la agencia y d\u00e1ndole cr\u00e9dito por la reducci\u00f3n del crimen, no se ha comprometido a mantenerla al frente del departamento.<\/p>\n<p>La marcada divisi\u00f3n ideol\u00f3gica entre Mamdani y Tisch sugiere que el futuro de ella bajo una posible administraci\u00f3n de Mamdani sigue siendo incierto, aunque la campa\u00f1a de Mamdani dice que no ha tomado decisiones sobre los principales cargos.<\/p>\n<p>Tisch, cuya familia controla la Loews Corporation, ha pasado gran parte de su carrera en el Gobierno municipal. Ella ha hecho hincapi\u00e9 en la vigilancia basada en tecnolog\u00eda y en t\u00e1cticas policiales tradicionales.<\/p>\n<p>Recientemente, Tisch se ha mostrado en\u00e9rgica contra las reformas de la justicia penal, abogando por cambios que Mamdani probablemente no apoyar\u00e1, como la ampliaci\u00f3n de los equipos policiales centrados en la vigilancia de la calidad de vida, una estrategia policial centrada en delitos menores como orinar en p\u00fablico, evadir el pago de tarifas o pedir limosna.<\/p>\n<p>La estrategia se basa en la creencia de que ignorar molestias visibles finalmente conduce a delitos m\u00e1s graves y que mantener el orden p\u00fablico resulta en mayor seguridad y mejores condiciones de vida. Los cr\u00edticos de esta pr\u00e1ctica dicen que la vigilancia de la calidad de vida afecta desproporcionadamente a las comunidades de color.<\/p>\n<p>Tisch tambi\u00e9n ha sido cr\u00edtica con la Ley de Aumento de Edad del estado, culpando a la medida por un aumento en la violencia juvenil en la ciudad. La ley, aprobada en 2017, eleva la edad de responsabilidad penal en Nueva York de 16 a 18 a\u00f1os, evitando que los j\u00f3venes infractores sean procesados en tribunales penales.<\/p>\n<p>El presidente Donald Trump y los republicanos han convertido a Mamdani en un objetivo clave mientras argumentan que las ciudades gobernadas por dem\u00f3cratas est\u00e1n mal gestionadas y son peligrosas. Trump ha desplegado militares de la Guardia Nacional en Washington y ha amenazado con hacer lo mismo en Chicago. El presidente ha prometido \u201cponer en orden\u201d Nueva York si Mamdani gana.<\/p>\n<p>Mamdani desestim\u00f3 la amenaza de Trump de enviar soldados a la ciudad, dando un giro para presentar al departamento como capaz y eficaz, al tiempo que dec\u00eda que Trump, en realidad, \u201cpondr\u00eda en peligro a los neoyorquinos\u201d.<\/p>\n<p>Mientras tanto, Tisch y la gobernadora de Nueva York, Kathy Hochul, se han comunicado directamente con el Gobierno de Trump.<\/p>\n<p>Hochul habl\u00f3 por tel\u00e9fono con Trump sobre su amenaza de desplegar soldados en los \u00faltimos d\u00edas, dijo a la prensa esta semana. Hochul, quien tambi\u00e9n ha enviado a la Guardia Nacional a patrullar algunos de los centros de transporte m\u00e1s concurridos de la ciudad, dijo que intent\u00f3 convencer a Trump de no enviar soldados, dici\u00e9ndole que el crimen en la ciudad de Nueva York ha bajado y que las pol\u00edticas del NYPD est\u00e1n funcionando.<\/p>\n<p>La conversaci\u00f3n pareci\u00f3 centrarse en Trump.<\/p>\n<p>\u201cMe llevo bien con Kathy. Si ella quisiera hacerlo, yo lo har\u00eda\u201d, dijo durante una reuni\u00f3n de gabinete cuando un periodista le pregunt\u00f3 sobre la posibilidad de desplegar soldados.<\/p>\n<p>Tisch tambi\u00e9n est\u00e1 presentando su caso. Una fuente con conocimiento de la reuni\u00f3n confirm\u00f3 a CNN que la comisionada y la secretaria de Justicia, Pam Bondi, se reunieron esta semana. Durante lo que se describi\u00f3 como una reuni\u00f3n \u201cpositiva y productiva\u201d que dur\u00f3 unos 30 minutos, Tisch le dijo a Bondi que la tasa de criminalidad en la ciudad de Nueva York es baja y que el NYPD no necesitaba ayuda federal ni la intervenci\u00f3n de la Guardia Nacional.<\/p>\n<p>Una primera prueba para Mamdani se produjo tras un tiroteo masivo dentro de un edificio de oficinas en Manhattan que dej\u00f3 5 muertos, incluido un agente de polic\u00eda fuera de servicio que trabajaba como guardia de seguridad en el vest\u00edbulo. El incidente ocurri\u00f3 mientras Mamdani estaba fuera del pa\u00eds de vacaciones. A su regreso, Mamdani fue r\u00e1pidamente recibido con los brazos abiertos por el agente ca\u00eddo d\u00edas despu\u00e9s de distanciarse de comentarios cr\u00edticos previos con la polic\u00eda.<\/p>\n<p>Bratton dijo que la propuesta de Mamdani de asignar a profesionales de la salud mental para responder a llamadas que involucren a personas en crisis mental es un \u201cesfuerzo bien intencionado\u201d que seguramente chocar\u00e1 con la enorme burocracia de la ciudad y con una red compleja de agencias y grupos de trabajo que ya intentan abordar la crisis de salud mental de la ciudad.<\/p>\n<p>\u201cApoyo firmemente el concepto de intervenci\u00f3n\u201d, dijo el excomisionado de polic\u00eda.<br \/>\u201cPero, \u00bfc\u00f3mo se equilibra la idea de la necesidad de la polic\u00eda en algunas de estas llamadas? Muchos no la necesitan, pero deben estar disponibles si se les necesita\u201d.<\/p>\n<p>Bratton, quien no se ha reunido con Mamdani, cree que cualquier esfuerzo por \u201creducir significativamente la aplicaci\u00f3n de la ley de calidad de vida\u201d por parte de una posible administraci\u00f3n Mamdani podr\u00eda deshacer muchos de los avances logrados en los \u00faltimos a\u00f1os.<\/p>\n<p>\u201cEl \u00fanico destello de luz positiva que veo es que Mamdani busca aprender, como lo hizo de Blasio al principio\u201d, dijo Bratton. \u201c\u00c9l trat\u00f3 de entender c\u00f3mo motivar a los polic\u00edas, c\u00f3mo lidiar con el crimen y el desorden al mismo tiempo.<\/p>\n<p>\u201c\u00bfEscuchar\u00e1? \u00bfY a qui\u00e9n escucha?\u201d, dijo. \u201cEsa es la pregunta\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meses antes de ganar las primarias dem\u00f3cratas para la alcald\u00eda de la ciudad de Nueva York, Zohran Mamdani se sent\u00f3 en un restaurante pakistan\u00ed en Queens junto a unas dos decenas de polic\u00edas fuera de servicio. Los agentes estaban familiarizados con los anteriores llamados del asamble\u00edsta de 33 a\u00f1os para recortar fondos a la mayor [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466014","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias\" \/>\n<meta property=\"og:description\" content=\"Meses antes de ganar las primarias dem\u00f3cratas para la alcald\u00eda de la ciudad de Nueva York, Zohran Mamdani se sent\u00f3 en un restaurante pakistan\u00ed en Queens junto a unas dos decenas de polic\u00edas fuera de servicio. Los agentes estaban familiarizados con los anteriores llamados del asamble\u00edsta de 33 a\u00f1os para recortar fondos a la mayor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-31T02:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York\",\"datePublished\":\"2025-08-31T02:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\"},\"wordCount\":2169,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\",\"name\":\"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-31T02:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias","og_description":"Meses antes de ganar las primarias dem\u00f3cratas para la alcald\u00eda de la ciudad de Nueva York, Zohran Mamdani se sent\u00f3 en un restaurante pakistan\u00ed en Queens junto a unas dos decenas de polic\u00edas fuera de servicio. Los agentes estaban familiarizados con los anteriores llamados del asamble\u00edsta de 33 a\u00f1os para recortar fondos a la mayor [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-31T02:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/"},"author":{"name":"","@id":""},"headline":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York","datePublished":"2025-08-31T02:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/"},"wordCount":2169,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","name":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-31T02:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Zohran Mamdani busca dialogar con la polic\u00eda de Nueva York","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/08\/30\/zohran-mamdani-policia-nueva-york-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-31T02:03:43Z","datePublished":"2025-08-31T02:03:43Z","dateModified":"2025-08-31T02:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Zohran Mamdani busca dialogar con la polic\\u00eda de Nueva York\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/30\\\/zohran-mamdani-policia-nueva-york-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/08\\\/30\\\/zohran-mamdani-policia-nueva-york-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-31T02:03:43Z\",\"datePublished\":\"2025-08-31T02:03:43Z\",\"dateModified\":\"2025-08-31T02:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468128,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/07\/ice-recluta-policia-nueva-york-mamdani-trax\/","url_meta":{"origin":1466014,"position":0},"title":"ICE est\u00e1 reclutando agentes de la Polic\u00eda de Nueva York tras la victoria de Zohran Mamdani","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"El Servicio de Inmigraci\u00f3n y Control de Aduanas de EE.UU. (ICE, por sus siglas en ingl\u00e9s) est\u00e1 utilizando la victoria del alcalde electo Zohran Mamdani para reclutar a agentes de polic\u00eda para que abandonen el Departamento de Polic\u00eda de Nueva York (NYPD, por sus siglas en ingl\u00e9s).Este viernes, ICE public\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472010,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/03\/09\/antiterrorista-fbi-explosivo-zohran-mamdani-trax\/","url_meta":{"origin":1466014,"position":1},"title":"Equipo antiterrorista del FBI investiga artefacto explosivo lanzado cerca de la residencia de Zohran Mamdani","author":"","date":"marzo 9, 2026","format":false,"excerpt":"Un hombre lanz\u00f3 el s\u00e1bado un dispositivo explosivo improvisado en medio de protestas enfrentadas afuera de la residencia del alcalde de Nueva York, Zohran Mamdani, lo que provoc\u00f3 una investigaci\u00f3n por parte de las autoridades federales contra el terrorismo y el descubrimiento de un dispositivo adicional en un autom\u00f3vil cercano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466461,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/15\/kathy-hochul-respalda-zohran-mamdani-alcaldia-nueva-york-trax\/","url_meta":{"origin":1466014,"position":2},"title":"La gobernadora de Nueva York, Kathy Hochul, respalda a Zohran Mamdani en la carrera por la alcald\u00eda de la ciudad","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"La gobernadora de Nueva York, Kathy Hochul, respald\u00f3 el domingo al candidato dem\u00f3crata a la alcald\u00eda de la ciudad de Nueva York, Zohran Mamdani, y lo calific\u00f3 de \u201cun l\u00edder centrado en hacer que la ciudad de Nueva York sea asequible\u201d a pesar de sus desacuerdos.El respaldo de Hochul, publicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464126,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/07\/01\/trump-arrestaria-zohran-mamdani-si-desafia-ice-nueva-york-trax\/","url_meta":{"origin":1466014,"position":3},"title":"Donald Trump dice que &#171;tendr\u00eda que arrestar&#187; a Zohran Mamdani si desaf\u00eda a los agentes de inmigraci\u00f3n en Nueva York","author":"","date":"julio 1, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump dijo que \u201ctendr\u00e1 que arrestar\u201d Zohran Mamdani \u2014quien se alz\u00f3 con la victoria en las primarias dem\u00f3cratas para la alcald\u00eda de Nueva York este martes\u2014 si desaf\u00eda al Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE) en la ciudad de Nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469708,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/01\/zohran-mamdani-asume-alcalde-nueva-york-trax\/","url_meta":{"origin":1466014,"position":4},"title":"Zohran Mamdani asume como alcalde de la ciudad de Nueva York","author":"","date":"enero 1, 2026","format":false,"excerpt":"Zohran Mamdani, el socialista democr\u00e1tico que hizo campa\u00f1a con la promesa de enfrentar la crisis de asequibilidad en una de las ciudades m\u00e1s caras de Estados Unidos, jur\u00f3 este jueves como el 112.\u00ba alcalde de la ciudad de Nueva York.Mamdani, un inmigrante de 34 a\u00f1os originario de Uganda, hace historia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468525,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/19\/trump-reunion-alcalde-nueva-york-zohran-mamdani-trax\/","url_meta":{"origin":1466014,"position":5},"title":"Trump dice que se reunir\u00e1 con el alcalde electo de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 este mi\u00e9rcoles que planea recibir al alcalde electo de la ciudad de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval, en la primera reuni\u00f3n cara a cara entre ambos desde que el joven pol\u00edtico gan\u00f3 los comicios a principios de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1466014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1466014"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1466014\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1466014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1466014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1466014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}