{"id":1466195,"date":"2025-09-05T18:03:45","date_gmt":"2025-09-06T01:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/"},"modified":"2025-09-05T18:03:45","modified_gmt":"2025-09-06T01:03:45","slug":"new-york-times-fallida-mision-comandos-marina-2019-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","title":{"rendered":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos"},"content":{"rendered":"<p>Una misi\u00f3n de 2019 en Corea del Norte, cuyo objetivo era que los comandos de la Marina de guerra de EE.UU. (conocidos como los Navy SEALs) de la Marina implantaran un dispositivo electr\u00f3nico para interceptar las comunicaciones del l\u00edder norcoreano, Kim Jong-un, result\u00f3 en una operaci\u00f3n fallida que dej\u00f3 a norcoreanos desarmados muertos, seg\u00fan un informe de <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.nytimes.com%2F2025%2F09%2F05%2Fus%2Fnavy-seal-north-korea-trump-2019.html%3Fsmid%3Dnytcore-ios-share%26referringSource%3DarticleShare&#038;data=05%7C02%7Clauren.chadwick%40cnn.com%7C2e574b5cb3b54a74d5ba08ddec80c40b%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638926759976646320%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=uUyxoOY%2BmrYAOZkthCBZ3%2FFTJonkAn7d2NF9ICt%2Byx0%3D&#038;reserved=0\">The New York Times<\/a> publicado el viernes.<\/p>\n<p>La misi\u00f3n, que tuvo lugar durante el primer mandato del presidente Donald Trump, requiri\u00f3 la aprobaci\u00f3n directa del presidente, seg\u00fan informa el Times, y se produjo en medio de conversaciones nucleares de alto nivel entre Estados Unidos y Corea del Norte.<\/p>\n<p>La Casa Blanca y el Pent\u00e1gono declinaron hacer comentarios. CNN tambi\u00e9n se ha puesto en contacto con el Comando de Operaciones Especiales de Estados Unidos y la misi\u00f3n permanente de Corea del Norte ante las Naciones Unidas en Nueva York para obtener comentarios sobre el informe.<\/p>\n<p>Trump, hablando con los periodistas en el Despacho Oval este viernes, dijo que no sabe \u201cnada\u201d sobre la misi\u00f3n de 2019 reportada por el Times.<\/p>\n<p>\u201cNo s\u00e9 nada al respecto, no. Podr\u00eda averiguar, pero no s\u00e9 nada sobre eso\u201d, dijo Trump. \u201cNo s\u00e9 nada al respecto. Lo estoy escuchando ahora por primera vez\u201d.<\/p>\n<p>Seg\u00fan el Times, el Escuadr\u00f3n Rojo del Equipo Seis de los comandos SEAL ensay\u00f3 durante meses un plan que requerir\u00eda que la Armada introdujera un submarino de propulsi\u00f3n nuclear en aguas norcoreanas, junto con dos minisubmarinos del grupo SEAL que navegar\u00edan a lo largo de la costa antes de nadar hasta el objetivo para instalar el dispositivo electr\u00f3nico.<\/p>\n<p>El Equipo SEAL Seis, una unidad militar estadounidense secreta formada en 1980, ha trabajado en diversas misiones secretas, peligrosas y de alto riesgo, incluyendo la operaci\u00f3n que mat\u00f3 a Osama bin Laden en Pakist\u00e1n en 2011.<\/p>\n<p>The New York Times informa que cuando un barco norcoreano, que posteriormente se suger\u00eda que conten\u00eda a dos o tres civiles norcoreanos buceando en busca de mariscos, se acerc\u00f3 al agua durante la operaci\u00f3n, los comandos SEAL abrieron fuego y los mataron. El informe tambi\u00e9n afirma que el Gobierno de Trump no notific\u00f3 a miembros clave del Congreso.<\/p>\n<p>La relaci\u00f3n entre Estados Unidos y Corea del Norte, un pa\u00eds altamente aislado, ha sido inestable a lo largo de los a\u00f1os. Trump lanz\u00f3 un ultim\u00e1tum a Corea del Norte en 2017 para que no lanzara m\u00e1s amenazas contra Estados Unidos o se enfrentar\u00edan a fuego y furia como el mundo nunca ha visto. Su advertencia se produjo cuando analistas de inteligencia estadounidenses evaluaron que Corea del Norte hab\u00eda producido una ojiva nuclear miniaturizada en ese momento.<\/p>\n<p>Kim y Trump intercambiar\u00edan una serie de halagos y cartas en 2018 y 2019 tras las significativas tensiones de 2017. Posteriormente, participar\u00edan en una serie de cumbres sin precedentes en 2018, con efusivas declaraciones de una nueva amistad, pero vagas promesas de desarme nuclear.<\/p>\n<p>En 2019, Trump har\u00eda historia al ser el primer l\u00edder estadounidense en funciones en pisar ese pa\u00eds ermita\u00f1o, al estrecharle la mano a Kim y dar 20 pasos hacia Corea del Norte. La administraci\u00f3n Biden, por su parte, adoptar\u00eda una estrategia diferente, seg\u00fan inform\u00f3 CNN en aquel momento, centrada en demostraciones de fuerza y \u200b\u200bunidad con Corea del Sur, as\u00ed como en avances graduales hacia la desnuclearizaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una misi\u00f3n de 2019 en Corea del Norte, cuyo objetivo era que los comandos de la Marina de guerra de EE.UU. (conocidos como los Navy SEALs) de la Marina implantaran un dispositivo electr\u00f3nico para interceptar las comunicaciones del l\u00edder norcoreano, Kim Jong-un, result\u00f3 en una operaci\u00f3n fallida que dej\u00f3 a norcoreanos desarmados muertos, seg\u00fan un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466195","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una misi\u00f3n de 2019 en Corea del Norte, cuyo objetivo era que los comandos de la Marina de guerra de EE.UU. (conocidos como los Navy SEALs) de la Marina implantaran un dispositivo electr\u00f3nico para interceptar las comunicaciones del l\u00edder norcoreano, Kim Jong-un, result\u00f3 en una operaci\u00f3n fallida que dej\u00f3 a norcoreanos desarmados muertos, seg\u00fan un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T01:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos\",\"datePublished\":\"2025-09-06T01:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\",\"name\":\"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-06T01:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","og_locale":"es_ES","og_type":"article","og_title":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias","og_description":"Una misi\u00f3n de 2019 en Corea del Norte, cuyo objetivo era que los comandos de la Marina de guerra de EE.UU. (conocidos como los Navy SEALs) de la Marina implantaran un dispositivo electr\u00f3nico para interceptar las comunicaciones del l\u00edder norcoreano, Kim Jong-un, result\u00f3 en una operaci\u00f3n fallida que dej\u00f3 a norcoreanos desarmados muertos, seg\u00fan un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-06T01:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/"},"author":{"name":"","@id":""},"headline":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos","datePublished":"2025-09-06T01:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","name":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-06T01:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"The New York Times: La fallida misi\u00f3n de los comandos de la Marina en 2019 dej\u00f3 a norcoreanos desarmados muertos","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/09\/05\/new-york-times-fallida-mision-comandos-marina-2019-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-06T01:03:45Z","datePublished":"2025-09-06T01:03:45Z","dateModified":"2025-09-06T01:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"The New York Times: La fallida misi\\u00f3n de los comandos de la Marina en 2019 dej\\u00f3 a norcoreanos desarmados muertos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/09\\\/05\\\/new-york-times-fallida-mision-comandos-marina-2019-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/09\\\/05\\\/new-york-times-fallida-mision-comandos-marina-2019-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-06T01:03:45Z\",\"datePublished\":\"2025-09-06T01:03:45Z\",\"dateModified\":\"2025-09-06T01:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466215,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/09\/06\/trump-viaje-corea-del-sur-reunion-xi-jinping-trax\/","url_meta":{"origin":1466195,"position":0},"title":"Trump se prepara discretamente para viajar a Corea del Sur el pr\u00f3ximo mes, donde podr\u00eda reunirse con Xi Jinping","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"El presidente Donald Trump y sus principales asesores se preparan discretamente para viajar a Corea del Sur en octubre para la reuni\u00f3n de los ministros de Comercio del Foro para la Cooperaci\u00f3n Econ\u00f3mica de Asia y el Pac\u00edfico (APEC), dijeron a CNN tres funcionarios del Gobierno de Trump.La cumbre, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455417,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/10\/29\/soldados-norcoreanos-comandos-rusos-frente-ucrania-trax\/","url_meta":{"origin":1466195,"position":1},"title":"Los soldados norcoreanos aprenden comandos rusos y podr\u00edan ser enviados al frente de Ucrania, dicen legisladores surcoreanos","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN) -- Los soldados norcoreanos podr\u00edan estar siendo preparados para un traslado al frente de la guerra de Rusia contra Ucrania despu\u00e9s de que se les ense\u00f1aron comandos rusos b\u00e1sicos, dijeron este martes legisladores surcoreanos a la agencia de noticias Yonhap, citando a funcionarios de inteligencia del pa\u00eds.Unos 10.000 soldados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456911,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/23\/soldados-norcoreanos-muertos-heridos-kursk-zelensky-trax\/","url_meta":{"origin":1466195,"position":2},"title":"M\u00e1s de 3.000 soldados norcoreanos muertos o heridos en la regi\u00f3n rusa de Kursk, seg\u00fan Zelensky","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Ucrania estima que m\u00e1s de 3.000 soldados norcoreanos han muerto o han resultado heridos en la regi\u00f3n rusa de Kursk, al oeste del pa\u00eds, dijo el lunes el presidente de Ucrania Volodymyr Zelensky.Se cree que los soldados norcoreanos han sufrido grandes p\u00e9rdidas en la regi\u00f3n, seg\u00fan funcionarios estadounidenses y ucranianos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456699,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/18\/adoctrinados-soldados-norcoreanos-rusia-expertos-trax\/","url_meta":{"origin":1466195,"position":3},"title":"Adoctrinados, leales y bien entrenados: no hay que subestimar a los soldados norcoreanos en Rusia, dicen algunos expertos","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Lejos de sus hogares, en uno de los Estados m\u00e1s aislados y herm\u00e9ticos del mundo, unos 11.000 soldados norcoreanos se encuentran en el centro del mayor conflicto de Europa desde la Segunda Guerra Mundial.Poco se sabe de las tropas norcoreanas desplegadas para apoyar a Rusia en su devastadora guerra de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469503,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/22\/muertos-accidente-avion-marina-mexico-texas-trax\/","url_meta":{"origin":1466195,"position":4},"title":"Al menos 4 muertos tras accidente de avi\u00f3n de la Marina de M\u00e9xico en misi\u00f3n m\u00e9dica en Texas","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"Al menos cuatro personas murieron despu\u00e9s de que un avi\u00f3n de la Marina de M\u00e9xico que transportaba pacientes con quemaduras se estrell\u00f3 en la bah\u00eda de Galveston, Texas, este lunes, informaron funcionarios del sheriff a la filial de CNN KPRC.Ocho personas iban a bordo de la aeronave, incluidos dos pilotos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456871,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/22\/ucrania-afirma-soldados-norcoreanos-identificaciones-rusas-falsas-trax\/","url_meta":{"origin":1466195,"position":5},"title":"Ucrania afirma que soldados norcoreanos recibieron identificaciones militares rusas falsas","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"Los soldados norcoreanos que luchan por Rusia recibieron documentos militares falsos con nombres y lugares de nacimiento rusos, inform\u00f3 el ej\u00e9rcito ucraniano, en medio de afirmaciones de Kyiv de que Mosc\u00fa est\u00e1 tratando de ocultar la presencia de combatientes extranjeros en el campo de batalla.Las fuerzas de operaciones especiales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1466195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1466195"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1466195\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1466195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1466195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1466195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}