{"id":1469393,"date":"2025-12-18T10:03:43","date_gmt":"2025-12-18T18:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/"},"modified":"2025-12-18T10:03:43","modified_gmt":"2025-12-18T18:03:43","slug":"choque-jet-privado-carolina-del-norte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","title":{"rendered":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte"},"content":{"rendered":"<p>Varias personas murieron despu\u00e9s de que un peque\u00f1o jet privado se estrellara poco despu\u00e9s de despegar en Statesville, Carolina del Norte, seg\u00fan inform\u00f3 un funcionario de la oficina del alguacil local.<\/p>\n<p>El incidente ocurri\u00f3 poco despu\u00e9s de las 10:15 a.m., dijo a CNN Bill Hamby, jefe adjunto del condado de Iredell.<\/p>\n<p>El n\u00famero exacto de v\u00edctimas mortales a\u00fan no se conoce, a\u00f1adi\u00f3.<\/p>\n<p>\u201cUn Cessna C550 se estrell\u00f3 mientras aterrizaba en el Aeropuerto Regional de Statesville, en Carolina del Norte, alrededor de las 10:20 a.m. hora local del jueves 18 de diciembre. La Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s) y la Junta Nacional de Seguridad del Transporte (NTSB, por sus siglas en ingl\u00e9s) investigar\u00e1n el incidente. La NTSB encabezar\u00e1 la investigaci\u00f3n y proporcionar\u00e1 cualquier actualizaci\u00f3n\u201d, dijo la FAA a CNN.<\/p>\n<p>CNN se comunic\u00f3 con la NTSB para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>Statesville se encuentra a unos 64 kil\u00f3metros al norte de Charlotte.<\/p>\n<p>\u201cEl Aeropuerto Regional de Statesville ofrece instalaciones de aviaci\u00f3n corporativa para compa\u00f1\u00edas de la lista Fortune 500 y varios equipos de NASCAR\u201d, seg\u00fan el sitio web de la ciudad.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varias personas murieron despu\u00e9s de que un peque\u00f1o jet privado se estrellara poco despu\u00e9s de despegar en Statesville, Carolina del Norte, seg\u00fan inform\u00f3 un funcionario de la oficina del alguacil local. El incidente ocurri\u00f3 poco despu\u00e9s de las 10:15 a.m., dijo a CNN Bill Hamby, jefe adjunto del condado de Iredell. El n\u00famero exacto de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469393","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias\" \/>\n<meta property=\"og:description\" content=\"Varias personas murieron despu\u00e9s de que un peque\u00f1o jet privado se estrellara poco despu\u00e9s de despegar en Statesville, Carolina del Norte, seg\u00fan inform\u00f3 un funcionario de la oficina del alguacil local. El incidente ocurri\u00f3 poco despu\u00e9s de las 10:15 a.m., dijo a CNN Bill Hamby, jefe adjunto del condado de Iredell. El n\u00famero exacto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T18:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte\",\"datePublished\":\"2025-12-18T18:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\"},\"wordCount\":233,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\",\"name\":\"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-18T18:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias","og_description":"Varias personas murieron despu\u00e9s de que un peque\u00f1o jet privado se estrellara poco despu\u00e9s de despegar en Statesville, Carolina del Norte, seg\u00fan inform\u00f3 un funcionario de la oficina del alguacil local. El incidente ocurri\u00f3 poco despu\u00e9s de las 10:15 a.m., dijo a CNN Bill Hamby, jefe adjunto del condado de Iredell. El n\u00famero exacto de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-18T18:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/"},"author":{"name":"","@id":""},"headline":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte","datePublished":"2025-12-18T18:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/"},"wordCount":233,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","name":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-18T18:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/choque-jet-privado-carolina-del-norte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-18T18:03:43Z","datePublished":"2025-12-18T18:03:43Z","dateModified":"2025-12-18T18:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mueren varias personas luego de que se estrellara un jet privado en Carolina del Norte\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/18\\\/choque-jet-privado-carolina-del-norte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/18\\\/choque-jet-privado-carolina-del-norte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-18T18:03:43Z\",\"datePublished\":\"2025-12-18T18:03:43Z\",\"dateModified\":\"2025-12-18T18:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458547,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/10\/colision-aviones-privados-arizona-trax\/","url_meta":{"origin":1469393,"position":0},"title":"Al menos un muerto y varios heridos tras colisi\u00f3n de dos aviones privados en Arizona","author":"","date":"febrero 10, 2025","format":false,"excerpt":"Al menos una persona ha muerto y varias resultaron heridas despu\u00e9s de que un avi\u00f3n privado de tama\u00f1o mediano chocara con otro avi\u00f3n al llegar al Aeropuerto de Scottsdale en Arizona el lunes por la tarde.Una persona muri\u00f3 y cuatro resultaron heridas, dijo el capit\u00e1n del Departamento de Bomberos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459195,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/25\/avion-southwest-aborta-aterrizaje-evitar-colisionar-jet-trax\/","url_meta":{"origin":1469393,"position":1},"title":"Avi\u00f3n de Southwest Airlines aborta aterrizaje para evitar colisionar con jet privado en el Aeropuerto Midway de Chicago","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Un avi\u00f3n de Southwest Airlines y un jet privado que ingresaron a la pista sin autorizaci\u00f3n casi colisionan en el Aeropuerto Internacional Midway de Chicago este martes por la ma\u00f1ana, inform\u00f3 la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s).El vuelo 2504 de Southwest aterriz\u00f3 de manera segura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464165,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/07\/02\/accidente-avion-paracaidismo-nueva-jersey-trax\/","url_meta":{"origin":1469393,"position":2},"title":"15 personas resultan heridas tras accidente de avi\u00f3n de paracaidismo en Nueva Jersey","author":"","date":"julio 2, 2025","format":false,"excerpt":"Un avi\u00f3n de paracaidismo con 15 personas a bordo se sali\u00f3 de la pista en un aeropuerto de Nueva Jersey la tarde del mi\u00e9rcoles, y varias personas fueron trasladadas al hospital, seg\u00fan informaron las autoridades.El Cessna 208B se estrell\u00f3 en un bosque en el aeropuerto Cross Keys, al sureste de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458936,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/19\/dos-aviones-chocan-arizona-un-muerto-trax\/","url_meta":{"origin":1469393,"position":3},"title":"Dos aviones peque\u00f1os chocan en el aire en Arizona, dejando al menos una persona muerta, informan las autoridades","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Al menos una persona muri\u00f3 despu\u00e9s de que dos aeronaves peque\u00f1as colisionaran en el aire cerca de un aeropuerto de Arizona este mi\u00e9rcoles, seg\u00fan informaron las autoridades.Una Cessna 172S y una Lancair 360 MK II colisionaron a las 8:28 a.m. (hora local) cerca del Aeropuerto Regional de Marana, de acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445241,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/02\/11\/avioneta-se-accidenta-en-una-autopista-en-naples-florida-y-deja-dos-personas-muertas\/","url_meta":{"origin":1469393,"position":4},"title":"Avioneta se accidenta en una autopista en Naples, Florida, y deja dos personas muertas","author":"","date":"febrero 11, 2024","format":false,"excerpt":"(CNN) \u2013Dos personas murieron luego de que una avioneta se estrellara el viernes por la tarde en la Interestatal 75 cerca de la ciudad de Naples, en Florida, y chocara con un veh\u00edculo, dijeron las autoridades.\u00a0 El accidente que ocurri\u00f3 poco despu\u00e9s de que un piloto informara de una emergencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469317,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/16\/segunda-casi-colision-venezuela-fuerza-aerea-trax\/","url_meta":{"origin":1469393,"position":5},"title":"Reportan otro incidente de una casi colisi\u00f3n cerca de Venezuela entre un jet privado y aeronave de la Fuerza A\u00e9rea de EE.UU.","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Transmisiones de radio revisadas por CNN detallan que los pilotos de un jet privado evitaron por poco una colisi\u00f3n con un avi\u00f3n cisterna de reabastecimiento de la Fuerza A\u00e9rea de Estados Unidos cerca de Venezuela el s\u00e1bado, un d\u00eda despu\u00e9s de un incidente similar en las cercan\u00edas.Los pilotos de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469393"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469393\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}