{"id":1469398,"date":"2025-12-18T11:03:41","date_gmt":"2025-12-18T19:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/"},"modified":"2025-12-18T11:03:41","modified_gmt":"2025-12-18T19:03:41","slug":"jake-paul-anthony-joshua-boxeo-explainer-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","title":{"rendered":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?"},"content":{"rendered":"<p>Jake Paul enfrent\u00e1ndose a Anthony Joshua en un combate de boxeo profesional era un escenario impensable hace apenas cinco a\u00f1os.<\/p>\n<p>En 2020, Joshua a\u00fan estaba en la cima de la divisi\u00f3n de peso pesado, tras haber recuperado sus t\u00edtulos mundiales ante Andy Ruiz Jr. el a\u00f1o anterior y haberlos retenido con una aplastante victoria sobre el retador b\u00falgaro Kubrat Pulev.<\/p>\n<p>En contraste, ese mismo a\u00f1o, Paul debutaba como profesional justo cuando el boxeo en YouTube empezaba a despegar.<\/p>\n<p>Paul gan\u00f3 su primera pelea contra su compa\u00f1ero YouTuber Ali Eson Gib, en una actuaci\u00f3n prometedora, aunque contra un oponente poco convencional, por decir mucho.<\/p>\n<p>Ambos parec\u00edan mundos aparte. Pero, en un extra\u00f1o giro del destino, se encaminaron a un choque que culminar\u00e1 en Miami el viernes.<\/p>\n<p>La pelea se llevar\u00e1 a cabo en el Kaseya Center de Miami el viernes por la noche, y se espera que el evento principal comience alrededor de las 10:30 p.m., hora del este.<\/p>\n<p>El combate, uno profesional sancionado por la Comisi\u00f3n Atl\u00e9tica de Florida, constar\u00e1 de ocho asaltos de tres minutos, con ambos boxeadores usando guantes de 10 onzas.<\/p>\n<p>La gran pelea cerrar\u00e1 una cartelera preliminar repleta de acci\u00f3n, que incluye a algunas de las mejores boxeadoras del mundo, en particular a la campeona mundial estadounidense Alycia Baumgardner.<\/p>\n<p>El evento principal se transmitir\u00e1 exclusivamente por Netflix, ya que la plataforma de streaming contin\u00faa su incursi\u00f3n en los deportes en vivo. La plataforma emiti\u00f3 previamente la pelea de Paul contra Mike Tyson, que atrajo a 108 millones de espectadores.<\/p>\n<p>Se espera que tanto Paul como Joshua ganen sumas extraordinarias de dinero con la pelea, a pesar de que no se han publicado las cifras oficiales.<\/p>\n<p>Durante mucho tiempo, Paul ha declarado p\u00fablicamente sus grandes ambiciones en la \u201cciencia dulce\u201d. Dice, y quiz\u00e1s realmente lo cree, que podr\u00eda ser campe\u00f3n mundial. Durante los \u00faltimos cinco a\u00f1os, se ha recluido en Puerto Rico, donde reside y entrena como boxeador profesional. Es un enfoque que ha dado resultados y ahora es un boxeador mucho mejor que hace cinco a\u00f1os.<\/p>\n<p>Pero si dejamos de lado su extraordinario perfil, el curr\u00edculum box\u00edstico de Paul no est\u00e1 a la altura de sus propias expectativas, con un r\u00e9cord de 12 victorias y una derrota algo enga\u00f1oso.<\/p>\n<p>La mayor\u00eda de sus peleas han sido contra ex peleadores de la UFC, y que para colmo ya hab\u00edan pasado su mejor momento. M\u00e1s recientemente, se enfrent\u00f3 a la leyenda del boxeo Tyson y obtuvo una victoria f\u00e1cil contra un hombre que se acercaba a su 60 cumplea\u00f1os.<\/p>\n<p>Su \u00fanica derrota fue contra un boxeador profesional, cuando Tommy Fury, primo del mundialmente famoso boxeador Tyson Fury, despach\u00f3 a Paul por puntos.<\/p>\n<p>Pero Paul sigue siendo una figura lucrativa en el deporte, capaz de atraer audiencias que rompen r\u00e9cords en todo el mundo.<\/p>\n<p>\u00c9l y su compa\u00f1\u00eda, Most Valuable Productions, se asociaron nuevamente con Netflix este a\u00f1o para pelear inicialmente contra el invicto campe\u00f3n mundial de peso ligero Gervonta \u201cTank\u201d Davis, quien es significativamente m\u00e1s peque\u00f1o que Paul.<\/p>\n<p>Se preve\u00eda una batalla de estilos: \u00bfpodr\u00eda el tama\u00f1o y la potencia superiores de Paul superar la velocidad y la habilidad de Davis, campe\u00f3n mundial de \u00e9lite?<\/p>\n<p>Sin embargo, la pelea se cancel\u00f3 en noviembre debido a un cargo menor de violencia dom\u00e9stica contra Davis, lo que signific\u00f3 que la serie programada en Netflix no tuvo evento principal.<\/p>\n<p>Fue entonces cuando la atenci\u00f3n se centr\u00f3 en Joshua, un hombre mucho m\u00e1s grande y poderoso que Davis.<\/p>\n<p>El brit\u00e1nico, de 36 a\u00f1os, es uno de los mejores pesos pesados \u200b\u200bbrit\u00e1nicos en la historia del deporte. Fue dos veces campe\u00f3n mundial unificado y tiene una medalla de oro ol\u00edmpica. Pero, en realidad, es probable que su mejor momento como luchador ya haya pasado.<\/p>\n<p>Hab\u00eda estado buscando la manera de regresar al ring despu\u00e9s de tomarse un a\u00f1o de descanso tras su derrota contra su compatriota brit\u00e1nico Daniel Dubois en 2024.<\/p>\n<p>Esa derrota gener\u00f3 muchas dudas sobre si Joshua deb\u00eda seguir peleando, ya que el excampe\u00f3n mundial parec\u00eda una sombra de lo que era.<\/p>\n<p>Pero Joshua hab\u00eda planeado inicialmente una pelea de preparaci\u00f3n en noviembre mientras buscaba reconstruir su carrera, con todas las miradas puestas en un posible enfrentamiento contra Tyson Fury en 2026, una pelea que muchos fan\u00e1ticos llevan a\u00f1os ansiando.<\/p>\n<p>As\u00ed que, cuando Paul llam\u00f3 a la puerta, Joshua y su promotor de toda la vida, Eddie Hearn, no lo pensaron dos veces.<\/p>\n<p>\u201cPero, simplemente, no pudimos rechazarlo\u201d, escribi\u00f3 Hearn en una columna en BBC Sport esta semana.<\/p>\n<p>\u201cNing\u00fan boxeador en su sano juicio habr\u00eda dicho que no. Cualquiera que diga que lo har\u00eda est\u00e1 mintiendo descaradamente. Aceptamos una pelea que creemos que ser\u00e1 muy directa, que le dar\u00e1 a AJ un gran reconocimiento en Estados Unidos y una de las mejores ganancias de su carrera\u201d.<\/p>\n<p>A Paul nunca le falta confianza; es un rasgo de personalidad sobre el que ha construido todo su imperio.<\/p>\n<p>Y el joven de 28 a\u00f1os, cuya mirada llega al pecho de Joshua, no ha dejado de decirle a cualquiera que lo escuche que tiene las habilidades para vencer a su colosal oponente, que le saca 13 cent\u00edmetros de altura.<\/p>\n<p>Es un cambio radical, dado que Paul se preparaba para pelear con Davis, mucho m\u00e1s peque\u00f1o, hasta hace relativamente poco. Ahora, los papeles se han invertido y su tarea es derrotar a un gigante.<\/p>\n<p>El desajuste f\u00edsico ha llevado a algunos en el mundo del boxeo a cuestionar si es seguro que la pelea se lleve a cabo, pero Paul sigue confiando en que puede sorprender al mundo.<\/p>\n<p>\u201cEsta no es una pelea tan unilateral como la gente piensa\u201d, dijo Paul en la conferencia de prensa la semana pasada.<\/p>\n<p>\u201cTengo poder, tengo la capacidad de dejar a la gente dormida, y por eso acept\u00e9 este desaf\u00edo. S\u00e9 que es una locura, pero estoy emocionado. Estoy realmente emocionado\u201d.<\/p>\n<p>Sin embargo, este desparejo combate a\u00fan mantiene a muchos cr\u00edticos buscando d\u00f3nde est\u00e1 el truco en todo esto.<\/p>\n<p>A algunos, especialmente en l\u00ednea, les cuesta creer que Paul se interpusiera en el camino de Joshua sin que existiera alg\u00fan tipo de acuerdo para que el brit\u00e1nico se lo tomara con calma.<\/p>\n<p>Ambas partes, sin embargo, han desmentido tales afirmaciones y Joshua, con el peso de las expectativas sobre sus hombros, ha prometido un combate corto.<\/p>\n<p>Los dos boxeadores se hab\u00edan mostrado bastante respetuosos durante la previa del evento, pero la situaci\u00f3n se complic\u00f3 en las \u00faltimas conferencias de prensa previas a la pelea de esta semana, con Joshua insistiendo en su afirmaci\u00f3n de que podr\u00eda \u201cmatar\u201d a Paul.<\/p>\n<p>Las amenazas de tal violencia suelen ser mal vistas en el boxeo, sobre todo por las diferencias f\u00edsicas entre ambos y el tr\u00e1gico historial de muertes en el ring en este deporte, pero Joshua dijo que esa es su mentalidad.<\/p>\n<p>\u201cSimplemente no lo veo desde un punto de vista f\u00edsico\u201d, dijo Joshua en un encuentro cara a cara con Paul a principios de esta semana. Conozco a la persona que est\u00e1 frente a m\u00ed y s\u00e9 que debo conquistar su alma. No se trata solo de lo f\u00edsico. Debo conquistar tu alma en el ring\u201d.<\/p>\n<p>\u201cHe visto peleas en las que puedo ver c\u00f3mo la energ\u00eda y la frecuencia de alguien abandonan su cuerpo. Ese es mi objetivo: hacer lo mismo contigo. Tienes ese instinto, lo ves cuando peleas, ves un peque\u00f1o destello de alguien que est\u00e1 a punto de desvanecerse y simplemente lo sigues explotando hasta que algunos se rinden, otros son noqueados\u201d, dijo Joshua.<\/p>\n<p>\u201cPara m\u00ed, no se trata solo de entrar y dominar f\u00edsicamente. Quiero destrozarlo espiritual y mentalmente\u201d, agreg\u00f3 el excampe\u00f3n.<\/p>\n<p>Sin embargo, Joshua tiene una limitaci\u00f3n. No debe pesar m\u00e1s de 111 kilos en el pesaje oficial el jueves por la noche (es la primera vez que ha tenido que dar el peso en su carrera).<\/p>\n<p>Primero, mucho dinero.<\/p>\n<p>Las cifras oficiales a\u00fan no se han publicado, pero se espera que ambos ganen decenas de millones de d\u00f3lares por el evento, que promete batir a\u00fan m\u00e1s r\u00e9cords de audiencia en Netflix.<\/p>\n<p>Desde la perspectiva del boxeo, muchos han pedido a Joshua que \u201csalve\u201d la credibilidad del boxeo despachando r\u00e1pidamente a Paul.<\/p>\n<p>Tambi\u00e9n se trata de una cuesti\u00f3n de legado para el \u00edcono brit\u00e1nico, quien ha ayudado a la divisi\u00f3n de peso pesado a ganar tanta popularidad en la \u00faltima d\u00e9cada. Una derrota ante un exyoutuber, dicen algunos, podr\u00eda restarle valor a todo lo que ha logrado en el deporte.<\/p>\n<p>Para Paul, solo hay que preocuparse por su seguridad. Pocos, si es que alguno, esperan realmente que pueda lastimar a Joshua, as\u00ed que no tiene nada que perder en ese aspecto.<\/p>\n<p>Por supuesto, siempre ha tenido la oportunidad de golpear, y es ese elemento de duda lo que probablemente atraer\u00e1 a millones de personas a la pantalla el viernes por la noche en Miami.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jake Paul enfrent\u00e1ndose a Anthony Joshua en un combate de boxeo profesional era un escenario impensable hace apenas cinco a\u00f1os. En 2020, Joshua a\u00fan estaba en la cima de la divisi\u00f3n de peso pesado, tras haber recuperado sus t\u00edtulos mundiales ante Andy Ruiz Jr. el a\u00f1o anterior y haberlos retenido con una aplastante victoria sobre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469398","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Jake Paul enfrent\u00e1ndose a Anthony Joshua en un combate de boxeo profesional era un escenario impensable hace apenas cinco a\u00f1os. En 2020, Joshua a\u00fan estaba en la cima de la divisi\u00f3n de peso pesado, tras haber recuperado sus t\u00edtulos mundiales ante Andy Ruiz Jr. el a\u00f1o anterior y haberlos retenido con una aplastante victoria sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T19:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?\",\"datePublished\":\"2025-12-18T19:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\"},\"wordCount\":1593,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\",\"name\":\"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-18T19:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias","og_description":"Jake Paul enfrent\u00e1ndose a Anthony Joshua en un combate de boxeo profesional era un escenario impensable hace apenas cinco a\u00f1os. En 2020, Joshua a\u00fan estaba en la cima de la divisi\u00f3n de peso pesado, tras haber recuperado sus t\u00edtulos mundiales ante Andy Ruiz Jr. el a\u00f1o anterior y haberlos retenido con una aplastante victoria sobre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-18T19:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?","datePublished":"2025-12-18T19:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/"},"wordCount":1593,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","name":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-18T19:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfC\u00f3mo y por qu\u00e9 Jake Paul pelea contra el excampe\u00f3n mundial de peso pesado Anthony Joshua?","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/jake-paul-anthony-joshua-boxeo-explainer-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-18T19:03:41Z","datePublished":"2025-12-18T19:03:41Z","dateModified":"2025-12-18T19:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfC\\u00f3mo y por qu\\u00e9 Jake Paul pelea contra el excampe\\u00f3n mundial de peso pesado Anthony Joshua?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/18\\\/jake-paul-anthony-joshua-boxeo-explainer-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/18\\\/jake-paul-anthony-joshua-boxeo-explainer-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-18T19:03:41Z\",\"datePublished\":\"2025-12-18T19:03:41Z\",\"dateModified\":\"2025-12-18T19:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468437,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/17\/jake-paul-anthony-joshua-miami-netflix-orix\/","url_meta":{"origin":1469398,"position":0},"title":"Jake Paul enfrentar\u00e1 al excampe\u00f3n mundial de boxeo Anthony Joshua en diciembre en Miami con transmisi\u00f3n por Netflix","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"Jake Paul est\u00e1, con toda seguridad, ante el desaf\u00edo m\u00e1s grande en su corta, discutida y estable incursi\u00f3n en el cuadril\u00e1tero. El youtuber, que desde hace algunos a\u00f1os ha ido ganando pantalla por las peleas de boxeo contra veteranos como Mike Tyson, enfrentar\u00e1 ahora al brit\u00e1nico Anthony Joshua, excampe\u00f3n mundial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469407,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/18\/jake-paul-anthony-jashua-netflix-cartelera-orix\/","url_meta":{"origin":1469398,"position":1},"title":"Jake Paul vs. Anthony Jashua: cartelera, previa, horario, cu\u00e1ndo y c\u00f3mo ver por TV e internet","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"Una de las \u00faltimas grandes veladas de boxeo del a\u00f1o llegar\u00e1 este viernes 19 de noviembre. De un lado, el dos veces campe\u00f3n mundial unificado de peso pesado Anthony Joshua. Del otro, el youtuber devenido en boxeador Jake Paul, quien est\u00e1, con toda certeza, ante su prueba m\u00e1s dif\u00edcil en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455847,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/11\/15\/quien-es-jake-paul-trayectoria-record-boxeador-orix\/","url_meta":{"origin":1469398,"position":2},"title":"Qui\u00e9n es Jake Paul y cu\u00e1l es su trayectoria y r\u00e9cord como boxeador","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Jake Paul tiene un estatus indiscutible de celebridad del siglo XXI. Comenz\u00f3 a crear contenido para redes sociales y en un vistazo horas antes de su pelea contra Mike Tyson se le pueden contar m\u00e1s de 27,2 millones de seguidores en su perfil de Instagram y 20,8\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455816,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/11\/14\/mike-tyson-jake-paul-preocupaciones-neurologicas-boxeo-trax\/","url_meta":{"origin":1469398,"position":3},"title":"Mike Tyson vuelve al boxeo profesional 19 a\u00f1os despu\u00e9s de su \u00faltima pelea, y existen preocupaciones sobre su salud neurol\u00f3gica","author":"","date":"noviembre 14, 2024","format":false,"excerpt":"(CNN) -- Mike Tyson entra al ring. Su apariencia juvenil oculta el poder que posee.Es 1985, y el peso pesado est\u00e1 a punto de hacer su debut profesional en el boxeo. Un minuto y 47 segundos despu\u00e9s, el joven de 18 a\u00f1os ya ha obligado a su oponente, H\u00e9ctor Mercedes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457514,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/01\/14\/tyson-fury-anuncio-retiro-boxeo-trax\/","url_meta":{"origin":1469398,"position":4},"title":"Tyson Fury anunci\u00f3 que se retira del boxeo, pero no todos le creen","author":"","date":"enero 14, 2025","format":false,"excerpt":"El mundo del boxeo se llev\u00f3 una sorpresa el lunes cuando el excampe\u00f3n mundial de peso pesado Tyson Fury anunci\u00f3 su retiro del deporte\u2026 otra vez.En un video de 17 segundos publicado en Instagram, Fury dijo: \u201cHola a todos, voy a ser breve y conciso, me gustar\u00eda anunciar mi retiro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469358,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/17\/jake-paul-david-benavidez-monstruo-mexicano-orix\/","url_meta":{"origin":1469398,"position":5},"title":"\u00bfQui\u00e9n es el &#171;Monstruo Mexicano&#187; al que Jake Paul no quiere enfrentar?","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Finalmente, despu\u00e9s de una ola continua de cr\u00edticas, algunas mordaces, y de ser menospreciado por la prensa especializada, Jake Paul asumi\u00f3 un verdadero reto arriba del ring. El youtuber de 28 a\u00f1os se enfrentar\u00e1 al brit\u00e1nico Anthony Joshua este viernes en Miami, en un combate profesional a ocho rounds.En las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469398"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469398\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}