{"id":1469414,"date":"2025-12-19T04:04:01","date_gmt":"2025-12-19T12:04:01","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/"},"modified":"2025-12-19T04:04:01","modified_gmt":"2025-12-19T12:04:01","slug":"pelicot-aleman-violacion-esposa-verdicto-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","title":{"rendered":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os"},"content":{"rendered":"<p>Un hombre alem\u00e1n fue declarado culpable de drogar, violar y filmar a su esposa inconsciente durante a\u00f1os, en un caso que ha sido comparado con el juicio de Dominique Pelicot en Francia.<\/p>\n<p>El conserje escolar de 61 a\u00f1os fue declarado culpable de abusar de su esposa dentro de la casa de la pareja, filmarlo y luego compartirlo en l\u00ednea sin el conocimiento de la v\u00edctima.<\/p>\n<p>Fue condenado el viernes a ocho a\u00f1os y seis meses de prisi\u00f3n tras un juicio en un tribunal de Aquisgr\u00e1n, en el oeste de Alemania. El tribunal declar\u00f3 que se puede presentar un recurso contra la sentencia en el plazo de una semana.<\/p>\n<p>El veredicto llega exactamente un a\u00f1o despu\u00e9s de que el franc\u00e9s Pelicot, quien durante casi diez a\u00f1os solicit\u00f3 <a href=\"https:\/\/www.cnn.com\/interactive\/2024\/12\/europe\/gisele-pelicot-france-case-messages\/\">a decenas de desconocidos en una sala de chat<\/a> la violaci\u00f3n y el abuso de su entonces esposa, Gis\u00e8le, fuera declarado culpable de violaci\u00f3n con agravantes. Otros cuarenta y nueve hombres fueron declarados culpables de violaci\u00f3n o agresi\u00f3n sexual en ese caso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre alem\u00e1n fue declarado culpable de drogar, violar y filmar a su esposa inconsciente durante a\u00f1os, en un caso que ha sido comparado con el juicio de Dominique Pelicot en Francia. El conserje escolar de 61 a\u00f1os fue declarado culpable de abusar de su esposa dentro de la casa de la pareja, filmarlo y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469414","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un hombre alem\u00e1n fue declarado culpable de drogar, violar y filmar a su esposa inconsciente durante a\u00f1os, en un caso que ha sido comparado con el juicio de Dominique Pelicot en Francia. El conserje escolar de 61 a\u00f1os fue declarado culpable de abusar de su esposa dentro de la casa de la pareja, filmarlo y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T12:04:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os\",\"datePublished\":\"2025-12-19T12:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\",\"name\":\"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-19T12:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias","og_description":"Un hombre alem\u00e1n fue declarado culpable de drogar, violar y filmar a su esposa inconsciente durante a\u00f1os, en un caso que ha sido comparado con el juicio de Dominique Pelicot en Francia. El conserje escolar de 61 a\u00f1os fue declarado culpable de abusar de su esposa dentro de la casa de la pareja, filmarlo y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-19T12:04:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/"},"author":{"name":"","@id":""},"headline":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os","datePublished":"2025-12-19T12:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","name":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-19T12:04:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Declaran culpable a un hombre alem\u00e1n de drogar, violar y filmar a su esposa durante a\u00f1os","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/pelicot-aleman-violacion-esposa-verdicto-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-19T12:04:01Z","datePublished":"2025-12-19T12:04:01Z","dateModified":"2025-12-19T12:04:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Declaran culpable a un hombre alem\\u00e1n de drogar, violar y filmar a su esposa durante a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/19\\\/pelicot-aleman-violacion-esposa-verdicto-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/19\\\/pelicot-aleman-violacion-esposa-verdicto-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-19T12:04:01Z\",\"datePublished\":\"2025-12-19T12:04:01Z\",\"dateModified\":\"2025-12-19T12:04:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470425,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/23\/reino-unido-hombre-culpable-violar-exesposa-trax\/","url_meta":{"origin":1469414,"position":0},"title":"Un hombre en el Reino Unido se declara culpable de drogar y violar a su exesposa durante m\u00e1s de una d\u00e9cada","author":"","date":"enero 23, 2026","format":false,"excerpt":"Un hombre se declar\u00f3 culpable este viernes ante un tribunal del Reino Unido de drogar y violar a su exesposa durante 13 a\u00f1os.Philip Young admiti\u00f3 48 de los 56 cargos en su contra, y se declar\u00f3 culpable de 14 cargos de voyeurismo, 11 de violaci\u00f3n y 11 de administrar una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456752,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/19\/pelicot-caso-que-paso-juicio-violacion-francia-orix\/","url_meta":{"origin":1469414,"position":1},"title":"Esto es lo que pas\u00f3 en el caso Pelicot, el juicio por violaci\u00f3n masiva en Francia","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Dominique P\u00e9licot, acusado de haber drogado a su esposa Gis\u00e8le con somn\u00edferos y ansiol\u00edticos y violarla repetidamente, as\u00ed como de haber reclutado a decenas de hombres por internet para que tambi\u00e9n la violaran mientras estaba inconsciente, fue condenado este jueves a 20 a\u00f1os de prisi\u00f3n en Francia.Otros 50 hombres acusados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456061,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/11\/25\/fiscal-pide-20-anos-de-prision-dominique-pelicot-juicio-violacion-masiva-trax\/","url_meta":{"origin":1469414,"position":2},"title":"Fiscal pide 20 a\u00f1os de prisi\u00f3n para Dominique Pelicot en juicio por violaci\u00f3n masiva","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"(CNN) -- Dominique Pelicot , el hombre que organiz\u00f3 a m\u00e1s de 50 hombres para violar a su esposa inconsciente, es \u201cplenamente responsable\u201d de sus acciones, dijo un fiscal franc\u00e9s ante el tribunal despu\u00e9s de solicitar la pena m\u00e1xima de prisi\u00f3n de 20 a\u00f1os.La fiscal Laure Chabaud dijo este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473000,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/09\/hombre-polaco-arrestado-investigacion-cnn-violacion-trax\/","url_meta":{"origin":1469414,"position":3},"title":"Un hombre polaco fue arrestado tras una investigaci\u00f3n encubierta de CNN sobre redes de violaci\u00f3n en l\u00ednea","author":"","date":"abril 9, 2026","format":false,"excerpt":"Las autoridades de Polonia arrestaron a un hombre en relaci\u00f3n con la presunta violaci\u00f3n de una \u201cv\u00edctima que no sab\u00eda lo que ocurr\u00eda\u201d, quien fue grabada y cuyo video fue compartido en internet, inform\u00f3 este jueves la Fiscal\u00eda de Distrito en Lublin.El arresto se produce tras una investigaci\u00f3n encubierta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456786,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/12\/20\/emmanuel-macron-agradece-gisele-pelicot-trax\/","url_meta":{"origin":1469414,"position":4},"title":"El presidente franc\u00e9s Emmanuel Macron agradece a Gis\u00e8le Pelicot su valent\u00eda tras el veredicto del juicio por violaci\u00f3n","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"El presidente de Francia, Emmanuel Macron, agradeci\u00f3 a Gis\u00e8le Pelicot, la mujer de Avignon en el centro del juicio por violaci\u00f3n masiva que conmocion\u00f3 al mundo, por su dignidad y valent\u00eda en un post en las redes sociales este viernes.\u201cGracias Gis\u00e8le P\u00e9licot\u201d, escribi\u00f3 Macron en X.\u201cPor esta palabra \u2018justicia\u2019, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473612,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/28\/definicion-violacion-ue-vacios-legales-trax\/","url_meta":{"origin":1469414,"position":5},"title":"Europa impulsa definir el sexo sin consentimiento activo como violaci\u00f3n para proteger a sobrevivientes","author":"","date":"abril 28, 2026","format":false,"excerpt":"Legisladores europeos votaron a favor de definir el sexo sin consentimiento activo como violaci\u00f3n, en lo que marca un paso hist\u00f3rico para los derechos de las mujeres y de los sobrevivientes de violencia sexual en la Uni\u00f3n Europea.La resoluci\u00f3n del Parlamento Europeo, aprobada el martes por una amplia mayor\u00eda, insta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469414\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}