{"id":1469431,"date":"2025-12-19T18:03:47","date_gmt":"2025-12-20T02:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/"},"modified":"2025-12-19T18:03:47","modified_gmt":"2025-12-20T02:03:47","slug":"petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","title":{"rendered":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump"},"content":{"rendered":"<p>Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/eeuu\/trump-ordena-bloqueo-petroleros-sancionados-venezuela-trax\">declar\u00f3 un \u201cbloqueo total y completo\u201d<\/a> a dichos buques que transitan por el pa\u00eds.<\/p>\n<p>El barco con bandera de Gambia, llamado Hyperion, fue visto cerca de una refiner\u00eda frente a la Bah\u00eda de Amuay, en Venezuela, el viernes despu\u00e9s de navegar por el Caribe, seg\u00fan datos de rastreo de barcos.<\/p>\n<p>El barco hab\u00eda sido sancionado por Estados Unidos el 10 de enero de 2025, como parte de los esfuerzos para reducir los ingresos energ\u00e9ticos de Rusia.<\/p>\n<p>CNN se ha puesto en contacto con el Departamento de Estado de EE.UU. para obtener comentarios.<\/p>\n<p>Venezuela critic\u00f3 el bloqueo a principios de esta semana, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/venezuela\/grotesca-amenaza-trump-bloqueo-petroleros-orix\">calific\u00e1ndolo de \u201cuna amenaza temeraria y grave\u201d<\/a>. Dijo que continuar\u00eda defendiendo su soberan\u00eda e intereses nacionales.<\/p>\n<p>Trump orden\u00f3 el bloqueo despu\u00e9s de que EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/eeuu-incauto-barco-petrolero-venezuela-trax\">incautara un petrolero sancionado<\/a> frente a la costa de Venezuela la semana pasada.<\/p>\n<p>Los bloqueos se consideran un acto de guerra seg\u00fan algunos tratados internacionales.<\/p>\n<p>La semana pasada, EE.UU. anunci\u00f3 sanciones contra compa\u00f1\u00edas navieras y buques que, seg\u00fan dice, ayudan a mover petr\u00f3leo venezolano. Tres sobrinos de la esposa del presidente Nicol\u00e1s Maduro, Cilia Flores, as\u00ed como otro empresario vinculado a Maduro, tambi\u00e9n fueron incluidos en la lista de sanciones.<\/p>\n<p>Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/eeuu\/rubio-gobierno-venezuela-intolerable-trump-trax\">impuso sanciones adicionales el viernes<\/a> a otros miembros de la familia Maduro, incluida su cu\u00f1ada.<\/p>\n<p>Las sanciones forman parte de una campa\u00f1a de presi\u00f3n que lleva meses contra el Gobierno de Venezuela. EE.UU. ha realizado ataques militares mortales en el Caribe y el Pac\u00edfico y ha ejercido presi\u00f3n econ\u00f3mica contra Caracas como parte de lo que ha descrito como una guerra contra el narcotr\u00e1fico.<\/p>\n<p>Maduro ha dicho que EE.UU. busca un cambio de r\u00e9gimen junto con la apropiaci\u00f3n del territorio y los recursos de Venezuela. EE.UU. ha rechazado esa caracterizaci\u00f3n, acusando a Maduro de ser ileg\u00edtimo y un narcotraficante.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, declar\u00f3 un \u201cbloqueo total y completo\u201d a dichos buques que transitan por el pa\u00eds. El barco con bandera de Gambia, llamado Hyperion, fue visto cerca [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469431","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, declar\u00f3 un \u201cbloqueo total y completo\u201d a dichos buques que transitan por el pa\u00eds. El barco con bandera de Gambia, llamado Hyperion, fue visto cerca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-20T02:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump\",\"datePublished\":\"2025-12-20T02:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\",\"name\":\"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-20T02:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias","og_description":"Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, declar\u00f3 un \u201cbloqueo total y completo\u201d a dichos buques que transitan por el pa\u00eds. El barco con bandera de Gambia, llamado Hyperion, fue visto cerca [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-20T02:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump","datePublished":"2025-12-20T02:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","name":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-20T02:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-20T02:03:47Z","datePublished":"2025-12-20T02:03:47Z","dateModified":"2025-12-20T02:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Datos de rastreo muestran que un petrolero sancionado entr\\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/19\\\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/19\\\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-20T02:03:47Z\",\"datePublished\":\"2025-12-20T02:03:47Z\",\"dateModified\":\"2025-12-20T02:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469811,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/05\/interceptar-petrolero-venezuela-rusia-trax\/","url_meta":{"origin":1469431,"position":0},"title":"EE.UU. se prepara para interceptar un petrolero vinculado con Venezuela pese a los reclamos de Rusia, seg\u00fan fuentes","author":"","date":"enero 5, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos prepara una operaci\u00f3n para intentar interceptar un petrolero que se ha convertido en el centro de una disputa internacional. Seg\u00fan confirmaron cuatro fuentes familiarizadas con el asunto, la embarcaci\u00f3n es objeto de un reclamo de jurisdicci\u00f3n por parte de Rusia, lo que posiciona este incidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469866,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/07\/eeuu-incauta-petrolero-venezuela-trax\/","url_meta":{"origin":1469431,"position":1},"title":"Estados Unidos incauta un petrolero con bandera rusa vinculado a Venezuela","author":"","date":"enero 7, 2026","format":false,"excerpt":"Estados Unidos incaut\u00f3 un petrolero vinculado a Venezuela tras rastrearlo a trav\u00e9s del Atl\u00e1ntico, seg\u00fan una publicaci\u00f3n en redes sociales del Gobierno estadounidense.Originalmente llamado Bella 1, el petrolero fue sancionado por Estados Unidos en 2024 por operar dentro de una \u201cflota fantasma\u201d de buques cisterna que transportaban petr\u00f3leo de forma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469500,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/22\/panama-irregularidades-buque-interceptado-orix\/","url_meta":{"origin":1469431,"position":2},"title":"Panam\u00e1 confirma irregularidades en el buque con presunta bandera paname\u00f1a incautado por EE.UU. en el Caribe","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"El ministro de Relaciones Exteriores de Panam\u00e1, Javier Martinez-Acha, dijo este lunes que un buque petrolero de bandera paname\u00f1a interceptado por Estados Unidos y otro buque \u2014sin bandera reportada\u2014 que estaba siendo perseguido por fuerzas estadounidenses en el Caribe no habr\u00edan cumplido con la legislaci\u00f3n del pa\u00eds ni con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469470,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/21\/intercepta-buque-venezuela-tercero-trax\/","url_meta":{"origin":1469431,"position":3},"title":"EE.UU. trabaj\u00f3 para interceptar otro buque cerca de Venezuela","author":"","date":"diciembre 21, 2025","format":false,"excerpt":"Personal de EE.UU. trabaj\u00f3 para interceptar este domingo otro buque cerca de Venezuela, dijo un funcionario estadounidense. Se trata del segundo barco intervenido este fin de semana, en medio del aumento de la presi\u00f3n de Washington sobre el presidente Nicol\u00e1s Maduro.A\u00fan no estaba claro el estado del buque ni si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471262,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/15\/eeuu-detiene-petrolero-veronica-iii-venezuela-trax\/","url_meta":{"origin":1469431,"position":4},"title":"EE.UU. detiene a otro buque petrolero vinculado con Venezuela","author":"","date":"febrero 15, 2026","format":false,"excerpt":"Fuerzas militares estadounidenses detuvieron y abordaron un petrolero vinculado a Venezuela durante la noche en el oc\u00e9ano \u00cdndico, seg\u00fan inform\u00f3 el Pent\u00e1gono en X.La embarcaci\u00f3n Ver\u00f3nica III, que navega bajo la bandera de Panam\u00e1, seg\u00fan el Departamento del Tesoro, es el m\u00e1s reciente petrolero que Estados Unidos dice haber atacado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469453,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/20\/incauta-otro-buque-costa-venezuela-trax\/","url_meta":{"origin":1469431,"position":5},"title":"EE.UU. incauta otro buque frente a la costa de Venezuela a medida que el Gobierno de Trump aumenta la presi\u00f3n sobre Caracas","author":"","date":"diciembre 20, 2025","format":false,"excerpt":"Personal estadounidense abord\u00f3 e incaut\u00f3 un buque frente a las costas de Venezuela, seg\u00fan un funcionario familiarizado con el asunto, en un momento en que el Gobierno de Donald Trump intensifica la presi\u00f3n sobre Caracas.Es el segundo caso conocido de una incautaci\u00f3n de un buque cerca de Venezuela por parte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469431"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469431\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}