{"id":1469457,"date":"2025-12-20T17:03:51","date_gmt":"2025-12-21T01:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/"},"modified":"2025-12-20T17:03:51","modified_gmt":"2025-12-21T01:03:51","slug":"historia-tres-paises-sedes-mundial-2026-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","title":{"rendered":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026"},"content":{"rendered":"<p>Si bien a\u00fan no ha rodado el bal\u00f3n en el Mundial 2026, s\u00ed comenz\u00f3 el camino mundialista luego que se conoci\u00f3 el destino \u2014<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/06\/deportes\/mundial-2026-sorteo-calendario-grupos-muerte-orix\">grupos, horarios y sedes<\/a>\u2014 de las 48 selecciones que a partir del 11 de junio buscar\u00e1n llevarse toda la gloria alzando el m\u00e1s codiciado de los premios del deporte en el planeta el 19 de julio en Nueva York\/Nueva Jersey, cuando se dispute la gran final de la Copa del Mundo de la FIFA.<\/p>\n<p>La emoci\u00f3n de los aficionados, sobre todo de aquellos cuyas selecciones ya cuentan con el boleto mundialista, es palpable. Se han vendido, hasta la fecha, 2 millones de entradas y 20 millones de personas aplicaron recientemente al sorteo aleatorio para comprar billetes en la tercera fase de venta. Sin embargo, los altos costos de los boletos provocaron cr\u00edticas de algunos aficionados y llevaron a la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/deportes\/fifa-rebaja-precio-boletos-mundial-2026-ap\">FIFA a reducir el precio<\/a> para hacerlo m\u00e1s asequible al p\u00fablico que desee asistir al mundial.<\/p>\n<p>Sin embargo, m\u00e1s all\u00e1 de ese ajuste pr\u00e1cticamente obligado por parte del organismo que rige al f\u00fatbol planetario, lo cierto es que el Mundial 2026 promete mucho. Es una justa in\u00e9dita y ambiciosa de 48 selecciones a realizarse en los tres pa\u00edses de Norteam\u00e9rica: M\u00e9xico, Estados Unidos y Canad\u00e1.<\/p>\n<p>Desde el anuncio en Mosc\u00fa, en 2018, de la elecci\u00f3n por amplia mayor\u00eda de la candidatura tripartita como sede del torneo, comenz\u00f3 una colaboraci\u00f3n hist\u00f3rica para la justa. Los tres pa\u00edses sede no solo comparten fronteras, sino tambi\u00e9n d\u00e9cadas de evoluci\u00f3n futbol\u00edstica, crecimiento econ\u00f3mico y una visi\u00f3n compartida que es convertir a la regi\u00f3n en epicentro del f\u00fatbol mundial en 2026.<\/p>\n<p>Vimos un adelanto el 5 de diciembre, cuando los mandatarios de las tres naciones sede \u2014el presidente de Estados Unidos, Donald Trump, su hom\u00f3loga mexicana Claudia Sheinbaum y el primer ministro de Canad\u00e1, Mark Carney\u2014 se presentaron en el escenario del Kennedy Center junto al presidente de la FIFA, Gianni Infantino, para simular sacar a sus respectivas selecciones y asignarlas a los bombos que ya se conoc\u00edan de antemano, previo a determinar la composici\u00f3n final de los 12 grupos. Posteriormente, los tres jefes de Estado se comprometieron a hacer que este pr\u00f3ximo Mundial, el vig\u00e9simotercero, sea el m\u00e1s grande de la historia.<\/p>\n<p>Lo cierto es que las trayectorias futbol\u00edsticas de los tres pa\u00edses han sido distintas. Mientras M\u00e9xico respira f\u00fatbol desde hace m\u00e1s de un siglo, Estados Unidos ha recorrido un camino irregular, lleno de altibajos y renacimientos, y Canad\u00e1 ha experimentado un despertar reciente, impulsado por el multiculturalismo y la irrupci\u00f3n de talentos internacionales.<\/p>\n<p>M\u00e9xico hace historia al ser la \u00fanica naci\u00f3n que albergar\u00e1 una Copa del Mundo por tercera ocasi\u00f3n y el partido inaugural en el Estadio Azteca. Ese honor coincide con ser el pa\u00eds con mayor tradici\u00f3n y peso hist\u00f3rico en el f\u00fatbol de los tres anfitriones.<\/p>\n<p>Su v\u00ednculo con el balompi\u00e9 se remonta a finales del siglo XIX, cuando mineros y trabajadores brit\u00e1nicos introdujeron el deporte en el pa\u00eds. Poco despu\u00e9s, nacieron los primeros clubes de comunidades europeas establecidas en la naci\u00f3n. Con el tiempo, el deporte pas\u00f3 de ser una actividad practicada por expatriados a convertirse en un s\u00edmbolo de identidad nacional que tiene en la <a href=\"https:\/\/cnnespanol.cnn.com\/deportes\/live-news\/resultado-toluca-tigres-final-apertura-2025-orix\">Liga MX<\/a> y el \u201cTri\u201d, sus bastiones del balompi\u00e9.<\/p>\n<p>La selecci\u00f3n mexicana, cuya naci\u00f3n alberg\u00f3 los mundiales de 1970 y 1986, jugar\u00e1 en 2026 por d\u00e9cimo octava ocasi\u00f3n en la justa, siendo su mejor participaci\u00f3n la llegada a cuartos de final en las dos primeras realizadas en casa. Tendr\u00e1n tres sedes, las cuales son la Ciudad de M\u00e9xico, Guadalajara y Monterrey.<\/p>\n<p>Estados Unidos ha tenido un recorrido muy diferente al de su vecino del sur. Aunque el f\u00fatbol lleg\u00f3 temprano al pa\u00eds y la selecci\u00f3n de las barras y las estrellas jug\u00f3 en el primer Mundial de la historia, en 1930 en Uruguay, llegando a semifinales, no logr\u00f3 competir con los deportes tradicionales estadounidenses.<\/p>\n<p>Sin embargo, la llegada de Pel\u00e9 al Cosmos a mediados de los setentas, ser sede del Mundial 1994, as\u00ed como la creaci\u00f3n de la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/30\/deportes\/mls-liga-retiro-mito-realidad-orix\">Major League Soccer (MLS)<\/a> dos a\u00f1os despu\u00e9s, han ayudado al crecimiento del f\u00fatbol en las \u00faltimas d\u00e9cadas. De hecho, la justa del 94, adem\u00e1s de ser un parteaguas en cuanto a la exposici\u00f3n del deporte en el pa\u00eds, tambi\u00e9n revel\u00f3 la capacidad organizativa de Estados Unidos. Hasta la fecha se mantiene como el Mundial con mayor asistencia en la historia de la FIFA, y la edici\u00f3n de 2026 ser\u00e1 su d\u00e9cimosegunda participaci\u00f3n mundialista.<\/p>\n<p>De los tres pa\u00edses anfitriones, ser\u00e1 el que tenga la mayor cantidad de ciudades sede, con 11: Atlanta, Boston, Dallas, Houston, Kansas City, Miami, Los \u00c1ngeles, Nueva York\/Nueva Jersey, Filadelfia, Seattle y San Francisco.<\/p>\n<p>De los tres pa\u00edses sede, Canad\u00e1 es el que menos tradici\u00f3n futbol\u00edstica tiene. Aun as\u00ed, es donde el crecimiento ha sido m\u00e1s r\u00e1pido en la \u00faltima d\u00e9cada. La historia de los inicios del deporte de M\u00e9xico y Estados Unidos se repiti\u00f3 en el vecino del norte con la llegada de los inmigrantes brit\u00e1nicos. El primer partido registrado se jug\u00f3 en Toronto en el siglo XIX. No obstante, y pese a que el f\u00fatbol se organiz\u00f3 de manera formal desde temprano con la creaci\u00f3n de lo que hoy se conoce como Canada Soccer, al deporte le cost\u00f3 competir con el hockey y no lleg\u00f3 a consolidarse hasta hace poco con la creaci\u00f3n de la Canadian Premier League y el impulso de tener tres equipos en la MLS.<\/p>\n<p>Ha tenido que ver en el crecimiento de la cultura futbolera la llegada de inmigrantes europeos y latinoamericanos. Canad\u00e1, la tercera sede de 2026, competir\u00e1 a su vez por tercera ocasi\u00f3n despu\u00e9s de debutar en M\u00e9xico 1986 y regresar tras una larga pausa en Qatar 2022. Precisamente en la justa pasada, Canad\u00e1 anot\u00f3 su primer gol mundialista, un s\u00edmbolo del progreso reciente del pa\u00eds en este deporte que recibir\u00e1 a la justa de 2026 en Toronto y Vancouver.<\/p>\n<p>La expectativa de la FIFA, las tres sedes y la regi\u00f3n es lograr que este pr\u00f3ximo mundial se recuerde como el evento que transform\u00f3 a Norteam\u00e9rica en una regi\u00f3n futbol\u00edstica unificada y poderosa. Veremos si lo consiguen.<\/p>\n<p>Mientras tanto, hay m\u00e1s preguntas tambi\u00e9n importantes pendientes: \u00bfpodr\u00e1 Argentina repetir el t\u00edtulo? \u00bfSer\u00e1 la oportunidad de ver un nuevo campe\u00f3n? \u00bfAlguna de las grandes favoritas se impondr\u00e1 sobre el resto? \u00bfO ser\u00e1 acaso un Mundial lleno de sorpresas?<\/p>\n<p>Lo sabremos en julio pr\u00f3ximo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien a\u00fan no ha rodado el bal\u00f3n en el Mundial 2026, s\u00ed comenz\u00f3 el camino mundialista luego que se conoci\u00f3 el destino \u2014grupos, horarios y sedes\u2014 de las 48 selecciones que a partir del 11 de junio buscar\u00e1n llevarse toda la gloria alzando el m\u00e1s codiciado de los premios del deporte en el planeta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469457","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Si bien a\u00fan no ha rodado el bal\u00f3n en el Mundial 2026, s\u00ed comenz\u00f3 el camino mundialista luego que se conoci\u00f3 el destino \u2014grupos, horarios y sedes\u2014 de las 48 selecciones que a partir del 11 de junio buscar\u00e1n llevarse toda la gloria alzando el m\u00e1s codiciado de los premios del deporte en el planeta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-21T01:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026\",\"datePublished\":\"2025-12-21T01:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\"},\"wordCount\":1173,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\",\"name\":\"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-21T01:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias","og_description":"Si bien a\u00fan no ha rodado el bal\u00f3n en el Mundial 2026, s\u00ed comenz\u00f3 el camino mundialista luego que se conoci\u00f3 el destino \u2014grupos, horarios y sedes\u2014 de las 48 selecciones que a partir del 11 de junio buscar\u00e1n llevarse toda la gloria alzando el m\u00e1s codiciado de los premios del deporte en el planeta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-21T01:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/"},"author":{"name":"","@id":""},"headline":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026","datePublished":"2025-12-21T01:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/"},"wordCount":1173,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","name":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-21T01:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un poco de historia sobre M\u00e9xico, EE.UU. y Canad\u00e1, los tres pa\u00edses sedes del Mundial 2026","url":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2025\/12\/20\/historia-tres-paises-sedes-mundial-2026-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-21T01:03:51Z","datePublished":"2025-12-21T01:03:51Z","dateModified":"2025-12-21T01:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un poco de historia sobre M\\u00e9xico, EE.UU. y Canad\\u00e1, los tres pa\\u00edses sedes del Mundial 2026\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/20\\\/historia-tres-paises-sedes-mundial-2026-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2025\\\/12\\\/20\\\/historia-tres-paises-sedes-mundial-2026-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-21T01:03:51Z\",\"datePublished\":\"2025-12-21T01:03:51Z\",\"dateModified\":\"2025-12-21T01:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468728,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/26\/boletos-mundial-2026-tercera-fase-orix\/","url_meta":{"origin":1469457,"position":0},"title":"\u00bfA\u00fan no tienes boletos para el Mundial 2026? As\u00ed ser\u00e1 la tercera fase de venta que comenzar\u00e1 el 11 de diciembre","author":"","date":"noviembre 26, 2025","format":false,"excerpt":"La fiebre mundialista ya se siente en Norteam\u00e9rica y el resto del planeta. La primera Copa del Mundo de 48 selecciones agot\u00f3 los cerca de dos millones de boletos que se pusieron a la venta de manera anticipada, seg\u00fan la FIFA, que ya estableci\u00f3 fecha de inicio para la tercera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469086,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/08\/mundial-2026-calor-tormentas-crisis-migratoria-orix\/","url_meta":{"origin":1469457,"position":1},"title":"Los mayores retos del Mundial 2026: del calor y la situaci\u00f3n migratoria al campo de juego de los estadios","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"La Copa Mundial de la FIFA 2026, que se disputar\u00e1 por primera vez en sus casi 100 a\u00f1os de existencia en tres pa\u00edses (Estados Unidos, M\u00e9xico y Canad\u00e1) representa un reto log\u00edstico, organizativo y social sin precedentes, en lo que ser\u00e1 su primera edici\u00f3n con 48 selecciones, 104 partidos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468863,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/01\/mundial-2026-calendario-completo-sorteo-orix\/","url_meta":{"origin":1469457,"position":2},"title":"La FIFA anunci\u00f3 cu\u00e1ndo y c\u00f3mo dar\u00e1 a conocer el calendario del Mundial 2026 con sedes y horarios confirmados","author":"","date":"diciembre 1, 2025","format":false,"excerpt":"La ansiedad es total. A cuatro d\u00edas de que se d\u00e9 a conocer el sorteo del Mundial 2026, la FIFA anunci\u00f3 cu\u00e1ndo y de qu\u00e9 manera se determinar\u00e1n las sedes y los horarios de cada uno de los 104 partidos que tendr\u00e1 la primera Copa del Mundo de 48 selecciones.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469646,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/29\/solicitudes-entradas-mundial-2026-records-fifa-orix\/","url_meta":{"origin":1469457,"position":3},"title":"Fiebre mundialista: solicitudes de entradas para la Copa Mundial 2026 baten todos los r\u00e9cords, seg\u00fan la FIFA","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"La Copa Mundial de la FIFA 2026 sigue haciendo historia antes de que ruede el bal\u00f3n.La demanda de entradas ha alcanzado cifras sin precedentes, seg\u00fan report\u00f3 el m\u00e1ximo organismo del f\u00fatbol. M\u00e1s de 150 millones de solicitudes se han recibido durante la fase de sorteo aleatorio, que sigue abierta hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468514,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/19\/repechaje-mundial-2026-guadalajara-monterrey-orix\/","url_meta":{"origin":1469457,"position":4},"title":"\u00a1Oficial! Los estadios de Guadalajara y Monterrey ser\u00e1n sede del repechaje de la FIFA para el Mundial 2026","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"M\u00e9xico ser\u00e1 sede del repechaje intercontinental de la FIFA para la Copa del Mundo de 2026. La casa madre del f\u00fatbol mundial confirm\u00f3 la noticia este mi\u00e9rcoles en un comunicado, donde especific\u00f3 que los partidos se jugar\u00e1n en los estadios de Guadalajara y de Monterrey (que en realidad queda en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468899,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/02\/mundial-2026-distancias-cabezas-serie-orix\/","url_meta":{"origin":1469457,"position":5},"title":"El recorrido de los cabezas de serie del Mundial 2026: \u00bfqui\u00e9n viajar\u00e1 m\u00e1s? \u00bfM\u00e9xico, Canad\u00e1 o EE.UU.?","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"El primer Mundial de f\u00fatbol de 48 selecciones tendr\u00e1 varias particularidades. Una de ellas es que, al jugarse en tres pa\u00edses, varias selecciones tendr\u00e1n que recorrer largas extensiones de terreno, y otras, en cambio, tendr\u00e1n calendarios y sedes m\u00e1s cercanas y favorables a la hora de armar la log\u00edstica del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469457"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469457\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}