{"id":1469961,"date":"2026-01-10T10:03:58","date_gmt":"2026-01-10T18:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/"},"modified":"2026-01-10T10:03:58","modified_gmt":"2026-01-10T18:03:58","slug":"futbol-americano-universitario-indiana-hoosiers-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","title":{"rendered":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia"},"content":{"rendered":"<p>Estaban a pocos metros de distancia en el campo cubierto de papel picado. Uno, un lineman ofensivo de \u00faltimo a\u00f1o que es el pilar de su equipo; el otro, un lineman defensivo de segundo a\u00f1o que a\u00fan no ha sido titular.<\/p>\n<p>Ambos hablaban del mismo tema: la m\u00e1quina en la que se han convertido los Indiana Hoosiers, pero desde perspectivas completamente diferentes. Sin embargo, ambos repet\u00edan la misma palabra una y otra vez.<\/p>\n<p>\u201cTenemos un miedo terrible al conformismo\u201d, dijo Pat Coogan, el lineman ofensivo.<\/p>\n<p>\u201cNunca nos conformaremos\u201d, dijo Daniel Ndukwe, el lineman defensivo.<\/p>\n<p>Suena simple. No lo es, por supuesto. Nadie quiere conformarse con menos, pero la naturaleza humana es as\u00ed e inevitablemente sucede. Un ligero descenso del ritmo, un milisegundo de distracci\u00f3n, la necesidad de tomar un respiro.<\/p>\n<p>Excepto, aparentemente, entre los Hoosiers que juegan al f\u00fatbol americano como si no jugar con intensidad fuera un pecado imperdonable. Es la \u00fanica forma de explicar lo que est\u00e1 haciendo Indiana en este momento, porque de lo contrario ser\u00eda demasiado absurdo.<\/p>\n<p>El cambio en el f\u00fatbol americano universitario no est\u00e1 llegando a trav\u00e9s de ganancias financieras inesperadas, como todos pensaban que podr\u00eda suceder en la era del NIL. Est\u00e1 llegando a trav\u00e9s de valores tradicionales que suelen arraigarse en el Medio Oeste. Trabajar duro. No dar nada por sentado. No conformarse. Nunca ser complaciente.<\/p>\n<p>Indiana no son los \u201cHoosiers\u201d de la famosa pel\u00edcula. De hecho, no son los valientes novatos que se enfrentan a los malos de la gran ciudad. No se dejen enga\u00f1ar por la seriedad de Fernando Mendoza. Los Hoosiers son los malos, los matones que vienen a quitarte el orgullo y el dinero del almuerzo, aunque con educaci\u00f3n. Mientras Carter Smith se dirig\u00eda al escenario de la celebraci\u00f3n posterior al Peach Bowl, gritaba \u201cDisculpen\u201d una y otra vez mientras se abr\u00eda paso entre los medios de comunicaci\u00f3n.<\/p>\n<p>Con una victoria aplastante de 56-22 sobre Oregon, Indiana ha arrasado en los Playoffs de F\u00fatbol Americano Universitario como nunca antes se hab\u00eda visto en a\u00f1os, si es que alguna vez se ha visto algo parecido. En los \u00faltimos tres partidos, los Hoosiers han limitado a Ohio State a 10 puntos, a Alabama a tres y a Oregon a 21, aunque esto \u00faltimo tiene un matiz importante. Los Ducks anotaron su \u00faltimo touchdown a 34 segundos del final del partido.<\/p>\n<p>Es decir, para recalcar, Ohio State, Alabama y Oregon. Los dos primeros han ganado juntos unos 25 t\u00edtulos nacionales. Indiana ha perdido m\u00e1s de 700 partidos en su historia y ahora est\u00e1 a un solo partido de un t\u00edtulo nacional.<\/p>\n<p>El siguiente rival es nada menos que The U, otro miembro de la \u00e9lite del f\u00fatbol americano universitario, en un partido por el campeonato para el que conseguir una entrada ser\u00e1 casi imposible. Los Miami Hurricanes juegan en casa, mientras que todo el estado de Indiana, salvo algunos en West Lafayette, est\u00e1 dispuesto a abandonar sus hogares para disfrutar de esta inesperada y asombrosa racha en los Playoffs.<\/p>\n<p>Para que nadie intente presentar esto como una especie de lecci\u00f3n moral, los chicos buenos de Indiana contra los malos de Miami, conviene recordar que Indiana es cabeza de serie; fue Miami quien tuvo que luchar para llegar a esta instancia.<\/p>\n<p>\u201cSon un equipo completo\u201d, dijo el entrenador de Oregon, Dan Lanning. \u201cNo tienen ninguna debilidad. Corren bien con el bal\u00f3n. Defienden bien la carrera. Lanzan bien el bal\u00f3n. Defienden bien el pase. Son excelentes. Se ve un equipo realmente completo y bien entrenado. Obviamente tienen mucha confianza, y con raz\u00f3n\u201d.<\/p>\n<p>Esa es la clave: Indiana es bueno en todo. Es casi como una trampa. Si te preocupas por la ofensiva, la defensa te sorprende. Si te concentras en encontrar maneras de anotar, la ofensiva te castiga. Y luego los equipos especiales rematan la faena.<\/p>\n<p>Si la l\u00ednea ofensiva mereci\u00f3 el trofeo de MVP en el Rose Bowl, los honores deber\u00edan haber sido para la defensa en este partido. En la primera jugada del partido, D\u2019Angelo Ponds anticip\u00f3 una jugada de RPO del quarterback de Oregon, Dante Moore. Ponds sigui\u00f3 la mirada de Moore en todo momento y, cuando Moore lanz\u00f3 el bal\u00f3n hacia la izquierda, Ponds intercept\u00f3 el pase y recorri\u00f3 25 yardas hasta la zona de anotaci\u00f3n.<\/p>\n<p>Si quieren saber c\u00f3mo suena cuando un estado entero estalla de alegr\u00eda, escuchen la repetici\u00f3n. Todo Indiana vitore\u00f3.<\/p>\n<p>La defensa luego procedi\u00f3 a regalarle 14 puntos m\u00e1s a la ofensiva. Consigui\u00f3 una primera oportunidad y gol desde la yarda tres despu\u00e9s de que Mario Landino recuperara un bal\u00f3n suelto de Dante Moore en el segundo cuarto, y le dio el bal\u00f3n a los Hoosiers en la yarda 21 cuando Ndukwe derrib\u00f3 a Moore para forzar otro bal\u00f3n suelto. En el cuarto cuarto, con el partido pr\u00e1cticamente ganado, Ndukwe bloque\u00f3 el despeje de James Ferguson-Reynolds, entreg\u00e1ndole el bal\u00f3n a IU en la yarda siete.<\/p>\n<p>La solidez defensiva de los Hoosiers no ha pasado desapercibida; est\u00e1n clasificados como el n\u00famero 2 del pa\u00eds, pero la precisi\u00f3n quir\u00fargica y el encanto cautivador que Mendoza aporta a la ofensiva tienden a acaparar gran parte de la atenci\u00f3n.<\/p>\n<p>No deber\u00eda ser as\u00ed. La defensa de Indiana es magistral, un equipo que funciona a la perfecci\u00f3n y que est\u00e1 aniquilando a sus oponentes sin su principal tacleador. Stephen Daley sufri\u00f3 una extra\u00f1a lesi\u00f3n celebrando el campeonato de la Big Ten y no ha jugado en los Playoffs.<\/p>\n<p>No importa. Los Hoosiers simplemente encuentran a otros jugadores. Ndukwe solo ten\u00eda ocho tacleadas en sus primeros 14 partidos; tuvo tres contra Oregon, incluyendo dos capturas, el bal\u00f3n suelto forzado y, como guinda del pastel, el despeje bloqueado.<\/p>\n<p>\u201cCuando tienes buena gente que se compromete y se prepara de la manera correcta\u2026, tenemos muchos de esos chicos\u201d, dijo el entrenador en jefe Curt Cignetti. \u201cSon chicos con gran car\u00e1cter e inteligentes\u201d.<\/p>\n<p>Al igual que Cignetti, el coordinador defensivo Bryant Haines se forj\u00f3 a la antigua usanza, comenzando en universidades que la mayor\u00eda de la gente ni siquiera sabe que existen: Manchester, una universidad de la Divisi\u00f3n 3 en Fort Wayne; Adrian, otro equipo de la Divisi\u00f3n 3 en Michigan. Ahora es uno de los coordinadores mejor pagos del f\u00fatbol americano universitario, gracias a un enfoque de cient\u00edfico loco en la defensa.<\/p>\n<p>Este hombre de 40 a\u00f1os idea maneras de hacer que los mariscales de campo sufran incluso en sue\u00f1os, dise\u00f1ando esquemas que buscan tanto enga\u00f1ar como confundir. Dice que ha moderado su estilo con la edad, aprendiendo cu\u00e1ndo arriesgarse y c\u00f3mo combinar mejor sus coberturas. \u201cAs\u00ed lo llamo yo, un cient\u00edfico loco\u201d, dijo Ndukwe, quien creci\u00f3 en Lithonia, Georgia, y disfrut\u00f3 del partido en casa. \u201cEstoy haciendo cosas que nunca antes hab\u00eda hecho y se nota que los otros equipos se confunden. Se puede sentir c\u00f3mo les afecta\u201d.<\/p>\n<p>Moore se ve\u00eda a veces abrumado, ya sea bailando en la zona de protecci\u00f3n intentando encontrar un receptor libre o rodeado por la defensa cuando la protecci\u00f3n se desmoronaba. No es el \u00fanico. Justin Sayin de Ohio State lanz\u00f3 una intercepci\u00f3n y fue derribado cinco veces, y Ty Simpson de Alabama lanz\u00f3 para solo 67 yardas antes de retirarse con una costilla fracturada.<\/p>\n<p>\u201cTe muestran una cosa\u201d, dijo Lanning a principios de esta semana, \u201cy te quitan otra. Son muy buenos en los movimientos despu\u00e9s del snap, lo que dificulta las cosas para el mariscal de campo. Su l\u00ednea defensiva juega con una intensidad implacable. Son dif\u00edciles de bloquear en la l\u00ednea de golpeo. Y su t\u00e9cnica sigue destacando\u201d.<\/p>\n<p>Todo en Indiana se repite una y otra vez con una consistencia metron\u00f3mica; su filosof\u00eda est\u00e1 tan arraigada que incluso la presidenta de la universidad canta la misma canci\u00f3n.<\/p>\n<p>Mientras el patrocinador Mark Cuban gritaba \u201c\u00a1Hoo hoo Hoosiers!\u201d fuera del vestuario con los aficionados, Pamela Whitten pas\u00f3 discretamente junto al vestuario antes de detenerse a charlar con un par de reporteros.<\/p>\n<p>\u201cEsto es genial, \u00bfverdad?\u201d, dijo. \u201cPero todav\u00eda nos queda un partido\u201d.<\/p>\n<p>No hay tiempo para la complacencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estaban a pocos metros de distancia en el campo cubierto de papel picado. Uno, un lineman ofensivo de \u00faltimo a\u00f1o que es el pilar de su equipo; el otro, un lineman defensivo de segundo a\u00f1o que a\u00fan no ha sido titular. Ambos hablaban del mismo tema: la m\u00e1quina en la que se han convertido los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469961","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estaban a pocos metros de distancia en el campo cubierto de papel picado. Uno, un lineman ofensivo de \u00faltimo a\u00f1o que es el pilar de su equipo; el otro, un lineman defensivo de segundo a\u00f1o que a\u00fan no ha sido titular. Ambos hablaban del mismo tema: la m\u00e1quina en la que se han convertido los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T18:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia\",\"datePublished\":\"2026-01-10T18:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\"},\"wordCount\":1435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\",\"name\":\"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-10T18:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias","og_description":"Estaban a pocos metros de distancia en el campo cubierto de papel picado. Uno, un lineman ofensivo de \u00faltimo a\u00f1o que es el pilar de su equipo; el otro, un lineman defensivo de segundo a\u00f1o que a\u00fan no ha sido titular. Ambos hablaban del mismo tema: la m\u00e1quina en la que se han convertido los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-10T18:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/"},"author":{"name":"","@id":""},"headline":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia","datePublished":"2026-01-10T18:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/"},"wordCount":1435,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","name":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-10T18:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\u00eda no puede bajar la guardia","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/01\/10\/futbol-americano-universitario-indiana-hoosiers-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-10T18:03:58Z","datePublished":"2026-01-10T18:03:58Z","dateModified":"2026-01-10T18:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tras aplastar a Alabama y a Oregon, Indiana confirma que ya no es un equipo menor. Pero todav\\u00eda no puede bajar la guardia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/01\\\/10\\\/futbol-americano-universitario-indiana-hoosiers-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/01\\\/10\\\/futbol-americano-universitario-indiana-hoosiers-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-10T18:03:58Z\",\"datePublished\":\"2026-01-10T18:03:58Z\",\"dateModified\":\"2026-01-10T18:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467517,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/10\/19\/san-jose-sharks-nhl-disculpas-mensaje-ofensivo-ice-trax\/","url_meta":{"origin":1469961,"position":0},"title":"Los San Jos\u00e9 Sharks se disculpan por el mensaje ofensivo sobre ICE mostrado durante la Noche de la Herencia Hispana","author":"","date":"octubre 19, 2025","format":false,"excerpt":"Los San Jose Sharks se disculparon despu\u00e9s de que un mensaje aparentemente ofensivo, que parec\u00eda elogiar al Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s), apareciera en el marcador del estadio durante la celebraci\u00f3n de la herencia hispana del equipo el s\u00e1bado por la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448660,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/29\/bills-draft-nfl-rugby-clayton-trax\/","url_meta":{"origin":1469961,"position":1},"title":"Por qu\u00e9 los Bills eligieron en el draft de la NFL a un deportista que nunca ha jugado f\u00fatbol americano","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- La transici\u00f3n del rugby al f\u00fatbol americano ha resultado dif\u00edcil en el pasado. Jarryd Hayne y Christian Wade dejaron el rugby cerca de la cima de sus poderes para probar suerte en el campo de f\u00fatbol americano, pero ninguno de ellos logr\u00f3 sobrevivir a largo plazo.El exinternacional gal\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472036,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/03\/09\/ohtani-arraez-soto-clasico-mundial-beisbol-orix\/","url_meta":{"origin":1469961,"position":2},"title":"Ohtani, Arr\u00e1ez, Soto\u2026 lo mejor de la primera ronda del Cl\u00e1sico Mundial de B\u00e9isbol 2026","author":"","date":"marzo 9, 2026","format":false,"excerpt":"El Cl\u00e1sico Mundial de B\u00e9isbol sigue en esa b\u00fasqueda de consolidarse como una marca a ser mirada de cerca por la parte del mundo que es ajeno al deporte del diamante. Pero, con torneos como este de 2026, al menos en lo que va de sus primeras jornadas, es seguro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470904,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/05\/seahawks-seattle-estrellas-entrenador-claves-orix\/","url_meta":{"origin":1469961,"position":3},"title":"As\u00ed son los Seahawks de Seattle: sus estrellas, el entrenador y las claves de su temporada","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Tal vez, y solo tal vez, solo los m\u00e1s fervientes seguidores de los Seahawks de Seattle entraron a la temporada 2025 con la idea de hacer el viaje completo al Super Bowl LX. Era una cuesti\u00f3n de fe, con alguna base s\u00f3lida.Ven\u00edan de una buena temporada en 2024, con r\u00e9cord\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458946,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/02\/19\/guardiola-ancelotti-playoffs-champions-league-real-madrid-manchester-city-efe\/","url_meta":{"origin":1469961,"position":4},"title":"Guardiola reconoce la superioridad del Real Madrid y dice que su equipo no pudo &#171;parar a Mbapp\u00e9&#187;","author":"","date":"febrero 19, 2025","format":false,"excerpt":"El entrenador del Manchester City, el espa\u00f1ol Pep Guardiola, reconoci\u00f3 este mi\u00e9rcoles que el Real Madrid fue \u201cmejor\u201d en los playoffs de la Liga de Campeones, al tiempo que asegur\u00f3 que su equipo no pudo \u201cparar\u201d a Kylian Mbapp\u00e9, autor de un triplete en la derrota de los ingleses (3-1).\u201cNo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461700,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/04\/28\/ejercito-ruso-motocicletas-evadir-drones-ucranianos-trax\/","url_meta":{"origin":1469961,"position":5},"title":"El Ej\u00e9rcito ruso recurre a motocicletas para evadir los drones ucranianos en el frente","author":"","date":"abril 28, 2025","format":false,"excerpt":"El Ej\u00e9rcito ruso est\u00e1 planeando incrementar el uso de peque\u00f1os escuadrones en motocicletas y cuatriciclos en las l\u00edneas del frente en Ucrania mientras prepara nuevas ofensivas, seg\u00fan militares ucranianos y analistas del conflicto.El Ministerio de Defensa ruso public\u00f3 el s\u00e1bado un video que muestra unidades practicando t\u00e1cticas en grupos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1469961"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1469961\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1469961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1469961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1469961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}