{"id":1473127,"date":"2026-04-14T05:03:39","date_gmt":"2026-04-14T12:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/"},"modified":"2026-04-14T05:03:39","modified_gmt":"2026-04-14T12:03:39","slug":"celia-cruz-salon-fama-rock-and-roll-2026-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","title":{"rendered":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026"},"content":{"rendered":"<p>El \u201c\u00a1Az\u00facar!\u201d de <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/08\/08\/ee-uu-celebra-legado-celia-cruz-moneda-orix\">Celia Cruz<\/a> se col\u00f3 al <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/entretenimiento\/shakira-nominada-salon-fama-rock-orix\">Sal\u00f3n de la Fama del Rock &#038; Roll<\/a>: la instituci\u00f3n anunci\u00f3 el martes la lista de artistas admitidos en 2026 y, de manera honor\u00edfica, incluy\u00f3 a la cantante cubana fallecida en 2003 a los 77 a\u00f1os en la categor\u00eda de \u201cInfluencia temprana\u201d.<\/p>\n<p>Y con esta buena noticia lleg\u00f3 una mala: la cantante colombiana Shakira, quien <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/entretenimiento\/shakira-nominada-salon-fama-rock-orix\">estaba nominada este a\u00f1o<\/a>, qued\u00f3 fuera de los admitidos.<\/p>\n<p>El Sal\u00f3n de la Fama del Rock &#038; Roll elige artistas mediante votos emitidos por un panel internacional de m\u00e1s de 1.200 artistas, historiadores y profesionales de la industria musical<\/p>\n<p>En total, el Sal\u00f3n de la Fama admiti\u00f3 a 18 artistas en 2026, ocho en la categor\u00eda de \u201cint\u00e9rprete\u201d, cinco en el rengl\u00f3n de \u201cinfluencia temprana\u201d, cuatro en el rubro de \u201cexcelencia musical\u201d y un ganador del premio Ahmet Ertegun.<\/p>\n<ul>\n<li>Phil Collins<\/li>\n<li>Billy Idol<\/li>\n<li>Iron Maiden<\/li>\n<li>Joy Division\/New Order<\/li>\n<li>Oasis<\/li>\n<li>Sade<\/li>\n<li>Luther Vandross<\/li>\n<li>Wu-Tang Clan<\/li>\n<\/ul>\n<p>Phil Collins era nominado por primera vez como artista en solitario, ya que figura en el Sal\u00f3n de la Fama como integrante de la banda Genesis. Collins es ahora el artista n\u00famero 29 en ser incluido en el Sal\u00f3n de la Fama del Rock &#038; Roll al menos dos veces.<\/p>\n<p>El Sal\u00f3n de la Fama del Rock &#038; Roll se ha abierto en los \u00faltimos a\u00f1os a otros g\u00e9neros musicales, como el pop, el rock, el blues, el R&#038;B, el soul, el hip hop, el heavy metal, el punk, el jazz y el dance.<\/p>\n<p>El \u00fanico requisito para ser nominado al Sal\u00f3n de la Fama del Rock &#038; Roll es que hayan transcurrido al menos 25 a\u00f1os desde el lanzamiento de la primera grabaci\u00f3n comercial del artista a nominar.<\/p>\n<ul>\n<li>Celia Cruz<\/li>\n<li>Fela Kuti<\/li>\n<li>Queen Latifah<\/li>\n<li>MC Lyte<\/li>\n<li>Gram Parsons<\/li>\n<\/ul>\n<p>As\u00ed describi\u00f3 el Sal\u00f3n de la Fama del Rock &#038; Roll en su <a href=\"https:\/\/rockhall.com\/inductees\/celia-cruz\/\">sitio web<\/a> a la llamada guarachera de Cuba: \u201cCruz fue pionera del pop latino del siglo XX y m\u00e1s all\u00e1 con sus aportes al estilo de guaracha afrocubana, as\u00ed como con la creaci\u00f3n y popularizaci\u00f3n de la salsa. Con su potente voz y su imagen vibrante, Cruz fue la voz del amor y la libertad tras la revoluci\u00f3n cubana y durante el Movimiento por los Derechos Civiles en Estados Unidos. Cruz vendi\u00f3 m\u00e1s de 30 millones de discos en todo el mundo, lo que la convierte en una de las artistas latinas m\u00e1s vendidas hasta la fecha. Con cl\u00e1sicos como \u2018Quimbara\u2019, \u2018La vida es un carnaval\u2019 y \u2018La negra tiene tumbao\u2019, Cruz reina como la indiscutible reina de la salsa\u201d.<\/p>\n<ul>\n<li>Linda Creed<\/li>\n<li>Arif Mardin<\/li>\n<li>Jimmy Miller<\/li>\n<li>Rick Rubin<\/li>\n<\/ul>\n<ul>\n<li>Ed Sullivan<\/li>\n<\/ul>\n<p>La ceremonia est\u00e1 programada para el 14 de noviembre en el Peacock Theater de Los \u00c1ngeles, y un especial de televisi\u00f3n est\u00e1 previsto para emitirse este diciembre en Estados Unidos en la cadena ABC y en la plataforma de streaming Disney+.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u201c\u00a1Az\u00facar!\u201d de Celia Cruz se col\u00f3 al Sal\u00f3n de la Fama del Rock &#038; Roll: la instituci\u00f3n anunci\u00f3 el martes la lista de artistas admitidos en 2026 y, de manera honor\u00edfica, incluy\u00f3 a la cantante cubana fallecida en 2003 a los 77 a\u00f1os en la categor\u00eda de \u201cInfluencia temprana\u201d. Y con esta buena noticia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473127","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &amp; Roll. Estos son los otros artistas admitidos en 2026 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &amp; Roll. Estos son los otros artistas admitidos en 2026 - Noticias\" \/>\n<meta property=\"og:description\" content=\"El \u201c\u00a1Az\u00facar!\u201d de Celia Cruz se col\u00f3 al Sal\u00f3n de la Fama del Rock &#038; Roll: la instituci\u00f3n anunci\u00f3 el martes la lista de artistas admitidos en 2026 y, de manera honor\u00edfica, incluy\u00f3 a la cantante cubana fallecida en 2003 a los 77 a\u00f1os en la categor\u00eda de \u201cInfluencia temprana\u201d. Y con esta buena noticia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T12:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026\",\"datePublished\":\"2026-04-14T12:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\",\"name\":\"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock & Roll. Estos son los otros artistas admitidos en 2026 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-14T12:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock & Roll. Estos son los otros artistas admitidos en 2026 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock & Roll. Estos son los otros artistas admitidos en 2026 - Noticias","og_description":"El \u201c\u00a1Az\u00facar!\u201d de Celia Cruz se col\u00f3 al Sal\u00f3n de la Fama del Rock &#038; Roll: la instituci\u00f3n anunci\u00f3 el martes la lista de artistas admitidos en 2026 y, de manera honor\u00edfica, incluy\u00f3 a la cantante cubana fallecida en 2003 a los 77 a\u00f1os en la categor\u00eda de \u201cInfluencia temprana\u201d. Y con esta buena noticia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-14T12:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/"},"author":{"name":"","@id":""},"headline":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026","datePublished":"2026-04-14T12:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","name":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock & Roll. Estos son los otros artistas admitidos en 2026 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-14T12:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Celia Cruz ingresa en el Sal\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/celia-cruz-salon-fama-rock-and-roll-2026-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-14T12:03:39Z","datePublished":"2026-04-14T12:03:39Z","dateModified":"2026-04-14T12:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Celia Cruz ingresa en el Sal\\u00f3n de la Fama del Rock &#038; Roll. Estos son los otros artistas admitidos en 2026\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/14\\\/celia-cruz-salon-fama-rock-and-roll-2026-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/14\\\/celia-cruz-salon-fama-rock-and-roll-2026-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-14T12:03:39Z\",\"datePublished\":\"2026-04-14T12:03:39Z\",\"dateModified\":\"2026-04-14T12:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471645,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/25\/shakira-nominada-salon-fama-rock-orix\/","url_meta":{"origin":1473127,"position":0},"title":"Nominan a Shakira al Sal\u00f3n de la Fama del Rock &#038; Roll","author":"","date":"febrero 25, 2026","format":false,"excerpt":"La cantante colombiana Shakira se encuentra entre los 17 artistas nominados al Sal\u00f3n de la Fama del Rock and Roll en 2026, seg\u00fan anunci\u00f3 la instituci\u00f3n en su sitio web este mi\u00e9rcoles.La lista de nominados 2026 re\u00fane a artistas que son reconocidos por primera vez este a\u00f1o y otros que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473186,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/15\/5-cosas-15-de-abril-orix\/","url_meta":{"origin":1473127,"position":1},"title":"Las 5 cosas que debes saber este 15 de abril","author":"","date":"abril 15, 2026","format":false,"excerpt":"EE.UU. levanta sanciones a bancos estatales de Venezuela. Sheinbaum sube el tono contra detenciones de ICE. Celia Cruz, ahora en el Sal\u00f3n de la Fama del Rock & Roll. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471669,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/26\/5-cosas-26-febrero-orix\/","url_meta":{"origin":1473127,"position":2},"title":"Las 5 cosas que debes saber este 26 de febrero","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Cuba dice que sus fuerzas mataron a cuatro personas despu\u00e9s de que una lancha r\u00e1pida de Florida intentara \u201cinfiltrarse\u201d. Lo que hab\u00eda en el interior del escondite del Mencho. Nominan a Shakira al Sal\u00f3n de la Fama del Rock & Roll. Esto es lo que debes saber para comenzar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470312,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/20\/salon-fama-mlb-latinos-carlos-beltran-andruw-jones-orix\/","url_meta":{"origin":1473127,"position":3},"title":"El Sal\u00f3n de la Fama de la MLB recibe a dos nuevos latinos: Carlos Beltr\u00e1n y Andruw Jones","author":"","date":"enero 20, 2026","format":false,"excerpt":"Latinoam\u00e9rica est\u00e1 de fiesta. Este martes son\u00f3 la plena puertorrique\u00f1a y la m\u00fasica alegre de las islas del Caribe en Cooperstown.Carlos Beltr\u00e1n y Andruw Jones se convirtieron en dos nuevos representantes latinos en ingresar al Sal\u00f3n de la Fama de las Grandes Ligas de B\u00e9isbol (MLB), despu\u00e9s de que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468664,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/11\/24\/jimmy-cliff-reggae-muere-trax\/","url_meta":{"origin":1473127,"position":4},"title":"Jimmy Cliff, leyenda del reggae e int\u00e9rprete de &#171;The Harder They Come\u2019&#187;, muere a los 81 a\u00f1os","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"Jimmy Cliff, el cantante de voz suave que ayud\u00f3 a popularizar el g\u00e9nero reggae, ha fallecido a los 81 a\u00f1os, anunci\u00f3 su esposa en Instagram el lunes.\u201cCon profunda tristeza comparto que mi esposo, Jimmy Cliff, ha partido debido a una convulsi\u00f3n seguida de neumon\u00eda\u201d, dijo Latifa Chambers.\u201cAgradezco a su familia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444349,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/01\/24\/adrian-beltre-se-convierte-en-el-quinto-dominicano-elegido-miembro-del-salon-de-la-fama-del-beisbol-de-grandes-ligas\/","url_meta":{"origin":1473127,"position":5},"title":"Adri\u00e1n Beltr\u00e9 se convierte en el quinto dominicano elegido miembro del Sal\u00f3n de la Fama del b\u00e9isbol de Grandes Ligas","author":"","date":"enero 24, 2024","format":false,"excerpt":"El tercera base dominicano Adri\u00e1n Beltr\u00e9 fue electo este martes miembro del Sal\u00f3n de la Fama del b\u00e9isbol de Grandes Ligas e hizo historia con 95,1% de la votaci\u00f3n de la Asociaci\u00f3n de Escritores de B\u00e9isbol de Estados Unidos, la decimos\u00e9ptima m\u00e1s alta.Beltr\u00e9 se convirti\u00f3 en el quinto dominicano en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1473127"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473127\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1473127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1473127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1473127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}