{"id":1473171,"date":"2026-04-14T15:03:47","date_gmt":"2026-04-14T22:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/"},"modified":"2026-04-14T15:03:47","modified_gmt":"2026-04-14T22:03:47","slug":"eeuu-reduce-sanciones-banco-central-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","title":{"rendered":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela"},"content":{"rendered":"<p>El Gobierno de Estados Unidos levant\u00f3 parcialmente las sanciones que manten\u00eda desde 2017 contra bancos de Venezuela, una medida que se suma a la distensi\u00f3n de las relaciones entre ambos pa\u00edses desde que el presidente Nicol\u00e1s Maduro fue capturado en un operativo militar estadounidense y Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada.<\/p>\n<p>La decisi\u00f3n <a href=\"https:\/\/ofac.treasury.gov\/media\/935516\/download?inline\">fue publicada este martes<\/a> por la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), que depende del Departamento del Tesoro.<\/p>\n<p>El documento se\u00f1ala que, a partir de ahora, las empresas de Estados Unidos podr\u00e1n realizar operaciones financieras con cuatro bancos estatales de Venezuela, as\u00ed como con individuos sobre los que no pesen sanciones adicionales.<\/p>\n<p>Los bancos de propiedad estatal involucrados son Banco Central de Venezuela, Banco de Venezuela, Banco Digital de los Trabajadores y Banco del Tesoro.<\/p>\n<p>Entre las operaciones que se podr\u00e1n realizar est\u00e1n manejo de cuentas, pr\u00e9stamos, transferencias, seguros, garant\u00edas, servicios de cheques y uso de billeteras digitales y tarjetas de cr\u00e9dito o d\u00e9bito.<\/p>\n<p>Con el anuncio de la OFAC, por el contrario, no se descongelan propiedades ni se permiten transacciones relacionadas con otras sanciones.<\/p>\n<p>La reducci\u00f3n de las medidas de la OFAC contra los bancos de Venezuela, vigentes desde la primera presidencia de Donald Trump (2017-2021), se produce mientras empresas estadounidenses buscan invertir en Venezuela y luego de que la presidenta encargada en varias ocasiones <a href=\"https:\/\/apnews.com\/article\/venezuela-trump-delcy-rodriguez-sanciones-inversion-licencias-2bac7f1056263aaf4e4aad4cfd1305b7\">pidiera al Gobierno de Trump dar este paso<\/a>, con el argumento de que es necesario para incentivar las inversiones y dar un impulso a la econom\u00eda venezolana.<\/p>\n<p>Desde la captura de Maduro \u2014acusado en Estados Unidos de delitos de narcoterrorismo, narcotr\u00e1fico y armas, que \u00e9l rechaza\u2014, Rodr\u00edguez ha criticado la operaci\u00f3n que deriv\u00f3 en su captura pero, al mismo tiempo, se ha declarado dispuesta a tener una relaci\u00f3n de cooperaci\u00f3n y respeto con Estados Unidos.<\/p>\n<p>El Gobierno de Trump, por su parte, ha elogiado el trabajo de Rodr\u00edguez como presidenta encargada e incluso ha tomado pasos en su favor, como <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/01\/venezuela\/eeuu-levanta-sanciones-delcy-rodriguez-orix\">levantar las sanciones que pesaban contra ella desde 2018<\/a>.<\/p>\n<p>Durante los \u00faltimos meses, adem\u00e1s, Venezuela ha aprobado reformas legales para abrir la inversi\u00f3n a empresas extranjeras en dos sectores clave para el pa\u00eds: <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/29\/venezuela\/asamblea-reforma-ley-hidrocarburos-petroleo-orix\">hidrocarburos<\/a> y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/09\/venezuela\/asamblea-nueva-ley-minas-inversiones-orix\">miner\u00eda<\/a>. El Gobierno de Trump hab\u00eda pedido esos cambios para dar garant\u00edas a las compa\u00f1\u00edas estadounidenses.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Estados Unidos levant\u00f3 parcialmente las sanciones que manten\u00eda desde 2017 contra bancos de Venezuela, una medida que se suma a la distensi\u00f3n de las relaciones entre ambos pa\u00edses desde que el presidente Nicol\u00e1s Maduro fue capturado en un operativo militar estadounidense y Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada. La decisi\u00f3n fue publicada [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473171","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Estados Unidos levant\u00f3 parcialmente las sanciones que manten\u00eda desde 2017 contra bancos de Venezuela, una medida que se suma a la distensi\u00f3n de las relaciones entre ambos pa\u00edses desde que el presidente Nicol\u00e1s Maduro fue capturado en un operativo militar estadounidense y Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada. La decisi\u00f3n fue publicada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T22:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela\",\"datePublished\":\"2026-04-14T22:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\"},\"wordCount\":435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\",\"name\":\"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-14T22:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias","og_description":"El Gobierno de Estados Unidos levant\u00f3 parcialmente las sanciones que manten\u00eda desde 2017 contra bancos de Venezuela, una medida que se suma a la distensi\u00f3n de las relaciones entre ambos pa\u00edses desde que el presidente Nicol\u00e1s Maduro fue capturado en un operativo militar estadounidense y Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada. La decisi\u00f3n fue publicada [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-14T22:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela","datePublished":"2026-04-14T22:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/"},"wordCount":435,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","name":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-14T22:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-14T22:03:47Z","datePublished":"2026-04-14T22:03:47Z","dateModified":"2026-04-14T22:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/14\\\/eeuu-reduce-sanciones-banco-central-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/14\\\/eeuu-reduce-sanciones-banco-central-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-14T22:03:47Z\",\"datePublished\":\"2026-04-14T22:03:47Z\",\"dateModified\":\"2026-04-14T22:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473285,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","url_meta":{"origin":1473171,"position":0},"title":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?","author":"","date":"abril 17, 2026","format":false,"excerpt":"Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra renunci\u00f3 a la presidencia del organismo y Luis P\u00e9rez fue designado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473204,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/15\/eeuu-sanciones-banco-central-venezuela-delcy-orix\/","url_meta":{"origin":1473171,"position":1},"title":"EE.UU. alivi\u00f3 las sanciones al Banco Central de Venezuela. \u00bfPor qu\u00e9 es una medida clave para la gesti\u00f3n de Delcy Rodr\u00edguez?","author":"","date":"abril 15, 2026","format":false,"excerpt":"El levantamiento parcial de las sanciones de EE.UU. sobre bancos de Venezuela es una medida clave para la estabilizaci\u00f3n de la econom\u00eda del pa\u00eds en un momento en que algunos indicadores permanecen fuera de control, seg\u00fan analistas que destacaron que la decisi\u00f3n debe estar acompa\u00f1ada por reformas fiscales que permitan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451501,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/07\/30\/sanciones-eeuu-venezuela-elecciones-orix\/","url_meta":{"origin":1473171,"position":2},"title":"\u00bfQu\u00e9 podr\u00eda pasar con las sanciones de EE.UU. a Venezuela tras las elecciones?","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La situaci\u00f3n en Venezuela tras las elecciones de este domingo se vuelve cada vez m\u00e1s compleja, mientras siguen sin difundirse datos oficiales adicionales de los resultados y tanto el oficialismo como la oposici\u00f3n se adjudican el triunfo. \u00bfC\u00f3mo puede afectar esto al pa\u00eds en cuanto a sanciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452406,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","url_meta":{"origin":1473171,"position":3},"title":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense.El secretario de Justicia de Estados Unidos, Merrick Garland,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470121,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/15\/por-que-trump-retiene-millones-dolares-petroleo-venezuela-banco-qatar-trax\/","url_meta":{"origin":1473171,"position":4},"title":"Por qu\u00e9 el Gobierno de Trump est\u00e1 reteniendo millones de d\u00f3lares de ventas de petr\u00f3leo venezolano en un banco de Qatar","author":"","date":"enero 15, 2026","format":false,"excerpt":"Cientos de millones de d\u00f3lares provenientes de la comercializaci\u00f3n de crudo venezolano han encontrado un destino inesperado: Qatar. Bajo la administraci\u00f3n del presidente Donald Trump, estos fondos permanecen retenidos en una cuenta bancaria qatar\u00ed, creando un laberinto financiero que, aunque promete convertirse en un salvavidas econ\u00f3mico para Caracas, ha desatado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448209,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/04\/17\/estados-unidos-reinstaura-sanciones-petroleo-gas-venezuela-orix\/","url_meta":{"origin":1473171,"position":5},"title":"Estados Unidos reinstaura las sanciones contra el sector de petr\u00f3leo y gas de Venezuela","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Estados Unidos decidi\u00f3 este mi\u00e9rcoles reinstaurar algunas de las sanciones sobre el sector de petr\u00f3leo y gas de Venezuela, seg\u00fan public\u00f3 el Departamento del Tesoro de EE.UU. en un documento. Este, adem\u00e1s, se\u00f1ala la prohibici\u00f3n de realizar transacciones con cualquier entidad con sede en Rusia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1473171"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473171\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1473171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1473171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1473171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}