{"id":1473285,"date":"2026-04-17T15:03:50","date_gmt":"2026-04-17T22:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/"},"modified":"2026-04-17T15:03:50","modified_gmt":"2026-04-17T22:03:50","slug":"cambios-banco-central-guerra-perez-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","title":{"rendered":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?"},"content":{"rendered":"<p>Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/16\/venezuela\/renuncia-presidenta-banco-central-venezuela-efe\">renunci\u00f3 a la presidencia del organismo<\/a> y Luis P\u00e9rez fue designado en su lugar.<\/p>\n<p>El cambio en el mando del BCV se dio a conocer apenas dos d\u00edas despu\u00e9s de que el Gobierno de Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/14\/venezuela\/eeuu-reduce-sanciones-banco-central-orix\">levant\u00f3 parcialmente las sanciones<\/a> que manten\u00eda desde 2017 contra bancos venezolanos, entre ellos el propio BCV, y el mismo d\u00eda que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/16\/venezuela\/fmi-reanuda-relaciones-venezuela-orix\">el Fondo Monetario Internacional<\/a> (FMI) y <a href=\"https:\/\/www.worldbank.org\/en\/news\/statement\/2026\/04\/16\/world-bank-group-announces-resumption-of-dealings-with-venezuela\">el Banco Mundial<\/a> (BM) informaron que reanudar\u00e1n relaciones con el pa\u00eds sudamericano.<\/p>\n<p>Tanto el levantamiento de las sanciones de Estados Unidos como la reanudaci\u00f3n de las relaciones del FMI y el BM se suman a los cambios que ha habido en la relaci\u00f3n de Venezuela con otros gobiernos y organismos internacionales desde la captura de Maduro, quien el 3 de enero fue detenido por fuerzas militares de Estados Unidos en un operativo realizado en Caracas y otras ciudades.<\/p>\n<p>Desde entonces, el Gobierno de Rodr\u00edguez ha restaurado las relaciones diplom\u00e1ticas con Estados Unidos y fomentado especialmente el v\u00ednculo con el presidente Donald Trump, que la ha elogiado repetidas veces mientras Venezuela abre su sector petrolero y minero a las inversiones estadounidenses.<\/p>\n<p>Laura Carolina Guerra Angulo presid\u00eda el BCV desde el 11 de abril de 2025. Ese d\u00eda, Maduro <a href=\"http:\/\/www.gacetaoficial.gob.ve\/gacetas\/6898\">public\u00f3 el decreto para su nombramiento<\/a>, luego de que ella y otras 45 personas participaron en el proceso de evaluaci\u00f3n de aspirantes a renovar el directorio del Banco. Uno de los integrantes del comit\u00e9 evaluador <a href=\"https:\/\/www.mppef.gob.ve\/comite-de-evaluacion-de-meritos-y-credenciales-de-candidatos-y-candidatas-al-directorio-del-banco-central-de-venezuela\/\">fue Larry Devoe<\/a>, reci\u00e9n electo como nuevo fiscal general de Venezuela.<\/p>\n<p>Guerra Angulo fue cu\u00f1ada de Maduro. Es hermana de Adriana Guerra Angulo, primera esposa del derrocado presidente. Por lo tanto, tambi\u00e9n es t\u00eda de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/09\/venezuela\/perfil-nicolasito-maduro-guerra-hijo-presidente-orix\">Nicol\u00e1s Maduro Guerra, \u201cNicolasito\u201d<\/a>, hijo de Maduro y hoy diputado en la Asamblea Nacional.<\/p>\n<p>La exfuncionaria es ingeniera petrolera y ocup\u00f3 otros cargos p\u00fablicos antes de llegar a la presidencia del BCV. De acuerdo con <a href=\"https:\/\/www.bcv.org.ve\/notas-de-prensa\/laura-guerra-es-designada-como-presidenta-del-bcv\">un comunicado del organismo publicado en abril de 2025<\/a>, dirigi\u00f3 el Fondo de Protecci\u00f3n Social de los Dep\u00f3sitos Bancarios, el Fondo para el Desarrollo Nacional y la Superintendencia Nacional de Auditor\u00eda Interna.<\/p>\n<p>Este jueves, la presidenta encargada dijo que Guerra Angulo <a href=\"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/2026\/04\/16\/designado-luis-perez-como-nuevo-presidente-del-banco-central-de-venezuela\/\">\u201cseguir\u00e1 con otras actividades en el \u00e1mbito de Gobierno\u201d<\/a>, sin dar detalles.<\/p>\n<p>Luis Alberto P\u00e9rez Gonz\u00e1lez ya era parte del BCV. El mismo d\u00eda que Maduro nombr\u00f3 presidenta del Banco a Guerra Angulo, <a href=\"http:\/\/www.gacetaoficial.gob.ve\/gacetas\/6898\">a \u00e9l lo design\u00f3 como uno de los directores de la instituci\u00f3n<\/a>.<\/p>\n<p>Antes de ocupar esa posici\u00f3n, P\u00e9rez fue viceministro de Seguimiento y Control del Desarrollo Ecominero, un \u00e1rea dependiente del Ministerio de Desarrollo Ecol\u00f3gico. Maduro lo ubic\u00f3 en ese cargo <a href=\"http:\/\/www.gacetaoficial.gob.ve\/gacetas\/42909\">con un decreto publicado el 27 de junio de 2024<\/a>.<\/p>\n<p>La llegada de P\u00e9rez a la cabeza del BCV en reemplazo de Guerra Angulo ha generado diversas reacciones en Venezuela.<\/p>\n<p>El analista Ricardo R\u00edos, presidente de la consultora venezolana Poder y Estrategia, <a href=\"https:\/\/x.com\/riosdefrente\/status\/2045116487493382606\">dijo este viernes en X<\/a> que, a su juicio, este cambio \u201cconsolida la tendencia observada\u201d desde que asumi\u00f3 el Gobierno encargado, pues \u201csale personal de confianza de Maduro y entra personal de confianza de Delcy Rodr\u00edguez\u201d.<\/p>\n<p>La periodista Blanca Vera Asaf, directora del sitio web Bit\u00e1cora Econ\u00f3mica, matiz\u00f3 los posibles efectos de este relevo. El jueves por la noche, <a href=\"https:\/\/x.com\/bevavera\/status\/2044961802518155352\">Vera se\u00f1al\u00f3 en X<\/a> que no es previsible que el nombramiento de P\u00e9rez signifique cambios en la operaci\u00f3n del BCV, sino que su designaci\u00f3n \u201cpareciera m\u00e1s bien una continuidad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra renunci\u00f3 a la presidencia del organismo y Luis P\u00e9rez fue designado en su lugar. El cambio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473285","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra renunci\u00f3 a la presidencia del organismo y Luis P\u00e9rez fue designado en su lugar. El cambio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T22:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?\",\"datePublished\":\"2026-04-17T22:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\"},\"wordCount\":662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\",\"name\":\"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T22:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias","og_description":"Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra renunci\u00f3 a la presidencia del organismo y Luis P\u00e9rez fue designado en su lugar. El cambio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-17T22:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/"},"author":{"name":"","@id":""},"headline":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?","datePublished":"2026-04-17T22:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/"},"wordCount":662,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","name":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T22:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T22:03:50Z","datePublished":"2026-04-17T22:03:50Z","dateModified":"2026-04-17T22:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cambios en el Banco Central de Venezuela: \\u00bfqui\\u00e9n era la presidenta del organismo y qui\\u00e9n lleg\\u00f3 en su lugar?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/cambios-banco-central-guerra-perez-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/cambios-banco-central-guerra-perez-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T22:03:50Z\",\"datePublished\":\"2026-04-17T22:03:50Z\",\"dateModified\":\"2026-04-17T22:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473204,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/15\/eeuu-sanciones-banco-central-venezuela-delcy-orix\/","url_meta":{"origin":1473285,"position":0},"title":"EE.UU. alivi\u00f3 las sanciones al Banco Central de Venezuela. \u00bfPor qu\u00e9 es una medida clave para la gesti\u00f3n de Delcy Rodr\u00edguez?","author":"","date":"abril 15, 2026","format":false,"excerpt":"El levantamiento parcial de las sanciones de EE.UU. sobre bancos de Venezuela es una medida clave para la estabilizaci\u00f3n de la econom\u00eda del pa\u00eds en un momento en que algunos indicadores permanecen fuera de control, seg\u00fan analistas que destacaron que la decisi\u00f3n debe estar acompa\u00f1ada por reformas fiscales que permitan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470322,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/21\/delcy-rodriguez-venezuela-eeuu-petroleo-300-millones-dolares-efe\/","url_meta":{"origin":1473285,"position":1},"title":"Venezuela recibi\u00f3 US$ 300 millones por la venta de crudo tras el acuerdo con EE.UU., anunci\u00f3 Delcy Rodr\u00edguez","author":"","date":"enero 21, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este martes el ingreso de US$ 300 millones al pa\u00eds \u201cproducto de la venta del petr\u00f3leo\u201d, d\u00edas despu\u00e9s de que Washington anunciara un acuerdo de venta de crudo del pa\u00eds suramericano por US$ 500 millones.\u201cDe los primeros 500 millones, han ingresado 300\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473031,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/10\/marcha-venezuela-trabajadores-salario-bloqueo-policial-efe\/","url_meta":{"origin":1473285,"position":2},"title":"Volvieron las marchas a las calles de Venezuela y tambi\u00e9n el bloqueo policial","author":"","date":"abril 10, 2026","format":false,"excerpt":"Un fuerte cerco de la Polic\u00eda Nacional Bolivariana (PNB) de Venezuela bloque\u00f3 y dispers\u00f3 con gas pimienta a cientos de trabajadores que intentaban marchan este jueves hacia el palacio presidencial de Miraflores, en el centro de Caracas, para exigir un aumento de salario, congelado desde 2022.En su intento por llegar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473171,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/14\/eeuu-reduce-sanciones-banco-central-orix\/","url_meta":{"origin":1473285,"position":3},"title":"EE.UU. levanta sanciones contra el Banco Central y otras tres entidades bancarias de Venezuela","author":"","date":"abril 14, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos levant\u00f3 parcialmente las sanciones que manten\u00eda desde 2017 contra bancos de Venezuela, una medida que se suma a la distensi\u00f3n de las relaciones entre ambos pa\u00edses desde que el presidente Nicol\u00e1s Maduro fue capturado en un operativo militar estadounidense y Delcy Rodr\u00edguez asumi\u00f3 como presidenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470776,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/02\/daniella-diosdado-cabello-ministra-turismo-orix\/","url_meta":{"origin":1473285,"position":4},"title":"Delcy Rodr\u00edguez nombra a la hija de Diosdado Cabello como ministra de Turismo en Venezuela","author":"","date":"febrero 2, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, design\u00f3 este lunes como ministra de Turismo a Daniella Cabello, hija del n\u00famero dos del chavismo, Diosdado Cabello, como parte de los cambios que est\u00e1 realizando en el gabinete tras la captura del mandatario Nicol\u00e1s Maduro por parte de Estados Unidos, hace casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473260,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","url_meta":{"origin":1473285,"position":5},"title":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n","author":"","date":"abril 16, 2026","format":false,"excerpt":"El Fondo Monetario Internacional (FMI) anunci\u00f3 este jueves la reanudaci\u00f3n de sus relaciones con Venezuela bajo el Gobierno de la presidenta interina, Delcy Rodr\u00edguez, tras haberlas suspendido en 2019 por cuestiones de \u201creconocimiento del Gobierno\u201d, seg\u00fan inform\u00f3 la directora gerente Kristalina Georgieva.El FMI anunci\u00f3 este jueves en Washington la reanudaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1473285"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473285\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1473285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1473285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1473285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}