{"id":1473287,"date":"2026-04-17T16:03:44","date_gmt":"2026-04-17T23:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/"},"modified":"2026-04-17T16:03:44","modified_gmt":"2026-04-17T23:03:44","slug":"empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","title":{"rendered":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor"},"content":{"rendered":"<p>Para el p\u00fablico, Lauren Bullis era una empleada dedicada del Departamento de Seguridad Nacional en Georgia: una profesional ejemplar comprometida con el servicio p\u00fablico.<\/p>\n<p>Para sus seres queridos, la mujer de 40 a\u00f1os, originaria de Decatur, era una exploradora aventurera que viajaba por el mundo y llevaba alegr\u00eda a amigos cercanos y lejanos.<\/p>\n<p>\u201cNo pod\u00edas conocerla y no ser su amigo\u201d, dijo a Associated Press Ashley Toillion, auditora del DHS. \u201cEra simplemente la persona m\u00e1s amable, m\u00e1s dulce y alentadora que he conocido\u201d.<\/p>\n<p>Ambas compart\u00edan la pasi\u00f3n por correr y planeaban participar en una carrera en Walt Disney World.<\/p>\n<p>Pero el lunes por la ma\u00f1ana, mientras Bullis paseaba a su bulldog franc\u00e9s Sancho, fue baleada y apu\u00f1alada en Panthersville, una comunidad no incorporada a unos 24 kil\u00f3metros al sureste del centro de Atlanta.<\/p>\n<p>Su muerte se produjo apenas horas despu\u00e9s de que otra mujer, Prianna Weathers, de 31 a\u00f1os, muriera a tiros cerca de un restaurante en Decatur. Una tercera v\u00edctima de un tiroteo, un hombre sin hogar que fue atacado afuera de una tienda de comestibles en Brookhaven, sobrevivi\u00f3, pero result\u00f3 gravemente herido.<\/p>\n<p>Con base en im\u00e1genes de vigilancia y lectores de matr\u00edculas, las autoridades creen que el mismo hombre, Olaolukitan Adon Abel, de 26 a\u00f1os, y residente de Atlanta, dispar\u00f3 contra las tres v\u00edctimas en una ola de violencia que ha sido destacada por el Gobierno de Trump.<\/p>\n<p>Aunque el motivo sigue sin estar claro, el empleo de Bullis en el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y la condici\u00f3n de Adon Abel como ciudadano naturalizado han suscitado interrogantes, y cr\u00edticas por parte de la agencia respecto a los delitos que el sospechoso cometi\u00f3 tras obtener la ciudadan\u00eda estadounidense.<\/p>\n<p>Bullis era una figura muy querida en su vecindario; a menudo se la ve\u00eda corriendo, paseando a Sancho o cuidando las hermosas flores que plantaba en su jard\u00edn.<\/p>\n<p>Seg\u00fan su <a href=\"https:\/\/www.legacy.com\/us\/obituaries\/name\/lauren-bullis-obituary?id=61257426\">obituario<\/a>, ella \u201cdisfrutaba enormemente del <em>running<\/em>, habiendo corrido 5 km, 10 km y medias maratones por todo el pa\u00eds\u201d. \u201cCuando visitaba a sus seres queridos, Lauren siempre ped\u00eda una llave de repuesto para poder correr sin despertar a sus anfitriones\u201d.<\/p>\n<p>Apenas el mes pasado, Bullis complet\u00f3 su primer marat\u00f3n en Atlanta.<\/p>\n<p>\u201cEs muy atl\u00e9tica\u201d, dijo su vecina Portia Powell. \u201cSi no est\u00e1 paseando al perro, est\u00e1 corriendo\u201d.<\/p>\n<p>Powell forj\u00f3 una s\u00f3lida amistad con Bullis en los \u00faltimos a\u00f1os, unidas por su amor compartido por la jardiner\u00eda.<\/p>\n<p>\u201cSiempre me saludaba: \u2018Hola, se\u00f1orita Portia, \u00bfc\u00f3mo est\u00e1?\u2019\u2026 era muy extrovertida y amigable\u201d, dijo Powell.<\/p>\n<p>La muerte de Bullis \u201cha impactado enormemente al vecindario\u201d, dijo Powell. \u201cCreo que nos har\u00e1 estar m\u00e1s atentos a lo que sucede en el vecindario y cuidarnos unos a otros\u201d.<\/p>\n<p>La tragedia devast\u00f3 a los colegas de la Oficina del Inspector General del DHS, donde Bullis era auditora y l\u00edder de equipo, inform\u00f3 la agencia.<\/p>\n<p>\u201cLauren abordaba su trabajo con integridad, consideraci\u00f3n y un compromiso con la excelencia que fortalec\u00eda nuestra organizaci\u00f3n y las comunidades a las que servimos\u201d, dijo el DHS. \u201cAportaba calidez, amabilidad y un genuino sentido de cuidado a sus colegas cada d\u00eda\u201d.<\/p>\n<p>El esposo, la hijastra, los padres y los hermanos de Bullis est\u00e1n ahora unidos en el duelo, privados de su generosa, hilarante, trotamundos y llena de luz.<\/p>\n<p>\u201cAntepon\u00eda las necesidades de los dem\u00e1s a las suyas, cuidando en numerosas ocasiones a amigos enfermos y a quienes simplemente se hab\u00edan excedido con la comida. Era tremendamente divertida, una gran anfitriona, digna, sencilla y muy graciosa\u201d, reza el obituario de Bullis.<\/p>\n<p>\u201cA Lauren le encantaba viajar, sola o acompa\u00f1ada, y visit\u00f3 lugares lejanos como Egipto, Per\u00fa, Grecia, Espa\u00f1a, Irlanda y Francia, entre muchos otros\u201d, se lee en el obituario. \u201cSiempre estaba planeando su pr\u00f3ximo viaje\u201d.<\/p>\n<p>Mientras la serie de ataques sacude a varias comunidades en Georgia, la madre de Prianna Weathers llora en privado en su casa de Carolina del Norte.<\/p>\n<p>\u201cEsta fue una muerte sin sentido\u201d, declar\u00f3 a CNN. \u201cTodas estas personas que mat\u00f3\u2026 eran personas inocentes. No ten\u00eda ninguna raz\u00f3n para hacerles da\u00f1o. No le estaban haciendo nada a \u00e9l\u201d.<\/p>\n<p>Weathers fue asesinada en Decatur, no muy lejos de donde naci\u00f3 hace 31 a\u00f1os, seg\u00fan su madre.<\/p>\n<p>Pidi\u00f3 permanecer en el anonimato para proteger la privacidad del hijo de 12 a\u00f1os de Weathers, a quien ahora cr\u00eda y que deber\u00e1 crecer sin su madre.<\/p>\n<p>No est\u00e1 claro por qu\u00e9 fueron atacadas las tres v\u00edctimas del tiroteo. La polic\u00eda dijo que el hombre que result\u00f3 herido de gravedad parec\u00eda haber sido atacado al azar, y los investigadores estaban analizando si las dos mujeres asesinadas tambi\u00e9n fueron atacadas al azar.<\/p>\n<p>Don Plummer, del Consejo de Defensores P\u00fablicos de Georgia, declin\u00f3 detallar el caso y los antecedentes del sospechoso.<\/p>\n<p>\u201cEntendemos la intensa atenci\u00f3n p\u00fablica que rodea este caso, pero el Sr. Abel tiene los mismos derechos constitucionales que cualquier otra persona acusada, y nuestro trabajo es proteger esos derechos en los tribunales\u201d, le dijo a CNN.<\/p>\n<p>\u201cEste es un caso tr\u00e1gico y grave. Nada de defender los derechos constitucionales minimiza eso. De hecho, el estado de derecho importa m\u00e1s cuando las emociones est\u00e1n a flor de piel y las acusaciones son las m\u00e1s graves\u201d.<\/p>\n<p>Adon Abel, originario del Reino Unido, se naturaliz\u00f3 ciudadano estadounidense en 2022, seg\u00fan inform\u00f3 el Departamento de Seguridad Nacional.<\/p>\n<p>El proceso de naturalizaci\u00f3n a menudo lleva a\u00f1os, y no est\u00e1 claro si la mayor parte del tr\u00e1mite de Adon Abel tuvo lugar durante el primer Gobierno de Trump o la gesti\u00f3n de Biden. El DHS no respondi\u00f3 a la pregunta de CNN sobre el cronograma de naturalizaci\u00f3n del sospechoso.<\/p>\n<p>Olaolukitan Adon Abel, de Atlanta, enfrenta cargos que incluyen agresi\u00f3n agravada y dos cargos de asesinato con malicia.<\/p>\n<p>El DHS culp\u00f3 al Gobierno anterior por la naturalizaci\u00f3n de Adon Abel, describiendo al sospechoso como un \u201cmonstruo\u201d en una <a href=\"https:\/\/www.facebook.com\/homelandsecurity\/posts\/pfbid02jY9m8s1XisbBZsR9jD4CkwsTyR3vNYRczTG4KX9NYh7gmfX9j2odBgspde3xwo1Pl\">publicaci\u00f3n de Facebook.<\/a><\/p>\n<p>La agencia tambi\u00e9n inform\u00f3 que Adon Abel fue condenado por varios delitos, incluidos abuso sexual y agresi\u00f3n con un arma mortal. Los registros judiciales muestran que un acusado identificado como Adon Olaolukitan se declar\u00f3 culpable de cuatro cargos de abuso sexual menor por un incidente de 2025 en Georgia, varios a\u00f1os despu\u00e9s de que el sospechoso se convirtiera en ciudadano estadounidense. Fue condenado a 48 meses de libertad condicional por esos delitos.<\/p>\n<p>Otro documento judicial muestra que un acusado llamado \u201cOlaolukitan Adonabel\u201d se declar\u00f3 culpable de un delito grave de 2024 por agresi\u00f3n con un arma mortal \u201cque no sea un arma de fuego contra un agente de polic\u00eda o bombero\u201d en California. Ese registro se\u00f1ala que el nombre del sospechoso tambi\u00e9n puede aparecer como Olaolukitan Adon Abel o Adon Olaolukitan.<\/p>\n<p>El consejo de defensores p\u00fablicos critic\u00f3 duramente la caracterizaci\u00f3n del sospechoso por parte del DHS.<\/p>\n<p>\u201cEs irresponsable y preocupante que funcionarios p\u00fablicos califiquen a una persona acusada de \u2018monstruo\u2019 antes del juicio\u201d, dijo Plummer. \u201cEse tipo de lenguaje puede ser pol\u00edticamente conveniente, pero atenta contra el debido proceso y para el derecho b\u00e1sico a un juicio justo\u201d.<\/p>\n<p>Los registros muestran otros cargos, pero esos casos fueron desestimados.<\/p>\n<p>El lunes, Adon Abel fue detenido durante una parada de tr\u00e1fico en el condado de Troup, en Georgia, que limita con Alabama. Ahora enfrenta varios cargos, incluidos dos cargos de asesinato con malicia, agresi\u00f3n con agravantes y posesi\u00f3n de un arma de fuego durante la comisi\u00f3n de un delito grave, indic\u00f3 la polic\u00eda.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el p\u00fablico, Lauren Bullis era una empleada dedicada del Departamento de Seguridad Nacional en Georgia: una profesional ejemplar comprometida con el servicio p\u00fablico. Para sus seres queridos, la mujer de 40 a\u00f1os, originaria de Decatur, era una exploradora aventurera que viajaba por el mundo y llevaba alegr\u00eda a amigos cercanos y lejanos. \u201cNo pod\u00edas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473287","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias\" \/>\n<meta property=\"og:description\" content=\"Para el p\u00fablico, Lauren Bullis era una empleada dedicada del Departamento de Seguridad Nacional en Georgia: una profesional ejemplar comprometida con el servicio p\u00fablico. Para sus seres queridos, la mujer de 40 a\u00f1os, originaria de Decatur, era una exploradora aventurera que viajaba por el mundo y llevaba alegr\u00eda a amigos cercanos y lejanos. \u201cNo pod\u00edas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T23:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor\",\"datePublished\":\"2026-04-17T23:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\"},\"wordCount\":1331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\",\"name\":\"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T23:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias","og_description":"Para el p\u00fablico, Lauren Bullis era una empleada dedicada del Departamento de Seguridad Nacional en Georgia: una profesional ejemplar comprometida con el servicio p\u00fablico. Para sus seres queridos, la mujer de 40 a\u00f1os, originaria de Decatur, era una exploradora aventurera que viajaba por el mundo y llevaba alegr\u00eda a amigos cercanos y lejanos. \u201cNo pod\u00edas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-17T23:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/"},"author":{"name":"","@id":""},"headline":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor","datePublished":"2026-04-17T23:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/"},"wordCount":1331,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","name":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T23:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T23:03:44Z","datePublished":"2026-04-17T23:03:44Z","dateModified":"2026-04-17T23:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qui\\u00e9nes eran las tres v\\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T23:03:44Z\",\"datePublished\":\"2026-04-17T23:03:44Z\",\"dateModified\":\"2026-04-17T23:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469899,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/08\/quien-mujer-murio-disparos-ice-minneapolis-trax\/","url_meta":{"origin":1473287,"position":0},"title":"\u00bfQui\u00e9n era Renee Nicole Good, la mujer que muri\u00f3 baleada por un agente de ICE en Minneapolis?","author":"","date":"enero 8, 2026","format":false,"excerpt":"La mujer que muri\u00f3 baleada por un agente de Inmigraci\u00f3n y Control de Aduanas en Minneapolis era una madre amorosa, una poeta y una compa\u00f1era cuya familia \u2014junto con los vecinos de su at\u00f3nita ciudad y extra\u00f1os mucho m\u00e1s all\u00e1\u2014 est\u00e1 conmocionada por las circunstancias que rodearon su muerte.Renee Nicole\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469889,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/08\/esto-sabemos-mujer-murio-ice-minneapolis-trax\/","url_meta":{"origin":1473287,"position":1},"title":"Esto sabemos sobre la mujer que muri\u00f3 por disparos de un agente de ICE en Minneapolis","author":"","date":"enero 8, 2026","format":false,"excerpt":"La mujer que muri\u00f3 por disparos de un agente de Inmigraci\u00f3n y Control de Aduanas en Minneapolis es recordada como una madre y compa\u00f1era amorosa cuya familia est\u00e1 conmocionada por las circunstancias que rodearon su fallecimiento.Renee Nicole Good, una ciudadana estadounidense de 37 a\u00f1os, perdi\u00f3 la vida cuando un agente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469910,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/01\/08\/que-paso-tiroteo-ice-muerte-mujer-minneapolis-trax\/","url_meta":{"origin":1473287,"position":2},"title":"\u00bfQu\u00e9 pas\u00f3 en el tiroteo en Minneapolis en el que un agente de ICE mat\u00f3 a una mujer? Esto sabemos","author":"","date":"enero 8, 2026","format":false,"excerpt":"El tiroteo mortal de una ciudadana estadounidense por parte de un agente del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Minneapolis este mi\u00e9rcoles podr\u00eda convertirse en un punto de inflexi\u00f3n en la ofensiva migratoria del presidente Donald Trump en las ciudades estadounidenses.Renee Nicole\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450626,"url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/06\/23\/hace-un-ano-su-anillo-de-compromiso-desaparecio-en-un-hospital-todavia-aprecia-al-hombre-que-se-lo-dio\/","url_meta":{"origin":1473287,"position":3},"title":"Hace un a\u00f1o, su anillo de compromiso desapareci\u00f3 en un hospital. Todav\u00eda aprecia al hombre que se lo dio","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN) --Faye Bauman llevaba su anillo de diamantes cuando se cay\u00f3 y se rompi\u00f3 la cadera. Era junio del a\u00f1o pasado y ten\u00eda 85 a\u00f1os. En el Hospital North Florida de Gainesville se quit\u00f3 varias joyas, entre ellas el anillo, y se las dio a una enfermera.Despu\u00e9s de la operaci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463561,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/06\/14\/quien-fue-melissa-hortman-representante-minnesota-mataron-a-tiros-trax\/","url_meta":{"origin":1473287,"position":4},"title":"\u00bfQui\u00e9n fue Melissa Hortman, la representante de Minnesota que mataron a tiros en su casa?","author":"","date":"junio 14, 2025","format":false,"excerpt":"Una voluntaria dedicada que ense\u00f1aba en la escuela dominical y amaba a los perros. Una abogada que fue l\u00edder de las Girl Scout y trabaj\u00f3 en la tienda de autopartes de su padre. Una madre y esposa cuyo esposo muri\u00f3 junto a ella. La representante estatal de Minnesota, Melissa Hortman,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442538,"url":"https:\/\/noticiasya.com\/colorado-springs\/2023\/12\/23\/surgen-nuevos-detalles-sobre-las-victimas-del-tiroteo-de-praga\/","url_meta":{"origin":1473287,"position":5},"title":"Surgen nuevos detalles sobre las v\u00edctimas del tiroteo de Praga","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN) -- Rep\u00fablica Checa observa este s\u00e1bado una jornada de luto nacional tras el peor tiroteo de la historia del pa\u00eds en tiempos de paz, que ha dejado 14 muertos y decenas de heridos en la Universidad Carolina de Praga.Entre las v\u00edctimas hab\u00eda varios j\u00f3venes estudiantes, un profesor muy querido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1473287"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473287\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1473287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1473287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1473287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}