{"id":1473290,"date":"2026-04-17T18:03:50","date_gmt":"2026-04-18T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/"},"modified":"2026-04-17T18:03:50","modified_gmt":"2026-04-18T01:03:50","slug":"economia-trump-confianza-consumidor-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","title":{"rendered":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos"},"content":{"rendered":"<p>Tras pasar la primera parte de la guerra con Ir\u00e1n intentando convencer a los estadounidenses de que la econom\u00eda se basaba en el sacrificio a corto plazo para obtener beneficios a largo plazo, el presidente Donald Trump y su equipo han vuelto cada vez m\u00e1s a su postura anterior: la de Kevin Bacon en \u201cAnimal House\u201d.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=PdbpmeUODME\">En esencia, est\u00e1n diciendo: \u201cMantengan la calma. Todo va bien\u201d.<\/a><\/p>\n<p>Era un mensaje pol\u00edtico desconcertante y arriesgado antes de la guerra; ahora lo es a\u00fan m\u00e1s.<\/p>\n<p>Usaron una versi\u00f3n de este mensaje en oto\u00f1o. Incluso cuando las preocupaciones por el <a href=\"https:\/\/cnnespanol.cnn.com\/economia\/economia-estados-unidos\">costo de vida<\/a> persist\u00edan cada vez m\u00e1s como un problema para Trump, \u00e9l se dispuso a argumentar que los precios en realidad estaban bajando \u2014y considerablemente\u2014, aunque no lo estaban.<\/p>\n<p>Hoy, el mensaje es m\u00e1s bien: a pesar de lo que los votantes oyen (o ven en cualquier gasolinera), la situaci\u00f3n es bastante buena. Y, adem\u00e1s, podr\u00eda haber sido mucho peor.<\/p>\n<p>\u201cPara ser honesto, nos est\u00e1 yendo muy bien\u201d, le dijo Trump a Maria Bartiromo de Fox Business en una entrevista emitida el mi\u00e9rcoles, citando un mercado burs\u00e1til s\u00f3lido.<\/p>\n<p>Cuando Bartiromo lo cuestion\u00f3 un poco, Trump argument\u00f3 que el petr\u00f3leo a US$ 92 por barril no era tan malo si se tiene en cuenta que algunos estaban hablando de US$ 200 por barril.<\/p>\n<p>\u201c\u00bfY saben qu\u00e9?\u201d, a\u00f1adi\u00f3 Trump. \u201cEstoy muy contento\u201d.<\/p>\n<p>Trump ampli\u00f3 esta l\u00ednea bastante optimista el jueves, tanto fuera de la Casa Blanca como durante un acto de campa\u00f1a en Las Vegas centrado en la reducci\u00f3n de impuestos.<\/p>\n<p>Afirm\u00f3 que la tasa de inflaci\u00f3n era \u201cmuy baja, y sigue si\u00e9ndolo\u201d. Esto a pesar de que el mes pasado alcanz\u00f3 su nivel m\u00e1s alto en dos a\u00f1os, y se espera que siga subiendo mientras persistan los efectos de la guerra. Se refiri\u00f3 a \u201cnuestra gran econom\u00eda\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 por la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/15\/venezuela\/venezuela-sistema-combustibles-subsidiado-premium-verde-rojo-orix\">gasolina a US$ 4 por gal\u00f3n<\/a>, mencion\u00f3 el mercado burs\u00e1til y dijo: \u201cTodo va realmente bien\u201d.<\/p>\n<p>Reiter\u00f3 que los precios de la gasolina no eran muy altos en comparaci\u00f3n con lo que deber\u00edan ser. (El secretario de Energ\u00eda, Chris Wright, declar\u00f3 a NBC News hace apenas un mes que hab\u00eda muchas probabilidades de que la gasolina bajara de los US$ 3 por gal\u00f3n para el verano).<\/p>\n<p>Trump tambi\u00e9n calific\u00f3 la inflaci\u00f3n de \u201cfalsa\u201d, ya que se deb\u00eda al aumento de los precios del combustible y la energ\u00eda.<\/p>\n<p>\u201cTuvimos la mejor econom\u00eda de la historia de nuestro pa\u00eds durante mi primer mandato\u201d, a\u00f1adi\u00f3 Trump. \u201cY ahora la estamos arruinando, la estamos desmoronando\u201d.<\/p>\n<p>Otros parecen estar en la misma sinton\u00eda.<\/p>\n<p>La secretaria de Prensa de la Casa Blanca, Karoline Leavitt, inst\u00f3 en una rueda de prensa esta semana a \u201cobservar c\u00f3mo disminuyeron los precios de la gasolina durante el \u00faltimo a\u00f1o desde que este presidente asumi\u00f3 el cargo\u201d. Incluso esa estad\u00edstica no es precisamente impresionante: la gasolina costaba alrededor de US$ 3,11 por gal\u00f3n cuando Trump asumi\u00f3 la presidencia, seg\u00fan datos de Gas Buddy; hab\u00eda bajado poco m\u00e1s de 10 centavos cuando comenz\u00f3 la guerra.<\/p>\n<p>El secretario del Tesoro, Scott Bessent, declar\u00f3 esta semana a CNBC que Trump pudo iniciar la guerra porque la econom\u00eda estaba en muy buen estado. Tambi\u00e9n afirm\u00f3 en una reuni\u00f3n informativa con Leavitt que la econom\u00eda sigue siendo \u201cmuy fuerte\u201d.<\/p>\n<p>En una entrevista concedida el D\u00eda de los Impuestos a la secci\u00f3n de <a href=\"https:\/\/thenationaldesk.com\/top-videos\/on-tax-day-treasury-secretary-weighs-in-on-souring-sentiment-tax-cuts-and-interest-rates-president-donald-trump-irs-interest-rate-economy\">National News Desk<\/a>, Bessent hizo algunos comentarios particularmente sorprendentes.<\/p>\n<p>Apost\u00f3 a que los estadounidenses son, en realidad, m\u00e1s optimistas respecto a la econom\u00eda de lo que aparentan.<\/p>\n<p>\u201cEl consumidor, aunque pueda estar sonando sombr\u00edo, en realidad est\u00e1 bastante animado\u201d, dijo, citando el comportamiento del gasto.<\/p>\n<p>Cuando el reportero plante\u00f3 que Bessent estaba diciendo que la gente no se sent\u00eda bien pero en realidad estaba actuando con confianza, indic\u00f3 que ni siquiera era eso.<br \/>Apost\u00f3 a que la gente en realidad s\u00ed se siente bien respecto a la econom\u00eda, aunque no lo diga.<\/p>\n<p>\u201cBueno, en el fondo, se sienten bien\u201d, dijo Bessent. \u201cNo s\u00e9 qu\u00e9 les dicen a los encuestadores\u201d.<\/p>\n<p>Bessent no est\u00e1 improvisando del todo aqu\u00ed.<\/p>\n<p>Hay un argumento para sostener que los fundamentos econ\u00f3micos no son ni de lejos tan sombr\u00edos como los estadounidenses parecen creer, como <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/economia\/analisis-trump-economia-ee-uu-gran-problema-trax\">escribi\u00f3 David Goldman<\/a>, de CNN, poco antes de que comenzara la guerra en febrero. El gasto del consumidor se ha mantenido bastante s\u00f3lido en la era posterior al covid.<\/p>\n<p>El hecho de que el mercado burs\u00e1til siga subiendo \u2014y ahora haya recuperado sus p\u00e9rdidas de principios de la guerra\u2014 parece confirmarlo.<\/p>\n<p>Pero el Gobierno de Biden plante\u00f3 argumentos similares luego de que bajara la tasa de inflaci\u00f3n, lo que no les sali\u00f3 tan bien en 2024, ya que los \u00edndices de aprobaci\u00f3n del expresidente Joe Biden sobre la econom\u00eda se desplomaron.<\/p>\n<p>Por lo tanto, si el argumento de Bessent se ha convertido en un principio rector, es realmente arriesgado. Porque los estadounidenses est\u00e1n diciendo cosas realmente desalentadoras a quienes realizan las encuestas.<\/p>\n<p>Recientemente, el muy observado \u00edndice de confianza del consumidor de la Universidad de Michigan alcanz\u00f3 un nuevo m\u00ednimo hist\u00f3rico en datos que abarcan d\u00e9cadas, hasta despu\u00e9s de la Segunda Guerra Mundial.<\/p>\n<p>Ahora es m\u00e1s bajo no solo que durante el repunte inflacionario posterior al covid, sino tambi\u00e9n que durante la Gran Recesi\u00f3n de finales de la d\u00e9cada de 2000 y durante otros per\u00edodos de dificultades econ\u00f3micas en la segunda mitad del siglo XX.<\/p>\n<p>Y las encuestas reflejan ese pesimismo.<\/p>\n<p>La <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/01\/eeuu\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\">encuesta m\u00e1s reciente de CNN<\/a> de finales de marzo, por ejemplo, mostr\u00f3 que solo el 23 % de los estadounidenses calific\u00f3 la econom\u00eda como al menos \u201calgo buena\u201d.<br \/>Esa cifra solo fue m\u00e1s baja en dos ocasiones durante el mandato de Biden, por un breve per\u00edodo en 2022.<\/p>\n<p>La encuesta tambi\u00e9n mostr\u00f3:<\/p>\n<ul>\n<li>El 62 % esperaba que la econom\u00eda siguiera mal durante el pr\u00f3ximo a\u00f1o, el peor resultado de este tipo en casi tres d\u00e9cadas de encuestas de CNN.<\/li>\n<li>M\u00e1s de 6 de cada 10 personas calificaron el aumento de los precios de la gasolina como una \u201cdificultad moderada\u201d.<\/li>\n<li>M\u00e1s de 6 de cada 10 dijeron haber modificado sus h\u00e1bitos de gasto de una forma u otra.<\/li>\n<\/ul>\n<p>Y, quiz\u00e1s m\u00e1s importante a\u00fan, los estadounidenses dijeron, en un 65 % frente a un 25 %, que Trump hab\u00eda empeorado la situaci\u00f3n econ\u00f3mica en lugar de mejorarla.<\/p>\n<p>Esa brecha de menos 40 puntos no solo es peor que en cualquier momento para Biden; tambi\u00e9n es significativamente peor que en enero, cuando Trump solo ten\u00eda una diferencia de 23 puntos.<\/p>\n<p>La guerra claramente ha convertido la econom\u00eda en una carga mayor para Trump. Quiz\u00e1s esto empiece a cambiar si la guerra termina.<\/p>\n<p>Pero intentar convencer a los votantes de que la econom\u00eda est\u00e1 bien, a pesar de la contundente evidencia en contra y sus arraigados sentimientos negativos al respecto, no parece una buena estrategia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras pasar la primera parte de la guerra con Ir\u00e1n intentando convencer a los estadounidenses de que la econom\u00eda se basaba en el sacrificio a corto plazo para obtener beneficios a largo plazo, el presidente Donald Trump y su equipo han vuelto cada vez m\u00e1s a su postura anterior: la de Kevin Bacon en \u201cAnimal [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473290","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras pasar la primera parte de la guerra con Ir\u00e1n intentando convencer a los estadounidenses de que la econom\u00eda se basaba en el sacrificio a corto plazo para obtener beneficios a largo plazo, el presidente Donald Trump y su equipo han vuelto cada vez m\u00e1s a su postura anterior: la de Kevin Bacon en \u201cAnimal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-18T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos\",\"datePublished\":\"2026-04-18T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\"},\"wordCount\":1241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\",\"name\":\"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-18T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias","og_description":"Tras pasar la primera parte de la guerra con Ir\u00e1n intentando convencer a los estadounidenses de que la econom\u00eda se basaba en el sacrificio a corto plazo para obtener beneficios a largo plazo, el presidente Donald Trump y su equipo han vuelto cada vez m\u00e1s a su postura anterior: la de Kevin Bacon en \u201cAnimal [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-18T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos","datePublished":"2026-04-18T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/"},"wordCount":1241,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","name":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-18T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Trump insiste en que la econom\u00eda va bien, pero los estadounidenses no est\u00e1n convencidos","url":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado-springs\/2026\/04\/17\/economia-trump-confianza-consumidor-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-18T01:03:50Z","datePublished":"2026-04-18T01:03:50Z","dateModified":"2026-04-18T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Trump insiste en que la econom\\u00eda va bien, pero los estadounidenses no est\\u00e1n convencidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/economia-trump-confianza-consumidor-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado-springs\\\/2026\\\/04\\\/17\\\/economia-trump-confianza-consumidor-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-18T01:03:50Z\",\"datePublished\":\"2026-04-18T01:03:50Z\",\"dateModified\":\"2026-04-18T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472545,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/03\/25\/trump-deterioro-economia-iran-guerra-trax\/","url_meta":{"origin":1473290,"position":0},"title":"Culpan cada vez m\u00e1s a Trump por el deterioro de la econom\u00eda debido a la guerra con Ir\u00e1n","author":"","date":"marzo 25, 2026","format":false,"excerpt":"En medio de la constante avalancha de acciones a menudo impopulares del presidente Donald Trump, puede ser f\u00e1cil perder de vista lo que probablemente m\u00e1s importa pol\u00edticamente: la econom\u00eda en crisis.Ha sido el mayor problema de Trump y del Partido Republicano (GOP), a unos siete meses de las elecciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471624,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/02\/25\/analisis-trump-economia-ee-uu-gran-problema-trax\/","url_meta":{"origin":1473290,"position":1},"title":"Trump tiene raz\u00f3n: la econom\u00eda de EE.UU. est\u00e1 fuerte, pero el presidente no ve el gran problema","author":"","date":"febrero 25, 2026","format":false,"excerpt":"El presidente Donald Trump hizo una apasionada defensa de la econom\u00eda estadounidense durante su discurso sobre el Estado de la Uni\u00f3n este martes por la noche.\u201cLa inflaci\u00f3n se desploma, los ingresos aumentan r\u00e1pidamente. La econom\u00eda, en pleno auge, avanza como nunca antes\u201d, manifest\u00f3.Hip\u00e9rboles aparte, tiene raz\u00f3n: la econom\u00eda estadounidense es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473207,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/04\/15\/conclusiones-encuestas-iran-trump-trax\/","url_meta":{"origin":1473290,"position":2},"title":"5 conclusiones de encuestas recientes sobre Ir\u00e1n que pintan un panorama cada vez m\u00e1s sombr\u00edo para Trump","author":"","date":"abril 15, 2026","format":false,"excerpt":"El presidente Donald Trump dijo en una nueva entrevista que se emitir\u00e1 este mi\u00e9rcoles que la guerra con Ir\u00e1n estaba \u201cmuy cerca de terminar\u201d (aunque conviene tomar esa afirmaci\u00f3n con cautela, ya que han pasado cinco semanas desde que dijo que estaba \u201ccompleta\u201d).Tambi\u00e9n present\u00f3, posiblemente, su argumento m\u00e1s extenso hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472618,"url":"https:\/\/noticiasya.com\/colorado-springs\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","url_meta":{"origin":1473290,"position":3},"title":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos.La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461915,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/05\/02\/trump-resta-importancia-recesion-desaceleracion-largo-plazo-trax\/","url_meta":{"origin":1473290,"position":4},"title":"Trump resta importancia a los temores de una recesi\u00f3n y dice que una desaceleraci\u00f3n estar\u00eda &#171;bien&#187; a largo plazo","author":"","date":"mayo 2, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, pareci\u00f3 desestimar las crecientes preocupaciones de que sus pol\u00edticas econ\u00f3micas podr\u00edan causar una recesi\u00f3n, diciendo a NBC News que la econom\u00eda estar\u00eda \u201cbien\u201d a largo plazo incluso si ocurre una recesi\u00f3n en el futuro pr\u00f3ximo.\u201cAlgunas personas en Wall Street dicen que vamos a tener\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469231,"url":"https:\/\/noticiasya.com\/colorado-springs\/2025\/12\/12\/trump-conomia-grande-problema-analisis-trax\/","url_meta":{"origin":1473290,"position":5},"title":"Trump dice que est\u00e1 haciendo que la econom\u00eda de EE.UU. vuelva a ser grande, pero est\u00e1 abordando el problema equivocado","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Para muchas personas, la econom\u00eda es una ecuaci\u00f3n simple: ingresos menos gastos. Cuando parece que nuestros ingresos crecen m\u00e1s r\u00e1pido que los precios, la econom\u00eda est\u00e1 en buena forma. Cuando no, est\u00e1 mal.El presidente Donald Trump parece estar haciendo un c\u00e1lculo diferente.En lugar de enfocarse en el costo de vida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/comments?post=1473290"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/posts\/1473290\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/media?parent=1473290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/categories?post=1473290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado-springs\/wp-json\/wp\/v2\/tags?post=1473290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}