{"id":1445008,"date":"2024-02-06T17:33:35","date_gmt":"2024-02-07T01:33:35","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445008"},"modified":"2024-02-06T17:33:35","modified_gmt":"2024-02-07T01:33:35","slug":"milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","title":{"rendered":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En Jerusal\u00e9n, que israel\u00edes y palestinos buscan que sea reconocida como su capital, no es com\u00fan encontrar embajadas de otros pa\u00edses, aunque s\u00ed las hay. El presidente de Argentina, Javier Milei, reiter\u00f3 este martes al arribar al pa\u00eds que tiene la intenci\u00f3n de trasladar la embajada de su pa\u00eds desde Tel Aviv, donde est\u00e1 actualmente, a Jerusal\u00e9n.<\/p>\n<p>&#171;Para mi es un placer y un honor poder estar aqu\u00ed, estoy cumpliendo mi promesa de que la primera visita como presidente es a Israel&#187;, dijo Milei al bajar del avi\u00f3n en Tel Aviv y ser recibido por el canciller Israel Katz. &#171;Obviamente mi plan es mudar la embajada a Jerusal\u00e9n Occidental&#187;, agreg\u00f3.<\/p>\n<p>Milei lleva a Israel e Italia su ambici\u00f3n de ser una figura global<\/p>\n<p>El compromiso de Milei<\/p>\n<p>En agosto pasado, Milei, entonces candidato presidencial de Argentina, ya hab\u00eda mencionado que, de llegar al cargo, cambiar\u00eda la embajada de la naci\u00f3n a Jerusal\u00e9n.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1445008-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/02\/20359618-atl-1.mp4?_=1\" \/><a href=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/02\/20359618-atl-1.mp4\">https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/02\/20359618-atl-1.mp4<\/a><\/video><\/div>\n<p>&#171;A Israel lo considero tan aliado que he dicho que voy a mudar la\u00a0embajada\u00a0desde Tel Aviv a Jerusal\u00e9n&#187;, dijo al canal de noticias LN+.<\/p>\n<p>Y en noviembre \u2015todav\u00eda como candidato\u2015 dijo al periodista Jaime Bayly que, si ganaba, la\u00a0embajada\u00a0argentina estar\u00eda en Jerusal\u00e9n porque &#171;al rey David, en un sue\u00f1o, el creador le manifiesta que la capital de Israel es Jerusal\u00e9n&#187;.<\/p>\n<p>El 3 de diciembre, ya como presidente electo y a unos d\u00edas de su toma de posesi\u00f3n, el Gobierno de Israel inform\u00f3 que el primer ministro, Benjamin Netanyahu, habl\u00f3 con Milei, a quien le agradeci\u00f3 &#171;su intenci\u00f3n de mover la\u00a0embajada\u00a0de Argentina a Jerusal\u00e9n&#187;. En ese momento, el equipo de Milei declin\u00f3 hacer comentarios al respecto, seg\u00fan Reuters. CNN solicit\u00f3 m\u00e1s informaci\u00f3n al respecto a la Presidencia de Argentina, pero por el momento no hemos obtenido respuesta.<\/p>\n<p>Este posible movimiento recuerda las promesas que hizo Donald Trump durante su campa\u00f1a presidencial de 2016, y que termin\u00f3 concretando en 2018: trasladar la\u00a0embajada\u00a0de Estados Unidos de Tel Aviv a Jerusal\u00e9n.<\/p>\n<p>Al reconocer formalmente a Jerusal\u00e9n como la capital en 2017, Trump cambi\u00f3 d\u00e9cadas de pol\u00edtica exterior estadounidense. En ese momento, los cr\u00edticos se\u00f1alaron que marcaba el final del papel de EE.UU. como un &#171;intermediario honesto&#187; en las negociaciones entre israel\u00edes y palestinos.<\/p>\n<p>\u00bfPor qu\u00e9 hay controversia?<\/p>\n<p>Las Naciones Unidas crearon el Estado de Israel en 1947\u00a0mientras\u00a0Gran Breta\u00f1a buscaba una salida\u00a0del\u00a0Medio Oriente. Agotados sus recursos y energ\u00edas por la Segunda Guerra Mundial, Londres ya no estaba interesada en asumir sus responsabilidades posteriores a la Primera Guerra Mundial como potencia mandataria para administrar el territorio.<\/p>\n<p>Gran Breta\u00f1a se hab\u00eda comprometido en 1917 a crear un &#171;hogar nacional jud\u00edo&#187; en lo que se conoci\u00f3 como la Declaraci\u00f3n de Balfour, para lo que utiliz\u00f3 su mandato respaldado internacionalmente. Pero\u00a0el Reino Unido\u00a0se vio pronto\u00a0atrapado\u00a0en medio del conflicto entre los nacionalismos jud\u00edo y \u00e1rabe.<\/p>\n<p>En 1947, la ONU pidi\u00f3 una soluci\u00f3n de dos Estados que dividiera la tierra entre jud\u00edos y \u00e1rabes. Ninguna de las partes qued\u00f3 plenamente satisfecha con este acuerdo, pero al menos respond\u00eda a algunas de sus preocupaciones.<\/p>\n<p>A pesar de que la resoluci\u00f3n ped\u00eda la internacionalizaci\u00f3n de Jerusal\u00e9n, la corriente principal de los sionistas acept\u00f3 lo que se conoci\u00f3 como el Plan de Partici\u00f3n. Aunque los cr\u00edticos internos atacaron por\u00a0su moderaci\u00f3n\u00a0a este bando, liderado por David Ben-Gurion y Chaim Weizmann, sus miembros demostraron un considerable coraje pol\u00edtico y no se disuadieron. Por el contrario, el bando \u00e1rabe consideraba injusto el Plan de Partici\u00f3n en su llamamiento a compartir el territorio, ya que cre\u00edan que los\u00a0jud\u00edos\u00a0no ten\u00edan ning\u00fan derecho sobre la tierra.<\/p>\n<p>Aunque Israel declar\u00f3 a Jerusal\u00e9n como su capital en 1950,\u00a0muchas\u00a0embajadas internacionales\u00a0siguen\u00a0en Tel Aviv.<\/p>\n<p>Estados Unidos fue el primer pa\u00eds en reconocer a Israel como Estado en 1948 y\u00a0al ser tambi\u00e9n el primero en\u00a0reconocer a Jerusal\u00e9n como su capital en 2017,\u00a0desat\u00f3 confrontaciones y protestas en Gaza y la Ribera Occidental, adem\u00e1s del rechazo de m\u00faltiples l\u00edderes isl\u00e1micos.<\/p>\n<p>Israel tiene en la actualidad relaciones diplom\u00e1ticas con 166 pa\u00edses, seg\u00fan su Gobierno.<\/p>\n<p>\u00bfPor qu\u00e9 Jerusal\u00e9n es un punto clave en el conflicto entre Israel y los palestinos?<\/p>\n<p>Sin embargo, los palestinos quieren que un futuro Estado para ellos tenga como capital el sector oriental de Jerusal\u00e9n, lugar que Israel ocupa desde la Guerra de los Seis D\u00edas de 1967. La situaci\u00f3n de los palestinos es compleja, puesto que si bien cuenta con el reconocimiento y relaciones bilaterales con 139 pa\u00edses, no es reconocido oficialmente como Estado ante Naciones Unidas, y los pa\u00edses que reconocen a una entidad palestina lo hacen a trav\u00e9s del Gobierno Aut\u00f3nomo Palestino, presidido por Mahmoud Abbas en la Ribera Occidental.<\/p>\n<p>Es por ello que el movimiento de la\u00a0embajada\u00a0se considera controversial, sobre todo en el contexto actual, en el que se desarrolla una guerra entre Israel y Hamas\u00a0en\u00a0el territorio palestino de Gaza.<\/p>\n<p>\u00bfQu\u00e9 pa\u00edses tienen su\u00a0embajada\u00a0en Tel Aviv?<\/p>\n<p>Albania<br \/>\nAngola<br \/>\nArgentina<br \/>\nArmenia<br \/>\nAustralia<br \/>\nAustria<br \/>\nAzerbaiy\u00e1n<br \/>\nBelar\u00fas<br \/>\nB\u00e9lgica<br \/>\nBosnia y Herzegovina<br \/>\nBrasil<br \/>\nBulgaria<br \/>\nCamer\u00fan<br \/>\nCanad\u00e1<br \/>\nChile<br \/>\nChina<br \/>\nColombia<br \/>\nCongo<br \/>\nRep\u00fablica Democr\u00e1tica del Congo<br \/>\nCosta Rica<br \/>\nCosta de Marfil<br \/>\nCroacia<br \/>\nChipre<br \/>\nRep\u00fablica Checa<br \/>\nDinamarca<br \/>\nRep\u00fablica Dominicana<br \/>\nEcuador<br \/>\nEgipto<br \/>\nEl Salvador<br \/>\nGuinea Ecuatorial<br \/>\nEritrea<br \/>\nEstonia<br \/>\nEtiop\u00eda<br \/>\nFinlandia<br \/>\nFrancia<br \/>\nGeorgia<br \/>\nAlemania<br \/>\nGhana<br \/>\nGrecia<br \/>\nVaticano<br \/>\nHungr\u00eda<br \/>\nIndia<br \/>\nIrlanda<br \/>\nItalia<br \/>\nJap\u00f3n<br \/>\nJordania<br \/>\nKazajst\u00e1n<br \/>\nKenYa<br \/>\nCorea del Sur<br \/>\nLetonia<br \/>\nLituania<br \/>\nMalta<br \/>\nM\u00e9xico<br \/>\nMoldova<br \/>\nMyanmar<br \/>\nNepal<br \/>\nPa\u00edses Bajos<br \/>\nNigeria<br \/>\nMacedonia del Norte<br \/>\nNoruega<br \/>\nPanam\u00e1<br \/>\nParaguay<br \/>\nPer\u00fa<br \/>\nFilipinas<br \/>\nPolonia<br \/>\nPortugal<br \/>\nRumania<br \/>\nRusia<br \/>\nRwanda<br \/>\nSerbia<br \/>\nSingapur<br \/>\nEslovenia<br \/>\nSud\u00e1frica<br \/>\nSud\u00e1n del Sur<br \/>\nEspa\u00f1a<br \/>\nSri Lanka<br \/>\nSuecia<br \/>\nSuiza<br \/>\nTailandia<br \/>\nTurqu\u00eda<br \/>\nUcrania<br \/>\nReino Unido<br \/>\nTanzania<br \/>\nUruguay<br \/>\nUzbekist\u00e1n<br \/>\nVietnam<br \/>\nZambia<\/p>\n<p>Fuente: Ministerio de Asuntos Exteriores de Israel<\/p>\n<p>\u00bfCu\u00e1les pa\u00edses tienen su\u00a0embajada\u00a0en Jerusal\u00e9n?<\/p>\n<p>Guatemala<br \/>\nPapua Nueva Guinea<br \/>\nEstados Unidos<\/p>\n<p>Fuente: Ministerio de Asuntos Exteriores de Israel<\/p>\n<p>De acuerdo con informaci\u00f3n del Ministerio de Asuntos Exteriores israel\u00ed, hay dos pa\u00edses que tienen su\u00a0embajada\u00a0fuera de la ciudad de Jerusal\u00e9n y del distrito de Tel Aviv. Se trata de la\u00a0embajada\u00a0de Honduras, ubicada en Rishon LeZion, ciudad en el Distrito Central; y la de Malawi, tambi\u00e9n en ese distrito.<\/p>\n<p>Con informaci\u00f3n Abbas Al Lawati, Oren Liebermann, Flora Charner, James Masters, Tim Hume, Nectar Gan y Ashley Fantz de CNN.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En Jerusal\u00e9n, que israel\u00edes y palestinos buscan que sea reconocida como su capital, no es com\u00fan encontrar embajadas de otros pa\u00edses, aunque s\u00ed las hay. El presidente de Argentina, Javier Milei, reiter\u00f3 este martes al arribar al pa\u00eds que tiene la intenci\u00f3n de trasladar la embajada de su pa\u00eds desde Tel Aviv, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445008","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; En Jerusal\u00e9n, que israel\u00edes y palestinos buscan que sea reconocida como su capital, no es com\u00fan encontrar embajadas de otros pa\u00edses, aunque s\u00ed las hay. El presidente de Argentina, Javier Milei, reiter\u00f3 este martes al arribar al pa\u00eds que tiene la intenci\u00f3n de trasladar la embajada de su pa\u00eds desde Tel Aviv, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T01:33:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?\",\"datePublished\":\"2024-02-07T01:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\"},\"wordCount\":1175,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\",\"name\":\"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-07T01:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; En Jerusal\u00e9n, que israel\u00edes y palestinos buscan que sea reconocida como su capital, no es com\u00fan encontrar embajadas de otros pa\u00edses, aunque s\u00ed las hay. El presidente de Argentina, Javier Milei, reiter\u00f3 este martes al arribar al pa\u00eds que tiene la intenci\u00f3n de trasladar la embajada de su pa\u00eds desde Tel Aviv, [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","og_site_name":"Noticias","article_published_time":"2024-02-07T01:33:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/"},"author":{"name":"","@id":""},"headline":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?","datePublished":"2024-02-07T01:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/"},"wordCount":1175,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","name":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-07T01:33:35+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?","url":"http:\/\/noticiasya.com\/colorado\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-07T01:33:35Z","datePublished":"2024-02-07T01:33:35Z","dateModified":"2024-02-07T01:33:35Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Milei reitera su intenci\\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\\u00e9n: \\u00bfqu\\u00e9 pa\\u00edses tienen su embajada en cada ciudad?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/06\\\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/06\\\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-07T01:33:35Z\",\"datePublished\":\"2024-02-07T01:33:35Z\",\"dateModified\":\"2024-02-07T01:33:35Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447932,"url":"https:\/\/noticiasya.com\/colorado\/2024\/04\/10\/javier-milei-embajador-de-la-luz-orix\/","url_meta":{"origin":1445008,"position":0},"title":"\u201cEmbajadores internacionales de la luz\u201d, \u00bfqu\u00e9 significa el reconocimiento a Javier Milei y su hermana Karina?","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, y su hermana y secretaria general de la presidencia, Karina Milei, recibir\u00e1n este mi\u00e9rcoles la distinci\u00f3n \u201cEmbajadores Internacionales de la Luz\u201d. \u00bfDe qu\u00e9 se trata este reconocimiento?Los hermanos Milei viajaron el martes en la noche en la aerol\u00ednea de bandera Aerol\u00edneas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447553,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/30\/milei-diplomacia-peleas-latinoamerica-orix\/","url_meta":{"origin":1445008,"position":1},"title":"Peleas con mandatarios regionales y acercamiento a EE.UU. e Israel, \u00bfhacia d\u00f3nde va la diplomacia de Milei?","author":"","date":"marzo 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Bast\u00f3 con un adelanto de una entrevista de CNN con el presidente de Argentina, Javier Milei, que se emitir\u00e1 este domingo, para que sus dichos explosivos crearan un conflicto diplom\u00e1tico con Colombia, que a\u00fan resta saber c\u00f3mo terminar\u00e1 de dirimirse, y un fuerte cruce con M\u00e9xico, que llev\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472056,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/10\/milei-sionista-discurso-nueva-york-iran-eeuu-israel-orix\/","url_meta":{"origin":1445008,"position":2},"title":"&#171;Me siento orgulloso de ser el presidente m\u00e1s sionista del mundo&#187;, dijo Milei desde Nueva York","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Mientras el conflicto en Medio Oriente sigue avanzando y la geopol\u00edtica se sacude, el presidente de Argentina, Javier Milei, volvi\u00f3 a posicionarse como aliado fiel de Estados Unidos e Israel.En una disertaci\u00f3n en la Universidad Yeshiva en Nueva York, Milei dijo que se siente orgulloso de \u201cser el presidente m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447613,"url":"https:\/\/noticiasya.com\/colorado\/2024\/04\/01\/amlo-relaciones-milei-mexico-argentina-trax\/","url_meta":{"origin":1445008,"position":3},"title":"AMLO dice que las relaciones entre M\u00e9xico y Argentina se mantienen a pesar de los cruces con Milei","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, asegur\u00f3 este lunes que su pa\u00eds mantiene las relaciones diplom\u00e1ticas con Argentina a pesar de la disputa verbal que intercambiaron \u00e9l y el mandatario de Argentina, Javier Milei, durante los \u00faltimos d\u00edas.Argentina y M\u00e9xico niegan conflicto diplom\u00e1tico tras cruce de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462676,"url":"https:\/\/noticiasya.com\/colorado\/2025\/05\/22\/quienes-son-victimas-tiroteo-museo-judio-washington-orix\/","url_meta":{"origin":1445008,"position":4},"title":"\u00bfQui\u00e9nes son las v\u00edctimas del tiroteo frente al Museo Jud\u00edo Capital en Washington?","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Este mi\u00e9rcoles, dos miembros del personal de la Embajada de Israel en la ciudad de Washington murieron luego de un tiroteo que tuvo lugar en las cercan\u00edas del Museo Jud\u00edo Capital.El sospechoso, a quien la jefa del Departamento de Polic\u00eda Metropolitana de Washington, Pamela Smith, identific\u00f3 como El\u00edas Rodr\u00edguez, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448260,"url":"https:\/\/noticiasya.com\/colorado\/2024\/04\/19\/riesgos-politica-javier-milei-medio-oriente-orix\/","url_meta":{"origin":1445008,"position":5},"title":"Los riesgos de la nueva pol\u00edtica de Javier Milei sobre Medio Oriente","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El ataque de Ir\u00e1n a Israel suscit\u00f3 una reacci\u00f3n in\u00e9dita en el gobierno argentino, poniendo sobre la mesa una pregunta que se instal\u00f3 en el debate p\u00fablico y se replic\u00f3 en diarios y canales de televisi\u00f3n, referentes pol\u00edticos y analistas.Con el antecedente de los atentados a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1445008"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445008\/revisions"}],"predecessor-version":[{"id":1445023,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445008\/revisions\/1445023"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1445008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1445008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1445008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}