{"id":1445038,"date":"2024-02-07T08:33:36","date_gmt":"2024-02-07T16:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445038"},"modified":"2024-02-07T08:33:36","modified_gmt":"2024-02-07T16:33:36","slug":"consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","title":{"rendered":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia"},"content":{"rendered":"<p>(CNN) &#8212; Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio.<\/p>\n<p>La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9 muri\u00f3 debido a una fractura en el cuello y que se le desprendi\u00f3 la cabeza, seg\u00fan un comunicado de prensa compartido con CNN.<\/p>\n<p>La mujer de 20 a\u00f1os, Jessica Ross, present\u00f3 una demanda en agosto alegando que el Centro M\u00e9dico Regional Sur intent\u00f3 ocultar la forma de muerte del beb\u00e9, Treveon Isaiah Taylor Jr., a ella y a su novio, Trevon Isaiah Taylor. Sr., junto con toda la familia.<\/p>\n<p>La oficina del m\u00e9dico forense dijo que el beb\u00e9 de Ross muri\u00f3 por \u201cfractura-dislocaci\u00f3n con secci\u00f3n completa, columna cervical superior (C1-C2) y m\u00e9dula espinal\u201d, debido a \u201cdistocia de hombros, detenci\u00f3n del parto y atrapamiento fetal en el canal del parto\u201d, seg\u00fan el comunicado de prensa.<\/p>\n<p>Una mujer de Georgia alega que su beb\u00e9 fue decapitado durante el parto y que intentaron ocult\u00e1rselo a la familia, seg\u00fan una demanda<\/p>\n<p>El m\u00e9dico forense dijo que la diabetes inducida por el embarazo y la rotura prematura de membranas tambi\u00e9n fueron condiciones importantes que contribuyeron a la muerte de Taylor.<\/p>\n<p>El centro m\u00e9dico est\u00e1 en Riverdale, a unos 20 kil\u00f3metros al sur del centro de Atlanta. El beb\u00e9, que lleva el nombre de su padre, naci\u00f3 tras cumplir los nueves meses de gestaci\u00f3n, seg\u00fan el abogado de la familia.<\/p>\n<p>Ross tuvo el parto el 9 de julio y su m\u00e9dico intent\u00f3 dar a luz al beb\u00e9 utilizando varios m\u00e9todos, incluida \u201caplicar tracci\u00f3n a la cabeza del beb\u00e9\u201d, dice la demanda.<\/p>\n<p>Durante el intento de parto, \u201cel beb\u00e9 no descendi\u00f3 adecuadamente debido a la distocia de hombros\u201d, una condici\u00f3n en la que los hombros del beb\u00e9 quedan atrapados en el canal vaginal, dice la demanda.<\/p>\n<p>Ross dice que el m\u00e9dico aplic\u00f3 tracci\u00f3n excesiva \u201cgroseramente\u201d y \u201cnegligentemente\u201d en la cabeza y el cuello de su beb\u00e9, dice la denuncia. El m\u00e9dico tambi\u00e9n est\u00e1 acusado de no realizar una ces\u00e1rea \u201cde manera oportuna y adecuada\u201d, lo que result\u00f3 en la decapitaci\u00f3n y muerte del beb\u00e9, seg\u00fan la demanda. La ces\u00e1rea se complet\u00f3 alrededor de las 3 a.m. del 10 de julio, seg\u00fan el documento.<\/p>\n<p>El racismo sist\u00e9mico impulsa el aumento de los trabajos de parto inducidos en madres latinas y negras, revela estudio<\/p>\n<p>En una declaraci\u00f3n emitida a CNN despu\u00e9s del anuncio del m\u00e9dico forense, un portavoz del Southern Regional Medical Center dijo: &#171;Debido al litigio actual, no podemos hacer comentarios&#187;.<\/p>\n<p>En agosto, despu\u00e9s de que Ross present\u00f3 la demanda, el hospital dijo en un comunicado que \u201cniega las acusaciones en la denuncia que hacen referencia al hospital\u201d.<\/p>\n<p>El portavoz de la familia dijo que cuando Ross y Taylor \u201cexigieron ver y sostener a su beb\u00e9, el personal del hospital les dijo que no se les permit\u00eda tocar ni sostener a su hijo\u201d.<\/p>\n<p>&#171;Nuestros m\u00e1s sinceros pensamientos y oraciones est\u00e1n con la familia y todos los afectados por este tr\u00e1gico evento\u201d, se lee en el comunicado del centro m\u00e9dico. \u201cNuestras oraciones tambi\u00e9n permanecen con el dedicado equipo de m\u00e9dicos, enfermeras y personal del Southern Regional Medical Center que atendieron a este paciente. Nuestro compromiso es brindar atenci\u00f3n compasiva y de calidad a cada paciente, y esta p\u00e9rdida es desgarradora\u201d.<\/p>\n<p>Los trabajadores s\u00f3lo permitieron a la pareja ver el cuerpo de su hijo muerto, dijo el portavoz de la familia.<\/p>\n<p>\u201cDurante esta visita, su beb\u00e9 estaba envuelto firmemente en una manta con la cabeza apoyada sobre su cuerpo de una manera tal que quienes lo vieron no pudieron identificar que hab\u00eda sido decapitado\u201d, dice el comunicado.<\/p>\n<p>\u201cNunca antes hab\u00eda presenciado algo as\u00ed. Nadie en nuestra oficina ha visto algo como esto. Todas las personas a las que hemos consultado nunca antes hab\u00edan visto una situaci\u00f3n como esta\u201d, dijo a CNN este martes el director del Departamento de medicina forense del condado de Clayton, Brian Byars. &#171;Me parece muy inusual que el hospital no se haya comunicado con nuestra oficina debido a la cantidad de trauma involucrado en este incidente&#187;.<\/p>\n<p>El caso a\u00fan est\u00e1 bajo investigaci\u00f3n por el Departamento de Polic\u00eda del condado de Clayton y podr\u00eda ser remitido a la oficina del Fiscal de Distrito, seg\u00fan el comunicado.<\/p>\n<p>Se espera que Ross y su novio den una conferencia de prensa p\u00fablica en Atlanta este mi\u00e9rcoles a las 11 a.m. hora del este de Estados Unidos.<\/p>\n<p>&#8212; Nick Valencia de CNN tambi\u00e9n contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio. La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9 muri\u00f3 debido a una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445038","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio. La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9 muri\u00f3 debido a una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T16:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia\",\"datePublished\":\"2024-02-07T16:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\"},\"wordCount\":850,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\",\"name\":\"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-07T16:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","og_locale":"es_ES","og_type":"article","og_title":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias","og_description":"(CNN) &#8212; Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio. La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9 muri\u00f3 debido a una [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","og_site_name":"Noticias","article_published_time":"2024-02-07T16:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/"},"author":{"name":"","@id":""},"headline":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia","datePublished":"2024-02-07T16:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/"},"wordCount":850,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","name":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-07T16:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia","url":"http:\/\/noticiasya.com\/colorado\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-07T16:33:36Z","datePublished":"2024-02-07T16:33:36Z","dateModified":"2024-02-07T16:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Consideran homicidio la muerte de un beb\\u00e9 que sufri\\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/07\\\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/07\\\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-07T16:33:36Z\",\"datePublished\":\"2024-02-07T16:33:36Z\",\"dateModified\":\"2024-02-07T16:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445036,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/07\/consideran-homicidio-la-muerte-de-un-bebe-que-sufrio-una-fractura-en-el-cuello-durante-el-parto-en-un-hospital-de-georgia\/","url_meta":{"origin":1445038,"position":0},"title":"Consideran homicidio la muerte de un beb\u00e9 que sufri\u00f3 una fractura en el cuello durante el parto en un hospital de Georgia","author":"","date":"febrero 7, 2024","format":false,"excerpt":"(CNN) -- Un m\u00e9dico forense dio a conocer este martes la forma de la muerte de un beb\u00e9 cuya madre acus\u00f3 a un hospital de Georgia y a otros de decapitarlo durante el parto, calific\u00e1ndolo de homicidio.La oficina del m\u00e9dico forense del condado de Clayton, Georgia, dijo que el beb\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450955,"url":"https:\/\/noticiasya.com\/colorado\/2024\/07\/08\/bebe-murio-abandonada-texas-acusaron-madre-trax\/","url_meta":{"origin":1445038,"position":1},"title":"El caso de una reci\u00e9n nacida que muri\u00f3 abandonada estuvo sin resolverse por 23 a\u00f1os. Las autoridades de Texas acaban de acusar a su madre de homicidio accidental","author":"","date":"julio 8, 2024","format":false,"excerpt":"(CNN) -- Una beb\u00e9 reci\u00e9n nacida que muri\u00f3 abandonada en una zanja de Texas estuvo sin identificar durante 23 a\u00f1os hasta que las autoridades dijeron que recientemente reconocieron y acusaron a la madre.La Oficina del Sheriff del Condado de Johnson se ha referido a la beb\u00e9 como \"Angel Baby Doe\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461288,"url":"https:\/\/noticiasya.com\/colorado\/2025\/04\/16\/causa-muerte-michelle-trachtenberg-complicaciones-diabetes-mellitus-trax\/","url_meta":{"origin":1445038,"position":2},"title":"Se revela que la causa de la muerte de Michelle Trachtenberg fueron complicaciones de la diabetes mellitus","author":"","date":"abril 16, 2025","format":false,"excerpt":"La causa de muerte de la actriz Michelle Trachtenberg, quien falleci\u00f3 en febrero, fue confirmada como complicaciones de diabetes mellitus, inform\u00f3 este mi\u00e9rcoles a CNN un portavoz de la oficina del m\u00e9dico forense de la ciudad de Nueva York.Su causa de muerte fue inicialmente considerada indeterminada porque su familia rechaz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456530,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/12\/prueba-adn-abuela-asesinato-trax\/","url_meta":{"origin":1445038,"position":3},"title":"Se hizo una prueba de ADN por diversi\u00f3n. La polic\u00eda la us\u00f3 para acusar a su abuela de un asesinato de 1997","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Era la mitad de la jornada laboral de Jenna Gerwatowski en la florister\u00eda local en Newberry, Michigan, cuando recibi\u00f3 una llamada de un n\u00famero desconocido.La mujer, que ahora tiene 23 a\u00f1os, no suele responder llamadas de n\u00fameros desconocidos, pero dice que decidi\u00f3 contestar esta vez, en mayo de 2022.Para su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470356,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/21\/medico-forense-muerte-cubano-ice-texas-homicidio-trax\/","url_meta":{"origin":1445038,"position":4},"title":"El m\u00e9dico forense dictamina que la muerte de un detenido cubano de ICE en una instalaci\u00f3n de Texas fue un homicidio","author":"","date":"enero 21, 2026","format":false,"excerpt":"A principios de este mes, el Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s) inform\u00f3 que un migrante cubano falleci\u00f3 en una instalaci\u00f3n de detenci\u00f3n en Texas tras experimentar \u201cangustia m\u00e9dica\u201d, sin ofrecer detalles sobre lo ocurrido en sus \u00faltimos momentos.Ahora, un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465014,"url":"https:\/\/noticiasya.com\/colorado\/2025\/07\/31\/revelan-causa-muerte-hulk-hogan-trax\/","url_meta":{"origin":1445038,"position":5},"title":"Revelan la causa de muerte de Hulk Hogan","author":"","date":"julio 31, 2025","format":false,"excerpt":"El luchador profesional Hulk Hogan muri\u00f3 de un ataque al coraz\u00f3n, seg\u00fan las autoridades.La causa oficial de muerte de Hogan se cita como \u201cinfarto agudo de miocardio\u201d, que en t\u00e9rminos sencillos significa un ataque al coraz\u00f3n, de acuerdo con un informe de aprobaci\u00f3n de cremaci\u00f3n de la oficina del m\u00e9dico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1445038"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445038\/revisions"}],"predecessor-version":[{"id":1445054,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445038\/revisions\/1445054"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1445038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1445038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1445038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}