{"id":1445146,"date":"2024-02-09T05:33:32","date_gmt":"2024-02-09T13:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445146"},"modified":"2024-02-09T05:33:32","modified_gmt":"2024-02-09T13:33:32","slug":"british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","title":{"rendered":"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful"},"content":{"rendered":"<p>(CNN) &#8212; En el \u00faltimo n\u00famero de la revista British Vogue bajo la direcci\u00f3n de Edward Enninful, el editor no puso a una superestrella en la portada, sino a 40.<\/p>\n<p>El editor de moda de origen ghan\u00e9s abandon\u00f3 inesperadamente su puesto en junio, tras m\u00e1s de seis a\u00f1os al frente de la revista. Su portada final re\u00fane a supermodelos, megaestrellas de Hollywood, iconos del pop y otras estrellas de la moda con las que ha trabajado, como Naomi Campbell, Cindy Crawford, Miley Cyrus, Linda Evangelista, Jane Fonda, Dua Lipa, Kate Moss y Serena Williams.<\/p>\n<p>Fotografiadas en Manhattan por Steven Meisel (para la portada) y Ned Rogers (para las p\u00e1ginas interiores), las 40 mujeres volaron desde Londres, Par\u00eds, Mil\u00e1n, Los \u00c1ngeles y otros lugares para formar parte de este n\u00famero hist\u00f3rico, se\u00f1al\u00f3 Enninful en su carta final al editor.<\/p>\n<p>(Cr\u00e9dito: Steven Meisel)<\/p>\n<p>&#171;Cuando lleg\u00f3 mi \u00faltimo n\u00famero, sab\u00eda que la portada estar\u00eda dedicada a las mujeres. \u00a1Por supuesto! Las mujeres han dado forma a British Vogue durante casi 108 a\u00f1os, y sin duda han influido en cada momento de mis seis a\u00f1os y medio aqu\u00ed, por no decir que me han guiado a lo largo de toda mi vida&#187;, escribi\u00f3 Enninful.<\/p>\n<p>&#171;Todos los miembros del equipo ten\u00edamos claro que ninguna mujer pod\u00eda o deb\u00eda encapsular estos \u00faltimos a\u00f1os para la revista&#187;, a\u00f1adi\u00f3. &#171;Lo que necesit\u00e1bamos era un grupo, apoyarnos en el poder del colectivo para dar vida a lo que espero que haya sido un periodo atrevido, disruptivo y evolutivo en la historia de Vogue&#187;.<\/p>\n<p>La noticia de la marcha de Enninful conmocion\u00f3 al mundo de la moda el a\u00f1o pasado. Despu\u00e9s de una carrera que influy\u00f3 en las altas esferas de la industria a trav\u00e9s de puestos en i-D, W y American Vogue, Enninful defendi\u00f3 la diversidad en la edici\u00f3n brit\u00e1nica de esta \u00faltima revista en lo que muchos vieron como una nueva direcci\u00f3n muy necesaria para la publicaci\u00f3n.<\/p>\n<p>Durante su mandato se produjeron varias primicias hist\u00f3ricas, como la contrataci\u00f3n de las fot\u00f3grafas negras Misan Harriman y Kennedi Carter para las portadas, ambas en 2020, y una serie de cinco portadas protagonizadas por activistas, modelos y creativos discapacitados para el n\u00famero de mayo de 2023.<\/p>\n<p>(Cr\u00e9dito: Ned Rogers)<\/p>\n<p>Enninful tambi\u00e9n eludi\u00f3 las normas edadistas de la industria con un n\u00famero de 2019 dedicado a mujeres de m\u00e1s de 50 a\u00f1os (con Fonda en portada). Otras de sus portadas fueron Miriam Margolyes, de 82 a\u00f1os, que pos\u00f3 desnuda para el n\u00famero del Mes del Orgullo del a\u00f1o pasado, y Dame Judi Dench, que entonces ten\u00eda 85 a\u00f1os.<\/p>\n<p>Para el \u00faltimo n\u00famero de Enninful, Christy Turlington, de 55 a\u00f1os, una de las 40 estrellas de la portada, reconoci\u00f3 un cambio en la aceptaci\u00f3n. &#171;Cada vez celebramos mejor a las mujeres de todas las edades&#187;, dijo.<\/p>\n<p>En 2022, se rumore\u00f3 que Enninful era el siguiente en la l\u00ednea de sucesi\u00f3n para el puesto m\u00e1s alto de American Vogue, aunque en aquel momento dijo a Christiane Amanpour, de CNN, que &#171;no quer\u00eda&#187; el puesto de Anna Wintour y que ella no iba a dimitir a corto plazo. Ahora asumir\u00e1 un puesto de asesor en Cond\u00e9 Nast, la editorial de Vogue, un movimiento que, seg\u00fan ha dicho anteriormente, le da &#171;la libertad de asumir proyectos creativos m\u00e1s amplios&#187;.<\/p>\n<p>Por su parte, Chioma Nnadi, exeditora digital de American Vogue, tomar\u00e1 el tim\u00f3n de British Vogue, convirti\u00e9ndose en la primera mujer negra en ocupar este puesto. Enninful ha calificado anteriormente a Nnadi de &#171;talento brillante y \u00fanico con una visi\u00f3n real, que llevar\u00e1 a la publicaci\u00f3n a cotas cada vez m\u00e1s altas&#187;.<\/p>\n<p>Naomi Campbell. (Cr\u00e9dito: Ned Rogers)<\/p>\n<p>Miley Cyrus. (Cr\u00e9dito: Ned Rogers)<\/p>\n<p>En referencia a su nuevo papel en su \u00faltima carta como editor, Enninful est\u00e1 &#171;decidido a seguir defendiendo la incre\u00edble variedad de voces en la moda y los medios de comunicaci\u00f3n, y a garantizar que mantenemos la explosi\u00f3n de energ\u00eda de los \u00faltimos a\u00f1os&#187;.<\/p>\n<p>&#171;Siempre lo decimos, porque siempre hay que decirlo: a\u00fan queda mucho por hacer&#187;, a\u00f1adi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; En el \u00faltimo n\u00famero de la revista British Vogue bajo la direcci\u00f3n de Edward Enninful, el editor no puso a una superestrella en la portada, sino a 40. El editor de moda de origen ghan\u00e9s abandon\u00f3 inesperadamente su puesto en junio, tras m\u00e1s de seis a\u00f1os al frente de la revista. Su portada [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445146","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>British Vogue retrata a 40 estrellas de portada &quot;legendarias&quot; en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"British Vogue retrata a 40 estrellas de portada &quot;legendarias&quot; en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; En el \u00faltimo n\u00famero de la revista British Vogue bajo la direcci\u00f3n de Edward Enninful, el editor no puso a una superestrella en la portada, sino a 40. El editor de moda de origen ghan\u00e9s abandon\u00f3 inesperadamente su puesto en junio, tras m\u00e1s de seis a\u00f1os al frente de la revista. Su portada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T13:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful\",\"datePublished\":\"2024-02-09T13:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\"},\"wordCount\":750,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\",\"url\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\",\"name\":\"British Vogue retrata a 40 estrellas de portada \\\"legendarias\\\" en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-09T13:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"British Vogue retrata a 40 estrellas de portada \"legendarias\" en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","og_locale":"es_ES","og_type":"article","og_title":"British Vogue retrata a 40 estrellas de portada \"legendarias\" en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias","og_description":"(CNN) &#8212; En el \u00faltimo n\u00famero de la revista British Vogue bajo la direcci\u00f3n de Edward Enninful, el editor no puso a una superestrella en la portada, sino a 40. El editor de moda de origen ghan\u00e9s abandon\u00f3 inesperadamente su puesto en junio, tras m\u00e1s de seis a\u00f1os al frente de la revista. Su portada [&hellip;]","og_url":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","og_site_name":"Noticias","article_published_time":"2024-02-09T13:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/"},"author":{"name":"","@id":""},"headline":"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful","datePublished":"2024-02-09T13:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/"},"wordCount":750,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","url":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","name":"British Vogue retrata a 40 estrellas de portada \"legendarias\" en el \u00faltimo n\u00famero del editor Edward Enninful - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-09T13:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/reno\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \u00faltimo n\u00famero del editor Edward Enninful","url":"http:\/\/noticiasya.com\/colorado\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2024\/02\/09\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-09T13:33:32Z","datePublished":"2024-02-09T13:33:32Z","dateModified":"2024-02-09T13:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"British Vogue retrata a 40 estrellas de portada &#171;legendarias&#187; en el \\u00faltimo n\\u00famero del editor Edward Enninful\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/09\\\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/09\\\/british-vogue-retrata-a-40-estrellas-de-portada-legendarias-en-el-ultimo-numero-del-editor-edward-enninful\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-09T13:33:32Z\",\"datePublished\":\"2024-02-09T13:33:32Z\",\"dateModified\":\"2024-02-09T13:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463981,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/26\/anna-wintour-deja-cargo-vogue-trax\/","url_meta":{"origin":1445146,"position":0},"title":"Anna Wintour deja su cargo como editora en jefe de Vogue","author":"","date":"junio 26, 2025","format":false,"excerpt":"Tras casi cuatro d\u00e9cadas como editora en jefe de Vogue Estados Unidos, Anna Wintour dejar\u00e1 el cargo y busca a su reemplazo, confirm\u00f3 Cond\u00e9 Nast \u2014la editorial de la revista\u2014 a CNN.Wintour comunic\u00f3 la noticia al equipo este jueves. Aunque dejar\u00e1 el puesto m\u00e1s alto en Vogue, no se desvincular\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450558,"url":"https:\/\/noticiasya.com\/colorado\/2024\/06\/20\/sobreviviente-holocausto-portada-vogue-alemania-trax\/","url_meta":{"origin":1445146,"position":1},"title":"Una sobreviviente del Holocausto de 102 a\u00f1os es la estrella de la portada de Vogue Alemania","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN) -- Una superviviente del Holocausto de 102 a\u00f1os cuya familia fue asesinada en Auschwitz es la estrella de la portada de la edici\u00f3n de julio\/agosto de Vogue Alemania.Margot Friedl\u00e4nder, cuyo apellido de soltera es Bendheim, naci\u00f3 en Berl\u00edn en 1921. Seg\u00fan una breve biograf\u00eda en el sitio web del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450836,"url":"https:\/\/noticiasya.com\/colorado\/2024\/07\/01\/jill-biden-portada-vogue-trax\/","url_meta":{"origin":1445146,"position":2},"title":"&#171;Seguiremos luchando&#187;: Jill Biden es la m\u00e1s reciente estrella de portada en Vogue","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN) -- La primera dama de Estados Unidos, la Dra. Jill Biden, es la estrella de la portada de agosto de Vogue justo cuando la temporada electoral se pone seria en el pa\u00eds, y s\u00f3lo d\u00edas despu\u00e9s de que la inestable actuaci\u00f3n del presidente Joe Biden en el primer debate\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466084,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/02\/anna-wintour-chloe-malle-vogue-trax\/","url_meta":{"origin":1445146,"position":3},"title":"Despu\u00e9s de meses de especulaci\u00f3n, Anna Wintour nombra a Chloe Malle para el principal puesto de Vogue","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"Despu\u00e9s de meses de especulaci\u00f3n sobre qui\u00e9n reemplazar\u00eda a la editora jefa m\u00e1s famosa de la moda, Anna Wintour ha designado a la nueva editora principal en Vogue, aunque el puesto no es exactamente el codiciado cargo que Wintour ocup\u00f3 durante casi 40 a\u00f1os.Chloe Malle, quien actualmente se desempe\u00f1a como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458417,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/07\/time-revista-provocativa-portada-elon-musk-escritorio-trump-trax\/","url_meta":{"origin":1445146,"position":4},"title":"La provocativa portada de la revista Time pone a Elon Musk tras el escritorio de Trump","author":"","date":"febrero 7, 2025","format":false,"excerpt":"En un movimiento provocador que podr\u00eda estar dirigido a avivar la ira del presidente de Estados Unidos, Donald Trump, la \u00faltima portada impresa de la revista Time muestra a Elon Musk detr\u00e1s del escritorio Resolute del Despacho Oval.La hist\u00f3rica publicaci\u00f3n quincenal, conocida por sus portadas hist\u00f3ricamente significativas, sale en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468654,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/criticas-patrocinio-bezos-gala-met-trax\/","url_meta":{"origin":1445146,"position":5},"title":"La Gala del Met enfrenta cr\u00edticas por el patrocinio de Jeff Bezos y su esposa Lauren S\u00e1nchez. Esto opina Anna Wintour","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"Anna Wintour describi\u00f3 a la fil\u00e1ntropa y experiodista estadounidense Lauren S\u00e1nchez Bezos como una \u201cgran amante del vestuario y, obviamente, de la moda\u201d al ser consultada sobre las cr\u00edticas en torno a su papel como patrocinadora de la Gala del Met de 2026.En declaraciones a CNN en Doha, Qatar, durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1445146"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445146\/revisions"}],"predecessor-version":[{"id":1445163,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445146\/revisions\/1445163"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1445146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1445146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1445146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}